{"id":6859,"date":"2024-01-06T17:21:34","date_gmt":"2024-01-06T16:21:34","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=6859"},"modified":"2024-01-06T17:21:34","modified_gmt":"2024-01-06T16:21:34","slug":"previa-castellon-osasuna-duelo-copero-despues-de-reyes","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/01\/06\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\/","title":{"rendered":"Previa Castell\u00f3n-Osasuna: Duelo copero despu\u00e9s de Reyes"},"content":{"rendered":"<p>El d\u00eda <strong>7 de enero a las 16:00 horas<\/strong> tendr\u00e1 lugar el encuentro entre<strong><a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/1a-rfef\/\"> Castell\u00f3n<\/a> y <a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/osasuna\/\">Osasuna<\/a><\/strong>, en el <strong>Estadio de Castalia<\/strong>, en la ronda de <strong>dieciseisavos de final de la <a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/copa-del-rey\/\">Copa del Rey<\/a><\/strong>. El encuentro ser\u00e1 retransmitido por <strong>Movistar+ Liga de Campeones 2<\/strong>, y ser\u00e1 arbitrado por el colegiado murciano <strong>S\u00e1nchez Mart\u00ednez<\/strong>.<\/p>\n<h2>Din\u00e1micas<\/h2>\n<p>El conjunto local se encuentra ante un partido hist\u00f3rico, ya que <strong>no jugaban unos dieciseisavos<\/strong> de Copa del Rey desde la <strong>temporada 08\/09<\/strong>, en los que acab\u00f3 con derrota por 2-0 ante el Real Betis. El Castell\u00f3n es uno de los <strong>equipos m\u00e1s en forma de 1 <a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/1a-rfef\/\">rfef<\/a><\/strong>, ya que lidera el grupo 2 y solo ha perdido 3 partidos en lo que llevamos de temporada.<\/p>\n<p>Por parte del conjunto rojillo, parte como gran favorito para llevarse la eliminatoria, debemos recordar que es el <strong>actual subcampe\u00f3n de la competici\u00f3n<\/strong> y disputar\u00e1 la Supercopa de Espa\u00f1a. Osasuna no se encuentra en su mejor momento ya que es duod\u00e9cimo en <a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-ea-sports\/\"><strong>La Liga EA Sports<\/strong><\/a>.<\/p>\n<figure style=\"width: 1200px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/media.bnn.network\/content\/uploads\/2024\/01\/osasuna-copa-del-rey-match-against-castellon-20240106153339.jpg\" alt=\"Osasuna vs Castellon: Copa del Rey Showdown\" width=\"1200\" height=\"675\" \/><figcaption class=\"wp-caption-text\">David Garc\u00eda y en el fondo sus compa\u00f1eros. Fuente BNN Breaking<\/figcaption><\/figure>\n<h2>An\u00e1lisis de los equipos<\/h2>\n<p>El conjunto de la comunidad valenciana es un equipo que est\u00e1 completando una campa\u00f1a espectacular pese a ser superado frente a algunos de sus rivales directos por el ascenso. En las fases previas de la Copa del Rey <strong>ha conseguido eliminar al Cacere\u00f1o<\/strong> en la pr\u00f3rroga y a un hist\u00f3rico como el <strong>Real Oviedo<\/strong> por 2-1.<\/p>\n<p>Por el lado de Osasuna, no est\u00e1n completando su mejor campa\u00f1a, pero est\u00e1 revirtiendo la situaci\u00f3n con dos victorias en los \u00faltimos tres partidos. El <strong>conjunto rojillo<\/strong>, va ha realizar su <strong>partido debut<\/strong> en la competici\u00f3n est\u00e1 temporada, gracias a su gran actuaci\u00f3n la temporada pasada y clasificarse para la Supercopa.<\/p>\n<figure style=\"width: 1200px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/estaticos-cdn.prensaiberica.es\/clip\/54e24b21-b216-41d9-82c3-21ff298b1965_16-9-discover-aspect-ratio_default_0_x2120y234.jpg\" alt=\"As\u00ed te hemos contado la victoria del Castell\u00f3n ante Osasuna B en el primer  partido de Albert Rud\u00e9 (1-3) - El Peri\u00f3dico Mediterr\u00e1neo\" width=\"1200\" height=\"675\" \/><figcaption class=\"wp-caption-text\">Jugadores del Castell\u00f3n festejando un gol. Fuente El Peri\u00f3dico Mediterr\u00e1neo<\/figcaption><\/figure>\n<h2>Principales armas<\/h2>\n<p>Por parte del Castell\u00f3n, tienen un claro referente,<strong> Jes\u00fas De Miguel<\/strong>, que ha conseguido 13 dianas y 2 asistencias en 18 partidos jugados. Tambi\u00e9n hay que tener en cuenta al jugador bosnio, <strong>Medunjanin<\/strong> que lleva 8 goles y 6 asistencias en 18 partidos.<\/p>\n<p>Por el lado rojillo, la mayor parte de los goles los acumula el delantero croata, <strong>Ante Budimir<\/strong> con 8 goles en 19 partidos disputados. El equipo navarro sufre una gran falta de gol, y puede pasarle factura en una competici\u00f3n tan exigente como esta.<\/p>\n<h2>Historial<\/h2>\n<p>Castell\u00f3n y Osasuna se han enfrentado un total de <strong>19 veces<\/strong>, contando con <strong>3 empates y 8 victorias para cada equipo<\/strong>. Casualmente su \u00faltimo enfrentamiento fue en la<strong> temporada 04\/05<\/strong> en un partido de <strong>Copa del Rey<\/strong> que se sald\u00f3 con una <strong>victoria para los navarros<\/strong> en la tanda de <strong>penaltis por un 2-4<\/strong>.<\/p>\n<p>Sin duda Osasuna, pese a ser el favorito, sufrir\u00e1 en el Castalia y ser\u00e1 un duelo de alto voltaje.<\/p>\n<figure style=\"width: 900px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/12\/jzU798e1.jpeg\" alt=\"Osasuna viajar\u00e1 Castell\u00f3n en Copa \u2013 Agente Libre Digital\" width=\"900\" height=\"506\" \/><figcaption class=\"wp-caption-text\">jugadores de Osasuna y Castell\u00f3n en uno de sus \u00faltimos encuentros. Fuente @castellonplaza_<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00eda 7 de enero a las 16:00 horas tendr\u00e1 lugar el encuentro entre Castell\u00f3n y Osasuna, en el Estadio de Castalia, en la ronda de dieciseisavos de final de&hellip; <\/p>\n","protected":false},"author":57,"featured_media":6871,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[9,22],"tags":[],"class_list":["post-6859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-copa-del-rey","category-osasuna"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Previa Castell\u00f3n-Osasuna: Duelo copero despu\u00e9s de Reyes\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Angel Yuste\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2024\/01\/06\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Previa Castell\u00f3n-Osasuna: Duelo copero despu\u00e9s de Reyes \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"Previa Castell\u00f3n-Osasuna: Duelo copero despu\u00e9s de Reyes\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2024\/01\/06\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/01\/match-cover-es-3754710519599291084-1501764243466109369.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/01\/match-cover-es-3754710519599291084-1501764243466109369.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-01-06T16:21:34+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-01-06T16:21:34+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Previa Castell\u00f3n-Osasuna: Duelo copero despu\u00e9s de Reyes \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Previa Castell\u00f3n-Osasuna: Duelo copero despu\u00e9s de Reyes\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/01\/match-cover-es-3754710519599291084-1501764243466109369.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/01\\\/06\\\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\\\/#blogposting\",\"name\":\"Previa Castell\\u00f3n-Osasuna: Duelo copero despu\\u00e9s de Reyes \\u2013 Agente Libre Digital\",\"headline\":\"Previa Castell\\u00f3n-Osasuna: Duelo copero despu\\u00e9s de Reyes\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/angel-yuste\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/match-cover-es-3754710519599291084-1501764243466109369.jpg\",\"width\":1200,\"height\":675,\"caption\":\"Castell\\u00f3n-Osasuna. Fuente Fichjaes.com\"},\"datePublished\":\"2024-01-06T17:21:34+01:00\",\"dateModified\":\"2024-01-06T17:21:34+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/01\\\/06\\\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/01\\\/06\\\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\\\/#webpage\"},\"articleSection\":\"Copa del Rey, Osasuna\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/01\\\/06\\\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/copa-del-rey\\\/#listItem\",\"name\":\"Copa del Rey\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/copa-del-rey\\\/#listItem\",\"position\":2,\"name\":\"Copa del Rey\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/copa-del-rey\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/01\\\/06\\\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\\\/#listItem\",\"name\":\"Previa Castell\\u00f3n-Osasuna: Duelo copero despu\\u00e9s de Reyes\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/01\\\/06\\\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\\\/#listItem\",\"position\":3,\"name\":\"Previa Castell\\u00f3n-Osasuna: Duelo copero despu\\u00e9s de Reyes\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/copa-del-rey\\\/#listItem\",\"name\":\"Copa del Rey\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/01\\\/06\\\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/01\\\/06\\\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/angel-yuste\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/angel-yuste\\\/\",\"name\":\"Angel Yuste\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/01\\\/06\\\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ff839ca1409153ee729d2114851ac59fc8944763cfdffb926e743de531c3e31?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Angel Yuste\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/01\\\/06\\\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/01\\\/06\\\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\\\/\",\"name\":\"Previa Castell\\u00f3n-Osasuna: Duelo copero despu\\u00e9s de Reyes \\u2013 Agente Libre Digital\",\"description\":\"Previa Castell\\u00f3n-Osasuna: Duelo copero despu\\u00e9s de Reyes\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/01\\\/06\\\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/angel-yuste\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/angel-yuste\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/match-cover-es-3754710519599291084-1501764243466109369.jpg\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/01\\\/06\\\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\\\/#mainImage\",\"width\":1200,\"height\":675,\"caption\":\"Castell\\u00f3n-Osasuna. Fuente Fichjaes.com\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/01\\\/06\\\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\\\/#mainImage\"},\"datePublished\":\"2024-01-06T17:21:34+01:00\",\"dateModified\":\"2024-01-06T17:21:34+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Previa Castell\u00f3n-Osasuna: Duelo copero despu\u00e9s de Reyes \u2013 Agente Libre Digital","description":"Previa Castell\u00f3n-Osasuna: Duelo copero despu\u00e9s de Reyes","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2024\/01\/06\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/01\/06\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\/#blogposting","name":"Previa Castell\u00f3n-Osasuna: Duelo copero despu\u00e9s de Reyes \u2013 Agente Libre Digital","headline":"Previa Castell\u00f3n-Osasuna: Duelo copero despu\u00e9s de Reyes","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/angel-yuste\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/01\/match-cover-es-3754710519599291084-1501764243466109369.jpg","width":1200,"height":675,"caption":"Castell\u00f3n-Osasuna. Fuente Fichjaes.com"},"datePublished":"2024-01-06T17:21:34+01:00","dateModified":"2024-01-06T17:21:34+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/01\/06\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/01\/06\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\/#webpage"},"articleSection":"Copa del Rey, Osasuna"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/01\/06\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/copa-del-rey\/#listItem","name":"Copa del Rey"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/copa-del-rey\/#listItem","position":2,"name":"Copa del Rey","item":"https:\/\/agentelibredigital.com\/index.php\/category\/copa-del-rey\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/01\/06\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\/#listItem","name":"Previa Castell\u00f3n-Osasuna: Duelo copero despu\u00e9s de Reyes"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/01\/06\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\/#listItem","position":3,"name":"Previa Castell\u00f3n-Osasuna: Duelo copero despu\u00e9s de Reyes","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/copa-del-rey\/#listItem","name":"Copa del Rey"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/01\/06\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/01\/06\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/angel-yuste\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/angel-yuste\/","name":"Angel Yuste","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/01\/06\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/9ff839ca1409153ee729d2114851ac59fc8944763cfdffb926e743de531c3e31?s=96&d=mm&r=g","width":96,"height":96,"caption":"Angel Yuste"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/01\/06\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2024\/01\/06\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\/","name":"Previa Castell\u00f3n-Osasuna: Duelo copero despu\u00e9s de Reyes \u2013 Agente Libre Digital","description":"Previa Castell\u00f3n-Osasuna: Duelo copero despu\u00e9s de Reyes","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/01\/06\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/angel-yuste\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/angel-yuste\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/01\/match-cover-es-3754710519599291084-1501764243466109369.jpg","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/01\/06\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\/#mainImage","width":1200,"height":675,"caption":"Castell\u00f3n-Osasuna. Fuente Fichjaes.com"},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/01\/06\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\/#mainImage"},"datePublished":"2024-01-06T17:21:34+01:00","dateModified":"2024-01-06T17:21:34+01:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"Previa Castell\u00f3n-Osasuna: Duelo copero despu\u00e9s de Reyes \u2013 Agente Libre Digital","og:description":"Previa Castell\u00f3n-Osasuna: Duelo copero despu\u00e9s de Reyes","og:url":"https:\/\/agentelibredigital.com\/index.php\/2024\/01\/06\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/01\/match-cover-es-3754710519599291084-1501764243466109369.jpg","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/01\/match-cover-es-3754710519599291084-1501764243466109369.jpg","og:image:width":1200,"og:image:height":675,"article:published_time":"2024-01-06T16:21:34+00:00","article:modified_time":"2024-01-06T16:21:34+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"Previa Castell\u00f3n-Osasuna: Duelo copero despu\u00e9s de Reyes \u2013 Agente Libre Digital","twitter:description":"Previa Castell\u00f3n-Osasuna: Duelo copero despu\u00e9s de Reyes","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/01\/match-cover-es-3754710519599291084-1501764243466109369.jpg"},"aioseo_meta_data":{"post_id":"6859","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-01-06 15:45:20","updated":"2025-06-04 19:33:52","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/copa-del-rey\/\" title=\"Copa del Rey\">Copa del Rey<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPrevia Castell\u00f3n-Osasuna: Duelo copero despu\u00e9s de Reyes\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"Copa del Rey","link":"https:\/\/agentelibredigital.com\/index.php\/category\/copa-del-rey\/"},{"label":"Previa Castell\u00f3n-Osasuna: Duelo copero despu\u00e9s de Reyes","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/01\/06\/previa-castellon-osasuna-duelo-copero-despues-de-reyes\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/6859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=6859"}],"version-history":[{"count":6,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/6859\/revisions"}],"predecessor-version":[{"id":6873,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/6859\/revisions\/6873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/6871"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=6859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=6859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=6859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}