{"id":64228,"date":"2026-07-03T03:49:01","date_gmt":"2026-07-03T01:49:01","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=64228"},"modified":"2026-07-03T03:57:04","modified_gmt":"2026-07-03T01:57:04","slug":"lionel-scaloni-no-va-a-ser-facil","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2026\/07\/03\/lionel-scaloni-no-va-a-ser-facil\/","title":{"rendered":"Lionel Scaloni: \u00abNo va a ser f\u00e1cil\u00bb"},"content":{"rendered":"<p><a href=\"https:\/\/agentelibredigital.com\/?s=scaloni\"><strong>Lionel Scaloni<\/strong><\/a> habl\u00f3 en conferencia de prensa, en la previa del duelo del viernes entre<strong><a href=\"https:\/\/agentelibredigital.com\/?s=argentina\"> Argentina<\/a> y <a href=\"https:\/\/agentelibredigital.com\/?s=cabo+verde\">Cabo Verde<\/a>.<\/strong><\/p>\n<p>En primer lugar, Scaloni hizo menci\u00f3n a la<strong> hinchada argentina<\/strong> que est\u00e1 copando Miami en los \u00faltimos d\u00edas: \u00abLa hinchada argentina<strong> siempre ha sido un plus<\/strong> para el jugador. A nosotros <strong>el apoyo nos encanta<\/strong>, nos da algo m\u00e1s y eso es evidente\u00bb. Adem\u00e1s destac\u00f3 el sentimiento del plantel: \u00ab<strong>Los jugadores son un hincha m\u00e1s<\/strong> jugando con la camiseta. Todos sienten las ganas de jugar y tener la presi\u00f3n linda de responderle a la gente.\u00bb<\/p>\n<figure style=\"width: 343px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets1.afa.com.ar\/2026\/Lau\/WhatsApp-Image-2026-07-02-at-16.24.18-(1).jpeg\" alt=\"\" width=\"343\" height=\"228\" \/><figcaption class=\"wp-caption-text\">Lionel Scaloni en la conferencia de prensa antes del cruce de dieciseisavos de final entre Argentina y Cabo Verde. Fuente: Asociaci\u00f3n del F\u00fatbol Argentino.<\/figcaption><\/figure>\n<p>Al ser consultado sobre el pr\u00f3ximo rival del seleccionado, el santafesino realiz\u00f3 una<strong> breve s\u00edntesis del juego de los africanos<\/strong>: \u00abEs un equipo que no ha perdido, que en algunos partidos mereci\u00f3 ganar. Ellos <strong>defienden bien, tapan bien los pases interiores, salen bien de contra y tienen jugadores de buen pie.\u00bb<\/strong><\/p>\n<p>El argentino lejos de subestimar a los caboverdianos, <strong>se mostr\u00f3 tranquilo y con mucha cautela<\/strong> a la hora de referirse al encuentro: \u00ab<strong>Estamos ilusionados como todo el mundo<\/strong> pero hay un rival al cual hay que enfrentar. <strong>Hay que respetar a un rival que ha hecho bien las cosas.<\/strong> El margen ahora se achica, el que pierde se vuelve y lo tenemos en cuenta pero nos agarra en un buen momento\u00bb<\/p>\n<p>Tambi\u00e9n habl\u00f3 sobre la dificultad de este Mundial y dijo: \u00ab<strong>Se est\u00e1n viendo partidos muy parejos<\/strong> y creo que no va a ser f\u00e1cil. (&#8230;) Al sumarse un partido m\u00e1s para llegar a las instancias finales se hace largo, duro\u00bb. En la misma l\u00ednea nombr\u00f3 a los equipos que para \u00e9l llegaran lejos: \u00ab<a href=\"https:\/\/agentelibredigital.com\/?s=francia\">Francia<\/a> y<a href=\"https:\/\/agentelibredigital.com\/?s=+brasil\"> Brasil<\/a> est\u00e1n muy bien. <a href=\"https:\/\/agentelibredigital.com\/?s=mexico+\">M\u00e9xico<\/a> hizo un gran partido con Ecuador. Tambi\u00e9n han jugado muy bien <a href=\"https:\/\/agentelibredigital.com\/?s=colombia\">Colombia<\/a>, <a href=\"https:\/\/agentelibredigital.com\/?s=portugal+\">Portugal<\/a>,<a href=\"https:\/\/agentelibredigital.com\/?s=espa%C3%B1a\"> Espa\u00f1a<\/a>, <a href=\"https:\/\/agentelibredigital.com\/?s=inglaterra\">Inglaterra<\/a>. Seguramente el ganador saldr\u00e1 de ah\u00ed\u00bb.<\/p>\n<figure style=\"width: 354px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/assets1.afa.com.ar\/2026\/Lau\/WhatsApp-Image-2026-07-02-at-16.24.18.jpeg\" alt=\"\" width=\"354\" height=\"236\" \/><figcaption class=\"wp-caption-text\">El DT de la selecci\u00f3n argentina en la rueda de prensa previa al cruce entre Argentina y Cabo Verde. Fuente: Asociaci\u00f3n del F\u00fatbol Argentino.<\/figcaption><\/figure>\n<p>Tras ser consultado acerca de las <strong>altas temperaturas que se esperan en <a href=\"https:\/\/agentelibredigital.com\/?s=miami\">Miami<\/a><\/strong> para la hora el partido, el entrenador del seleccionado argentino dijo: \u00abQuiz\u00e1s hubiera sido mejor jugar de noche pero <strong>el calor es para los dos.<\/strong> Los horarios son los que son y ya est\u00e1. Jugaremos el partido como lo tenemos que jugar,\u00a0 eso no lo va a cambiar el calor.<\/p>\n<p>Por \u00faltimo, la conferencia de prensa dej\u00f3 distintos momentos parte de las declaraciones sobre lo futbol\u00edstico,\u00a0 como cuando <strong>se solidariz\u00f3 con la gente de Venezuela<\/strong> tras el terremoto. Tambi\u00e9n tuvo un lindo <strong>reencuentro con su amigo German Denis<\/strong>, exfutbolista y ahora periodista.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lionel Scaloni habl\u00f3 en conferencia de prensa, en la previa del duelo del viernes entre Argentina y Cabo Verde. En primer lugar, Scaloni hizo menci\u00f3n a la hinchada argentina que&hellip; <\/p>\n","protected":false},"author":346,"featured_media":64229,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[48,5544],"tags":[708,5557,3731,4084,5005],"class_list":["post-64228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol-internacional","category-mundial-2026","tag-argentina","tag-cabo-verde","tag-lionel-messi","tag-lionel-scaloni","tag-mundial-2026"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Lionel Scaloni: \u00abNo va a ser f\u00e1cil\u00bb\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Lucas Arballo\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2026\/07\/03\/lionel-scaloni-no-va-a-ser-facil\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Lionel Scaloni: \u00abNo va a ser f\u00e1cil\u00bb \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"Lionel Scaloni: \u00abNo va a ser f\u00e1cil\u00bb\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2026\/07\/03\/lionel-scaloni-no-va-a-ser-facil\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/07\/AMLY37J52FHZ7PROGOOM4KQ4HY.avif\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/07\/AMLY37J52FHZ7PROGOOM4KQ4HY.avif\" \/>\n\t\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t\t<meta property=\"og:image:height\" content=\"251\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-03T01:49:01+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-03T01:57:04+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Lionel Scaloni: \u00abNo va a ser f\u00e1cil\u00bb \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Lionel Scaloni: \u00abNo va a ser f\u00e1cil\u00bb\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/07\/AMLY37J52FHZ7PROGOOM4KQ4HY.avif\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/07\\\/03\\\/lionel-scaloni-no-va-a-ser-facil\\\/#blogposting\",\"name\":\"Lionel Scaloni: \\u00abNo va a ser f\\u00e1cil\\u00bb \\u2013 Agente Libre Digital\",\"headline\":\"Lionel Scaloni: \\u00abNo va a ser f\\u00e1cil\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/lucas-arballo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/AMLY37J52FHZ7PROGOOM4KQ4HY.avif\",\"width\":350,\"height\":251},\"datePublished\":\"2026-07-03T03:49:01+02:00\",\"dateModified\":\"2026-07-03T03:57:04+02:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/07\\\/03\\\/lionel-scaloni-no-va-a-ser-facil\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/07\\\/03\\\/lionel-scaloni-no-va-a-ser-facil\\\/#webpage\"},\"articleSection\":\"F\\u00fatbol Internacional, Mundial 2026, Argentina, Cabo Verde, Lionel Messi, Lionel Scaloni, Mundial 2026\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/07\\\/03\\\/lionel-scaloni-no-va-a-ser-facil\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/futbol-internacional\\\/#listItem\",\"name\":\"F\\u00fatbol Internacional\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/futbol-internacional\\\/#listItem\",\"position\":2,\"name\":\"F\\u00fatbol Internacional\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/futbol-internacional\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/07\\\/03\\\/lionel-scaloni-no-va-a-ser-facil\\\/#listItem\",\"name\":\"Lionel Scaloni: \\u00abNo va a ser f\\u00e1cil\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/07\\\/03\\\/lionel-scaloni-no-va-a-ser-facil\\\/#listItem\",\"position\":3,\"name\":\"Lionel Scaloni: \\u00abNo va a ser f\\u00e1cil\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/futbol-internacional\\\/#listItem\",\"name\":\"F\\u00fatbol Internacional\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/07\\\/03\\\/lionel-scaloni-no-va-a-ser-facil\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/07\\\/03\\\/lionel-scaloni-no-va-a-ser-facil\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/lucas-arballo\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/lucas-arballo\\\/\",\"name\":\"Lucas Arballo\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/07\\\/03\\\/lionel-scaloni-no-va-a-ser-facil\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e9dfd9bfebda64a57cc6b8c88e747323a59ba898e89281d06dea48b9da5f2a10?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Lucas Arballo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/07\\\/03\\\/lionel-scaloni-no-va-a-ser-facil\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/07\\\/03\\\/lionel-scaloni-no-va-a-ser-facil\\\/\",\"name\":\"Lionel Scaloni: \\u00abNo va a ser f\\u00e1cil\\u00bb \\u2013 Agente Libre Digital\",\"description\":\"Lionel Scaloni: \\u00abNo va a ser f\\u00e1cil\\u00bb\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/07\\\/03\\\/lionel-scaloni-no-va-a-ser-facil\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/lucas-arballo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/lucas-arballo\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/AMLY37J52FHZ7PROGOOM4KQ4HY.avif\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/07\\\/03\\\/lionel-scaloni-no-va-a-ser-facil\\\/#mainImage\",\"width\":350,\"height\":251},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/07\\\/03\\\/lionel-scaloni-no-va-a-ser-facil\\\/#mainImage\"},\"datePublished\":\"2026-07-03T03:49:01+02:00\",\"dateModified\":\"2026-07-03T03:57:04+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Lionel Scaloni: \u00abNo va a ser f\u00e1cil\u00bb \u2013 Agente Libre Digital","description":"Lionel Scaloni: \u00abNo va a ser f\u00e1cil\u00bb","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2026\/07\/03\/lionel-scaloni-no-va-a-ser-facil\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/07\/03\/lionel-scaloni-no-va-a-ser-facil\/#blogposting","name":"Lionel Scaloni: \u00abNo va a ser f\u00e1cil\u00bb \u2013 Agente Libre Digital","headline":"Lionel Scaloni: \u00abNo va a ser f\u00e1cil\u00bb","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/lucas-arballo\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/07\/AMLY37J52FHZ7PROGOOM4KQ4HY.avif","width":350,"height":251},"datePublished":"2026-07-03T03:49:01+02:00","dateModified":"2026-07-03T03:57:04+02:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/07\/03\/lionel-scaloni-no-va-a-ser-facil\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/07\/03\/lionel-scaloni-no-va-a-ser-facil\/#webpage"},"articleSection":"F\u00fatbol Internacional, Mundial 2026, Argentina, Cabo Verde, Lionel Messi, Lionel Scaloni, Mundial 2026"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/07\/03\/lionel-scaloni-no-va-a-ser-facil\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/futbol-internacional\/#listItem","name":"F\u00fatbol Internacional"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/futbol-internacional\/#listItem","position":2,"name":"F\u00fatbol Internacional","item":"https:\/\/agentelibredigital.com\/index.php\/category\/futbol-internacional\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/07\/03\/lionel-scaloni-no-va-a-ser-facil\/#listItem","name":"Lionel Scaloni: \u00abNo va a ser f\u00e1cil\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/07\/03\/lionel-scaloni-no-va-a-ser-facil\/#listItem","position":3,"name":"Lionel Scaloni: \u00abNo va a ser f\u00e1cil\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/futbol-internacional\/#listItem","name":"F\u00fatbol Internacional"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/07\/03\/lionel-scaloni-no-va-a-ser-facil\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/07\/03\/lionel-scaloni-no-va-a-ser-facil\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/lucas-arballo\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/lucas-arballo\/","name":"Lucas Arballo","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/07\/03\/lionel-scaloni-no-va-a-ser-facil\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e9dfd9bfebda64a57cc6b8c88e747323a59ba898e89281d06dea48b9da5f2a10?s=96&d=mm&r=g","width":96,"height":96,"caption":"Lucas Arballo"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/07\/03\/lionel-scaloni-no-va-a-ser-facil\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2026\/07\/03\/lionel-scaloni-no-va-a-ser-facil\/","name":"Lionel Scaloni: \u00abNo va a ser f\u00e1cil\u00bb \u2013 Agente Libre Digital","description":"Lionel Scaloni: \u00abNo va a ser f\u00e1cil\u00bb","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/07\/03\/lionel-scaloni-no-va-a-ser-facil\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/lucas-arballo\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/lucas-arballo\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/07\/AMLY37J52FHZ7PROGOOM4KQ4HY.avif","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/07\/03\/lionel-scaloni-no-va-a-ser-facil\/#mainImage","width":350,"height":251},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/07\/03\/lionel-scaloni-no-va-a-ser-facil\/#mainImage"},"datePublished":"2026-07-03T03:49:01+02:00","dateModified":"2026-07-03T03:57:04+02:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"Lionel Scaloni: \u00abNo va a ser f\u00e1cil\u00bb \u2013 Agente Libre Digital","og:description":"Lionel Scaloni: \u00abNo va a ser f\u00e1cil\u00bb","og:url":"https:\/\/agentelibredigital.com\/index.php\/2026\/07\/03\/lionel-scaloni-no-va-a-ser-facil\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/07\/AMLY37J52FHZ7PROGOOM4KQ4HY.avif","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/07\/AMLY37J52FHZ7PROGOOM4KQ4HY.avif","og:image:width":350,"og:image:height":251,"article:published_time":"2026-07-03T01:49:01+00:00","article:modified_time":"2026-07-03T01:57:04+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"Lionel Scaloni: \u00abNo va a ser f\u00e1cil\u00bb \u2013 Agente Libre Digital","twitter:description":"Lionel Scaloni: \u00abNo va a ser f\u00e1cil\u00bb","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/07\/AMLY37J52FHZ7PROGOOM4KQ4HY.avif"},"aioseo_meta_data":{"post_id":"64228","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-07-03 00:31:20","updated":"2026-07-03 01:58:06","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/futbol-internacional\/\" title=\"F\u00fatbol Internacional\">F\u00fatbol Internacional<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLionel Scaloni: \u00abNo va a ser f\u00e1cil\u00bb\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"F\u00fatbol Internacional","link":"https:\/\/agentelibredigital.com\/index.php\/category\/futbol-internacional\/"},{"label":"Lionel Scaloni: \u00abNo va a ser f\u00e1cil\u00bb","link":"https:\/\/agentelibredigital.com\/index.php\/2026\/07\/03\/lionel-scaloni-no-va-a-ser-facil\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/64228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/346"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=64228"}],"version-history":[{"count":5,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/64228\/revisions"}],"predecessor-version":[{"id":64243,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/64228\/revisions\/64243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/64229"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=64228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=64228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=64228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}