{"id":63922,"date":"2026-06-24T20:52:46","date_gmt":"2026-06-24T18:52:46","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=63922"},"modified":"2026-06-24T20:55:48","modified_gmt":"2026-06-24T18:55:48","slug":"la-juventus-de-pesca-por-galicia","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/24\/la-juventus-de-pesca-por-galicia\/","title":{"rendered":"La Juventus, de pesca por Galicia"},"content":{"rendered":"<h4>El cuadro <em>bianconeri<\/em> tendr\u00eda en su mira tanto al jugador del <a href=\"https:\/\/agentelibredigital.com\/?s=Celta\">Celta<\/a> Ilaix Moriba como a la perla del <a href=\"https:\/\/agentelibredigital.com\/?s=Deportivo\">Deportivo<\/a> David Mella.<\/h4>\n<p>El <strong>presente de los clubes de Galicia como son el Celta y Deportivo<\/strong> es muy dulce. Tras el ascenso a <a href=\"https:\/\/agentelibredigital.com\/?s=La+Liga\">La Liga<\/a> de los herculinos y la clasificaci\u00f3n a Europa de los vigueses, varios jugadores est\u00e1n a la palestra. Entre ellos est\u00e1n los j\u00f3venes <strong>Ilaix Moriba y David Mella, que tuvieron un rendimiento destacable<\/strong>. Su temporada no ha pasado desapercibida, ya que <strong>la <a href=\"https:\/\/agentelibredigital.com\/?s=Juventus\">Juventus<\/a> tendr\u00eda ambos nombres en su radar de fichajes<\/strong>.<\/p>\n<figure id=\"attachment_63926\" aria-describedby=\"caption-attachment-63926\" style=\"width: 702px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-63926\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/06\/david-mella-deportivo-huesca.png\" alt=\"\" width=\"702\" height=\"336\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/06\/david-mella-deportivo-huesca.png 702w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/06\/david-mella-deportivo-huesca-300x144.png 300w\" sizes=\"auto, (max-width: 702px) 100vw, 702px\" \/><figcaption id=\"caption-attachment-63926\" class=\"wp-caption-text\">David Mella controla un bal\u00f3n en un partido con el Deportivo. Fuente: Diego Sim\u00f3n<\/figcaption><\/figure>\n<p>Haciendo hincapi\u00e9 en el extremo gallego, <strong>el conjunto turin\u00e9s no le pierden de vista seg\u00fan Massimo Pavan.<\/strong> Sin embargo, <strong>Mella tiene contrato con el equipo coru\u00f1\u00e9s hasta 2029<\/strong>. Asimismo, <strong>el Deportivo se remite al pago de su cl\u00e1usula de 20 millones para hacerse con los servicios del extremo de Teo<\/strong>.\u00a0 Su actual temporada se ha visto marcada por una lesi\u00f3n en marzo que le hizo terminar prematuramente. Hasta ese momento <strong>Mella<\/strong> fue capaz de lograr <strong>5 goles y 1 asistencia<\/strong> en <strong>29 partidos<\/strong>.<\/p>\n<p>En cuanto a <strong>Ilaix Moriba<\/strong>, el agente de los <em>bianconeri<\/em> <strong>Giovanni Carnevali pregunt\u00f3 a los agentes del guineano seg\u00fan Matteo Moretto<\/strong>. Pese a esto,<strong> la escuadra ol\u00edvica pide entre 15 y 20 millones<\/strong> por el fichaje del jugador. Otro aspecto a tener en cuenta es que<strong> para la Juventus no es imprescindible este fichaje<\/strong>, ya que no es la primera opci\u00f3n. Esta temporada actual, el jugador guineano ha logrado <strong>2 goles y 4 asistencias<\/strong> en <strong>48 partidos<\/strong>.<\/p>\n<h2>\u00bfQu\u00e9 podr\u00edan aportar y mejorar a la Juventus en caso de un posible fichaje?<\/h2>\n<p>Haciendo referencia al tema t\u00e1ctico, <strong>Moriba y Mella son dos perfiles que a priori ser\u00edan interesantes para la Juventus<\/strong>. El guineano <strong>aportar\u00eda entre otras caracter\u00edsticas versatilidad en el esquema t\u00e1ctico y potencia f\u00edsic<\/strong>a. Sin embargo, <strong>el guineano tendr\u00eda que pulir entre otras cosas m\u00e1s regularidad en la toma de decisiones<\/strong> con el bal\u00f3n. Mientras,<strong> Mella puede aportar a la <em>Vecchia Signora<\/em> desequilibrio y velocidad<\/strong>. Aun as\u00ed, <strong>el gallego podr\u00eda pecar de inexperiencia en grandes escenarios<\/strong> con un equipo de renombre como es la <strong>Juventus<\/strong>.<\/p>\n<p>Son nombres talentosos y j\u00f3venes que podr\u00edan potenciar la calidad a largo plazo de la <em><strong>Vecchia Signora<\/strong><\/em>.<\/p>\n<h3>Autor del art\u00edculo: <a href=\"https:\/\/x.com\/Marcosiglss__\">Marcos Iglesias Rodr\u00edguez<\/a>.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>El cuadro bianconeri tendr\u00eda en su mira tanto al jugador del Celta Ilaix Moriba como a la perla del Deportivo David Mella. El presente de los clubes de Galicia como&hellip; <\/p>\n","protected":false},"author":179,"featured_media":63925,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1,48,33],"tags":[718,658,1786,94],"class_list":["post-63922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-futbol-internacional","category-serie-a","tag-deportivo-de-la-coruna","tag-juventus","tag-rc-celta-de-vigo","tag-serie-a"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La Juventus, de pesca por Galicia El cuadro bianconeri tendr\u00eda en su mira tanto al jugador del Celta Ilaix Moriba como a la perla del Deportivo David Mella.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Marcos Iglesias\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/24\/la-juventus-de-pesca-por-galicia\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La Juventus, de pesca por Galicia \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"La Juventus, de pesca por Galicia El cuadro bianconeri tendr\u00eda en su mira tanto al jugador del Celta Ilaix Moriba como a la perla del Deportivo David Mella.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/24\/la-juventus-de-pesca-por-galicia\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/06\/real-club-celta-v-olympique-lyonnais-uefa-europa-league-2025-26-round-of-16-first-leg-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/06\/real-club-celta-v-olympique-lyonnais-uefa-europa-league-2025-26-round-of-16-first-leg-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-06-24T18:52:46+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-24T18:55:48+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La Juventus, de pesca por Galicia \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La Juventus, de pesca por Galicia El cuadro bianconeri tendr\u00eda en su mira tanto al jugador del Celta Ilaix Moriba como a la perla del Deportivo David Mella.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/06\/real-club-celta-v-olympique-lyonnais-uefa-europa-league-2025-26-round-of-16-first-leg-scaled.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/24\\\/la-juventus-de-pesca-por-galicia\\\/#blogposting\",\"name\":\"La Juventus, de pesca por Galicia \\u2013 Agente Libre Digital\",\"headline\":\"La Juventus, de pesca por Galicia\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-iglesias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/real-club-celta-v-olympique-lyonnais-uefa-europa-league-2025-26-round-of-16-first-leg-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Ilaix Moriba, uno de los jugadores que est\\u00e1n en el radar de la Juventus. Fuente: Jose Manuel Alvarez Rey\\\/Getty Images\"},\"datePublished\":\"2026-06-24T20:52:46+02:00\",\"dateModified\":\"2026-06-24T20:55:48+02:00\",\"inLanguage\":\"es-ES\",\"commentCount\":8,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/24\\\/la-juventus-de-pesca-por-galicia\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/24\\\/la-juventus-de-pesca-por-galicia\\\/#webpage\"},\"articleSection\":\"Blog, F\\u00fatbol Internacional, Serie A, Deportivo de La Coru\\u00f1a, Juventus, RC Celta de Vigo, Serie A\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/24\\\/la-juventus-de-pesca-por-galicia\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/blog\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/blog\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/24\\\/la-juventus-de-pesca-por-galicia\\\/#listItem\",\"name\":\"La Juventus, de pesca por Galicia\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/24\\\/la-juventus-de-pesca-por-galicia\\\/#listItem\",\"position\":3,\"name\":\"La Juventus, de pesca por Galicia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/24\\\/la-juventus-de-pesca-por-galicia\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/24\\\/la-juventus-de-pesca-por-galicia\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-iglesias\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-iglesias\\\/\",\"name\":\"Marcos Iglesias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/24\\\/la-juventus-de-pesca-por-galicia\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b12d4fac150c550921f0486912033479abc571a43af887303e0aa75b2023fa6a?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Marcos Iglesias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/24\\\/la-juventus-de-pesca-por-galicia\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/24\\\/la-juventus-de-pesca-por-galicia\\\/\",\"name\":\"La Juventus, de pesca por Galicia \\u2013 Agente Libre Digital\",\"description\":\"La Juventus, de pesca por Galicia El cuadro bianconeri tendr\\u00eda en su mira tanto al jugador del Celta Ilaix Moriba como a la perla del Deportivo David Mella.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/24\\\/la-juventus-de-pesca-por-galicia\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-iglesias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-iglesias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/real-club-celta-v-olympique-lyonnais-uefa-europa-league-2025-26-round-of-16-first-leg-scaled.jpg\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/24\\\/la-juventus-de-pesca-por-galicia\\\/#mainImage\",\"width\":2560,\"height\":1707,\"caption\":\"Ilaix Moriba, uno de los jugadores que est\\u00e1n en el radar de la Juventus. Fuente: Jose Manuel Alvarez Rey\\\/Getty Images\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/24\\\/la-juventus-de-pesca-por-galicia\\\/#mainImage\"},\"datePublished\":\"2026-06-24T20:52:46+02:00\",\"dateModified\":\"2026-06-24T20:55:48+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La Juventus, de pesca por Galicia \u2013 Agente Libre Digital","description":"La Juventus, de pesca por Galicia El cuadro bianconeri tendr\u00eda en su mira tanto al jugador del Celta Ilaix Moriba como a la perla del Deportivo David Mella.","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/24\/la-juventus-de-pesca-por-galicia\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/24\/la-juventus-de-pesca-por-galicia\/#blogposting","name":"La Juventus, de pesca por Galicia \u2013 Agente Libre Digital","headline":"La Juventus, de pesca por Galicia","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-iglesias\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/06\/real-club-celta-v-olympique-lyonnais-uefa-europa-league-2025-26-round-of-16-first-leg-scaled.jpg","width":2560,"height":1707,"caption":"Ilaix Moriba, uno de los jugadores que est\u00e1n en el radar de la Juventus. Fuente: Jose Manuel Alvarez Rey\/Getty Images"},"datePublished":"2026-06-24T20:52:46+02:00","dateModified":"2026-06-24T20:55:48+02:00","inLanguage":"es-ES","commentCount":8,"mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/24\/la-juventus-de-pesca-por-galicia\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/24\/la-juventus-de-pesca-por-galicia\/#webpage"},"articleSection":"Blog, F\u00fatbol Internacional, Serie A, Deportivo de La Coru\u00f1a, Juventus, RC Celta de Vigo, Serie A"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/24\/la-juventus-de-pesca-por-galicia\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/blog\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/blog\/#listItem","position":2,"name":"Blog","item":"https:\/\/agentelibredigital.com\/index.php\/category\/blog\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/24\/la-juventus-de-pesca-por-galicia\/#listItem","name":"La Juventus, de pesca por Galicia"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/24\/la-juventus-de-pesca-por-galicia\/#listItem","position":3,"name":"La Juventus, de pesca por Galicia","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/blog\/#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/24\/la-juventus-de-pesca-por-galicia\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/24\/la-juventus-de-pesca-por-galicia\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-iglesias\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-iglesias\/","name":"Marcos Iglesias","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/24\/la-juventus-de-pesca-por-galicia\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b12d4fac150c550921f0486912033479abc571a43af887303e0aa75b2023fa6a?s=96&d=mm&r=g","width":96,"height":96,"caption":"Marcos Iglesias"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/24\/la-juventus-de-pesca-por-galicia\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/24\/la-juventus-de-pesca-por-galicia\/","name":"La Juventus, de pesca por Galicia \u2013 Agente Libre Digital","description":"La Juventus, de pesca por Galicia El cuadro bianconeri tendr\u00eda en su mira tanto al jugador del Celta Ilaix Moriba como a la perla del Deportivo David Mella.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/24\/la-juventus-de-pesca-por-galicia\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-iglesias\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-iglesias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/06\/real-club-celta-v-olympique-lyonnais-uefa-europa-league-2025-26-round-of-16-first-leg-scaled.jpg","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/24\/la-juventus-de-pesca-por-galicia\/#mainImage","width":2560,"height":1707,"caption":"Ilaix Moriba, uno de los jugadores que est\u00e1n en el radar de la Juventus. Fuente: Jose Manuel Alvarez Rey\/Getty Images"},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/24\/la-juventus-de-pesca-por-galicia\/#mainImage"},"datePublished":"2026-06-24T20:52:46+02:00","dateModified":"2026-06-24T20:55:48+02:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"La Juventus, de pesca por Galicia \u2013 Agente Libre Digital","og:description":"La Juventus, de pesca por Galicia El cuadro bianconeri tendr\u00eda en su mira tanto al jugador del Celta Ilaix Moriba como a la perla del Deportivo David Mella.","og:url":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/24\/la-juventus-de-pesca-por-galicia\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/06\/real-club-celta-v-olympique-lyonnais-uefa-europa-league-2025-26-round-of-16-first-leg-scaled.jpg","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/06\/real-club-celta-v-olympique-lyonnais-uefa-europa-league-2025-26-round-of-16-first-leg-scaled.jpg","og:image:width":2560,"og:image:height":1707,"article:published_time":"2026-06-24T18:52:46+00:00","article:modified_time":"2026-06-24T18:55:48+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"La Juventus, de pesca por Galicia \u2013 Agente Libre Digital","twitter:description":"La Juventus, de pesca por Galicia El cuadro bianconeri tendr\u00eda en su mira tanto al jugador del Celta Ilaix Moriba como a la perla del Deportivo David Mella.","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/06\/real-club-celta-v-olympique-lyonnais-uefa-europa-league-2025-26-round-of-16-first-leg-scaled.jpg"},"aioseo_meta_data":{"post_id":"63922","title":null,"description":"#post_title El cuadro bianconeri tendr\u00eda en su mira tanto al jugador del Celta Ilaix Moriba como a la perla del Deportivo David Mella.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-06-24 18:52:46","updated":"2026-06-24 18:56:38","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/blog\/\" title=\"Blog\">Blog<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa Juventus, de pesca por Galicia\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"Blog","link":"https:\/\/agentelibredigital.com\/index.php\/category\/blog\/"},{"label":"La Juventus, de pesca por Galicia","link":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/24\/la-juventus-de-pesca-por-galicia\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/63922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/179"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=63922"}],"version-history":[{"count":1,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/63922\/revisions"}],"predecessor-version":[{"id":63928,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/63922\/revisions\/63928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/63925"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=63922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=63922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=63922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}