{"id":63895,"date":"2026-06-23T21:00:19","date_gmt":"2026-06-23T19:00:19","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=63895"},"modified":"2026-06-23T18:19:37","modified_gmt":"2026-06-23T16:19:37","slug":"canada-suiza-una-final-por-el-liderato-del-grupo-b","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/23\/canada-suiza-una-final-por-el-liderato-del-grupo-b\/","title":{"rendered":"Canad\u00e1 &#8211; Suiza: una final por el liderato del Grupo B"},"content":{"rendered":"<h2>Jonathan David desaf\u00eda a la experiencia de Xhaka en un duelo que decidir\u00e1 qui\u00e9n evita un cruce de m\u00e1xima exigencia en los octavos de final<\/h2>\n<p>El BC Place de Vancouver acoge este mi\u00e9rcoles uno de los partidos m\u00e1s atractivos de la \u00faltima jornada de la fase de grupos del Mundial 2026. Canad\u00e1 y Suiza llegan empatadas con cuatro puntos y se jugar\u00e1n el liderato del Grupo B en un enfrentamiento que puede marcar el camino de ambas selecciones en las eliminatorias.<\/p>\n<p>Los canadienses parten con una ligera ventaja gracias a su mejor diferencia de goles. Despu\u00e9s de empatar en su estreno frente a Bosnia y Herzegovina (1-1), el conjunto de Jesse Marsch firm\u00f3 una exhibici\u00f3n ofensiva ante Catar (6-0) para situarse en lo m\u00e1s alto de la clasificaci\u00f3n. Suiza, por su parte, comenz\u00f3 el torneo dejando escapar la victoria ante Catar (1-1), pero reaccion\u00f3 con contundencia goleando 4-1 a Bosnia y Herzegovina para llegar con opciones intactas de terminar como primera de grupo.<\/p>\n<p>Mientras que el empate clasificar\u00eda a ambas selecciones, solo una podr\u00e1 hacerlo como l\u00edder, un detalle que puede resultar decisivo para evitar un cruce mucho m\u00e1s exigente en los octavos de final.<\/p>\n<h2>Canad\u00e1 quiere seguir haciendo historia<\/h2>\n<p>La selecci\u00f3n canadiense atraviesa el mejor momento de su historia en una Copa del Mundo.<\/p>\n<p>Tras despedirse de los Mundiales de 1986 y 2022 sin sumar un solo punto, el combinado norteamericano logr\u00f3 en esta edici\u00f3n su primer empate y, pocos d\u00edas despu\u00e9s, celebr\u00f3 la primera victoria mundialista de su historia con una contundente goleada sobre Catar.<\/p>\n<p>El gran protagonista fue Jonathan David. El delantero firm\u00f3 un espectacular triplete que confirm\u00f3 su condici\u00f3n de referencia ofensiva y de gran esperanza del f\u00fatbol canadiense para seguir so\u00f1ando con una clasificaci\u00f3n hist\u00f3rica a las rondas eliminatorias.<\/p>\n<p>Sin embargo, no todo fueron buenas noticias para Jesse Marsch. La grave lesi\u00f3n de Isma\u00ebl Kon\u00e9, que sufri\u00f3 una fractura de pierna frente a Catar, supone un duro golpe para el centro del campo canadiense. Nathan Saliba apunta a ocupar su lugar, aunque Stephen Eust\u00e1quio, Mathieu Choini\u00e8re y Jonathan Osorio tambi\u00e9n cuentan con opciones para reforzar una zona clave.<\/p>\n<p>La otra inc\u00f3gnita pasa por Alphonso Davies. El capit\u00e1n todav\u00eda no ha debutado en el torneo debido a una lesi\u00f3n muscular, aunque ya estuvo disponible desde el banquillo en la segunda jornada y no se descarta que pueda disputar sus primeros minutos precisamente en el partido m\u00e1s importante de la fase de grupos.<\/p>\n<h2>Suiza quiere demostrar que sigue siendo la favorita<\/h2>\n<p>En el lado helv\u00e9tico no hay espacio para la relajaci\u00f3n.<\/p>\n<p>El empate concedido en el descuento frente a Catar oblig\u00f3 a Suiza a reaccionar, y lo hizo con una convincente goleada frente a Bosnia y Herzegovina. Ahora, el conjunto dirigido por Murat Yakin afronta una aut\u00e9ntica final con un \u00fanico objetivo: ganar para terminar primero de grupo.<\/p>\n<p>La experiencia vuelve a ser el gran argumento de la Nati. Granit Xhaka atraviesa un excelente momento de forma y contin\u00faa siendo el l\u00edder absoluto del equipo. El capit\u00e1n firm\u00f3 una exhibici\u00f3n ante Bosnia y llega acompa\u00f1ado por futbolistas de enorme nivel como Manuel Akanji, Breel Embolo, Rub\u00e9n Vargas, Ricardo Rodr\u00edguez y Gregor Kobel.<\/p>\n<p>Adem\u00e1s, el t\u00e9cnico suizo encontr\u00f3 una gran noticia con la irrupci\u00f3n de Johan Manzambi, autor de un doblete en la segunda jornada, una actuaci\u00f3n que podr\u00eda abrirle las puertas de un papel mucho m\u00e1s protagonista en el tramo decisivo del campeonato.<\/p>\n<h2>Un duelo de estilos<\/h2>\n<p>El partido enfrentar\u00e1 dos propuestas completamente diferentes.<\/p>\n<p>Canad\u00e1 buscar\u00e1 imponer un ritmo alto, aprovechar la velocidad de Jonathan David y tratar de hacer da\u00f1o en las transiciones r\u00e1pidas, especialmente si Alphonso Davies puede participar.<\/p>\n<p>Suiza, por el contrario, intentar\u00e1 controlar el encuentro desde la posesi\u00f3n, con Xhaka marcando el ritmo y aprovechando la experiencia de un bloque acostumbrado a competir en las grandes citas internacionales.<\/p>\n<p>Sobre el papel, la selecci\u00f3n helv\u00e9tica mantiene un ligero favoritismo gracias a la profundidad de su plantilla y a su recorrido en fases finales, aunque el empuje del p\u00fablico de Vancouver puede convertir el ambiente en un factor decisivo para los locales.<\/p>\n<h2>El primer puesto est\u00e1 en juego<\/h2>\n<p>M\u00e1s all\u00e1 de la clasificaci\u00f3n, el liderato del Grupo B puede resultar determinante para el futuro de ambas selecciones en el Mundial.<\/p>\n<p>Canad\u00e1 tiene la ventaja del empate y la ilusi\u00f3n de seguir escribiendo la p\u00e1gina m\u00e1s brillante de su historia futbol\u00edstica. Suiza, en cambio, sabe que solo una victoria le permitir\u00e1 confirmar las expectativas con las que lleg\u00f3 al torneo y presentarse en los octavos de final como primera de grupo.<\/p>\n<p>Todo est\u00e1 preparado para una aut\u00e9ntica final antes de las eliminatorias. El premio no solo son tres puntos: tambi\u00e9n puede ser un camino mucho m\u00e1s favorable hacia el sue\u00f1o mundialista.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jonathan David desaf\u00eda a la experiencia de Xhaka en un duelo que decidir\u00e1 qui\u00e9n evita un cruce de m\u00e1xima exigencia en los octavos de final El BC Place de Vancouver&hellip; <\/p>\n","protected":false},"author":361,"featured_media":63896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[5544],"tags":[],"class_list":["post-63895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundial-2026"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Canad\u00e1 \u2013 Suiza: una final por el liderato del Grupo B Canad\u00e1 y Suiza juegan el liderato del Grupo B del Mundial 2026. Jonathan David o Xhaka en un duelo clave\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Izan Delgado\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/23\/canada-suiza-una-final-por-el-liderato-del-grupo-b\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Canad\u00e1 \u2013 Suiza: una final por el liderato del Grupo B \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"Canad\u00e1 \u2013 Suiza: una final por el liderato del Grupo B Canad\u00e1 y Suiza juegan el liderato del Grupo B del Mundial 2026. Jonathan David o Xhaka en un duelo clave\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/23\/canada-suiza-una-final-por-el-liderato-del-grupo-b\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/06\/switzerland-v-bosnia-and-herzegovina-group-b-fifa-world-cup-2026-1-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/06\/switzerland-v-bosnia-and-herzegovina-group-b-fifa-world-cup-2026-1-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-06-23T19:00:19+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-23T16:19:37+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Canad\u00e1 \u2013 Suiza: una final por el liderato del Grupo B \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Canad\u00e1 \u2013 Suiza: una final por el liderato del Grupo B Canad\u00e1 y Suiza juegan el liderato del Grupo B del Mundial 2026. Jonathan David o Xhaka en un duelo clave\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/06\/switzerland-v-bosnia-and-herzegovina-group-b-fifa-world-cup-2026-1-scaled.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/23\\\/canada-suiza-una-final-por-el-liderato-del-grupo-b\\\/#blogposting\",\"name\":\"Canad\\u00e1 \\u2013 Suiza: una final por el liderato del Grupo B \\u2013 Agente Libre Digital\",\"headline\":\"Canad\\u00e1 &#8211; Suiza: una final por el liderato del Grupo B\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/izan-delgado\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/switzerland-v-bosnia-and-herzegovina-group-b-fifa-world-cup-2026-1-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"INGLEWOOD, CALIFORNIA - JUNE 18: Players of both teams including Captain, Edin Dzeko of Bosnia and Herzegovina walk off the field at half time during the FIFA World Cup 2026 Group B match between Switzerland and Bosnia and Herzegovina at Los Angeles Stadium on June 18, 2026 in Inglewood, California. (Photo by Dean Mouhtaropoulos\\\/Getty Images)\"},\"datePublished\":\"2026-06-23T21:00:19+02:00\",\"dateModified\":\"2026-06-23T18:19:37+02:00\",\"inLanguage\":\"es-ES\",\"commentCount\":763,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/23\\\/canada-suiza-una-final-por-el-liderato-del-grupo-b\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/23\\\/canada-suiza-una-final-por-el-liderato-del-grupo-b\\\/#webpage\"},\"articleSection\":\"Mundial 2026\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/23\\\/canada-suiza-una-final-por-el-liderato-del-grupo-b\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/mundial-2026\\\/#listItem\",\"name\":\"Mundial 2026\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/mundial-2026\\\/#listItem\",\"position\":2,\"name\":\"Mundial 2026\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/mundial-2026\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/23\\\/canada-suiza-una-final-por-el-liderato-del-grupo-b\\\/#listItem\",\"name\":\"Canad\\u00e1 &#8211; Suiza: una final por el liderato del Grupo B\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/23\\\/canada-suiza-una-final-por-el-liderato-del-grupo-b\\\/#listItem\",\"position\":3,\"name\":\"Canad\\u00e1 &#8211; Suiza: una final por el liderato del Grupo B\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/mundial-2026\\\/#listItem\",\"name\":\"Mundial 2026\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/23\\\/canada-suiza-una-final-por-el-liderato-del-grupo-b\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/23\\\/canada-suiza-una-final-por-el-liderato-del-grupo-b\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/izan-delgado\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/izan-delgado\\\/\",\"name\":\"Izan Delgado\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/23\\\/canada-suiza-una-final-por-el-liderato-del-grupo-b\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e12eaef4503209228a4a375791286beb543c211ccfe7202a262d88e4ccf7aa0e?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Izan Delgado\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/23\\\/canada-suiza-una-final-por-el-liderato-del-grupo-b\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/23\\\/canada-suiza-una-final-por-el-liderato-del-grupo-b\\\/\",\"name\":\"Canad\\u00e1 \\u2013 Suiza: una final por el liderato del Grupo B \\u2013 Agente Libre Digital\",\"description\":\"Canad\\u00e1 \\u2013 Suiza: una final por el liderato del Grupo B Canad\\u00e1 y Suiza juegan el liderato del Grupo B del Mundial 2026. Jonathan David o Xhaka en un duelo clave\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/23\\\/canada-suiza-una-final-por-el-liderato-del-grupo-b\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/izan-delgado\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/izan-delgado\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/switzerland-v-bosnia-and-herzegovina-group-b-fifa-world-cup-2026-1-scaled.jpg\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/23\\\/canada-suiza-una-final-por-el-liderato-del-grupo-b\\\/#mainImage\",\"width\":2560,\"height\":1707,\"caption\":\"INGLEWOOD, CALIFORNIA - JUNE 18: Players of both teams including Captain, Edin Dzeko of Bosnia and Herzegovina walk off the field at half time during the FIFA World Cup 2026 Group B match between Switzerland and Bosnia and Herzegovina at Los Angeles Stadium on June 18, 2026 in Inglewood, California. (Photo by Dean Mouhtaropoulos\\\/Getty Images)\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/06\\\/23\\\/canada-suiza-una-final-por-el-liderato-del-grupo-b\\\/#mainImage\"},\"datePublished\":\"2026-06-23T21:00:19+02:00\",\"dateModified\":\"2026-06-23T18:19:37+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Canad\u00e1 \u2013 Suiza: una final por el liderato del Grupo B \u2013 Agente Libre Digital","description":"Canad\u00e1 \u2013 Suiza: una final por el liderato del Grupo B Canad\u00e1 y Suiza juegan el liderato del Grupo B del Mundial 2026. Jonathan David o Xhaka en un duelo clave","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/23\/canada-suiza-una-final-por-el-liderato-del-grupo-b\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/23\/canada-suiza-una-final-por-el-liderato-del-grupo-b\/#blogposting","name":"Canad\u00e1 \u2013 Suiza: una final por el liderato del Grupo B \u2013 Agente Libre Digital","headline":"Canad\u00e1 &#8211; Suiza: una final por el liderato del Grupo B","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/izan-delgado\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/06\/switzerland-v-bosnia-and-herzegovina-group-b-fifa-world-cup-2026-1-scaled.jpg","width":2560,"height":1707,"caption":"INGLEWOOD, CALIFORNIA - JUNE 18: Players of both teams including Captain, Edin Dzeko of Bosnia and Herzegovina walk off the field at half time during the FIFA World Cup 2026 Group B match between Switzerland and Bosnia and Herzegovina at Los Angeles Stadium on June 18, 2026 in Inglewood, California. (Photo by Dean Mouhtaropoulos\/Getty Images)"},"datePublished":"2026-06-23T21:00:19+02:00","dateModified":"2026-06-23T18:19:37+02:00","inLanguage":"es-ES","commentCount":763,"mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/23\/canada-suiza-una-final-por-el-liderato-del-grupo-b\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/23\/canada-suiza-una-final-por-el-liderato-del-grupo-b\/#webpage"},"articleSection":"Mundial 2026"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/23\/canada-suiza-una-final-por-el-liderato-del-grupo-b\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/mundial-2026\/#listItem","name":"Mundial 2026"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/mundial-2026\/#listItem","position":2,"name":"Mundial 2026","item":"https:\/\/agentelibredigital.com\/index.php\/category\/mundial-2026\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/23\/canada-suiza-una-final-por-el-liderato-del-grupo-b\/#listItem","name":"Canad\u00e1 &#8211; Suiza: una final por el liderato del Grupo B"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/23\/canada-suiza-una-final-por-el-liderato-del-grupo-b\/#listItem","position":3,"name":"Canad\u00e1 &#8211; Suiza: una final por el liderato del Grupo B","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/mundial-2026\/#listItem","name":"Mundial 2026"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/23\/canada-suiza-una-final-por-el-liderato-del-grupo-b\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/23\/canada-suiza-una-final-por-el-liderato-del-grupo-b\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/izan-delgado\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/izan-delgado\/","name":"Izan Delgado","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/23\/canada-suiza-una-final-por-el-liderato-del-grupo-b\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e12eaef4503209228a4a375791286beb543c211ccfe7202a262d88e4ccf7aa0e?s=96&d=mm&r=g","width":96,"height":96,"caption":"Izan Delgado"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/23\/canada-suiza-una-final-por-el-liderato-del-grupo-b\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/23\/canada-suiza-una-final-por-el-liderato-del-grupo-b\/","name":"Canad\u00e1 \u2013 Suiza: una final por el liderato del Grupo B \u2013 Agente Libre Digital","description":"Canad\u00e1 \u2013 Suiza: una final por el liderato del Grupo B Canad\u00e1 y Suiza juegan el liderato del Grupo B del Mundial 2026. Jonathan David o Xhaka en un duelo clave","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/23\/canada-suiza-una-final-por-el-liderato-del-grupo-b\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/izan-delgado\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/izan-delgado\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/06\/switzerland-v-bosnia-and-herzegovina-group-b-fifa-world-cup-2026-1-scaled.jpg","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/23\/canada-suiza-una-final-por-el-liderato-del-grupo-b\/#mainImage","width":2560,"height":1707,"caption":"INGLEWOOD, CALIFORNIA - JUNE 18: Players of both teams including Captain, Edin Dzeko of Bosnia and Herzegovina walk off the field at half time during the FIFA World Cup 2026 Group B match between Switzerland and Bosnia and Herzegovina at Los Angeles Stadium on June 18, 2026 in Inglewood, California. (Photo by Dean Mouhtaropoulos\/Getty Images)"},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/23\/canada-suiza-una-final-por-el-liderato-del-grupo-b\/#mainImage"},"datePublished":"2026-06-23T21:00:19+02:00","dateModified":"2026-06-23T18:19:37+02:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"Canad\u00e1 \u2013 Suiza: una final por el liderato del Grupo B \u2013 Agente Libre Digital","og:description":"Canad\u00e1 \u2013 Suiza: una final por el liderato del Grupo B Canad\u00e1 y Suiza juegan el liderato del Grupo B del Mundial 2026. Jonathan David o Xhaka en un duelo clave","og:url":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/23\/canada-suiza-una-final-por-el-liderato-del-grupo-b\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/06\/switzerland-v-bosnia-and-herzegovina-group-b-fifa-world-cup-2026-1-scaled.jpg","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/06\/switzerland-v-bosnia-and-herzegovina-group-b-fifa-world-cup-2026-1-scaled.jpg","og:image:width":2560,"og:image:height":1707,"article:published_time":"2026-06-23T19:00:19+00:00","article:modified_time":"2026-06-23T16:19:37+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"Canad\u00e1 \u2013 Suiza: una final por el liderato del Grupo B \u2013 Agente Libre Digital","twitter:description":"Canad\u00e1 \u2013 Suiza: una final por el liderato del Grupo B Canad\u00e1 y Suiza juegan el liderato del Grupo B del Mundial 2026. Jonathan David o Xhaka en un duelo clave","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/06\/switzerland-v-bosnia-and-herzegovina-group-b-fifa-world-cup-2026-1-scaled.jpg"},"aioseo_meta_data":{"post_id":"63895","title":null,"description":"#post_title Canad\u00e1 y Suiza juegan el liderato del Grupo B del Mundial 2026. Jonathan David o Xhaka en un duelo clave","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-06-23 16:19:22","updated":"2026-06-23 19:01:07","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/mundial-2026\/\" title=\"Mundial 2026\">Mundial 2026<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCanad\u00e1 \u2013 Suiza: una final por el liderato del Grupo B\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"Mundial 2026","link":"https:\/\/agentelibredigital.com\/index.php\/category\/mundial-2026\/"},{"label":"Canad\u00e1 &#8211; Suiza: una final por el liderato del Grupo B","link":"https:\/\/agentelibredigital.com\/index.php\/2026\/06\/23\/canada-suiza-una-final-por-el-liderato-del-grupo-b\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/63895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/361"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=63895"}],"version-history":[{"count":1,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/63895\/revisions"}],"predecessor-version":[{"id":63897,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/63895\/revisions\/63897"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/63896"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=63895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=63895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=63895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}