{"id":61759,"date":"2026-03-22T16:22:43","date_gmt":"2026-03-22T15:22:43","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=61759"},"modified":"2026-03-22T16:48:04","modified_gmt":"2026-03-22T15:48:04","slug":"joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2026\/03\/22\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\/","title":{"rendered":"Joan Garc\u00eda descarta cualquier molestia: \u00abten\u00eda algo de sobrecarga pero nada serio\u00bb"},"content":{"rendered":"<h4>El guardameta de Sallent ha pasado por los micr\u00f3fonos de DAZN Espa\u00f1a tras salvar de la p\u00e9rdida de puntos al FC Barcelona ante el Rayo Vallecano (1-0)<\/h4>\n<p>Una vez superada la fase de <strong>octavos de final<\/strong> de la <a href=\"https:\/\/es.uefa.com\/uefachampionsleague\/\">UEFA Champions League<\/a>, donde el <a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/fc-barcelona\/\">Bar\u00e7a<\/a> se impuso con<a href=\"https:\/\/agentelibredigital.com\/index.php\/2026\/03\/19\/analisis-post-fc-barcelona-7-2-newcastle-united-goleada-y-a-cuartos\/\"> relativa facilidad al <strong>Newcastle United<\/strong> en el Spotify Camp Nou (7-2)<\/a>, tocaba fijarse en la competici\u00f3n liguera. Enfrente, un <strong>Rayo Vallecano<\/strong> que llegaba a la Ciudad Condal en condiciones similares: de sufrir en Europa despu\u00e9s de un <strong>calendario apretado<\/strong>. Sobre la <strong>victoria por la m\u00ednima<\/strong> del conjunto blaugrana ha querido referirse el jugador del encuentro, <strong>Joan Garc\u00eda<\/strong>.<\/p>\n<h2>Deberes hechos<\/h2>\n<p>\u00abTen\u00edamos claro que <strong>era importante conseguir estas tres victorias antes del par\u00f3n<\/strong>. Lo hemos conseguido, hoy sufriendo un poco m\u00e1s de lo que nos hubiera gustado. Pero lo importante es que hemos sacado los tres puntos\u00bb.<\/p>\n<h2>Joan Garc\u00eda amerita al Rayo<\/h2>\n<p>\u00ab<strong>Es un gran equipo, con un gran entrenador<\/strong>, que prepara muy bien los partidos y <strong>sabe c\u00f3mo hacernos da\u00f1o<\/strong>. Nosotros no hemos estado al nivel al que ven\u00edamos compitiendo, sobre todo con bal\u00f3n\u00bb.<\/p>\n<figure id=\"attachment_61762\" aria-describedby=\"caption-attachment-61762\" style=\"width: 613px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-61762\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/03\/fc-barcelona-v-rayo-vallecano-de-madrid-laliga-ea-sports-300x209.jpg\" alt=\"\" width=\"613\" height=\"427\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/03\/fc-barcelona-v-rayo-vallecano-de-madrid-laliga-ea-sports-300x209.jpg 300w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/03\/fc-barcelona-v-rayo-vallecano-de-madrid-laliga-ea-sports-1024x713.jpg 1024w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/03\/fc-barcelona-v-rayo-vallecano-de-madrid-laliga-ea-sports-768x535.jpg 768w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/03\/fc-barcelona-v-rayo-vallecano-de-madrid-laliga-ea-sports-1536x1070.jpg 1536w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/03\/fc-barcelona-v-rayo-vallecano-de-madrid-laliga-ea-sports-2048x1427.jpg 2048w\" sizes=\"auto, (max-width: 613px) 100vw, 613px\" \/><figcaption id=\"caption-attachment-61762\" class=\"wp-caption-text\">Isi Palaz\u00f3n, liderando al Rayo Vallecano ofensivamente. Fuente: Alex Caparros \/ Getty Images.<\/figcaption><\/figure>\n<h2>En manos del Real Madrid<\/h2>\n<p>\u00abTen\u00edamos claro que hab\u00eda que ganar. Ahora, <strong>lo que hagan los otros equipos no depende de nosotros<\/strong>\u00ab.<\/p>\n<h2>Primera convocatoria con Espa\u00f1a para Joan Garc\u00eda<\/h2>\n<p>\u00abMuy contento por mi primera llamada con la selecci\u00f3n absoluta. <strong>Tengo muchas ganas y mucha ilusi\u00f3n<\/strong> de estar tambi\u00e9n con compa\u00f1eros nuevos\u00bb.<\/p>\n<h2>Descartando molestias<\/h2>\n<p>\u00abEstoy bien. <strong>Ten\u00eda algo de sobrecarga pero nada serio<\/strong>\u00ab.<\/p>\n<p><strong>Redactor:<\/strong>\u00a0<em><a href=\"https:\/\/agentelibredigital.com\/index.php\/author\/adrian-garcia\/\">Adrian Garcia<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El guardameta de Sallent ha pasado por los micr\u00f3fonos de DAZN Espa\u00f1a tras salvar de la p\u00e9rdida de puntos al FC Barcelona ante el Rayo Vallecano (1-0) Una vez superada&hellip; <\/p>\n","protected":false},"author":195,"featured_media":61769,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[12,46],"tags":[55,3454,106,169],"class_list":["post-61759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fc-barcelona","category-laliga-ea-sports","tag-fc-barcelona","tag-joan-garcia","tag-laliga-ea-sports","tag-rayo-vallecano"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Joan Garc\u00eda descarta cualquier molestia: \u00abten\u00eda algo de sobrecarga pero nada serio\u00bb El guardameta de Sallent ha pasado por los micr\u00f3fonos de DAZN Espa\u00f1a tras salvar de la p\u00e9rdida de puntos al FC Barcelona ante el Rayo Vallecano (1-0)\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Adrian Garcia\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2026\/03\/22\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Joan Garc\u00eda descarta cualquier molestia: \u00abten\u00eda algo de sobrecarga pero nada serio\u00bb \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"Joan Garc\u00eda descarta cualquier molestia: \u00abten\u00eda algo de sobrecarga pero nada serio\u00bb El guardameta de Sallent ha pasado por los micr\u00f3fonos de DAZN Espa\u00f1a tras salvar de la p\u00e9rdida de puntos al FC Barcelona ante el Rayo Vallecano (1-0)\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2026\/03\/22\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/03\/fc-barcelona-v-rayo-vallecano-de-madrid-laliga-ea-sports-3-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/03\/fc-barcelona-v-rayo-vallecano-de-madrid-laliga-ea-sports-3-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-03-22T15:22:43+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-03-22T15:48:04+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Joan Garc\u00eda descarta cualquier molestia: \u00abten\u00eda algo de sobrecarga pero nada serio\u00bb \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Joan Garc\u00eda descarta cualquier molestia: \u00abten\u00eda algo de sobrecarga pero nada serio\u00bb El guardameta de Sallent ha pasado por los micr\u00f3fonos de DAZN Espa\u00f1a tras salvar de la p\u00e9rdida de puntos al FC Barcelona ante el Rayo Vallecano (1-0)\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/03\/fc-barcelona-v-rayo-vallecano-de-madrid-laliga-ea-sports-3-scaled.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/03\\\/22\\\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\\\/#blogposting\",\"name\":\"Joan Garc\\u00eda descarta cualquier molestia: \\u00abten\\u00eda algo de sobrecarga pero nada serio\\u00bb \\u2013 Agente Libre Digital\",\"headline\":\"Joan Garc\\u00eda descarta cualquier molestia: \\u00abten\\u00eda algo de sobrecarga pero nada serio\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/adrian-garcia\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/fc-barcelona-v-rayo-vallecano-de-madrid-laliga-ea-sports-3-scaled.jpg\",\"width\":2560,\"height\":1706,\"caption\":\"Joan Garc\\u00eda salva tres puntos fundamentales de cara a la pelea por el campeonato liguero. Fuente: Alex Caparros \\\/ Getty Images.\"},\"datePublished\":\"2026-03-22T16:22:43+01:00\",\"dateModified\":\"2026-03-22T16:48:04+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/03\\\/22\\\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/03\\\/22\\\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\\\/#webpage\"},\"articleSection\":\"FC Barcelona, LaLiga EA Sports, FC Barcelona, Joan Garc\\u00eda, LaLiga EA Sports, Rayo Vallecano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/03\\\/22\\\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/fc-barcelona\\\/#listItem\",\"name\":\"FC Barcelona\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/fc-barcelona\\\/#listItem\",\"position\":2,\"name\":\"FC Barcelona\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/fc-barcelona\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/03\\\/22\\\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\\\/#listItem\",\"name\":\"Joan Garc\\u00eda descarta cualquier molestia: \\u00abten\\u00eda algo de sobrecarga pero nada serio\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/03\\\/22\\\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\\\/#listItem\",\"position\":3,\"name\":\"Joan Garc\\u00eda descarta cualquier molestia: \\u00abten\\u00eda algo de sobrecarga pero nada serio\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/fc-barcelona\\\/#listItem\",\"name\":\"FC Barcelona\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/03\\\/22\\\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/03\\\/22\\\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/adrian-garcia\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/adrian-garcia\\\/\",\"name\":\"Adrian Garcia\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/03\\\/22\\\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2646a2b8728a01c9eb97c14f2f14f7deab1473afcab44d4d51eac59cdf517f3b?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Adrian Garcia\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/03\\\/22\\\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/03\\\/22\\\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\\\/\",\"name\":\"Joan Garc\\u00eda descarta cualquier molestia: \\u00abten\\u00eda algo de sobrecarga pero nada serio\\u00bb \\u2013 Agente Libre Digital\",\"description\":\"Joan Garc\\u00eda descarta cualquier molestia: \\u00abten\\u00eda algo de sobrecarga pero nada serio\\u00bb El guardameta de Sallent ha pasado por los micr\\u00f3fonos de DAZN Espa\\u00f1a tras salvar de la p\\u00e9rdida de puntos al FC Barcelona ante el Rayo Vallecano (1-0)\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/03\\\/22\\\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/adrian-garcia\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/adrian-garcia\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/fc-barcelona-v-rayo-vallecano-de-madrid-laliga-ea-sports-3-scaled.jpg\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/03\\\/22\\\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\\\/#mainImage\",\"width\":2560,\"height\":1706,\"caption\":\"Joan Garc\\u00eda salva tres puntos fundamentales de cara a la pelea por el campeonato liguero. Fuente: Alex Caparros \\\/ Getty Images.\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2026\\\/03\\\/22\\\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\\\/#mainImage\"},\"datePublished\":\"2026-03-22T16:22:43+01:00\",\"dateModified\":\"2026-03-22T16:48:04+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Joan Garc\u00eda descarta cualquier molestia: \u00abten\u00eda algo de sobrecarga pero nada serio\u00bb \u2013 Agente Libre Digital","description":"Joan Garc\u00eda descarta cualquier molestia: \u00abten\u00eda algo de sobrecarga pero nada serio\u00bb El guardameta de Sallent ha pasado por los micr\u00f3fonos de DAZN Espa\u00f1a tras salvar de la p\u00e9rdida de puntos al FC Barcelona ante el Rayo Vallecano (1-0)","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2026\/03\/22\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/03\/22\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\/#blogposting","name":"Joan Garc\u00eda descarta cualquier molestia: \u00abten\u00eda algo de sobrecarga pero nada serio\u00bb \u2013 Agente Libre Digital","headline":"Joan Garc\u00eda descarta cualquier molestia: \u00abten\u00eda algo de sobrecarga pero nada serio\u00bb","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/adrian-garcia\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/03\/fc-barcelona-v-rayo-vallecano-de-madrid-laliga-ea-sports-3-scaled.jpg","width":2560,"height":1706,"caption":"Joan Garc\u00eda salva tres puntos fundamentales de cara a la pelea por el campeonato liguero. Fuente: Alex Caparros \/ Getty Images."},"datePublished":"2026-03-22T16:22:43+01:00","dateModified":"2026-03-22T16:48:04+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/03\/22\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/03\/22\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\/#webpage"},"articleSection":"FC Barcelona, LaLiga EA Sports, FC Barcelona, Joan Garc\u00eda, LaLiga EA Sports, Rayo Vallecano"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/03\/22\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/fc-barcelona\/#listItem","name":"FC Barcelona"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/fc-barcelona\/#listItem","position":2,"name":"FC Barcelona","item":"https:\/\/agentelibredigital.com\/index.php\/category\/fc-barcelona\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/03\/22\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\/#listItem","name":"Joan Garc\u00eda descarta cualquier molestia: \u00abten\u00eda algo de sobrecarga pero nada serio\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/03\/22\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\/#listItem","position":3,"name":"Joan Garc\u00eda descarta cualquier molestia: \u00abten\u00eda algo de sobrecarga pero nada serio\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/fc-barcelona\/#listItem","name":"FC Barcelona"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/03\/22\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/03\/22\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/adrian-garcia\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/adrian-garcia\/","name":"Adrian Garcia","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/03\/22\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/2646a2b8728a01c9eb97c14f2f14f7deab1473afcab44d4d51eac59cdf517f3b?s=96&d=mm&r=g","width":96,"height":96,"caption":"Adrian Garcia"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/03\/22\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2026\/03\/22\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\/","name":"Joan Garc\u00eda descarta cualquier molestia: \u00abten\u00eda algo de sobrecarga pero nada serio\u00bb \u2013 Agente Libre Digital","description":"Joan Garc\u00eda descarta cualquier molestia: \u00abten\u00eda algo de sobrecarga pero nada serio\u00bb El guardameta de Sallent ha pasado por los micr\u00f3fonos de DAZN Espa\u00f1a tras salvar de la p\u00e9rdida de puntos al FC Barcelona ante el Rayo Vallecano (1-0)","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/03\/22\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/adrian-garcia\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/adrian-garcia\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/03\/fc-barcelona-v-rayo-vallecano-de-madrid-laliga-ea-sports-3-scaled.jpg","@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/03\/22\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\/#mainImage","width":2560,"height":1706,"caption":"Joan Garc\u00eda salva tres puntos fundamentales de cara a la pelea por el campeonato liguero. Fuente: Alex Caparros \/ Getty Images."},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2026\/03\/22\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\/#mainImage"},"datePublished":"2026-03-22T16:22:43+01:00","dateModified":"2026-03-22T16:48:04+01:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"Joan Garc\u00eda descarta cualquier molestia: \u00abten\u00eda algo de sobrecarga pero nada serio\u00bb \u2013 Agente Libre Digital","og:description":"Joan Garc\u00eda descarta cualquier molestia: \u00abten\u00eda algo de sobrecarga pero nada serio\u00bb El guardameta de Sallent ha pasado por los micr\u00f3fonos de DAZN Espa\u00f1a tras salvar de la p\u00e9rdida de puntos al FC Barcelona ante el Rayo Vallecano (1-0)","og:url":"https:\/\/agentelibredigital.com\/index.php\/2026\/03\/22\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/03\/fc-barcelona-v-rayo-vallecano-de-madrid-laliga-ea-sports-3-scaled.jpg","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/03\/fc-barcelona-v-rayo-vallecano-de-madrid-laliga-ea-sports-3-scaled.jpg","og:image:width":2560,"og:image:height":1706,"article:published_time":"2026-03-22T15:22:43+00:00","article:modified_time":"2026-03-22T15:48:04+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"Joan Garc\u00eda descarta cualquier molestia: \u00abten\u00eda algo de sobrecarga pero nada serio\u00bb \u2013 Agente Libre Digital","twitter:description":"Joan Garc\u00eda descarta cualquier molestia: \u00abten\u00eda algo de sobrecarga pero nada serio\u00bb El guardameta de Sallent ha pasado por los micr\u00f3fonos de DAZN Espa\u00f1a tras salvar de la p\u00e9rdida de puntos al FC Barcelona ante el Rayo Vallecano (1-0)","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2026\/03\/fc-barcelona-v-rayo-vallecano-de-madrid-laliga-ea-sports-3-scaled.jpg"},"aioseo_meta_data":{"post_id":"61759","title":null,"description":"#post_title El guardameta de Sallent ha pasado por los micr\u00f3fonos de DAZN Espa\u00f1a tras salvar de la p\u00e9rdida de puntos al FC Barcelona ante el Rayo Vallecano (1-0)","keywords":null,"keyphrases":{"focus":{"keyphrase":"Joan","score":91,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-03-22 15:22:43","updated":"2026-03-22 15:48:28","seo_analyzer_scan_date":null,"focus_keyword":"Joan","additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/fc-barcelona\/\" title=\"FC Barcelona\">FC Barcelona<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tJoan Garc\u00eda descarta cualquier molestia: \u00abten\u00eda algo de sobrecarga pero nada serio\u00bb\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"FC Barcelona","link":"https:\/\/agentelibredigital.com\/index.php\/category\/fc-barcelona\/"},{"label":"Joan Garc\u00eda descarta cualquier molestia: \u00abten\u00eda algo de sobrecarga pero nada serio\u00bb","link":"https:\/\/agentelibredigital.com\/index.php\/2026\/03\/22\/joan-garcia-descarta-cualquier-molestia-tenia-algo-de-sobrecarga-pero-nada-serio\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/61759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/195"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=61759"}],"version-history":[{"count":1,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/61759\/revisions"}],"predecessor-version":[{"id":61764,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/61759\/revisions\/61764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/61769"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=61759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=61759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=61759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}