{"id":6145,"date":"2023-12-20T18:26:18","date_gmt":"2023-12-20T17:26:18","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=6145"},"modified":"2023-12-20T18:26:18","modified_gmt":"2023-12-20T17:26:18","slug":"previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2023\/12\/20\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\/","title":{"rendered":"Previa Real Valladolid &#8211; Racing de Ferrol: \u00daltimo combate del a\u00f1o"},"content":{"rendered":"<h4>Vuelve el estadio de la pulmon\u00eda el jueves 21 de diciembre a las 21:30 horas contra el Racing de Ferrol<\/h4>\n<p>La<strong> jornada 21 de la <a href=\"https:\/\/agentelibredigital.com\/?s=la+liga+hypermotion\">Liga Hypermotion<\/a><\/strong> regresa a casa para el equipo vallisoletano, tras una <strong>amarga visita en el estadio de la\u00a0 <a href=\"https:\/\/agentelibredigital.com\/?s=la+ceramica\">Cer\u00e1mica, <\/a><\/strong>dejando atr\u00e1s tres puntos claves con la oportunidad de empatar al l\u00edder y sacar cuatro puntos al tercer clasificado. A pesar de esa derrota dolorosa, los aficionados pucelanos cumplir\u00e1n con su asistencia en el <strong>\u00faltimo partido del a\u00f1o<\/strong>, esperando una respuesta mutua del equipo <strong>para pelear los tres puntos claves con la mirada puesta en el ascenso.<\/strong><\/p>\n<figure style=\"width: 1374px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/s3.ppllstatics.com\/elnortedecastilla\/www\/multimedia\/2023\/12\/18\/1475388715.jpg\" alt=\"\" width=\"1374\" height=\"926\" \/><figcaption class=\"wp-caption-text\">Iv\u00e1n S\u00e1nchez contra el Villareal B. FUENTE: El Norte de Castilla<\/figcaption><\/figure>\n<h4>Din\u00e1mica de ambos equipos<\/h4>\n<p>Los chicos de Crist\u00f3bal Parraro llegan en un momento muy dulce al <a href=\"https:\/\/agentelibredigital.com\/?s=Jose+zorrilla\">Jos\u00e9 Zorrilla<\/a>, acumulando un total de <strong>cinco victorias y tres empates en los \u00faltimos partidos<\/strong>, dej\u00e1ndolos en la <strong>cuarta posici\u00f3n a un punto del Real Valladolid.<\/strong> Sin duda alguna, los gallegos han ca\u00eddo de pie como<strong> reci\u00e9n ascendidos en esta temporada<\/strong>, convirti\u00e9ndose en uno de los equipos revelaci\u00f3n luchando por esos puestos de ascenso.<\/p>\n<figure style=\"width: 750px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/racingclubferrol.net\/wp-content\/uploads\/2023\/12\/MJN_3429-copia-scaled-e1702161004723-750x350.jpg\" alt=\"\" width=\"750\" height=\"350\" \/><figcaption class=\"wp-caption-text\">Jugador del Racing de Ferrol. Fuente: Racing de Ferrol<\/figcaption><\/figure>\n<p>En el otro lado del campo como <strong>locales encontramos al<a href=\"https:\/\/agentelibredigital.com\/?s=real+valladolid\"> Real Valladolid<\/a>,<\/strong> que tras su pinchazo en la jornada anterior,\u00a0 mantiene su posici\u00f3n como <strong>segundos clasificados<\/strong>. Los blanquivioletas dentro de casa se convierten en <strong>el mejor equipo local<\/strong> de la competici\u00f3n, con un total de<strong> siete victorias, tres derrotas y un empate<\/strong>, cifras que el t\u00e9cnico <a href=\"https:\/\/agentelibredigital.com\/?s=pezzolano\">Pezzolano<\/a> saca a relucir orgulloso del calor de su afici\u00f3n y de la entrega de sus chicos en el terreno de juego.<\/p>\n<p>A\u00fan as\u00ed, este jueves tendr\u00e1 lugar una<strong> gran cita bajo la niebla del Jos\u00e9 Zorrilla<\/strong>, convirti\u00e9ndose en un campo de guerra con el objetivo de salir victoriosos <strong>contra el Racing de Ferrol.<\/strong> Pezzolano es consciente de la importancia de este partido, por eso, no subestima al <strong>octavo equipo m\u00e1s peligroso de la Liga Hypermotion como visitantes.<\/strong><\/p>\n<h4>El cara a cara del pasado<\/h4>\n<p>Ambos equipos se han enfrentado <strong>un total de 35 ocasiones,<\/strong> dejando caer la balanza con <strong>18 victorias para los vallisoletanos<\/strong>, <strong>10 para los gallegos<\/strong> y <strong>7 terminaron en tablas<\/strong>. Para remontarnos al pasado de estos vis a vis, tenemos que poner la mirada en las <strong>temporadas 04\/05 y 05\/06 convirti\u00e9ndose en los \u00faltimos enfrentamientos<\/strong> hasta el d\u00eda de hoy.<\/p>\n<p>No solo se han enfrentado en la liga, si no tambi\u00e9n,\u00a0 encontramos antecedentes en <strong>la copa del general\u00edsimo con dos encuentros<\/strong>, una <strong>victoria pucelana<\/strong> en el 1941 y un <strong>empate<\/strong>. En la <strong>copa del rey<\/strong> retrocedemos al 2001, sumando <strong>otra victoria<\/strong> al registro <strong>blanquivioleta<\/strong> con un parcial de 2-0.<\/p>\n<figure style=\"width: 474px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/th.bing.com\/th\/id\/OIP.fwZjVT6oZPoDxZIdsP1EagHaKT?rs=1&amp;pid=ImgDetMain\" alt=\"El Racing de Ferrol partir\u00e1 hacia Logro\u00f1o tras el entrenamiento del ...\" width=\"474\" height=\"659\" \/><figcaption class=\"wp-caption-text\">Jugador del Racing de Ferrol contra el Valladolid B. Fuente: Ferrol360<\/figcaption><\/figure>\n<h4>Posibles alineaciones<\/h4>\n<p>Real Valladolid: <strong>Masip; Escudero; Boyomo; David Torres; Luis P\u00e9rez; Monchu; Juric; Moro; Meseguer; Kenedy y\u00a0 Salazar<\/strong><\/p>\n<p>Racing de Ferrol: <strong>Ander Cantero; Mois\u00e9s Delgado; Castro; Jon Garc\u00eda; Delm\u00e1s; Jes\u00fas Bernal; Alejandro L\u00f3pez; H\u00e9ber Pena; Losada; Carlos Vicente y \u00c1lvaro Gim\u00e9nez<\/strong><\/p>\n<h4>\u00c1rbitro del partido<\/h4>\n<p>El colegiado para este partido ser\u00e1 <strong>Andr\u00e9s Fuentes Molina<\/strong>, \u00e1rbitro valenciano con el que ya se ha encontrado el Real Valladolid en la tercera jornada de la competici\u00f3n, contra el Alcorc\u00f3n. Andr\u00e9s estar\u00e1 acompa\u00f1ado en<strong> las bandas por Jim\u00e9nez Yustos y Mart\u00ednez Caballeros<\/strong>, y en la <strong>sala VOR por Gorostegui Fern\u00e1ndez &#8211; Ortega.<\/strong><\/p>\n<figure style=\"width: 1700px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/statics-maker.llt-services.com\/vll\/images\/2023\/12\/18\/xlarge-wp\/6a63080c-8673-47b6-a4a7-30c5bd42c1d0-31.webp\" alt=\"\" width=\"1700\" height=\"956\" \/><figcaption class=\"wp-caption-text\">Jornada tres de la competici\u00f3n arbitrada por Andr\u00e9s Fuentes Molina<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Vuelve el estadio de la pulmon\u00eda el jueves 21 de diciembre a las 21:30 horas contra el Racing de Ferrol La jornada 21 de la Liga Hypermotion regresa a casa&hellip; <\/p>\n","protected":false},"author":4,"featured_media":6152,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[47,8],"tags":[1116,1115,189,123],"class_list":["post-6145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol-espanol","category-laliga-hypermotion","tag-jornada-21","tag-jose-zorrilla","tag-racing-de-ferrol","tag-real-valladolid"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Previa Real Valladolid \u2013 Racing de Ferrol: \u00daltimo combate del a\u00f1o\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Lucia Arroyo\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2023\/12\/20\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Previa Real Valladolid \u2013 Racing de Ferrol: \u00daltimo combate del a\u00f1o \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"Previa Real Valladolid \u2013 Racing de Ferrol: \u00daltimo combate del a\u00f1o\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2023\/12\/20\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/12\/partido-valladolid22.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/12\/partido-valladolid22.webp\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1374\" \/>\n\t\t<meta property=\"og:image:height\" content=\"984\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-12-20T17:26:18+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-12-20T17:26:18+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Previa Real Valladolid \u2013 Racing de Ferrol: \u00daltimo combate del a\u00f1o \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Previa Real Valladolid \u2013 Racing de Ferrol: \u00daltimo combate del a\u00f1o\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/12\/partido-valladolid22.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/12\\\/20\\\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\\\/#blogposting\",\"name\":\"Previa Real Valladolid \\u2013 Racing de Ferrol: \\u00daltimo combate del a\\u00f1o \\u2013 Agente Libre Digital\",\"headline\":\"Previa Real Valladolid &#8211; Racing de Ferrol: \\u00daltimo combate del a\\u00f1o\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/lucia-arroyo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/partido-valladolid22.webp\",\"width\":1374,\"height\":984},\"datePublished\":\"2023-12-20T18:26:18+01:00\",\"dateModified\":\"2023-12-20T18:26:18+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/12\\\/20\\\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/12\\\/20\\\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\\\/#webpage\"},\"articleSection\":\"F\\u00fatbol Espa\\u00f1ol, LaLiga Hypermotion, Jornada 21, Jos\\u00e9 Zorrilla, Racing de Ferrol, Real Valladolid\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/12\\\/20\\\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/laliga-hypermotion\\\/#listItem\",\"name\":\"LaLiga Hypermotion\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/laliga-hypermotion\\\/#listItem\",\"position\":2,\"name\":\"LaLiga Hypermotion\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/laliga-hypermotion\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/12\\\/20\\\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\\\/#listItem\",\"name\":\"Previa Real Valladolid &#8211; Racing de Ferrol: \\u00daltimo combate del a\\u00f1o\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/12\\\/20\\\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\\\/#listItem\",\"position\":3,\"name\":\"Previa Real Valladolid &#8211; Racing de Ferrol: \\u00daltimo combate del a\\u00f1o\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/laliga-hypermotion\\\/#listItem\",\"name\":\"LaLiga Hypermotion\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/12\\\/20\\\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/12\\\/20\\\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/lucia-arroyo\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/lucia-arroyo\\\/\",\"name\":\"Lucia Arroyo\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/12\\\/20\\\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ceaee324e10cff2b379591f3b44b926d49d22225c6f2c5ea3bb3bf4f2d629e62?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Lucia Arroyo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/12\\\/20\\\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/12\\\/20\\\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\\\/\",\"name\":\"Previa Real Valladolid \\u2013 Racing de Ferrol: \\u00daltimo combate del a\\u00f1o \\u2013 Agente Libre Digital\",\"description\":\"Previa Real Valladolid \\u2013 Racing de Ferrol: \\u00daltimo combate del a\\u00f1o\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/12\\\/20\\\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/lucia-arroyo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/lucia-arroyo\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/partido-valladolid22.webp\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/12\\\/20\\\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\\\/#mainImage\",\"width\":1374,\"height\":984},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/12\\\/20\\\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\\\/#mainImage\"},\"datePublished\":\"2023-12-20T18:26:18+01:00\",\"dateModified\":\"2023-12-20T18:26:18+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Previa Real Valladolid \u2013 Racing de Ferrol: \u00daltimo combate del a\u00f1o \u2013 Agente Libre Digital","description":"Previa Real Valladolid \u2013 Racing de Ferrol: \u00daltimo combate del a\u00f1o","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2023\/12\/20\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/12\/20\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\/#blogposting","name":"Previa Real Valladolid \u2013 Racing de Ferrol: \u00daltimo combate del a\u00f1o \u2013 Agente Libre Digital","headline":"Previa Real Valladolid &#8211; Racing de Ferrol: \u00daltimo combate del a\u00f1o","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/lucia-arroyo\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/12\/partido-valladolid22.webp","width":1374,"height":984},"datePublished":"2023-12-20T18:26:18+01:00","dateModified":"2023-12-20T18:26:18+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/12\/20\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/12\/20\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\/#webpage"},"articleSection":"F\u00fatbol Espa\u00f1ol, LaLiga Hypermotion, Jornada 21, Jos\u00e9 Zorrilla, Racing de Ferrol, Real Valladolid"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/12\/20\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/#listItem","name":"LaLiga Hypermotion"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/#listItem","position":2,"name":"LaLiga Hypermotion","item":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/12\/20\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\/#listItem","name":"Previa Real Valladolid &#8211; Racing de Ferrol: \u00daltimo combate del a\u00f1o"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/12\/20\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\/#listItem","position":3,"name":"Previa Real Valladolid &#8211; Racing de Ferrol: \u00daltimo combate del a\u00f1o","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/#listItem","name":"LaLiga Hypermotion"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/12\/20\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/12\/20\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/lucia-arroyo\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/lucia-arroyo\/","name":"Lucia Arroyo","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/12\/20\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/ceaee324e10cff2b379591f3b44b926d49d22225c6f2c5ea3bb3bf4f2d629e62?s=96&d=mm&r=g","width":96,"height":96,"caption":"Lucia Arroyo"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/12\/20\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2023\/12\/20\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\/","name":"Previa Real Valladolid \u2013 Racing de Ferrol: \u00daltimo combate del a\u00f1o \u2013 Agente Libre Digital","description":"Previa Real Valladolid \u2013 Racing de Ferrol: \u00daltimo combate del a\u00f1o","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/12\/20\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/lucia-arroyo\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/lucia-arroyo\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/12\/partido-valladolid22.webp","@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/12\/20\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\/#mainImage","width":1374,"height":984},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/12\/20\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\/#mainImage"},"datePublished":"2023-12-20T18:26:18+01:00","dateModified":"2023-12-20T18:26:18+01:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"Previa Real Valladolid \u2013 Racing de Ferrol: \u00daltimo combate del a\u00f1o \u2013 Agente Libre Digital","og:description":"Previa Real Valladolid \u2013 Racing de Ferrol: \u00daltimo combate del a\u00f1o","og:url":"https:\/\/agentelibredigital.com\/index.php\/2023\/12\/20\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/12\/partido-valladolid22.webp","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/12\/partido-valladolid22.webp","og:image:width":1374,"og:image:height":984,"article:published_time":"2023-12-20T17:26:18+00:00","article:modified_time":"2023-12-20T17:26:18+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"Previa Real Valladolid \u2013 Racing de Ferrol: \u00daltimo combate del a\u00f1o \u2013 Agente Libre Digital","twitter:description":"Previa Real Valladolid \u2013 Racing de Ferrol: \u00daltimo combate del a\u00f1o","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/12\/partido-valladolid22.webp"},"aioseo_meta_data":{"post_id":"6145","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-12-20 17:26:19","updated":"2025-06-04 19:23:53","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/\" title=\"LaLiga Hypermotion\">LaLiga Hypermotion<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPrevia Real Valladolid \u2013 Racing de Ferrol: \u00daltimo combate del a\u00f1o\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"LaLiga Hypermotion","link":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/"},{"label":"Previa Real Valladolid &#8211; Racing de Ferrol: \u00daltimo combate del a\u00f1o","link":"https:\/\/agentelibredigital.com\/index.php\/2023\/12\/20\/previa-real-valladolid-racing-de-ferrol-ultimo-combate-del-ano\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/6145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=6145"}],"version-history":[{"count":1,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/6145\/revisions"}],"predecessor-version":[{"id":6153,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/6145\/revisions\/6153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/6152"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=6145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=6145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=6145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}