{"id":58182,"date":"2025-12-09T22:58:46","date_gmt":"2025-12-09T21:58:46","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=58182"},"modified":"2025-12-09T23:06:08","modified_gmt":"2025-12-09T22:06:08","slug":"barca-2-1-eintracht-frankfurt-kounde-remata-y-remonta-en-el-regreso-de-la-champions-al-camp-nou","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2025\/12\/09\/barca-2-1-eintracht-frankfurt-kounde-remata-y-remonta-en-el-regreso-de-la-champions-al-camp-nou\/","title":{"rendered":"Bar\u00e7a 2-1 Eintracht Frankfurt: Kound\u00e9 remata y remonta en el regreso de la Champions al Camp Nou"},"content":{"rendered":"<h4>Con dos testarazos en tres minutos, Kound\u00e9 da la vuelta al marcador tras un primer tiempo que auguraba los peores presagios<\/h4>\n<p>A <strong>mitad de tabla<\/strong> afrontaba el quinto encuentro de la fase regular de la <a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/uefa-champions-league\/\">UEFA Champions League<\/a> el <a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/fc-barcelona\/\">Bar\u00e7a<\/a> de Hansi Flick. Un equipo que, habiendo recuperado los futbolistas lesionados y, por ende, un <strong>buen estado de forma<\/strong>, regresaba al <strong><a href=\"https:\/\/www.marca.com\/futbol\/barcelona\/2025\/12\/09\/spotify-camp-nou-da-bienvenida-champions-league.html\">Spotify Camp Nou<\/a> <\/strong>en las grandes noches europeas.<\/p>\n<p>Una vez debutado en <strong>LaLiga EA Sports<\/strong>, el templo blaugrana <a href=\"https:\/\/www.espn.com.ar\/futbol\/partido\/_\/juegoId\/633249\/eintracht-frankfurt-barcelona\">volv\u00eda a recibir al <strong>Eintracht Frankfurt<\/strong><\/a>, recordando de buena mano el episodio sucedido hace tres temporadas con la superioridad visitante en las gradas. Sin embargo, esta vez no ocurrir\u00eda lo mismo, ya que el club hab\u00eda tomado las medidas pertinentes, bajo <strong>revisiones y seguimiento a los socios<\/strong>, para <strong>evitar la reventa de entradas<\/strong> que precipit\u00f3 la invasi\u00f3n alemana el 14 de abril de 2022.<\/p>\n<figure id=\"attachment_58187\" aria-describedby=\"caption-attachment-58187\" style=\"width: 644px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-58187\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/fc-barcelona-v-eintracht-frankfurt-quarter-final-leg-two-uefa-europa-league-300x200.jpg\" alt=\"\" width=\"644\" height=\"429\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/fc-barcelona-v-eintracht-frankfurt-quarter-final-leg-two-uefa-europa-league-300x200.jpg 300w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/fc-barcelona-v-eintracht-frankfurt-quarter-final-leg-two-uefa-europa-league-1024x683.jpg 1024w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/fc-barcelona-v-eintracht-frankfurt-quarter-final-leg-two-uefa-europa-league-768x512.jpg 768w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/fc-barcelona-v-eintracht-frankfurt-quarter-final-leg-two-uefa-europa-league-1536x1024.jpg 1536w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/fc-barcelona-v-eintracht-frankfurt-quarter-final-leg-two-uefa-europa-league-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><figcaption id=\"caption-attachment-58187\" class=\"wp-caption-text\">La imagen de la abrumadora superioridad germana en las gradas del antiguo Camp Nou. Fuente: David Ramos.<\/figcaption><\/figure>\n<h2>Primera parte<\/h2>\n<p>Un <strong>lleno absoluto en el Spotify Camp Nou<\/strong>, esta vez gracias al socio cul\u00e9, demostraba las ganas de que regresara la m\u00e1xima competici\u00f3n a nivel europeo a su hist\u00f3rica sede. La <strong>misma emoci\u00f3n e intensidad se viv\u00eda desde las gradas que desde el c\u00e9sped<\/strong>, donde el conjunto liderado por Hansi Flick avanzaba a pasos agigantados rumbo al primer tanto con el paso de los minutos. Con el <strong>gol anulado a Lewandowski<\/strong>, que ven\u00eda precedido por un buen centro de Raphinha, marcar\u00eda el Bar\u00e7a los tiempos del partido: presi\u00f3n alta, intensidad y creatividad que hac\u00edan recordar la versi\u00f3n de la temporada pasada.<\/p>\n<p>Pero nada m\u00e1s lejos de la realidad, otro contragolpe pondr\u00eda en desventaja al Bar\u00e7a. Ser\u00eda <strong>Knauff<\/strong> el encargado de aprovechar las <strong>dudas defensivas de Balde<\/strong> para poner el bal\u00f3n lejos de las posibilidades de Joan Garcia. A partir de este bacatazo, lo intentar\u00eda por diestro y siniestro el conjunto azulgrana, pero sin \u00e9xito. El motivo, un t\u00e9cnico que hab\u00eda conseguido su prop\u00f3sito: anotar r\u00e1pido, cerrar por dentro cualquier intentona elaborativa y dejar el ataque en manos de Knauff y su velocidad.<\/p>\n<figure id=\"attachment_58197\" aria-describedby=\"caption-attachment-58197\" style=\"width: 631px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-58197\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/fc-barcelona-v-eintracht-frankfurt-uefa-champions-league-2025-26-league-phase-md6-300x196.jpg\" alt=\"\" width=\"631\" height=\"412\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/fc-barcelona-v-eintracht-frankfurt-uefa-champions-league-2025-26-league-phase-md6-300x196.jpg 300w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/fc-barcelona-v-eintracht-frankfurt-uefa-champions-league-2025-26-league-phase-md6-1024x668.jpg 1024w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/fc-barcelona-v-eintracht-frankfurt-uefa-champions-league-2025-26-league-phase-md6-768x501.jpg 768w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/fc-barcelona-v-eintracht-frankfurt-uefa-champions-league-2025-26-league-phase-md6-1536x1003.jpg 1536w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/fc-barcelona-v-eintracht-frankfurt-uefa-champions-league-2025-26-league-phase-md6-2048x1337.jpg 2048w\" sizes=\"auto, (max-width: 631px) 100vw, 631px\" \/><figcaption id=\"caption-attachment-58197\" class=\"wp-caption-text\">El Eintracht celebra el \u00fanico gol cosechado en la primera parte. Fuente: Judit Cartiel \/ Getty Images.<\/figcaption><\/figure>\n<p>Llegaban los <strong>vitoreos<\/strong> a la Ciudad Condal, consecuencia directa de la <strong>desesperaci\u00f3n por no lograr llegar al \u00e1rea contraria con efectividad<\/strong>. Para m\u00e1s inri, el Eintracht continuaba causando m\u00e1s peligro en acciones solitarias que el Bar\u00e7a con posesiones interminables. La \u00faltima baza antes del descanso, otro contragolpe que dejaba su finalizaci\u00f3n Knauff en los pies de Skhiri, quien enviar\u00eda el disparo por encima del travesa\u00f1o desde el borde del \u00e1rea.<\/p>\n<h2><strong>Segunda parte<\/strong><\/h2>\n<p><strong>Rashford<\/strong> ser\u00eda el cambio escogido por Flick para tratar de darle la vuelta al resultado, cuya entrada dej\u00f3 en el banquillo a un <strong>Ferm\u00edn poco participativo<\/strong>. Y cinco minutos le bastaron para, primeramente, dar una asistencia al punto de penalti a Raphinha que no acabar\u00eda de aprovechar y, a continuaci\u00f3n, poner un <strong>bal\u00f3n teledirigido a la cabeza de Kound\u00e9<\/strong>, quien enviar\u00eda la pelota a la red no solo una vez, sino <strong>dos<\/strong>. En primer lugar, tras asistencia del ingl\u00e9s pero, dos minutos despu\u00e9s, a trav\u00e9s de un <strong>centro de Lamine Yamal<\/strong> desde la misma banda.<\/p>\n<figure id=\"attachment_58198\" aria-describedby=\"caption-attachment-58198\" style=\"width: 734px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-58198\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/fc-barcelona-v-eintracht-frankfurt-uefa-champions-league-2025-26-league-phase-md6-1-300x196.jpg\" alt=\"\" width=\"734\" height=\"480\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/fc-barcelona-v-eintracht-frankfurt-uefa-champions-league-2025-26-league-phase-md6-1-300x196.jpg 300w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/fc-barcelona-v-eintracht-frankfurt-uefa-champions-league-2025-26-league-phase-md6-1-1024x669.jpg 1024w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/fc-barcelona-v-eintracht-frankfurt-uefa-champions-league-2025-26-league-phase-md6-1-768x502.jpg 768w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/fc-barcelona-v-eintracht-frankfurt-uefa-champions-league-2025-26-league-phase-md6-1-1536x1004.jpg 1536w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/fc-barcelona-v-eintracht-frankfurt-uefa-champions-league-2025-26-league-phase-md6-1-2048x1338.jpg 2048w\" sizes=\"auto, (max-width: 734px) 100vw, 734px\" \/><figcaption id=\"caption-attachment-58198\" class=\"wp-caption-text\">Kound\u00e9 remata dos jugadas consecutivas con el mismo resultado: una remontada en su cabeza. Fuente: Judit Cartiel \/ Getty Images.<\/figcaption><\/figure>\n<p>Con la remontada efectuada un partido m\u00e1s, retornaba la tranquilidad al Spotify Camp Nou. No obstante, la diferencia segu\u00eda siendo de un solo tanto, y ese era un dato bien sabido por Dino Toppm\u00f6ller, el t\u00e9cnico alem\u00e1n que ir\u00eda introduciendo sus sustituciones conforme se acercaban los \u00faltimos diez minutos de juego.<\/p>\n<p>A pesar de los cambios, <strong>no ve\u00eda puerta el Eintracht<\/strong>, mientras que el Bar\u00e7a exhib\u00eda comodidad a ratos, ya que tratar\u00eda de aguantar el resultado sin arriesgar en demas\u00eda. En esa l\u00ednea, se llevaban a cabo los dos \u00faltimos cambios en el banquillo blaugrana, del mismo modo que tambi\u00e9n el \u00faltimo en el germano. Ya dormido y bajo control local, <strong>el encuentro llegaba a su fin dejando los tres puntos en la capital catalana<\/strong>.<\/p>\n<h2>Ficha t\u00e9cnica<\/h2>\n<p><strong>XI Barcelona (4-2-3-1)<\/strong>: Joan Garcia (P); Kound\u00e9, Cubars\u00ed, Gerard Mart\u00edn, Balde (Christensen 89&#8242;); Eric Garcia, Pedri; Lamine Yamal (Bardghji 89&#8242;), Ferm\u00edn (Rashford 46&#8242;), Raphinha (de Jong 66&#8242;); Lewandowski (Ferran Torres 66&#8242;).<\/p>\n<p><strong>Entrenador<\/strong>: Hansi Flick<\/p>\n<p><strong>XI Eintracht Frankfurt (4-2-3-1)<\/strong>: Zetterer (P); Kristensen, Koch, Theate, Brown; Skhiri, Larsson; Doan (Ngankam 89&#8242;), G\u00f6tze (Bahoya 77&#8242;), Cha\u00efbi (Uzun 77&#8242;); Knauff (Wahi 68&#8242;).<\/p>\n<p><strong>Entrenador<\/strong>: Dino Toppm\u00f6ller<\/p>\n<p><strong>Goleadores Barcelona<\/strong>: Kound\u00e9 50&#8242; 53&#8242;<\/p>\n<p><strong>Amonestaciones Barcelona<\/strong>: Lamine Yamal 56&#8242;, Gerard Mart\u00edn 60&#8242;<\/p>\n<p><strong>Goleadores Eintracht Frankfurt<\/strong>: Knauff 21&#8242;<\/p>\n<p><strong>Amonestaciones Eintracht Frankfurt<\/strong>: Knauff 27&#8242;<\/p>\n<p><strong>\u00c1rbitro Principal<\/strong>: Davide Massa<\/p>\n<p><strong>\u00c1rbitro VAR<\/strong>: Marco Di Bello<\/p>\n<p><strong>Estadio<\/strong>: Spotify Camp Nou<\/p>\n<p><strong>Redactor:<\/strong>\u00a0<em><a href=\"https:\/\/agentelibredigital.com\/index.php\/author\/adrian-garcia\/\">Adrian Garcia<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con dos testarazos en tres minutos, Kound\u00e9 da la vuelta al marcador tras un primer tiempo que auguraba los peores presagios A mitad de tabla afrontaba el quinto encuentro de&hellip; <\/p>\n","protected":false},"author":195,"featured_media":58200,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[12,36],"tags":[4613,55,1473,80],"class_list":["post-58182","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fc-barcelona","category-uefa-champions-league","tag-eintracht-frankfurt","tag-fc-barcelona","tag-jules-kounde","tag-uefa-champions-league"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/58182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/195"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=58182"}],"version-history":[{"count":4,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/58182\/revisions"}],"predecessor-version":[{"id":58211,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/58182\/revisions\/58211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/58200"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=58182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=58182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=58182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}