{"id":58129,"date":"2025-12-08T14:41:08","date_gmt":"2025-12-08T13:41:08","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=58129"},"modified":"2025-12-08T14:41:34","modified_gmt":"2025-12-08T13:41:34","slug":"ivan-aurrecoechea-rescinde-contrato-con-el-coviran-granada","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2025\/12\/08\/ivan-aurrecoechea-rescinde-contrato-con-el-coviran-granada\/","title":{"rendered":"Iv\u00e1n Aurrecoechea rescinde contrato con el Coviran Granada"},"content":{"rendered":"<p><strong>El p\u00edvot madrile\u00f1o, Iv\u00e1n Aurrecoechea, y el Coviran Granada han llegado a un acuerdo para rescindir el contrato que les un\u00eda<\/strong><\/p>\n<p>Se ha confirmado una noticia que era un secreto a voces en Granada durante las \u00faltimas semanas, <strong><a href=\"https:\/\/fundacioncbgranada.es\/ivan-aurrecoechea-y-el-coviran-granada-separan-sus-caminos\/\">la rescisi\u00f3n de contrato de Iv\u00e1n Aurrecoechea con el Coviran<\/a><\/strong>. El fichaje de<strong> <a href=\"https:\/\/agentelibredigital.com\/index.php\/2025\/12\/04\/amida-brimah-refuerza-al-coviran-granada\/\">Amida Brimah<\/a><\/strong> el pasado jueves, fue la confirmaci\u00f3n de que este corte se iba a producir, tras<strong> los escasos minutos del p\u00edvot internacional con la Selecci\u00f3n Espa\u00f1ola 3&#215;3<\/strong> en el primer tramo de la temporada.<\/p>\n<p><strong>Iv\u00e1n Aurrecoechea<\/strong> ha sumado <strong>27 partidos disputados con el Coviran Granada<\/strong> desde su fichaje en verano del 2024, siendo un <strong>p\u00edvot de rotaci\u00f3n<\/strong> tanto la pasada campa\u00f1a (part\u00eda por detr\u00e1s en la rotaci\u00f3n de Jacob Wiley, Rub\u00e9n Gurrero y Giorgi Bezhanishvili) como esta (tambi\u00e9n part\u00eda por detr\u00e1s de Zach Hankins y Babatunde Olumuyiwa), pero aportando fuerza, vigor y capacidad reboteadora en los minutos que ha estado en pista. Adem\u00e1s de ser un gran profesional y<strong> aportar cohesi\u00f3n en el vestuario<\/strong>, en lo extradeportivo.<\/p>\n<p><strong><a href=\"https:\/\/www.acb.com\/jugador\/temporada-a-temporada\/id\/20210887\">Sus promedios en ACB<\/a> han sido de 7:55 minutos, 2,3 puntos, 1,9 rebotes, 0,2 asistencias y 0,1 tapones por partido<\/strong>. Se desconoce por el momento si su futuro pasar\u00e1 por<strong> un regreso a la Primera FEB<\/strong>, donde mostr\u00f3 su mejor rendimiento como un interior dominante antes de fichar por el equipo nazar\u00ed.<\/p>\n<figure id=\"attachment_58141\" aria-describedby=\"caption-attachment-58141\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-58141 size-large\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/GgzkYZ4XQAAzmcA-1024x683.jpeg\" alt=\"Iv\u00e1n Aurrecoechea\" width=\"1024\" height=\"683\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/GgzkYZ4XQAAzmcA-1024x683.jpeg 1024w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/GgzkYZ4XQAAzmcA-300x200.jpeg 300w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/GgzkYZ4XQAAzmcA-768x512.jpeg 768w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/GgzkYZ4XQAAzmcA-1536x1024.jpeg 1536w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/12\/GgzkYZ4XQAAzmcA-2048x1366.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-58141\" class=\"wp-caption-text\">Iv\u00e1n Aurrecoechea captura un rebote frente al Real Madrid la pasada temporada (Foto: v\u00eda Coviran Granada\/redes sociales \u00b4X`)<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2>Activos en el mercado<\/h2>\n<p>En clave Coviran Granada, <strong>Brimah ocupar\u00e1 la posici\u00f3n de tercer p\u00edvot<\/strong>, un puesto donde parece que habr\u00e1 m\u00e1s movimientos en las pr\u00f3ximas horas, dado que seg\u00fan ha informado el periodista <a href=\"https:\/\/x.com\/chemadelucas\/status\/1997977330963116053\"><strong>Chema de Lucas<\/strong><\/a>, <strong>Zach Hankins negocia su fichaje por el Maccabi Tel Aviv<\/strong>, lo que obligar\u00e1 al Coviran Granada a seguir en el mercado, adem\u00e1s de <strong>seguir buscando el dos que sustituya a Jovan Kljajic<\/strong> hasta que regrese en unos meses.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El p\u00edvot madrile\u00f1o, Iv\u00e1n Aurrecoechea, y el Coviran Granada han llegado a un acuerdo para rescindir el contrato que les un\u00eda Se ha confirmado una noticia que era un secreto&hellip; <\/p>\n","protected":false},"author":276,"featured_media":58138,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[49,39],"tags":[1984,682,5118,561,4293,3713,4350],"class_list":["post-58129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baloncesto","category-liga-endesa","tag-acb","tag-coviran-granada","tag-ivan-aurrecoechea","tag-liga-endesa","tag-news","tag-rescision-de-contrato","tag-temporada-2025-2026"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/58129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/276"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=58129"}],"version-history":[{"count":12,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/58129\/revisions"}],"predecessor-version":[{"id":58143,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/58129\/revisions\/58143"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/58138"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=58129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=58129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=58129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}