{"id":57012,"date":"2025-11-16T20:53:36","date_gmt":"2025-11-16T19:53:36","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=57012"},"modified":"2025-11-16T20:53:36","modified_gmt":"2025-11-16T19:53:36","slug":"cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2025\/11\/16\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\/","title":{"rendered":"CD Mirand\u00e9s 0-2 Burgos CF: Mario Gonz\u00e1lez hace blanquinegro el derbi"},"content":{"rendered":"<h4>Un doblete en los minutos finales de Mario Gonz\u00e1lez da una important\u00edsima victoria a los blanquinegros en un partido muy atascado<\/h4>\n<p>El <a href=\"https:\/\/agentelibredigital.com\/?s=burgos+cf\">Burgos CF<\/a> ha ganado 0-2 contra el CD Mirand\u00e9s en Mendizorroza en la jornada 14 de<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/\"> La Liga Hypermotion<\/a>. El primer tiempo fue completamente infumable. El Mirand\u00e9s tuvo m\u00e1s el dominio, pero sin generar casi nada de peligro. Solo hubo dos grandes ocasiones en el primer acto y las dos fueron en los \u00faltimos 5 minutos y en tiros desde fuera del \u00e1rea. Hasta el minuto 70 del segundo tiempo el partido sigui\u00f3 en la misma t\u00f3nica. Comenz\u00f3 dominando el Burgos y luego el Mirand\u00e9s fue creciendo. El Mirand\u00e9s tuvo dos ocasiones muy claras, pero termin\u00f3 siendo el Burgos, gracias a un doblete de Mario Gonz\u00e1lez, el que se llev\u00f3 la victoria.<\/p>\n<h2>Primer tiempo para ahorrarse de ver<\/h2>\n<p>El partido comenz\u00f3 con dominio del Burgos, aunque la mayor\u00eda en campo propio. Con el paso de los minutos, el Mirand\u00e9s se hizo con el control del juego y empez\u00f3 a llegar con cierto peligro durante unos minutos. El partido era completamente mon\u00f3tono y no pasaba nada. En el minuto 22, Pascual punteaba el bal\u00f3n y posteriormente se llevaba por delante a Iv\u00e1n Morante, impidi\u00e9ndole continuar la jugada. Ese leve toque con la puntera parece ser que eximi\u00f3 al central rojillo de cometer penalti, ya que la jugada es dentro del \u00e1rea, ya que ni Alonso de Ena en directo, ni Rub\u00e9n \u00c1valos desde el VAR, apreciaron nada punible. El Mirand\u00e9s se fue haciendo cada vez m\u00e1s con el dominio hasta llegar a tenerlo casi absoluto por momentos, pero sin generar absolutamente nada de peligro. En el minuto 40 lleg\u00f3 la primera gran ocasi\u00f3n del partido. Alberto Mar\u00ed cogi\u00f3 el bal\u00f3n en zona de tres cuartos, se dio la vuelta y desde algo m\u00e1s lejos de la frontal prob\u00f3 con un gran disparo que se march\u00f3 rozando el palo. Cuatro minutos despu\u00e9s, Lizancos hizo lo propio y sac\u00f3 un gran disparo que oblig\u00f3 a intervenir a Juanpa, que desvi\u00f3 a c\u00f3rner. No dio tiempo a m\u00e1s en el primer tiempo.<\/p>\n<figure style=\"width: 899px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/G55UUGIW4AABW4c?format=jpg&amp;name=large\" alt=\"Imagen\" width=\"899\" height=\"599\" \/><figcaption class=\"wp-caption-text\">Alberto Mar\u00ed y Sergio Gonz\u00e1lez disputando un bal\u00f3n. Fuente CD Mirand\u00e9s<\/figcaption><\/figure>\n<h2>Mario Gonz\u00e1lez termina resolvi\u00e9ndolo<\/h2>\n<p>El segundo tiempo no trajo grandes novedades en cuanto a juego en su inicio, ya que sigui\u00f3 siendo tan mon\u00f3tono como el primero durante los primeros minutos del segundo tiempo. Lo que s\u00ed cambi\u00f3 fue que el Burgos se hizo con la posesi\u00f3n y se asent\u00f3 en campo contrario. En el minuto 60, Ramis realiz\u00f3 los primeros cambios del partido.<em> Introdujo a Aitor C\u00f3rdoba y Appin en el lugar de Sergio Gonz\u00e1lez e \u00cd\u00f1igo C\u00f3rdoba.\u00a0<\/em>El Mirand\u00e9s volvi\u00f3 a entrar en juego y el Burgos dej\u00f3 de estar tan presente en campo rival, pero segu\u00eda sin suceder m\u00e1s de lo sucedido hasta el momento. En el minuto 69, Galv\u00e1n realiz\u00f3 su primer cambio. <em>Retir\u00f3 del campo a Aar\u00f3n Mart\u00edn para dar entrada a Cardero.<\/em> Instant\u00e1neamente despu\u00e9s, Pascual cabece\u00f3 un bal\u00f3n que hab\u00eda sido peinado, pero se encontr\u00f3 con una grand\u00edsima parada de Cantero. Dos minutos despu\u00e9s, Ramis volvi\u00f3 a mover el banquillo,<em> metiendo a Mollejo por David Gonz\u00e1lez.\u00a0<\/em>El Mirand\u00e9s se creci\u00f3 tras su \u00faltima ocasi\u00f3n y volvi\u00f3 a tenerla en el minuto 74, cuando Atienza intercept\u00f3 providencialmente un remate en el coraz\u00f3n del \u00e1rea del reci\u00e9n entrado, Cardero. Igualmente el desvi\u00f3 del madrile\u00f1o estuvo a punto de entrar. En el minuto 80, Ramis agot\u00f3 los cambios. <em>Retir\u00f3 a Fer Ni\u00f1o y Curro para dar entrada a Mario Gonz\u00e1lez y Ferm\u00edn.\u00a0<\/em><\/p>\n<p>El Burgos hab\u00eda vuelto a despertar tras esos minutos de agobio. En el minuto 85,<em><strong> Ferm\u00edn puso un c\u00f3rner casi a ras de suelo. Morante lo prolong\u00f3 en el primer palo y Mario Gonz\u00e1lez marc\u00f3 a placer en el \u00e1rea peque\u00f1a el primero del partido.<\/strong> <\/em>Le sent\u00f3 muy bien el gol al Burgos y en el minuto 88,<strong> Appin puso un centro que golpe\u00f3 claramente en la mano de Tamarit. Alonso de Ena no lo vio en directo, pero obviamente Rub\u00e9n \u00c1valos lo vio desde el VAR y le llam\u00f3 para que se\u00f1alara la pena m\u00e1xima. <\/strong><em><strong>Mario Gonz\u00e1lez tom\u00f3 la responsabilidad y no fall\u00f3 para hacer el segundo en su cuenta y de su equipo.<\/strong><\/em>Galv\u00e1n lo intent\u00f3 a la desesperada con un triple cambio, que ya ten\u00eda preparado antes del segundo gol. Introdujo a El Jebari, Novoa y Eto&#8217;o en el lugar de Helguera, Pascual y Tamarit, pero no dio tiempo a mucho m\u00e1s y se termin\u00f3 concretando la primera victoria a domicilio del Burgos en un derbi burgal\u00e9s en m\u00e1s de 20 a\u00f1os.<\/p>\n<figure style=\"width: 897px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.diariodeburgos.es\/media\/IMG\/2025\/797644C4-113B-419C-A353EB22A23CB2EF.WebP\" alt=\"\" width=\"897\" height=\"598\" \/><figcaption class=\"wp-caption-text\">Los jugadores del Burgos regresando a su campo tras celebrar un gol. Fuente El Diario de Burgos \/ Alberto Rodrigo<\/figcaption><\/figure>\n<h2>El Burgos sigue subiendo y el Mirand\u00e9s hundi\u00e9ndose<\/h2>\n<p><strong>El CD Mirand\u00e9s se mantiene 21\u00ba con 12 puntos, a 3 de la salvaci\u00f3n,<\/strong> a la espera de lo que haga el Huesca. Vuelve a perder tras haber logrado haber cortado una racha de 8 partidos de liga sin ganar. Sigue sin hacerse fuerte en Mendizorroza, donde solo ha ganado 1 partido y sacado 4 de 21 posibles.<\/p>\n<p><strong>El <a href=\"https:\/\/www.burgoscf.es\/\">Burgos CF<\/a> se coloca 4\u00ba con 25 puntos, a 1 del ascenso directo y 5 sobre las posiciones fuera de play-off.<\/strong> Con esta victoria consigue la mitad de la salvaci\u00f3n en menos de media temporada. Suma su 5\u00ba partido sin perder y la 4\u00ba victoria en los \u00faltimos 5 partidos. Tambi\u00e9n es su 3\u00ba victoria consecutiva como visitante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un doblete en los minutos finales de Mario Gonz\u00e1lez da una important\u00edsima victoria a los blanquinegros en un partido muy atascado El Burgos CF ha ganado 0-2 contra el CD&hellip; <\/p>\n","protected":false},"author":49,"featured_media":57014,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[47,8],"tags":[569,932,218,1082],"class_list":["post-57012","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol-espanol","category-laliga-hypermotion","tag-burgos-cf","tag-cd-mirandes","tag-futbol-espanol","tag-la-liga-hypermotion"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"CD Mirand\u00e9s 0-2 Burgos CF: Mario Gonz\u00e1lez hace blanquinegro el derbi\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Rafael Pereda\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2025\/11\/16\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"CD Mirand\u00e9s 0-2 Burgos CF: Mario Gonz\u00e1lez hace blanquinegro el derbi \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"CD Mirand\u00e9s 0-2 Burgos CF: Mario Gonz\u00e1lez hace blanquinegro el derbi\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2025\/11\/16\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/11\/burgos-mirandes.avif\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/11\/burgos-mirandes.avif\" \/>\n\t\t<meta property=\"og:image:width\" content=\"976\" \/>\n\t\t<meta property=\"og:image:height\" content=\"549\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-11-16T19:53:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-11-16T19:53:36+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"CD Mirand\u00e9s 0-2 Burgos CF: Mario Gonz\u00e1lez hace blanquinegro el derbi \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"CD Mirand\u00e9s 0-2 Burgos CF: Mario Gonz\u00e1lez hace blanquinegro el derbi\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/11\/burgos-mirandes.avif\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/11\\\/16\\\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\\\/#blogposting\",\"name\":\"CD Mirand\\u00e9s 0-2 Burgos CF: Mario Gonz\\u00e1lez hace blanquinegro el derbi \\u2013 Agente Libre Digital\",\"headline\":\"CD Mirand\\u00e9s 0-2 Burgos CF: Mario Gonz\\u00e1lez hace blanquinegro el derbi\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/rafael-pereda\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/burgos-mirandes.avif\",\"width\":976,\"height\":549,\"caption\":\"Mario Gonz\\u00e1lez celebrando un gol. Fuente Diario As\"},\"datePublished\":\"2025-11-16T20:53:36+01:00\",\"dateModified\":\"2025-11-16T20:53:36+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/11\\\/16\\\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/11\\\/16\\\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\\\/#webpage\"},\"articleSection\":\"F\\u00fatbol Espa\\u00f1ol, LaLiga Hypermotion, Burgos CF, CD Mirand\\u00e9s, futbol espa\\u00f1ol, La liga HYpermotion\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/11\\\/16\\\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/laliga-hypermotion\\\/#listItem\",\"name\":\"LaLiga Hypermotion\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/laliga-hypermotion\\\/#listItem\",\"position\":2,\"name\":\"LaLiga Hypermotion\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/laliga-hypermotion\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/11\\\/16\\\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\\\/#listItem\",\"name\":\"CD Mirand\\u00e9s 0-2 Burgos CF: Mario Gonz\\u00e1lez hace blanquinegro el derbi\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/11\\\/16\\\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\\\/#listItem\",\"position\":3,\"name\":\"CD Mirand\\u00e9s 0-2 Burgos CF: Mario Gonz\\u00e1lez hace blanquinegro el derbi\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/laliga-hypermotion\\\/#listItem\",\"name\":\"LaLiga Hypermotion\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/11\\\/16\\\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/11\\\/16\\\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/rafael-pereda\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/rafael-pereda\\\/\",\"name\":\"Rafael Pereda\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/11\\\/16\\\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b011881c808245d96da0fec527c19d4905183fa8f648250e570f070e9c6c144f?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Rafael Pereda\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/11\\\/16\\\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/11\\\/16\\\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\\\/\",\"name\":\"CD Mirand\\u00e9s 0-2 Burgos CF: Mario Gonz\\u00e1lez hace blanquinegro el derbi \\u2013 Agente Libre Digital\",\"description\":\"CD Mirand\\u00e9s 0-2 Burgos CF: Mario Gonz\\u00e1lez hace blanquinegro el derbi\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/11\\\/16\\\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/rafael-pereda\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/rafael-pereda\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/burgos-mirandes.avif\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/11\\\/16\\\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\\\/#mainImage\",\"width\":976,\"height\":549,\"caption\":\"Mario Gonz\\u00e1lez celebrando un gol. Fuente Diario As\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/11\\\/16\\\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\\\/#mainImage\"},\"datePublished\":\"2025-11-16T20:53:36+01:00\",\"dateModified\":\"2025-11-16T20:53:36+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"CD Mirand\u00e9s 0-2 Burgos CF: Mario Gonz\u00e1lez hace blanquinegro el derbi \u2013 Agente Libre Digital","description":"CD Mirand\u00e9s 0-2 Burgos CF: Mario Gonz\u00e1lez hace blanquinegro el derbi","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2025\/11\/16\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/11\/16\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\/#blogposting","name":"CD Mirand\u00e9s 0-2 Burgos CF: Mario Gonz\u00e1lez hace blanquinegro el derbi \u2013 Agente Libre Digital","headline":"CD Mirand\u00e9s 0-2 Burgos CF: Mario Gonz\u00e1lez hace blanquinegro el derbi","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/rafael-pereda\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/11\/burgos-mirandes.avif","width":976,"height":549,"caption":"Mario Gonz\u00e1lez celebrando un gol. Fuente Diario As"},"datePublished":"2025-11-16T20:53:36+01:00","dateModified":"2025-11-16T20:53:36+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/11\/16\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/11\/16\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\/#webpage"},"articleSection":"F\u00fatbol Espa\u00f1ol, LaLiga Hypermotion, Burgos CF, CD Mirand\u00e9s, futbol espa\u00f1ol, La liga HYpermotion"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/11\/16\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/#listItem","name":"LaLiga Hypermotion"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/#listItem","position":2,"name":"LaLiga Hypermotion","item":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/11\/16\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\/#listItem","name":"CD Mirand\u00e9s 0-2 Burgos CF: Mario Gonz\u00e1lez hace blanquinegro el derbi"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/11\/16\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\/#listItem","position":3,"name":"CD Mirand\u00e9s 0-2 Burgos CF: Mario Gonz\u00e1lez hace blanquinegro el derbi","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/#listItem","name":"LaLiga Hypermotion"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/11\/16\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/11\/16\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/rafael-pereda\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/rafael-pereda\/","name":"Rafael Pereda","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/11\/16\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b011881c808245d96da0fec527c19d4905183fa8f648250e570f070e9c6c144f?s=96&d=mm&r=g","width":96,"height":96,"caption":"Rafael Pereda"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/11\/16\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2025\/11\/16\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\/","name":"CD Mirand\u00e9s 0-2 Burgos CF: Mario Gonz\u00e1lez hace blanquinegro el derbi \u2013 Agente Libre Digital","description":"CD Mirand\u00e9s 0-2 Burgos CF: Mario Gonz\u00e1lez hace blanquinegro el derbi","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/11\/16\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/rafael-pereda\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/rafael-pereda\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/11\/burgos-mirandes.avif","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/11\/16\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\/#mainImage","width":976,"height":549,"caption":"Mario Gonz\u00e1lez celebrando un gol. Fuente Diario As"},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/11\/16\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\/#mainImage"},"datePublished":"2025-11-16T20:53:36+01:00","dateModified":"2025-11-16T20:53:36+01:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"CD Mirand\u00e9s 0-2 Burgos CF: Mario Gonz\u00e1lez hace blanquinegro el derbi \u2013 Agente Libre Digital","og:description":"CD Mirand\u00e9s 0-2 Burgos CF: Mario Gonz\u00e1lez hace blanquinegro el derbi","og:url":"https:\/\/agentelibredigital.com\/index.php\/2025\/11\/16\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/11\/burgos-mirandes.avif","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/11\/burgos-mirandes.avif","og:image:width":976,"og:image:height":549,"article:published_time":"2025-11-16T19:53:36+00:00","article:modified_time":"2025-11-16T19:53:36+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"CD Mirand\u00e9s 0-2 Burgos CF: Mario Gonz\u00e1lez hace blanquinegro el derbi \u2013 Agente Libre Digital","twitter:description":"CD Mirand\u00e9s 0-2 Burgos CF: Mario Gonz\u00e1lez hace blanquinegro el derbi","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/11\/burgos-mirandes.avif"},"aioseo_meta_data":{"post_id":"57012","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-11-16 19:53:36","updated":"2025-11-16 19:54:04","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/\" title=\"LaLiga Hypermotion\">LaLiga Hypermotion<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCD Mirand\u00e9s 0-2 Burgos CF: Mario Gonz\u00e1lez hace blanquinegro el derbi\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"LaLiga Hypermotion","link":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/"},{"label":"CD Mirand\u00e9s 0-2 Burgos CF: Mario Gonz\u00e1lez hace blanquinegro el derbi","link":"https:\/\/agentelibredigital.com\/index.php\/2025\/11\/16\/cd-mirandes-0-2-burgos-cf-mario-gonzalez-hace-blanquinegro-el-derbi\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/57012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=57012"}],"version-history":[{"count":1,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/57012\/revisions"}],"predecessor-version":[{"id":57015,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/57012\/revisions\/57015"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/57014"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=57012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=57012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=57012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}