{"id":53202,"date":"2025-09-21T18:16:26","date_gmt":"2025-09-21T16:16:26","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=53202"},"modified":"2025-09-21T18:25:15","modified_gmt":"2025-09-21T16:25:15","slug":"rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2025\/09\/21\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\/","title":{"rendered":"RCD Mallorca 1-1 Atl\u00e9tico de Madrid: El Atleti vuelve a pinchar"},"content":{"rendered":"<h4>Una grand\u00edsima actuaci\u00f3n de Leo Rom\u00e1n y un gol de Muriqi en el 85 nivelan el gol de Gallagher<\/h4>\n<p>El <a href=\"https:\/\/agentelibredigital.com\/?s=atl%C3%A9tico+de+madrid\">Atl\u00e9tico de Madrid<\/a> ha empatado 1-1 contra el RCD Mallorca en Son Moix en la jornada 5 de <a href=\"https:\/\/agentelibredigital.com\/?s=la+liga+ea+sports\">La Liga EA Sports<\/a>. El Atl\u00e9tico de Madrid mostr\u00f3 una gran versi\u00f3n en la primera parte, pero Leo Rom\u00e1n, parando incluso un penalti, hizo que el partido se marchar\u00e1 igualado al descanso. En el segundo tiempo sigui\u00f3 dominando el Atl\u00e9tico de Madrid, pero sin tan buen rendimiento como en el primer tiempo, hasta que Sorloth fue expulsado. Marc\u00f3 Gallagher en el 79, pero lo igual\u00f3 Muriqi en el 85.<\/p>\n<h2>Leo Rom\u00e1n mantiene el empate<\/h2>\n<p>El partido comenz\u00f3 con dominio colchonero, quienes sobre todo estaban asentados en campo rival. En el minuto 3, Leo Rom\u00e1n tuvo que intervenir para volver a desviar a c\u00f3rner un lanzamiento de c\u00f3rner ol\u00edmpico de Raspadori. El Atl\u00e9tico de Madrid sigui\u00f3 dominando y en el minuto 6, Pablo Barrios prob\u00f3 con un disparo potent\u00edsimo desde fuera del \u00e1rea, que par\u00f3 como pudo Leo Rom\u00e1n y acab\u00f3 estrell\u00e1ndose en el palo. En el minuto 11, <strong>Hancko remat\u00f3 un bal\u00f3n que se estrell\u00f3 en la mano de Ra\u00edllo. Francisco Jos\u00e9 Hern\u00e1ndez no lo dud\u00f3 y se\u00f1al\u00f3 la pena m\u00e1xima. Juli\u00e1n \u00c1lvarez se encarg\u00f3 de tirarlo, pero por tercera vez en el partido aparecer\u00eda Leo Rom\u00e1n para evitar el gol con una gran parada.<\/strong> El dominio del Atl\u00e9tico de Madrid era absoluto ante un Mallorca que mayormente se limitaba a defender. En el minuto 17, Leo Rom\u00e1n volv\u00eda a desviar ligeramente un pase de gol de Raspadori hacia Juli\u00e1n \u00c1lvarez para que La Ara\u00f1a no pudiera rematar. A partir del minuto 20, el Mallorca logr\u00f3 entrar en juego durante algunos minutos antes de que el Atl\u00e9tico de Madrid volviera a coger el dominio. A\u00fan as\u00ed, ahora el Mallorca si consegu\u00eda salir a la contra en alguna ocasi\u00f3n. En el minuto 35, <em>Kumbulla se lesion\u00f3 y tuvo que retirarse del terreno de juego. Entr\u00f3 en su lugar Pablo Torre<\/em>, lo que signific\u00f3 un cambio de dibujo para los de Arrasate. Tras la pausa de hidrataci\u00f3n lleg\u00f3 la etapa m\u00e1s igualada en cuanto a juego del primer tiempo. En el minuto 40, Marcos Llorente, que part\u00eda de fuera de juego, se introdujo en el \u00e1rea, busc\u00f3 un pase atr\u00e1s, pero Ra\u00edllo lo interrumpi\u00f3, pero se envenen\u00f3 su despeje. Pero, Leo Rom\u00e1n volv\u00eda a realizar una gran intervenci\u00f3n de reflejos. El conjunto colchonero lo sigui\u00f3 intentando, pero sin \u00e9xito hasta el descanso.<\/p>\n<figure id=\"attachment_53215\" aria-describedby=\"caption-attachment-53215\" style=\"width: 336px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53215\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/09\/rcd-mallorca-v-atletico-de-madrid-laliga-ea-sports-1-300x200.jpg\" alt=\"\" width=\"336\" height=\"224\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/09\/rcd-mallorca-v-atletico-de-madrid-laliga-ea-sports-1-300x200.jpg 300w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/09\/rcd-mallorca-v-atletico-de-madrid-laliga-ea-sports-1-1024x683.jpg 1024w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/09\/rcd-mallorca-v-atletico-de-madrid-laliga-ea-sports-1-768x512.jpg 768w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/09\/rcd-mallorca-v-atletico-de-madrid-laliga-ea-sports-1-1536x1024.jpg 1536w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/09\/rcd-mallorca-v-atletico-de-madrid-laliga-ea-sports-1-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><figcaption id=\"caption-attachment-53215\" class=\"wp-caption-text\">Giuliano y Mojica disputando un bal\u00f3n. Fuente Getty Images\/ Rafa Babot<\/figcaption><\/figure>\n<h2>Gallagher y Muriqi firman los goles del empate<\/h2>\n<p>El Atl\u00e9tico de Madrid sigui\u00f3 dominando al comienzo del segundo tiempo, pero le costaba m\u00e1s llegar a situaciones de peligro. En el minuto 52, Giuliano se meti\u00f3 en el \u00e1rea y le pas\u00f3 el bal\u00f3n a Juli\u00e1n \u00c1lvarez. El argentino se dio la media vuelta y remat\u00f3 a puerta, pero se volvi\u00f3 a encontrar con la parada de Leo Rom\u00e1n. El club rojiblanco, hoy de azul, segu\u00eda dominando, pero su rendimiento no era tan bueno como el del primer tiempo. En el minuto 61, Simeone realiz\u00f3 sus primeros cambios buscando una reacci\u00f3n de su equipo que estaba yendo claramente de m\u00e1s a menos. <em>Meti\u00f3 a Griezmann, Sorloth y Nahuel Molina por Juli\u00e1n \u00c1lvarez, Giuliano y Raspadori. En el minuto 67, Arrasate y Simeone volvieron a mover el banquillo. Arrasate retir\u00f3 a Asano y Samu Costa para dar entrada a Marc Dom\u00e9nech y Antonio S\u00e1nchez. Simeone quit\u00f3 a Barrios, con aparentes molestias, para meter a Gallagher.\u00a0<\/em>A la jugada siguiente de los cambios, Gallagher pis\u00f3 \u00e1rea y le cedi\u00f3 el bal\u00f3n a Griezmann que remat\u00f3 de primeras a las manos de Leo Rom\u00e1n.<\/p>\n<p>En el minuto 70, Sorloth y Ra\u00edllo disputaron un bal\u00f3n y el atacante noruego termin\u00f3 impactando en la pierna del capit\u00e1n bermell\u00f3n. Francisco Jos\u00e9 Hern\u00e1ndez no apreci\u00f3 nada m\u00e1s que falta, pero Javier Iglesias le llam\u00f3 desde el VAR para revisarla y <strong>tras consultarla en el VAR le mostr\u00f3 la cartulina roja a Sorloth.<\/strong> Despu\u00e9s de la pausa de hidrataci\u00f3n, <em>Simeone agot\u00f3 los cambios metiendo a Ruggeri por Nico Gonz\u00e1lez. <strong>En el minuto 79, Marcos Llorente se fue a la contra, pis\u00f3 \u00e1rea y remat\u00f3. Leo Rom\u00e1n lo volvi\u00f3 a parar, pero nada pudo hacer ante el remate de Gallagher que perfor\u00f3 la porter\u00eda y puso el 0-1.<\/strong><\/em> En el minuto 81, <em>Arrasate agot\u00f3 los cambios metiendo a Abd\u00f3n y Vigili por Morlanes y Morey.\u00a0<\/em>El Mallorca se ech\u00f3 arriba en busca del gol. En el minuto 85, <strong>Vigili lanz\u00f3 un centro exquisito al que se anticip\u00f3 Muriqi para batir a Oblak con un gran cabezazo y poner el 1-1.\u00a0<\/strong>El Mallorca se vino totalmente arriba y asedi\u00f3 a los colchoneros, que se defend\u00edan a rega\u00f1adientes, en los minutos finales del partido, pero sin tener grandes ocasiones.<\/p>\n<figure id=\"attachment_53223\" aria-describedby=\"caption-attachment-53223\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-53223\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/09\/rcd-mallorca-v-atletico-de-madrid-laliga-ea-sports-2-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/09\/rcd-mallorca-v-atletico-de-madrid-laliga-ea-sports-2-300x200.jpg 300w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/09\/rcd-mallorca-v-atletico-de-madrid-laliga-ea-sports-2-1024x683.jpg 1024w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/09\/rcd-mallorca-v-atletico-de-madrid-laliga-ea-sports-2-768x512.jpg 768w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/09\/rcd-mallorca-v-atletico-de-madrid-laliga-ea-sports-2-1536x1024.jpg 1536w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/09\/rcd-mallorca-v-atletico-de-madrid-laliga-ea-sports-2-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-53223\" class=\"wp-caption-text\">Marcos Llorente y Pablo Torre disputando el bal\u00f3n. Fuente Getty Images\/ Rafa Babot<\/figcaption><\/figure>\n<h2>Punto que no termina de servir a nadie<\/h2>\n<p><strong>El RCD Mallorca se mantiene 19\u00ba y eleva su suma a 2 puntos.<\/strong> Sigue en puestos de descenso y sin ganar, pero vuelve a puntuar dos jornadas despu\u00e9s.<\/p>\n<p><strong>El Atl\u00e9tico de Madrid sube a la 12\u00ba posici\u00f3n y eleva su suma a 6 puntos.<\/strong> Contin\u00faa su mal inicio y vuelve a dejarse puntos por cuarta vez en la temporada.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una grand\u00edsima actuaci\u00f3n de Leo Rom\u00e1n y un gol de Muriqi en el 85 nivelan el gol de Gallagher El Atl\u00e9tico de Madrid ha empatado 1-1 contra el RCD Mallorca&hellip; <\/p>\n","protected":false},"author":49,"featured_media":53214,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[13,46,25],"tags":[62,218,1082,1211],"class_list":["post-53202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atletico-de-madrid","category-laliga-ea-sports","category-mallorca","tag-atletico-de-madrid","tag-futbol-espanol","tag-la-liga-hypermotion","tag-rcd-mallorca"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"RCD Mallorca 1-1 Atl\u00e9tico de Madrid: El Atleti vuelve a pinchar Una grand\u00edsima actuaci\u00f3n de Leo Rom\u00e1n y un gol de Muriqi en el 85 nivelan el gol de Gallagher\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Rafael Pereda\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2025\/09\/21\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"RCD Mallorca 1-1 Atl\u00e9tico de Madrid: El Atleti vuelve a pinchar \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"RCD Mallorca 1-1 Atl\u00e9tico de Madrid: El Atleti vuelve a pinchar Una grand\u00edsima actuaci\u00f3n de Leo Rom\u00e1n y un gol de Muriqi en el 85 nivelan el gol de Gallagher\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2025\/09\/21\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/09\/rcd-mallorca-v-atletico-de-madrid-laliga-ea-sports-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/09\/rcd-mallorca-v-atletico-de-madrid-laliga-ea-sports-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-09-21T16:16:26+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-09-21T16:25:15+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"RCD Mallorca 1-1 Atl\u00e9tico de Madrid: El Atleti vuelve a pinchar \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"RCD Mallorca 1-1 Atl\u00e9tico de Madrid: El Atleti vuelve a pinchar Una grand\u00edsima actuaci\u00f3n de Leo Rom\u00e1n y un gol de Muriqi en el 85 nivelan el gol de Gallagher\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/09\/rcd-mallorca-v-atletico-de-madrid-laliga-ea-sports-scaled.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/09\\\/21\\\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\\\/#blogposting\",\"name\":\"RCD Mallorca 1-1 Atl\\u00e9tico de Madrid: El Atleti vuelve a pinchar \\u2013 Agente Libre Digital\",\"headline\":\"RCD Mallorca 1-1 Atl\\u00e9tico de Madrid: El Atleti vuelve a pinchar\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/rafael-pereda\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/rcd-mallorca-v-atletico-de-madrid-laliga-ea-sports-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Giuliano y M\\u00f3jica disputando un bal\\u00f3n. Fuente Getty Images\\\/ Rafa Babot\"},\"datePublished\":\"2025-09-21T18:16:26+02:00\",\"dateModified\":\"2025-09-21T18:25:15+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/09\\\/21\\\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/09\\\/21\\\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\\\/#webpage\"},\"articleSection\":\"Atl\\u00e9tico de Madrid, LaLiga EA Sports, Mallorca, Atl\\u00e9tico de Madrid, futbol espa\\u00f1ol, La liga HYpermotion, RCD Mallorca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/09\\\/21\\\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/atletico-de-madrid\\\/#listItem\",\"name\":\"Atl\\u00e9tico de Madrid\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/atletico-de-madrid\\\/#listItem\",\"position\":2,\"name\":\"Atl\\u00e9tico de Madrid\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/atletico-de-madrid\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/09\\\/21\\\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\\\/#listItem\",\"name\":\"RCD Mallorca 1-1 Atl\\u00e9tico de Madrid: El Atleti vuelve a pinchar\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/09\\\/21\\\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\\\/#listItem\",\"position\":3,\"name\":\"RCD Mallorca 1-1 Atl\\u00e9tico de Madrid: El Atleti vuelve a pinchar\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/atletico-de-madrid\\\/#listItem\",\"name\":\"Atl\\u00e9tico de Madrid\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/09\\\/21\\\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/09\\\/21\\\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/rafael-pereda\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/rafael-pereda\\\/\",\"name\":\"Rafael Pereda\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/09\\\/21\\\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b011881c808245d96da0fec527c19d4905183fa8f648250e570f070e9c6c144f?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Rafael Pereda\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/09\\\/21\\\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/09\\\/21\\\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\\\/\",\"name\":\"RCD Mallorca 1-1 Atl\\u00e9tico de Madrid: El Atleti vuelve a pinchar \\u2013 Agente Libre Digital\",\"description\":\"RCD Mallorca 1-1 Atl\\u00e9tico de Madrid: El Atleti vuelve a pinchar Una grand\\u00edsima actuaci\\u00f3n de Leo Rom\\u00e1n y un gol de Muriqi en el 85 nivelan el gol de Gallagher\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/09\\\/21\\\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/rafael-pereda\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/rafael-pereda\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/rcd-mallorca-v-atletico-de-madrid-laliga-ea-sports-scaled.jpg\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/09\\\/21\\\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\\\/#mainImage\",\"width\":2560,\"height\":1707,\"caption\":\"Giuliano y M\\u00f3jica disputando un bal\\u00f3n. Fuente Getty Images\\\/ Rafa Babot\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/09\\\/21\\\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\\\/#mainImage\"},\"datePublished\":\"2025-09-21T18:16:26+02:00\",\"dateModified\":\"2025-09-21T18:25:15+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"RCD Mallorca 1-1 Atl\u00e9tico de Madrid: El Atleti vuelve a pinchar \u2013 Agente Libre Digital","description":"RCD Mallorca 1-1 Atl\u00e9tico de Madrid: El Atleti vuelve a pinchar Una grand\u00edsima actuaci\u00f3n de Leo Rom\u00e1n y un gol de Muriqi en el 85 nivelan el gol de Gallagher","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2025\/09\/21\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/09\/21\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\/#blogposting","name":"RCD Mallorca 1-1 Atl\u00e9tico de Madrid: El Atleti vuelve a pinchar \u2013 Agente Libre Digital","headline":"RCD Mallorca 1-1 Atl\u00e9tico de Madrid: El Atleti vuelve a pinchar","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/rafael-pereda\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/09\/rcd-mallorca-v-atletico-de-madrid-laliga-ea-sports-scaled.jpg","width":2560,"height":1707,"caption":"Giuliano y M\u00f3jica disputando un bal\u00f3n. Fuente Getty Images\/ Rafa Babot"},"datePublished":"2025-09-21T18:16:26+02:00","dateModified":"2025-09-21T18:25:15+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/09\/21\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/09\/21\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\/#webpage"},"articleSection":"Atl\u00e9tico de Madrid, LaLiga EA Sports, Mallorca, Atl\u00e9tico de Madrid, futbol espa\u00f1ol, La liga HYpermotion, RCD Mallorca"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/09\/21\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/atletico-de-madrid\/#listItem","name":"Atl\u00e9tico de Madrid"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/atletico-de-madrid\/#listItem","position":2,"name":"Atl\u00e9tico de Madrid","item":"https:\/\/agentelibredigital.com\/index.php\/category\/atletico-de-madrid\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/09\/21\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\/#listItem","name":"RCD Mallorca 1-1 Atl\u00e9tico de Madrid: El Atleti vuelve a pinchar"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/09\/21\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\/#listItem","position":3,"name":"RCD Mallorca 1-1 Atl\u00e9tico de Madrid: El Atleti vuelve a pinchar","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/atletico-de-madrid\/#listItem","name":"Atl\u00e9tico de Madrid"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/09\/21\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/09\/21\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/rafael-pereda\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/rafael-pereda\/","name":"Rafael Pereda","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/09\/21\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b011881c808245d96da0fec527c19d4905183fa8f648250e570f070e9c6c144f?s=96&d=mm&r=g","width":96,"height":96,"caption":"Rafael Pereda"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/09\/21\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2025\/09\/21\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\/","name":"RCD Mallorca 1-1 Atl\u00e9tico de Madrid: El Atleti vuelve a pinchar \u2013 Agente Libre Digital","description":"RCD Mallorca 1-1 Atl\u00e9tico de Madrid: El Atleti vuelve a pinchar Una grand\u00edsima actuaci\u00f3n de Leo Rom\u00e1n y un gol de Muriqi en el 85 nivelan el gol de Gallagher","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/09\/21\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/rafael-pereda\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/rafael-pereda\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/09\/rcd-mallorca-v-atletico-de-madrid-laliga-ea-sports-scaled.jpg","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/09\/21\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\/#mainImage","width":2560,"height":1707,"caption":"Giuliano y M\u00f3jica disputando un bal\u00f3n. Fuente Getty Images\/ Rafa Babot"},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/09\/21\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\/#mainImage"},"datePublished":"2025-09-21T18:16:26+02:00","dateModified":"2025-09-21T18:25:15+02:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"RCD Mallorca 1-1 Atl\u00e9tico de Madrid: El Atleti vuelve a pinchar \u2013 Agente Libre Digital","og:description":"RCD Mallorca 1-1 Atl\u00e9tico de Madrid: El Atleti vuelve a pinchar Una grand\u00edsima actuaci\u00f3n de Leo Rom\u00e1n y un gol de Muriqi en el 85 nivelan el gol de Gallagher","og:url":"https:\/\/agentelibredigital.com\/index.php\/2025\/09\/21\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/09\/rcd-mallorca-v-atletico-de-madrid-laliga-ea-sports-scaled.jpg","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/09\/rcd-mallorca-v-atletico-de-madrid-laliga-ea-sports-scaled.jpg","og:image:width":2560,"og:image:height":1707,"article:published_time":"2025-09-21T16:16:26+00:00","article:modified_time":"2025-09-21T16:25:15+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"RCD Mallorca 1-1 Atl\u00e9tico de Madrid: El Atleti vuelve a pinchar \u2013 Agente Libre Digital","twitter:description":"RCD Mallorca 1-1 Atl\u00e9tico de Madrid: El Atleti vuelve a pinchar Una grand\u00edsima actuaci\u00f3n de Leo Rom\u00e1n y un gol de Muriqi en el 85 nivelan el gol de Gallagher","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/09\/rcd-mallorca-v-atletico-de-madrid-laliga-ea-sports-scaled.jpg"},"aioseo_meta_data":{"post_id":"53202","title":null,"description":"#post_title Una grand\u00edsima actuaci\u00f3n de Leo Rom\u00e1n y un gol de Muriqi en el 85 nivelan el gol de Gallagher","keywords":null,"keyphrases":{"focus":{"keyphrase":"Atl\u00e9tico de Madrid","score":82,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":4},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-09-21 16:16:27","updated":"2025-09-21 16:39:49","seo_analyzer_scan_date":null,"focus_keyword":"Atl\u00e9tico de Madrid","additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/atletico-de-madrid\/\" title=\"Atl\u00e9tico de Madrid\">Atl\u00e9tico de Madrid<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRCD Mallorca 1-1 Atl\u00e9tico de Madrid: El Atleti vuelve a pinchar\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"Atl\u00e9tico de Madrid","link":"https:\/\/agentelibredigital.com\/index.php\/category\/atletico-de-madrid\/"},{"label":"RCD Mallorca 1-1 Atl\u00e9tico de Madrid: El Atleti vuelve a pinchar","link":"https:\/\/agentelibredigital.com\/index.php\/2025\/09\/21\/rcd-mallorca-1-1-atletico-de-madrid-el-atleti-vuelve-a-pinchar\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/53202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=53202"}],"version-history":[{"count":4,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/53202\/revisions"}],"predecessor-version":[{"id":53236,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/53202\/revisions\/53236"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/53214"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=53202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=53202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=53202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}