{"id":51145,"date":"2025-08-10T23:04:19","date_gmt":"2025-08-10T21:04:19","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=51145"},"modified":"2025-08-10T23:06:53","modified_gmt":"2025-08-10T21:06:53","slug":"fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2025\/08\/10\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\/","title":{"rendered":"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona"},"content":{"rendered":"<h4>El FC Barcelona vence c\u00f3modamente al Como de Cesc F\u00e1bregas con un marcador de 5-0 y goles de Ferm\u00edn, Lamine y Raphinha para as\u00ed sentenciar el triunfo blaugrana.<\/h4>\n<h2>Puntuaciones<\/h2>\n<p><em><strong>Criterio de\u00a0calificaci\u00f3n:\u00a00-3. Desastroso\/ 4. Mal \/ 5. Aprobado raspado \/ 6. Bien \/ 7. Notable \/ 8. Muy bien \/ 9. Fant\u00e1stico \/ 10. Excelente \/ NC. No Calificable.<\/strong><\/em><\/p>\n<h2>11 Inicial<\/h2>\n<p>Joan Garc\u00eda (8): Su calidad bajo los 3 palos es innegable, con el bal\u00f3n en los pies no cometi\u00f3 ning\u00fan error. En caso de mostrar este nivel en el transcurso de la temporada, ser\u00e1 una de las caras del <a href=\"https:\/\/agentelibredigital.com\/?s=FC+Barcelona\">FC Barcelona<\/a>.<\/p>\n<p>Eric Garc\u00eda (7): Partido correcto del plurifuncional jugador espa\u00f1ol, casi no se le exigi\u00f3 en lo defensivo, mientras que en la faceta ofensiva di\u00f3 buenas carreras para apoyar a Lamine por el carril derecho.<\/p>\n<p>Ronald Ara\u00fajo (7): A pesar de no ser tan exigido se vio bien el nuevo capit\u00e1n del <a href=\"https:\/\/agentelibredigital.com\/?s=FC+Barcelona\">FC Barcelona<\/a>. El central uruguayo fue correcto desde su posici\u00f3n, aunque con el bal\u00f3n en los pies le cost\u00f3 buscar pases en profundidad.<\/p>\n<p>Pau Cubars\u00ed (8): Buena exhibici\u00f3n defensiva de Cubars\u00ed, heredando el dorsal &#8216;5&#8217; de I\u00f1igo Mart\u00ednez. Correcto en el corte y siempre bien posicionado para que siga funcionando la trampa del fuera de juego de Hansi Flick.<\/p>\n<p>Alejandro Bald\u00e9 (8): En un nuevo rol que le hace probar Hansi Flick, pisando carriles interiores con su velocidad, tuvo un gran partido.<\/p>\n<p>Frenkie De Jong (7): Partido bueno del mediocampista neerland\u00e9s, dej\u00f3 grandes muestras con sus carreras con el bal\u00f3n en los pies, claridad en el pase y buen posicionamiento.<\/p>\n<p>Pedri (8): Siempre seguro con el bal\u00f3n, encontrando pases que nadie m\u00e1s ve, desde la base le brindaba muchas opciones a sus compa\u00f1eros con sus pases. El centrocampista canario es el gu\u00eda en la presi\u00f3n del FC Barcelona, siendo quien dicta la altura en la que se posicionen sus compa\u00f1eros.<\/p>\n<p>Lamine Yamal (9): Gran partido del extremo espa\u00f1ol, quien no tiene piedad con ninguno de sus rivales. Su regate y frescura con el bal\u00f3n le dieron muchas opciones ofensivas en el carril derecho.\u00a0 2 buenos goles y una gran cantidad de regates, dignos de uno de lo que es, uno de los mejores jugadores del mundo, fueron sus saldo en este partido.<\/p>\n<p>Ferm\u00edn L\u00f3pez (9): Dej\u00f3 buenas sensaciones, demostrando que puede luchar por un puesto en el 11 inicial. Su picard\u00eda e \u00edmpetu dejaron frutos con el 1-0. Su golpeo, fue puesto a prueba exitosamente y haciendo muestra de el anot\u00f3 el 2-0.<\/p>\n<p>Raphinha (9): Gol y asistencia en los primeros 45&#8242;. El &#8217;11&#8217; cul\u00e9 parece que va a comenzar las temporada con el gran nivel que demostr\u00f3 en la campa\u00f1a anterior. Presi\u00f3n, efectividad y buen posicionamiento que el colectivo \u00abblaugrana\u00bb aprovecha para sacar ventaja a sus rivales.<\/p>\n<p>Marcus Rashford (8): No recul\u00f3 en esfuerzos, el tiempo que estuvo dej\u00f3 todo en el campo, dio una gran asistencia para el 3-0 a Raphinha. El intercambio de posiciones entre \u00e9l y el brasile\u00f1o ser\u00e1 uno de los puntos a analizar en la temporada. A pesar de su gran ocasi\u00f3n fallada, dej\u00f3 muy buenas sensaciones.<\/p>\n<figure id=\"attachment_51164\" aria-describedby=\"caption-attachment-51164\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-51164\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/08\/fc-barcelona-v-como1907-joan-gamper-trophy-1-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/08\/fc-barcelona-v-como1907-joan-gamper-trophy-1-1-300x200.jpg 300w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/08\/fc-barcelona-v-como1907-joan-gamper-trophy-1-1-1024x683.jpg 1024w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/08\/fc-barcelona-v-como1907-joan-gamper-trophy-1-1-768x512.jpg 768w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/08\/fc-barcelona-v-como1907-joan-gamper-trophy-1-1-1536x1024.jpg 1536w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/08\/fc-barcelona-v-como1907-joan-gamper-trophy-1-1-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-51164\" class=\"wp-caption-text\">Ferm\u00edn L\u00f3pez celebrando el 1-0. V\u00eda: Judit Cartiel\/Getty Images.<\/figcaption><\/figure>\n<h2>Sustituciones<\/h2>\n<p>Jules Kound\u00e9 (6): Sin ser tan exigido, el lateral franc\u00e9s estuvo correcto con el bal\u00f3n y alrededor del 70&#8242; le entreg\u00f3 un gran pase a Lamine que no pudo pasar a m\u00e1s.<\/p>\n<p>Ferran Torres (7): Ingres\u00f3 al campo con ganas de comerse al rival y en menos de 5&#8242; le regal\u00f3 una gran asistencia a Lamine. Otra vez como un &#8216;9&#8217; m\u00e1s posicional tuvo grandes minutos.<\/p>\n<p>Gavi (7): Desde el momento en el que entr\u00f3 al campo se not\u00f3 su garra y determinaci\u00f3n a dejar todo por cada bal\u00f3n. Buen partido con el bal\u00f3n en los pies, encontrando siempre a sus compa\u00f1eros.<\/p>\n<p>Marc Casad\u00f3 (6): Sin grandes intervenciones, fue correcto cuando sus compa\u00f1eros le hac\u00edan llegar el bal\u00f3n.<\/p>\n<p>Gerard Mart\u00edn (6): Despu\u00e9s de jugar varios partidos como central por izquierda, Gerard regres\u00f3 al puesto de lateral izquierdo y en 10 minutos tuvo una exhibici\u00f3n sobria.<\/p>\n<p>Roony Bardghji (6): Entr\u00f3 en la \u00faltima ventana de cambios y quiso mostrar sus atributos como el regate, aunque sin poder mostrarse en el marcador.<\/p>\n<p>Dro (7): Los 1o minutos que estuvo sobre el c\u00e9sped fue muy bueno, intentando mostrarse con el primer equipo, su regate y habilidad asociativa podr\u00eda dar grandes frutos en el futuro.<\/p>\n<figure id=\"attachment_51165\" aria-describedby=\"caption-attachment-51165\" style=\"width: 300px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-51165\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/08\/fc-barcelona-v-como1907-joan-gamper-trophy-2-1-300x213.jpg\" alt=\"\" width=\"300\" height=\"213\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/08\/fc-barcelona-v-como1907-joan-gamper-trophy-2-1-300x213.jpg 300w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/08\/fc-barcelona-v-como1907-joan-gamper-trophy-2-1-1024x726.jpg 1024w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/08\/fc-barcelona-v-como1907-joan-gamper-trophy-2-1-768x545.jpg 768w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/08\/fc-barcelona-v-como1907-joan-gamper-trophy-2-1-1536x1089.jpg 1536w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/08\/fc-barcelona-v-como1907-joan-gamper-trophy-2-1-2048x1453.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-51165\" class=\"wp-caption-text\">Toni Fern\u00e1ndez siendo presionado por M\u00e1ximo Perrone. V\u00eda: Judit Cartiel\/Getty Images.<\/figcaption><\/figure>\n<p>Antonio Fern\u00e1ndez (7): Ingres\u00f3 explosivo del joven de La Mas\u00eda que busc\u00f3 asociarse siempre con Dro, una buena jugada asociativa entre \u00e9l y sus compa\u00f1eros por poco culmina en un sexto gol para el equipo cul\u00e9.<\/p>\n<p>Andreas Christensen (6): 10 minutos correctos del central dan\u00e9s que no fue exigido.<\/p>\n<p>Jofre Torrents (N\/C):<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El FC Barcelona vence c\u00f3modamente al Como de Cesc F\u00e1bregas con un marcador de 5-0 y goles de Ferm\u00edn, Lamine y Raphinha para as\u00ed sentenciar el triunfo blaugrana. Puntuaciones Criterio&hellip; <\/p>\n","protected":false},"author":227,"featured_media":51158,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[12,47],"tags":[55,2799,2825,2837],"class_list":["post-51145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fc-barcelona","category-futbol-espanol","tag-fc-barcelona","tag-hansi-flick","tag-joan-gamper","tag-pretemporada"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Karel Barron\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2025\/08\/10\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2025\/08\/10\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/08\/fc-barcelona-v-como1907-joan-gamper-trophy.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/08\/fc-barcelona-v-como1907-joan-gamper-trophy.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2219\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1480\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-08-10T21:04:19+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-08-10T21:06:53+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/08\/fc-barcelona-v-como1907-joan-gamper-trophy.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/08\\\/10\\\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\\\/#blogposting\",\"name\":\"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona \\u2013 Agente Libre Digital\",\"headline\":\"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/karel-barron\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fc-barcelona-v-como1907-joan-gamper-trophy.jpg\",\"width\":2219,\"height\":1480,\"caption\":\"Trofeo Joan Gamper. V\\u00eda: Judit Cartiel\\\/Getty Images.\"},\"datePublished\":\"2025-08-10T23:04:19+02:00\",\"dateModified\":\"2025-08-10T23:06:53+02:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/08\\\/10\\\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/08\\\/10\\\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\\\/#webpage\"},\"articleSection\":\"FC Barcelona, F\\u00fatbol Espa\\u00f1ol, FC Barcelona, Hansi Flick, Joan Gamper, pretemporada\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/08\\\/10\\\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/fc-barcelona\\\/#listItem\",\"name\":\"FC Barcelona\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/fc-barcelona\\\/#listItem\",\"position\":2,\"name\":\"FC Barcelona\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/fc-barcelona\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/08\\\/10\\\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\\\/#listItem\",\"name\":\"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/08\\\/10\\\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\\\/#listItem\",\"position\":3,\"name\":\"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/fc-barcelona\\\/#listItem\",\"name\":\"FC Barcelona\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/08\\\/10\\\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/08\\\/10\\\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/karel-barron\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/karel-barron\\\/\",\"name\":\"Karel Barron\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/08\\\/10\\\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/325be10ec4d99f36d48b664562e3393d6e53eda4a4d4d893afb38841fe273b70?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Karel Barron\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/08\\\/10\\\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/08\\\/10\\\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\\\/\",\"name\":\"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona \\u2013 Agente Libre Digital\",\"description\":\"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/08\\\/10\\\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/karel-barron\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/karel-barron\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/fc-barcelona-v-como1907-joan-gamper-trophy.jpg\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/08\\\/10\\\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\\\/#mainImage\",\"width\":2219,\"height\":1480,\"caption\":\"Trofeo Joan Gamper. V\\u00eda: Judit Cartiel\\\/Getty Images.\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/08\\\/10\\\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\\\/#mainImage\"},\"datePublished\":\"2025-08-10T23:04:19+02:00\",\"dateModified\":\"2025-08-10T23:06:53+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona \u2013 Agente Libre Digital","description":"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2025\/08\/10\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/08\/10\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\/#blogposting","name":"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona \u2013 Agente Libre Digital","headline":"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/karel-barron\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/08\/fc-barcelona-v-como1907-joan-gamper-trophy.jpg","width":2219,"height":1480,"caption":"Trofeo Joan Gamper. V\u00eda: Judit Cartiel\/Getty Images."},"datePublished":"2025-08-10T23:04:19+02:00","dateModified":"2025-08-10T23:06:53+02:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/08\/10\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/08\/10\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\/#webpage"},"articleSection":"FC Barcelona, F\u00fatbol Espa\u00f1ol, FC Barcelona, Hansi Flick, Joan Gamper, pretemporada"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/08\/10\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/fc-barcelona\/#listItem","name":"FC Barcelona"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/fc-barcelona\/#listItem","position":2,"name":"FC Barcelona","item":"https:\/\/agentelibredigital.com\/index.php\/category\/fc-barcelona\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/08\/10\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\/#listItem","name":"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/08\/10\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\/#listItem","position":3,"name":"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/fc-barcelona\/#listItem","name":"FC Barcelona"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/08\/10\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/08\/10\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/karel-barron\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/karel-barron\/","name":"Karel Barron","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/08\/10\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/325be10ec4d99f36d48b664562e3393d6e53eda4a4d4d893afb38841fe273b70?s=96&d=mm&r=g","width":96,"height":96,"caption":"Karel Barron"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/08\/10\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2025\/08\/10\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\/","name":"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona \u2013 Agente Libre Digital","description":"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/08\/10\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/karel-barron\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/karel-barron\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/08\/fc-barcelona-v-como1907-joan-gamper-trophy.jpg","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/08\/10\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\/#mainImage","width":2219,"height":1480,"caption":"Trofeo Joan Gamper. V\u00eda: Judit Cartiel\/Getty Images."},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/08\/10\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\/#mainImage"},"datePublished":"2025-08-10T23:04:19+02:00","dateModified":"2025-08-10T23:06:53+02:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona \u2013 Agente Libre Digital","og:description":"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona","og:url":"https:\/\/agentelibredigital.com\/index.php\/2025\/08\/10\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/08\/fc-barcelona-v-como1907-joan-gamper-trophy.jpg","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/08\/fc-barcelona-v-como1907-joan-gamper-trophy.jpg","og:image:width":2219,"og:image:height":1480,"article:published_time":"2025-08-10T21:04:19+00:00","article:modified_time":"2025-08-10T21:06:53+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona \u2013 Agente Libre Digital","twitter:description":"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/08\/fc-barcelona-v-como1907-joan-gamper-trophy.jpg"},"aioseo_meta_data":{"post_id":"51145","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-08-10 21:04:19","updated":"2025-08-10 21:19:50","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/fc-barcelona\/\" title=\"FC Barcelona\">FC Barcelona<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tFC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"FC Barcelona","link":"https:\/\/agentelibredigital.com\/index.php\/category\/fc-barcelona\/"},{"label":"FC Barcelona 5-0 Como 1907: Puntuaciones FC Barcelona","link":"https:\/\/agentelibredigital.com\/index.php\/2025\/08\/10\/fc-barcelona-1-0-como-1907-calificaciones-fc-barcelona\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/51145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/227"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=51145"}],"version-history":[{"count":4,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/51145\/revisions"}],"predecessor-version":[{"id":51169,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/51145\/revisions\/51169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/51158"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=51145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=51145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=51145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}