{"id":50249,"date":"2025-07-21T18:36:40","date_gmt":"2025-07-21T16:36:40","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=50249"},"modified":"2025-07-21T18:36:40","modified_gmt":"2025-07-21T16:36:40","slug":"jacobo-ramon-muy-cerca-de-irse-al-como-1907","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2025\/07\/21\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\/","title":{"rendered":"Jacobo Ram\u00f3n, muy cerca de irse al Como 1907"},"content":{"rendered":"<h4>Seg\u00fan <a href=\"https:\/\/x.com\/FabrizioRomano\/status\/1947233792772522026\">Fabrizio Romano<\/a>, el defensa espa\u00f1ol abandona el <a href=\"https:\/\/agentelibredigital.com\/?s=Real+Madrid\">Real Madrid<\/a> para convertirse en nuevo jugador de los <em>Lariani<\/em> por 2,5 millones de euros m\u00e1s variables.<\/h4>\n<p>Muchos equipos lo est\u00e1n dando todo en el mercado veraniego de fichajes. Ejemplo de ello es el <strong>Como<\/strong> de <a href=\"https:\/\/agentelibredigital.com\/?s=Serie+A\">Serie A<\/a>. Tras mantener a <strong>M\u00e1ximo Perrone <\/strong>en el equipo, los <em>voltiani\u00a0<\/em>estar\u00edan cerca de incorporar en sus filar a una destacada promesa. Se trata del espa\u00f1ol del <strong>Real Madrid<\/strong> <strong>Jacobo Ram\u00f3n<\/strong>. El jugador de 20 a\u00f1os <strong>llegar\u00eda a la Lombard\u00eda por 2,5 millones de euros m\u00e1s variables<\/strong>. A pesar de esto, <strong>los merengues tendr\u00edan opci\u00f3n de poder repescarlo<\/strong> llegando a hacer la misma operaci\u00f3n que con<strong> Nico Paz<\/strong>.<\/p>\n<figure id=\"attachment_50251\" aria-describedby=\"caption-attachment-50251\" style=\"width: 2560px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-50251\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/07\/real-madrid-cf-v-rcd-mallorca-la-liga-ea-sports-1-1-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/07\/real-madrid-cf-v-rcd-mallorca-la-liga-ea-sports-1-1-scaled.jpg 2560w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/07\/real-madrid-cf-v-rcd-mallorca-la-liga-ea-sports-1-1-300x200.jpg 300w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/07\/real-madrid-cf-v-rcd-mallorca-la-liga-ea-sports-1-1-1024x683.jpg 1024w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/07\/real-madrid-cf-v-rcd-mallorca-la-liga-ea-sports-1-1-768x512.jpg 768w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/07\/real-madrid-cf-v-rcd-mallorca-la-liga-ea-sports-1-1-1536x1024.jpg 1536w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/07\/real-madrid-cf-v-rcd-mallorca-la-liga-ea-sports-1-1-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-50251\" class=\"wp-caption-text\">Jacobo Ram\u00f3n da un pase en un partido con el Real Madrid. Fuente: Florencia Tan Jun\/Getty Images.<\/figcaption><\/figure>\n<p><strong>La \u00faltima temporada del jugador se puede definir como su salto al primer equipo merengue<\/strong>. <strong>Ram\u00f3n<\/strong>, que estuvo convocado en la <a href=\"https:\/\/agentelibredigital.com\/?s=Supercopa+de+Europa\">Supercopa de Europa<\/a>, debut\u00f3 con el primer equipo en <a href=\"https:\/\/agentelibredigital.com\/?s=Champions\">Champions<\/a> contra el <a href=\"https:\/\/agentelibredigital.com\/?s=Salzburgo\"><strong>Salzburgo<\/strong><\/a> y unos meses m\u00e1s tarde<strong> marc\u00f3 su primer gol en <a href=\"https:\/\/agentelibredigital.com\/?s=Liga\">Liga<\/a> contra el <a href=\"https:\/\/agentelibredigital.com\/?s=Mallorca\">Mallorca<\/a><\/strong>. Pese a ello, <strong>Jacobo Ram\u00f3n ha compaginado sus pocas actuaciones en el primer equipo con el Castilla y el Juvenil<\/strong>. Actualmente es una de las promesas m\u00e1s destacadas dentro de la cantera de \u00ablos Blancos\u00bb.<\/p>\n<p><strong>Jacobo Ram\u00f3n es un central que destaca por el car\u00e1cter, por su salida de bal\u00f3n y por su velocidad<\/strong>. Su posible llegada al <strong>Como<\/strong> casa muy bien con el estilo t\u00e1ctico de <strong>Cesc F\u00e1bregas<\/strong>. Muestra de ello es su <strong>velocidad y su salida en defensa<\/strong>. Adem\u00e1s tendr\u00eda a un viejo conocido en la escuadra transalpina como es <strong>Nico Paz<\/strong>. Para <strong>Jacobo Ram\u00f3n<\/strong>, <strong>la Serie A es un lugar que puede ser id\u00f3neo para coger experiencia y foguearse con jugadores experimentados<\/strong>. Nadie duda de que el <strong>Como<\/strong> est\u00e1 yendo a por todas este verano para dar guerra en la pr\u00f3xima temporada.<\/p>\n<h4>Autor del art\u00edculo: <a href=\"https:\/\/x.com\/Markinhooos11\">Marcos Iglesias Rodr\u00edguez<\/a>.<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan Fabrizio Romano, el defensa espa\u00f1ol abandona el Real Madrid para convertirse en nuevo jugador de los Lariani por 2,5 millones de euros m\u00e1s variables. Muchos equipos lo est\u00e1n dando&hellip; <\/p>\n","protected":false},"author":179,"featured_media":50250,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[48,33],"tags":[2821,94],"class_list":["post-50249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol-internacional","category-serie-a","tag-como-1907","tag-serie-a"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Jacobo Ram\u00f3n, muy cerca de irse al Como 1907 Jacobo Ram\u00f3n se convierte en nuevo jugador del Como 1907 por 2,5 millones de euros m\u00e1s variables.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Marcos Iglesias\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2025\/07\/21\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Jacobo Ram\u00f3n, muy cerca de irse al Como 1907\" \/>\n\t\t<meta property=\"og:description\" content=\"Jacobo Ram\u00f3n, muy cerca de irse al Como 1907 Jacobo Ram\u00f3n se convierte en nuevo jugador del Como 1907 por 2,5 millones de euros m\u00e1s variables.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2025\/07\/21\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/07\/real-madrid-cf-v-rcd-mallorca-la-liga-ea-sports-1-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/07\/real-madrid-cf-v-rcd-mallorca-la-liga-ea-sports-1-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1751\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-07-21T16:36:40+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-07-21T16:36:40+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Jacobo Ram\u00f3n, muy cerca de irse al Como 1907\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Jacobo Ram\u00f3n, muy cerca de irse al Como 1907 Jacobo Ram\u00f3n se convierte en nuevo jugador del Como 1907 por 2,5 millones de euros m\u00e1s variables.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/07\/real-madrid-cf-v-rcd-mallorca-la-liga-ea-sports-1-scaled.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/07\\\/21\\\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\\\/#blogposting\",\"name\":\"Jacobo Ram\\u00f3n, muy cerca de irse al Como 1907\",\"headline\":\"Jacobo Ram\\u00f3n, muy cerca de irse al Como 1907\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-iglesias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/real-madrid-cf-v-rcd-mallorca-la-liga-ea-sports-1-scaled.jpg\",\"width\":2560,\"height\":1751,\"caption\":\"Jacobo Ram\\u00f3n celebra un gol en un partido con el Real Madrid. Fuente: Angel Martinez\\\/Getty Images.\"},\"datePublished\":\"2025-07-21T18:36:40+02:00\",\"dateModified\":\"2025-07-21T18:36:40+02:00\",\"inLanguage\":\"es-ES\",\"commentCount\":126,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/07\\\/21\\\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/07\\\/21\\\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\\\/#webpage\"},\"articleSection\":\"F\\u00fatbol Internacional, Serie A, Como 1907, Serie A\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/07\\\/21\\\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/serie-a\\\/#listItem\",\"name\":\"Serie A\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/serie-a\\\/#listItem\",\"position\":2,\"name\":\"Serie A\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/serie-a\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/07\\\/21\\\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\\\/#listItem\",\"name\":\"Jacobo Ram\\u00f3n, muy cerca de irse al Como 1907\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/07\\\/21\\\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\\\/#listItem\",\"position\":3,\"name\":\"Jacobo Ram\\u00f3n, muy cerca de irse al Como 1907\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/serie-a\\\/#listItem\",\"name\":\"Serie A\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/07\\\/21\\\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/07\\\/21\\\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-iglesias\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-iglesias\\\/\",\"name\":\"Marcos Iglesias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/07\\\/21\\\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b12d4fac150c550921f0486912033479abc571a43af887303e0aa75b2023fa6a?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Marcos Iglesias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/07\\\/21\\\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/07\\\/21\\\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\\\/\",\"name\":\"Jacobo Ram\\u00f3n, muy cerca de irse al Como 1907\",\"description\":\"Jacobo Ram\\u00f3n, muy cerca de irse al Como 1907 Jacobo Ram\\u00f3n se convierte en nuevo jugador del Como 1907 por 2,5 millones de euros m\\u00e1s variables.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/07\\\/21\\\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-iglesias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-iglesias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/real-madrid-cf-v-rcd-mallorca-la-liga-ea-sports-1-scaled.jpg\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/07\\\/21\\\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\\\/#mainImage\",\"width\":2560,\"height\":1751,\"caption\":\"Jacobo Ram\\u00f3n celebra un gol en un partido con el Real Madrid. Fuente: Angel Martinez\\\/Getty Images.\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/07\\\/21\\\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\\\/#mainImage\"},\"datePublished\":\"2025-07-21T18:36:40+02:00\",\"dateModified\":\"2025-07-21T18:36:40+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Jacobo Ram\u00f3n, muy cerca de irse al Como 1907","description":"Jacobo Ram\u00f3n, muy cerca de irse al Como 1907 Jacobo Ram\u00f3n se convierte en nuevo jugador del Como 1907 por 2,5 millones de euros m\u00e1s variables.","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2025\/07\/21\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/07\/21\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\/#blogposting","name":"Jacobo Ram\u00f3n, muy cerca de irse al Como 1907","headline":"Jacobo Ram\u00f3n, muy cerca de irse al Como 1907","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-iglesias\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/07\/real-madrid-cf-v-rcd-mallorca-la-liga-ea-sports-1-scaled.jpg","width":2560,"height":1751,"caption":"Jacobo Ram\u00f3n celebra un gol en un partido con el Real Madrid. Fuente: Angel Martinez\/Getty Images."},"datePublished":"2025-07-21T18:36:40+02:00","dateModified":"2025-07-21T18:36:40+02:00","inLanguage":"es-ES","commentCount":126,"mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/07\/21\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/07\/21\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\/#webpage"},"articleSection":"F\u00fatbol Internacional, Serie A, Como 1907, Serie A"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/07\/21\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/serie-a\/#listItem","name":"Serie A"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/serie-a\/#listItem","position":2,"name":"Serie A","item":"https:\/\/agentelibredigital.com\/index.php\/category\/serie-a\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/07\/21\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\/#listItem","name":"Jacobo Ram\u00f3n, muy cerca de irse al Como 1907"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/07\/21\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\/#listItem","position":3,"name":"Jacobo Ram\u00f3n, muy cerca de irse al Como 1907","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/serie-a\/#listItem","name":"Serie A"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/07\/21\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/07\/21\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-iglesias\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-iglesias\/","name":"Marcos Iglesias","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/07\/21\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b12d4fac150c550921f0486912033479abc571a43af887303e0aa75b2023fa6a?s=96&d=mm&r=g","width":96,"height":96,"caption":"Marcos Iglesias"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/07\/21\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2025\/07\/21\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\/","name":"Jacobo Ram\u00f3n, muy cerca de irse al Como 1907","description":"Jacobo Ram\u00f3n, muy cerca de irse al Como 1907 Jacobo Ram\u00f3n se convierte en nuevo jugador del Como 1907 por 2,5 millones de euros m\u00e1s variables.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/07\/21\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-iglesias\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-iglesias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/07\/real-madrid-cf-v-rcd-mallorca-la-liga-ea-sports-1-scaled.jpg","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/07\/21\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\/#mainImage","width":2560,"height":1751,"caption":"Jacobo Ram\u00f3n celebra un gol en un partido con el Real Madrid. Fuente: Angel Martinez\/Getty Images."},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/07\/21\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\/#mainImage"},"datePublished":"2025-07-21T18:36:40+02:00","dateModified":"2025-07-21T18:36:40+02:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"Jacobo Ram\u00f3n, muy cerca de irse al Como 1907","og:description":"Jacobo Ram\u00f3n, muy cerca de irse al Como 1907 Jacobo Ram\u00f3n se convierte en nuevo jugador del Como 1907 por 2,5 millones de euros m\u00e1s variables.","og:url":"https:\/\/agentelibredigital.com\/index.php\/2025\/07\/21\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/07\/real-madrid-cf-v-rcd-mallorca-la-liga-ea-sports-1-scaled.jpg","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/07\/real-madrid-cf-v-rcd-mallorca-la-liga-ea-sports-1-scaled.jpg","og:image:width":2560,"og:image:height":1751,"article:published_time":"2025-07-21T16:36:40+00:00","article:modified_time":"2025-07-21T16:36:40+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"Jacobo Ram\u00f3n, muy cerca de irse al Como 1907","twitter:description":"Jacobo Ram\u00f3n, muy cerca de irse al Como 1907 Jacobo Ram\u00f3n se convierte en nuevo jugador del Como 1907 por 2,5 millones de euros m\u00e1s variables.","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/07\/real-madrid-cf-v-rcd-mallorca-la-liga-ea-sports-1-scaled.jpg"},"aioseo_meta_data":{"post_id":"50249","title":"#post_title","description":"#post_title Jacobo Ram\u00f3n se convierte en nuevo jugador del Como 1907 por 2,5 millones de euros m\u00e1s variables.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-07-21 16:20:41","updated":"2025-07-21 16:49:09","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/serie-a\/\" title=\"Serie A\">Serie A<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tJacobo Ram\u00f3n, muy cerca de irse al Como 1907\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"Serie A","link":"https:\/\/agentelibredigital.com\/index.php\/category\/serie-a\/"},{"label":"Jacobo Ram\u00f3n, muy cerca de irse al Como 1907","link":"https:\/\/agentelibredigital.com\/index.php\/2025\/07\/21\/jacobo-ramon-muy-cerca-de-irse-al-como-1907\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/50249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/179"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=50249"}],"version-history":[{"count":2,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/50249\/revisions"}],"predecessor-version":[{"id":50253,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/50249\/revisions\/50253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/50250"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=50249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=50249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=50249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}