{"id":49334,"date":"2025-06-30T23:03:20","date_gmt":"2025-06-30T21:03:20","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=49334"},"modified":"2025-06-30T23:03:20","modified_gmt":"2025-06-30T21:03:20","slug":"inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2025\/06\/30\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\/","title":{"rendered":"Inter Milan 0-2 Fluminense: La samba frena el sue\u00f1o milan\u00e9s"},"content":{"rendered":"<h4>El <a href=\"https:\/\/agentelibredigital.com\/?s=Inter\">Inter<\/a> pierde 0-2 contra el <a href=\"https:\/\/agentelibredigital.com\/?s=Fluminense\">Fluminense<\/a> en Charlotte y se despide del <a href=\"https:\/\/agentelibredigital.com\/?s=Mundial+de+Clubes\">Mundial de Clubes<\/a>.<\/h4>\n<h2>Primera parte<\/h2>\n<p>Nada m\u00e1s empezar, <strong>el Inter ya tuvo que intervenir con Sommer a una llegada de ataque<\/strong> por parte de los cariocas. Poco despu\u00e9s <strong>Germ\u00e1n Cano adelant\u00f3 al <em>Flu<\/em> en el minuto 2 con un cabezazo<\/strong> que castigar\u00eda el error defensivo de los transalpinos. Tras el gol, <strong>los pupilos de Cristian Chivu lo intentaron <\/strong>en el minuto 5 <strong>con un centro de Darmian<\/strong> que acab\u00f3 atajando <strong>F\u00e1bio<\/strong>.<\/p>\n<figure id=\"attachment_49338\" aria-describedby=\"caption-attachment-49338\" style=\"width: 2560px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-49338\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-2-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-2-scaled.jpg 2560w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-2-300x200.jpg 300w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-2-1024x683.jpg 1024w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-2-768x512.jpg 768w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-2-1536x1024.jpg 1536w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-2-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-49338\" class=\"wp-caption-text\">Germ\u00e1n Cano celebra su gol en el encuentro. Fuente: Buda Mendes\/Getty Images.<\/figcaption><\/figure>\n<p><strong>Dimarco busc\u00f3 el empate en el minuto 11<\/strong> con un tiro dentro del \u00e1rea que acab\u00f3 salvando el veterano arquero brasile\u00f1o. Pocos minutos despu\u00e9s, <strong>F\u00e1bio tuvo que sacar las manos para evitar un centro que pintaba peligroso<\/strong> por parte de los lombardos. <strong>El Fluminense intent\u00f3 una contra a trav\u00e9s de un robo de bal\u00f3n<\/strong> en el minuto 23 aunque acab\u00f3 en nada.<\/p>\n<p>A continuaci\u00f3n <strong>Thuram intent\u00f3 sin fortuna conectar dentro del \u00e1rea una volea<\/strong> que acab\u00f3 y\u00e9ndose por arriba de la porter\u00eda. <strong>Freytes caus\u00f3 en el minuto 26 una falta peligrosa al borde del \u00e1rea<\/strong> a favor de los <em>nerazzurri<\/em> aunque concluy\u00f3 rebotando en la barrera del <em>Fluz\u00e3o<\/em>. <strong>Samuel Xavier la tuvo a la media hora<\/strong> tras intentar aprovechar un rechace de <strong>Sommer<\/strong> que roz\u00f3 el palo de la porter\u00eda interista.<\/p>\n<p>En estos instantes del encuentro, <strong>el Inter estaba en una situaci\u00f3n comprometida ya que se estaba encontrando a un Fluminense muy competitivo<\/strong>. Los brasile\u00f1os estuvieron cerca de aumentar la ventaja en el minuto 40 con una jugada a bal\u00f3n parada que fue anulado por fuera de juego de <strong>Ignacio.<\/strong><\/p>\n<figure id=\"attachment_49340\" aria-describedby=\"caption-attachment-49340\" style=\"width: 2560px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-49340\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-3-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-3-scaled.jpg 2560w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-3-300x200.jpg 300w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-3-1024x683.jpg 1024w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-3-768x512.jpg 768w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-3-1536x1024.jpg 1536w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-3-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-49340\" class=\"wp-caption-text\">Kristjan Asllani presiona a Jhon Arias en el partido. Fuente: Michael Reaves\/Getty Images.<\/figcaption><\/figure>\n<p>En el descuento <strong>Jhon Arias prob\u00f3 un disparo en el \u00e1rea aunque la acab\u00f3 despejando la defensa italiana<\/strong>. <strong>Con el entretiempo al acecho los transalpinos lo intentaron con un centro<\/strong> que se resolvi\u00f3 en saque de esquina. Al final el partido se fue al descanso con ventaja favorable a los sudamericanos mientras que el conjunto europeo necesitaba cambiar el &#8216;chip&#8217; si quer\u00edan seguir so\u00f1ando con el torneo.<\/p>\n<h2>Segunda parte<\/h2>\n<p>Tras un entretiempo ya finiquitado, <strong>el Inter sali\u00f3 con la idea de revertir el nivel mostrado del <em>Fluz\u00e3o <\/em><\/strong>en la primera parte<em>.\u00a0<\/em>Aun as\u00ed los pupilos de <strong>Renato Ga\u00facho<\/strong> iban manteniendo el nivel que tuvieron anterior a la primera parte. <strong>Germ\u00e1n Cano la tuvo en en el minuto 56 con una volea en el segundo palo<\/strong> que se fue desviado de la porter\u00eda.<\/p>\n<p>Dos minutos despu\u00e9s el <em>Flu<\/em> busc\u00f3 crear una ocasi\u00f3n de ataque en la que no lleg\u00f3 ning\u00fan rematador. <strong>Sommer salvaba al Inter con una atajada para evitar que un tiro de Jhon Arias<\/strong> en el minuto 62 se convirtiera en gol. Los italianos pedir\u00edan una posible mano en el minuto 67 <strong>tras un control de Barella que dio en Thiago Silva<\/strong>.<\/p>\n<figure id=\"attachment_49345\" aria-describedby=\"caption-attachment-49345\" style=\"width: 2560px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-49345\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-6-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-6-scaled.jpg 2560w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-6-300x200.jpg 300w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-6-1024x683.jpg 1024w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-6-768x512.jpg 768w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-6-1536x1024.jpg 1536w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-6-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-49345\" class=\"wp-caption-text\">Valent\u00edn Carboni se intenta escapar con el bal\u00f3n de Samuel Xavier. Fuente: Michael Reaves\/Getty Images.<\/figcaption><\/figure>\n<p>Justo despu\u00e9s <strong>De Vrij roz\u00f3 el empate con un remate que no fue con mucha fortuna de cara a puerta<\/strong>. Los pupilos de <strong>Cristian Chivu<\/strong> lo volvieron a buscar con una falta lanzada por<strong> Dimarco que se fue rozando el poste<\/strong> en el minuto 75. <strong>Francesco Esposito intent\u00f3 con una llegada crear alg\u00fan susto a los cariocas en el minuto 78<\/strong> aunque no vali\u00f3 por fuera de juego.<\/p>\n<p>A pocos minutos del final, <strong>Lautaro tuvo dos clar\u00edsimas ocasiones en la que no tuvo mucha fortuna<\/strong> ya que la primera se top\u00f3 con una gran parada de <strong>F\u00e1bio<\/strong> y la segunda vio el poste. <strong>Lima intent\u00f3 aumentar la ventaja en el minuto 84 desde fuera del \u00e1rea<\/strong> aunque el bal\u00f3n se fue por arriba del arco del <em>Flu.<\/em><\/p>\n<p><strong>Carlos Augusto<\/strong> tuvo la opci\u00f3n de poner el empate en el descuento aunque se fue por encima del larguero. Poco despu\u00e9s <strong>Hercules sentenci\u00f3 el partido con un remate cruzado dentro del \u00e1rea<\/strong> en el que <strong>Sommer<\/strong> no pudo evitarlo. El partido <strong>acab\u00f3 0-2 favorable a los brasile\u00f1os que acabaron eliminando a todo un subcampe\u00f3n como es el Inter.<\/strong><\/p>\n<figure id=\"attachment_49346\" aria-describedby=\"caption-attachment-49346\" style=\"width: 2028px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-49346\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-7.jpg\" alt=\"\" width=\"2028\" height=\"1352\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-7.jpg 2028w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-7-300x200.jpg 300w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-7-1024x683.jpg 1024w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-7-768x512.jpg 768w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-7-1536x1024.jpg 1536w\" sizes=\"auto, (max-width: 2028px) 100vw, 2028px\" \/><figcaption id=\"caption-attachment-49346\" class=\"wp-caption-text\">Hercules celebra con su compa\u00f1ero el segundo gol del Fluminense. Fuente: Buda Mendes\/Getty Images.<\/figcaption><\/figure>\n<h4>Autor del art\u00edculo:<a href=\"https:\/\/x.com\/Markinhooos11\"> Marcos Iglesias Rodr\u00edguez<\/a>.<\/h4>\n<h2>Ficha t\u00e9cnica<\/h2>\n<p>Inter Milan (3-5-2): Sommer; Darmian, De Vrij, Bastoni (Carlos Augusto 71&#8242;); Dumfries (Luis Henrique 53&#8242;), Barella, Asllani (Sucic 53&#8242;), Mkhitaryan (Carboni 53&#8242;), Dimarco; Marcus Thuram (Sebastiano Esposito 66&#8242;), Lautaro.<\/p>\n<p>Fluminense (5-3-2): F\u00e1bio; Freytes, Ignacio, Thiago Silva Samuel Brito; Matheus Martinelli (Hercules 60&#8242;), Bernal, Nonato (Lima 60&#8242;); Jhon Arias, Germ\u00e1n Cano (Everaldo 66&#8242;).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Inter pierde 0-2 contra el Fluminense en Charlotte y se despide del Mundial de Clubes. Primera parte Nada m\u00e1s empezar, el Inter ya tuvo que intervenir con Sommer a&hellip; <\/p>\n","protected":false},"author":179,"featured_media":49342,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[48],"tags":[2073,1006,1888],"class_list":["post-49334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol-internacional","tag-fluminense","tag-inter-de-milan","tag-mundial-de-clubes"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Inter Milan 0-2 Fluminense: La samba frena el sue\u00f1o milan\u00e9s El Inter pierde 0-2 contra el Fluminense en Charlotte y se despide del Mundial de Clubes.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Marcos Iglesias\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2025\/06\/30\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Inter Milan 0-2 Fluminense: La samba frena el sue\u00f1o milan\u00e9s\" \/>\n\t\t<meta property=\"og:description\" content=\"Inter Milan 0-2 Fluminense: La samba frena el sue\u00f1o milan\u00e9s El Inter pierde 0-2 contra el Fluminense en Charlotte y se despide del Mundial de Clubes.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2025\/06\/30\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-5-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-5-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-06-30T21:03:20+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-06-30T21:03:20+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Inter Milan 0-2 Fluminense: La samba frena el sue\u00f1o milan\u00e9s\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Inter Milan 0-2 Fluminense: La samba frena el sue\u00f1o milan\u00e9s El Inter pierde 0-2 contra el Fluminense en Charlotte y se despide del Mundial de Clubes.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-5-scaled.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/06\\\/30\\\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\\\/#blogposting\",\"name\":\"Inter Milan 0-2 Fluminense: La samba frena el sue\\u00f1o milan\\u00e9s\",\"headline\":\"Inter Milan 0-2 Fluminense: La samba frena el sue\\u00f1o milan\\u00e9s\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-iglesias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-5-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Jugadores del Inter de Mil\\u00e1n y del Fluminense se saludan instantes previos al encuentro. Fuente:  Buda Mendes\\\/Getty Images.\"},\"datePublished\":\"2025-06-30T23:03:20+02:00\",\"dateModified\":\"2025-06-30T23:03:20+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/06\\\/30\\\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/06\\\/30\\\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\\\/#webpage\"},\"articleSection\":\"F\\u00fatbol Internacional, Fluminense, Inter de Milan, Mundial de Clubes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/06\\\/30\\\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/futbol-internacional\\\/#listItem\",\"name\":\"F\\u00fatbol Internacional\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/futbol-internacional\\\/#listItem\",\"position\":2,\"name\":\"F\\u00fatbol Internacional\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/futbol-internacional\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/06\\\/30\\\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\\\/#listItem\",\"name\":\"Inter Milan 0-2 Fluminense: La samba frena el sue\\u00f1o milan\\u00e9s\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/06\\\/30\\\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\\\/#listItem\",\"position\":3,\"name\":\"Inter Milan 0-2 Fluminense: La samba frena el sue\\u00f1o milan\\u00e9s\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/futbol-internacional\\\/#listItem\",\"name\":\"F\\u00fatbol Internacional\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/06\\\/30\\\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/06\\\/30\\\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-iglesias\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-iglesias\\\/\",\"name\":\"Marcos Iglesias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/06\\\/30\\\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b12d4fac150c550921f0486912033479abc571a43af887303e0aa75b2023fa6a?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Marcos Iglesias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/06\\\/30\\\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/06\\\/30\\\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\\\/\",\"name\":\"Inter Milan 0-2 Fluminense: La samba frena el sue\\u00f1o milan\\u00e9s\",\"description\":\"Inter Milan 0-2 Fluminense: La samba frena el sue\\u00f1o milan\\u00e9s El Inter pierde 0-2 contra el Fluminense en Charlotte y se despide del Mundial de Clubes.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/06\\\/30\\\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-iglesias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-iglesias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-5-scaled.jpg\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/06\\\/30\\\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\\\/#mainImage\",\"width\":2560,\"height\":1707,\"caption\":\"Jugadores del Inter de Mil\\u00e1n y del Fluminense se saludan instantes previos al encuentro. Fuente:  Buda Mendes\\\/Getty Images.\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/06\\\/30\\\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\\\/#mainImage\"},\"datePublished\":\"2025-06-30T23:03:20+02:00\",\"dateModified\":\"2025-06-30T23:03:20+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Inter Milan 0-2 Fluminense: La samba frena el sue\u00f1o milan\u00e9s","description":"Inter Milan 0-2 Fluminense: La samba frena el sue\u00f1o milan\u00e9s El Inter pierde 0-2 contra el Fluminense en Charlotte y se despide del Mundial de Clubes.","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2025\/06\/30\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/06\/30\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\/#blogposting","name":"Inter Milan 0-2 Fluminense: La samba frena el sue\u00f1o milan\u00e9s","headline":"Inter Milan 0-2 Fluminense: La samba frena el sue\u00f1o milan\u00e9s","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-iglesias\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-5-scaled.jpg","width":2560,"height":1707,"caption":"Jugadores del Inter de Mil\u00e1n y del Fluminense se saludan instantes previos al encuentro. Fuente:  Buda Mendes\/Getty Images."},"datePublished":"2025-06-30T23:03:20+02:00","dateModified":"2025-06-30T23:03:20+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/06\/30\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/06\/30\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\/#webpage"},"articleSection":"F\u00fatbol Internacional, Fluminense, Inter de Milan, Mundial de Clubes"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/06\/30\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/futbol-internacional\/#listItem","name":"F\u00fatbol Internacional"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/futbol-internacional\/#listItem","position":2,"name":"F\u00fatbol Internacional","item":"https:\/\/agentelibredigital.com\/index.php\/category\/futbol-internacional\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/06\/30\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\/#listItem","name":"Inter Milan 0-2 Fluminense: La samba frena el sue\u00f1o milan\u00e9s"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/06\/30\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\/#listItem","position":3,"name":"Inter Milan 0-2 Fluminense: La samba frena el sue\u00f1o milan\u00e9s","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/futbol-internacional\/#listItem","name":"F\u00fatbol Internacional"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/06\/30\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/06\/30\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-iglesias\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-iglesias\/","name":"Marcos Iglesias","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/06\/30\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b12d4fac150c550921f0486912033479abc571a43af887303e0aa75b2023fa6a?s=96&d=mm&r=g","width":96,"height":96,"caption":"Marcos Iglesias"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/06\/30\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2025\/06\/30\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\/","name":"Inter Milan 0-2 Fluminense: La samba frena el sue\u00f1o milan\u00e9s","description":"Inter Milan 0-2 Fluminense: La samba frena el sue\u00f1o milan\u00e9s El Inter pierde 0-2 contra el Fluminense en Charlotte y se despide del Mundial de Clubes.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/06\/30\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-iglesias\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-iglesias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-5-scaled.jpg","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/06\/30\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\/#mainImage","width":2560,"height":1707,"caption":"Jugadores del Inter de Mil\u00e1n y del Fluminense se saludan instantes previos al encuentro. Fuente:  Buda Mendes\/Getty Images."},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/06\/30\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\/#mainImage"},"datePublished":"2025-06-30T23:03:20+02:00","dateModified":"2025-06-30T23:03:20+02:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"Inter Milan 0-2 Fluminense: La samba frena el sue\u00f1o milan\u00e9s","og:description":"Inter Milan 0-2 Fluminense: La samba frena el sue\u00f1o milan\u00e9s El Inter pierde 0-2 contra el Fluminense en Charlotte y se despide del Mundial de Clubes.","og:url":"https:\/\/agentelibredigital.com\/index.php\/2025\/06\/30\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-5-scaled.jpg","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-5-scaled.jpg","og:image:width":2560,"og:image:height":1707,"article:published_time":"2025-06-30T21:03:20+00:00","article:modified_time":"2025-06-30T21:03:20+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"Inter Milan 0-2 Fluminense: La samba frena el sue\u00f1o milan\u00e9s","twitter:description":"Inter Milan 0-2 Fluminense: La samba frena el sue\u00f1o milan\u00e9s El Inter pierde 0-2 contra el Fluminense en Charlotte y se despide del Mundial de Clubes.","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/06\/fc-internazionale-milano-v-fluminense-fc-round-of-16-fifa-club-world-cup-2025-5-scaled.jpg"},"aioseo_meta_data":{"post_id":"49334","title":"#post_title","description":"#post_title El Inter pierde 0-2 contra el Fluminense en Charlotte y se despide del Mundial de Clubes.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-06-30 19:09:35","updated":"2025-06-30 21:15:00","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/futbol-internacional\/\" title=\"F\u00fatbol Internacional\">F\u00fatbol Internacional<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tInter Milan 0-2 Fluminense: La samba frena el sue\u00f1o milan\u00e9s\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"F\u00fatbol Internacional","link":"https:\/\/agentelibredigital.com\/index.php\/category\/futbol-internacional\/"},{"label":"Inter Milan 0-2 Fluminense: La samba frena el sue\u00f1o milan\u00e9s","link":"https:\/\/agentelibredigital.com\/index.php\/2025\/06\/30\/inter-milan-0-2-fluminense-la-samba-frena-el-sueno-milanes\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/49334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/179"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=49334"}],"version-history":[{"count":2,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/49334\/revisions"}],"predecessor-version":[{"id":49347,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/49334\/revisions\/49347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/49342"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=49334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=49334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=49334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}