{"id":47344,"date":"2025-05-01T02:59:02","date_gmt":"2025-05-01T00:59:02","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=47344"},"modified":"2025-05-01T03:07:10","modified_gmt":"2025-05-01T01:07:10","slug":"chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2025\/05\/01\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\/","title":{"rendered":"Chus Mateo: \u00abLa experiencia nos dice que hay que seguir hasta el final\u00bb"},"content":{"rendered":"<h4>El t\u00e9cnico del Real Madrid ha atendido a la prensa en la previa del cuarto partido ante Olympiacos<\/h4>\n<p><strong>Chus Mateo<\/strong>\u00a0y\u00a0<strong>Dzanan <b>Musa<\/b><\/strong>\u00a0atendieron ayer a los medios de comunicaci\u00f3n en la previa del\u00a0<strong>cuarto partido de la primera ronda de los Playoffs de la <a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/euroliga\/\">Euroliga<\/a><\/strong>. El\u00a0<strong><a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/real-madrid\/\">Real Madrid<\/a><\/strong>\u00a0necesita ganar ante\u00a0<a href=\"https:\/\/www.olympiacosbc.gr\/en\/\"><strong>Olympiacos<\/strong><\/a> para forzar el quinto y definitivo partido. Por ello, el t\u00e9cnico espa\u00f1ol y el bosnio han analizado la <strong>actualidad<\/strong>\u00a0y la\u00a0<strong>situaci\u00f3n<\/strong>\u00a0del equipo de cara al partido que se disputar\u00e1 hoy en el\u00a0<strong>Movistar Arena<\/strong>. El partido se podr\u00e1 seguir en directo a las\u00a0<strong>21:00h<\/strong>\u00a0de este\u00a0<strong>jueves 1 de mayo<\/strong>\u00a0a trav\u00e9s de\u00a0<strong>Movistar Deportes<\/strong>.<\/p>\n<p>\u201cJugar como equipo te ayuda a entender mejor c\u00f3mo doblegar a un rival de tantas armas y buenos jugadores. <strong>Ayer hicimos un buen partido defensivo, especialmente en la segunda parte, con mucha colaboraci\u00f3n de todos y el aliento de la afici\u00f3n<\/strong>. Nos hizo sentirnos seguros y nos ayud\u00f3 a recuperar muchos balones durante el partido\u201d, afirmaba Chus Mateo.<\/p>\n<figure style=\"width: 1000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.defensacentral.com\/uploads\/s1\/36\/54\/48\/3\/chus-mateo-rueda-prensa_88_1000x563.jpeg\" alt=\"Chus Mateo\" width=\"1000\" height=\"563\" \/><figcaption class=\"wp-caption-text\">Chus Mateo en rueda de prensa. Fuente: OneFootball<\/figcaption><\/figure>\n<h2>Sensaciones de cara al partido<\/h2>\n<p>\u201cSi nuestra intenci\u00f3n es hacer un buen partido, <strong>tenemos que mejorar m\u00e1s<\/strong>, a todos los niveles, y pensar que ma\u00f1ana va a ser m\u00e1s complicado y que<strong> tenemos que rayar a un nivel cercano a la perfecci\u00f3n<\/strong>\u201d.<\/p>\n<h2>Vuelta de Fournier<\/h2>\n<p><b><\/b>\u201cS\u00ed, va a jugar. <strong>Tenemos la certeza de que va a ser as\u00ed y lo prepararemos pensando que est\u00e1 \u00e9l<\/strong>. Si no est\u00e1 no va a ser m\u00e1s f\u00e1cil. Ayer no lo fue. <strong>Es un gran equipo que no depende de uno o dos jugadores<\/strong>. Independientemente de que est\u00e9 o no, <strong>no podemos pensar que el Olympiacos es m\u00e1s d\u00e9bil sin \u00e9l<\/strong>\u201d.<\/p>\n<figure style=\"width: 950px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/images.eurohoops.net\/2025\/04\/5c70828c-fournier-olympiacos.jpg\" alt=\"Chus Mateo\" width=\"950\" height=\"500\" \/><figcaption class=\"wp-caption-text\">Evan Fournier agradece el apoyo a su afici\u00f3n. Fuente: Eurohoops<\/figcaption><\/figure>\n<h2>Aspecto mental<\/h2>\n<p>\u201cHay que mentalizarse en valorar los partidos de una forma individual. Es solo un partido. <strong>El de ayer es pasado y ahora hay que centrarse solo en el siguiente. Es la manera de afrontarlo con m\u00e1s seguridad<\/strong>. Hay que tener paciencia y no volvernos locos sabiendo de la importancia del partido. No tratando de querer ganar el partido en 39 minutos, son 40 los que hay que jugar. <strong>La experiencia nos dice que hay que seguir hasta el final porque muchas veces hemos dado la vuelta a un partido adverso<\/strong>\u201d.<\/p>\n<h2>Aportaci\u00f3n de todos<\/h2>\n<p>\u201c<strong>Es obvio que cuanta m\u00e1s gente a\u00f1ada cosas positivas al equipo es mucho mejor<\/strong>. El partido hay que valorarlo en 40 minutos. Ese momento fue muy bueno a nivel defensivo porque ven\u00edamos de 30 minutos anteriores y conseguimos llevar el partido donde quer\u00edamos. <strong>Es un trabajo de equipo, de equilibrio ofensivo y defensivo<\/strong>. Eso es lo que buscamos y se dio muy bien de principio al final\u201d.<\/p>\n<figure style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/cadenaser.com\/resizer\/v2\/QKX5JI7LKFG7NIGRCDLI5TCZZI.jpg?auth=df718074317a13b945f0e391fef6c0616ed9d2e07ccd27b5035e1b48161e895f&amp;quality=70&amp;width=1200&amp;height=900&amp;smart=true\" alt=\"Chus Mateo\" width=\"1200\" height=\"900\" \/><figcaption class=\"wp-caption-text\">La celebraci\u00f3n de los blancos tras forzar el cuarto partido ante Olympiacos. Fuente: Cadena SER<\/figcaption><\/figure>\n<h2>Musa: \u201cLa clave es estar juntos\u201d<\/h2>\n<p>\u201c<strong>No es f\u00e1cil ganar al <a href=\"https:\/\/www.bing.com\/search?q=Olympiacos%20cb&amp;qs=n&amp;form=QBRE&amp;sp=-1&amp;ghc=1&amp;lq=0&amp;pq=olympiacos%20cb&amp;sc=12-13&amp;sk=&amp;cvid=B86146D213A14F08AFF9F2A512A63ED6\">Olympiacos<\/a> dos veces seguidas, pero tenemos la f\u00f3rmula para jugar contra ellos y ganarles<\/strong>. Es un gran equipo, con un magn\u00edfico entrenador, pero nosotros tambi\u00e9n tenemos nuestras fortalezas. <strong>La clave es estar juntos<\/strong> para poder ganar otra final que tenemos y poder ir a <strong>Atenas<\/strong> a seguir luchando para la\u00a0<b>Final Four<\/b>\u201d.<\/p>\n<h2>Aspecto individual<\/h2>\n<p>\u201c<strong>Mentalmente estoy bien<\/strong>. Quiero afrontar este final de temporada as\u00ed y luchar por este escudo cada d\u00eda y cada partido\u201d.<\/p>\n<figure style=\"width: 485px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/img.vavel.com\/c700_373_captura-de-pantalla-2025-04-14-230008-1744664415097.png\" alt=\"Chus Mateo\" width=\"485\" height=\"328\" \/><figcaption class=\"wp-caption-text\">La euforia de Dzanan Musa tras una canasta. Fuente: VAVEL.com<\/figcaption><\/figure>\n<h2>Afici\u00f3n<\/h2>\n<p><b><\/b>\u201cEs muy dif\u00edcil jugar contra nosotros cuando tenemos a la afici\u00f3n detr\u00e1s. En casa es muy dif\u00edcil ganarnos y necesitamos toda su ayuda. <strong>Si ellos y nosotros estamos con energ\u00eda seguro que ganamos<\/strong>\u201d.<\/p>\n<h2>Vezenkov y Fournier<\/h2>\n<p><b><\/b>\u201c<strong>Vezenkov es un jugador extraordinario<\/strong>. Tiene mucho talento, pero es un deporte de equipo. <strong>No nos importa si Fournier juega o no<\/strong>, nos vamos a preparar igual para ganar este partido\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El t\u00e9cnico del Real Madrid ha atendido a la prensa en la previa del cuarto partido ante Olympiacos Chus Mateo\u00a0y\u00a0Dzanan Musa\u00a0atendieron ayer a los medios de comunicaci\u00f3n en la previa&hellip; <\/p>\n","protected":false},"author":10,"featured_media":47346,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[49,41,6],"tags":[403,404,1641,56],"class_list":["post-47344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baloncesto","category-euroliga","category-real-madrid","tag-baloncesto","tag-euroliga","tag-olympiacos","tag-real-madrid"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Chus Mateo: \u00abLa experiencia nos dice que hay que seguir hasta el final\u00bb El t\u00e9cnico del Madrid ha atendido a la prensa antes del cuarto partido ante Olympiacos\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Marcos Morales\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2025\/05\/01\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Chus Mateo: \u00abLa experiencia nos dice que hay que seguir hasta el final\u00bb \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"Chus Mateo: \u00abLa experiencia nos dice que hay que seguir hasta el final\u00bb El t\u00e9cnico del Madrid ha atendido a la prensa antes del cuarto partido ante Olympiacos\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2025\/05\/01\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/05\/ND_RP_CHUS_MATEO_SG26754.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/05\/ND_RP_CHUS_MATEO_SG26754.webp\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-05-01T00:59:02+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-05-01T01:07:10+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Chus Mateo: \u00abLa experiencia nos dice que hay que seguir hasta el final\u00bb \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Chus Mateo: \u00abLa experiencia nos dice que hay que seguir hasta el final\u00bb El t\u00e9cnico del Madrid ha atendido a la prensa antes del cuarto partido ante Olympiacos\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/05\/ND_RP_CHUS_MATEO_SG26754.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/05\\\/01\\\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\\\/#blogposting\",\"name\":\"Chus Mateo: \\u00abLa experiencia nos dice que hay que seguir hasta el final\\u00bb \\u2013 Agente Libre Digital\",\"headline\":\"Chus Mateo: \\u00abLa experiencia nos dice que hay que seguir hasta el final\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-morales\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/ND_RP_CHUS_MATEO_SG26754.webp\",\"width\":1440,\"height\":810,\"caption\":\"Chus Mateo en rueda de prensa. Fuente: Real Madrid\"},\"datePublished\":\"2025-05-01T02:59:02+02:00\",\"dateModified\":\"2025-05-01T03:07:10+02:00\",\"inLanguage\":\"es-ES\",\"commentCount\":31,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/05\\\/01\\\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/05\\\/01\\\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\\\/#webpage\"},\"articleSection\":\"Baloncesto, Euroliga, Real Madrid, baloncesto, euroliga, Olympiacos, Real Madrid\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/05\\\/01\\\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/real-madrid\\\/#listItem\",\"name\":\"Real Madrid\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/real-madrid\\\/#listItem\",\"position\":2,\"name\":\"Real Madrid\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/real-madrid\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/05\\\/01\\\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\\\/#listItem\",\"name\":\"Chus Mateo: \\u00abLa experiencia nos dice que hay que seguir hasta el final\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/05\\\/01\\\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\\\/#listItem\",\"position\":3,\"name\":\"Chus Mateo: \\u00abLa experiencia nos dice que hay que seguir hasta el final\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/real-madrid\\\/#listItem\",\"name\":\"Real Madrid\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/05\\\/01\\\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/05\\\/01\\\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-morales\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-morales\\\/\",\"name\":\"Marcos Morales\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/05\\\/01\\\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d349ff249ec21a07032ba29fad5ce947cdea742609eaa319e6f1b9eb65a42b9f?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Marcos Morales\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/05\\\/01\\\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/05\\\/01\\\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\\\/\",\"name\":\"Chus Mateo: \\u00abLa experiencia nos dice que hay que seguir hasta el final\\u00bb \\u2013 Agente Libre Digital\",\"description\":\"Chus Mateo: \\u00abLa experiencia nos dice que hay que seguir hasta el final\\u00bb El t\\u00e9cnico del Madrid ha atendido a la prensa antes del cuarto partido ante Olympiacos\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/05\\\/01\\\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-morales\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-morales\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/ND_RP_CHUS_MATEO_SG26754.webp\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/05\\\/01\\\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\\\/#mainImage\",\"width\":1440,\"height\":810,\"caption\":\"Chus Mateo en rueda de prensa. Fuente: Real Madrid\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/05\\\/01\\\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\\\/#mainImage\"},\"datePublished\":\"2025-05-01T02:59:02+02:00\",\"dateModified\":\"2025-05-01T03:07:10+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Chus Mateo: \u00abLa experiencia nos dice que hay que seguir hasta el final\u00bb \u2013 Agente Libre Digital","description":"Chus Mateo: \u00abLa experiencia nos dice que hay que seguir hasta el final\u00bb El t\u00e9cnico del Madrid ha atendido a la prensa antes del cuarto partido ante Olympiacos","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2025\/05\/01\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/05\/01\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\/#blogposting","name":"Chus Mateo: \u00abLa experiencia nos dice que hay que seguir hasta el final\u00bb \u2013 Agente Libre Digital","headline":"Chus Mateo: \u00abLa experiencia nos dice que hay que seguir hasta el final\u00bb","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-morales\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/05\/ND_RP_CHUS_MATEO_SG26754.webp","width":1440,"height":810,"caption":"Chus Mateo en rueda de prensa. Fuente: Real Madrid"},"datePublished":"2025-05-01T02:59:02+02:00","dateModified":"2025-05-01T03:07:10+02:00","inLanguage":"es-ES","commentCount":31,"mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/05\/01\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/05\/01\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\/#webpage"},"articleSection":"Baloncesto, Euroliga, Real Madrid, baloncesto, euroliga, Olympiacos, Real Madrid"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/05\/01\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/real-madrid\/#listItem","name":"Real Madrid"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/real-madrid\/#listItem","position":2,"name":"Real Madrid","item":"https:\/\/agentelibredigital.com\/index.php\/category\/real-madrid\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/05\/01\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\/#listItem","name":"Chus Mateo: \u00abLa experiencia nos dice que hay que seguir hasta el final\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/05\/01\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\/#listItem","position":3,"name":"Chus Mateo: \u00abLa experiencia nos dice que hay que seguir hasta el final\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/real-madrid\/#listItem","name":"Real Madrid"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/05\/01\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/05\/01\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-morales\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-morales\/","name":"Marcos Morales","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/05\/01\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/d349ff249ec21a07032ba29fad5ce947cdea742609eaa319e6f1b9eb65a42b9f?s=96&d=mm&r=g","width":96,"height":96,"caption":"Marcos Morales"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/05\/01\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2025\/05\/01\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\/","name":"Chus Mateo: \u00abLa experiencia nos dice que hay que seguir hasta el final\u00bb \u2013 Agente Libre Digital","description":"Chus Mateo: \u00abLa experiencia nos dice que hay que seguir hasta el final\u00bb El t\u00e9cnico del Madrid ha atendido a la prensa antes del cuarto partido ante Olympiacos","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/05\/01\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-morales\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-morales\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/05\/ND_RP_CHUS_MATEO_SG26754.webp","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/05\/01\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\/#mainImage","width":1440,"height":810,"caption":"Chus Mateo en rueda de prensa. Fuente: Real Madrid"},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/05\/01\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\/#mainImage"},"datePublished":"2025-05-01T02:59:02+02:00","dateModified":"2025-05-01T03:07:10+02:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"Chus Mateo: \u00abLa experiencia nos dice que hay que seguir hasta el final\u00bb \u2013 Agente Libre Digital","og:description":"Chus Mateo: \u00abLa experiencia nos dice que hay que seguir hasta el final\u00bb El t\u00e9cnico del Madrid ha atendido a la prensa antes del cuarto partido ante Olympiacos","og:url":"https:\/\/agentelibredigital.com\/index.php\/2025\/05\/01\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/05\/ND_RP_CHUS_MATEO_SG26754.webp","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/05\/ND_RP_CHUS_MATEO_SG26754.webp","og:image:width":1440,"og:image:height":810,"article:published_time":"2025-05-01T00:59:02+00:00","article:modified_time":"2025-05-01T01:07:10+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"Chus Mateo: \u00abLa experiencia nos dice que hay que seguir hasta el final\u00bb \u2013 Agente Libre Digital","twitter:description":"Chus Mateo: \u00abLa experiencia nos dice que hay que seguir hasta el final\u00bb El t\u00e9cnico del Madrid ha atendido a la prensa antes del cuarto partido ante Olympiacos","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/05\/ND_RP_CHUS_MATEO_SG26754.webp"},"aioseo_meta_data":{"post_id":"47344","title":null,"description":"#post_title El t\u00e9cnico del Madrid ha atendido a la prensa antes del cuarto partido ante Olympiacos","keywords":null,"keyphrases":{"focus":{"keyphrase":"Chus Mateo","score":78,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-05-01 00:59:02","updated":"2025-06-05 14:09:50","seo_analyzer_scan_date":null,"focus_keyword":"Chus Mateo","additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/real-madrid\/\" title=\"Real Madrid\">Real Madrid<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tChus Mateo: \u00abLa experiencia nos dice que hay que seguir hasta el final\u00bb\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"Real Madrid","link":"https:\/\/agentelibredigital.com\/index.php\/category\/real-madrid\/"},{"label":"Chus Mateo: \u00abLa experiencia nos dice que hay que seguir hasta el final\u00bb","link":"https:\/\/agentelibredigital.com\/index.php\/2025\/05\/01\/chus-mateo-la-experiencia-nos-dice-que-hay-que-seguir-hasta-el-final\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/47344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=47344"}],"version-history":[{"count":2,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/47344\/revisions"}],"predecessor-version":[{"id":47351,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/47344\/revisions\/47351"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/47346"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=47344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=47344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=47344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}