{"id":44647,"date":"2025-03-16T16:24:17","date_gmt":"2025-03-16T15:24:17","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=44647"},"modified":"2025-03-16T16:26:32","modified_gmt":"2025-03-16T15:26:32","slug":"arsenal-1-chelsea-0-merino-se-gana-londres","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2025\/03\/16\/arsenal-1-chelsea-0-merino-se-gana-londres\/","title":{"rendered":"Arsenal 1 &#8211; Chelsea 0: Merino se gana Londres"},"content":{"rendered":"<p><strong>Mikel Merino da la victoria al Arsenal en el derbi de Londres con un gol de cabeza, su sexto este curso. El Chelsea no cre\u00f3 demasiado peligro y Enzo Maresca pag\u00f3 cara la ausencia de Cole Palmer.<\/strong><\/p>\n<p>El <a href=\"https:\/\/agentelibredigital.com\/?s=arsenal\"><strong>Arsenal<\/strong><\/a> se impuso al <a href=\"https:\/\/agentelibredigital.com\/?s=chelsea\"><strong>Chelsea<\/strong><\/a> en el derbi de Londres. <strong>Mikel Merino decidi\u00f3 el encuentro con un gol de c\u00f3rner<\/strong> y el Chelsea apenas gener\u00f3 ocasiones de peligro. <strong>Marc Cucurella<\/strong> fue de los mejores del equipo de Enzo Maresca, mientras que Mikel Arteta plante\u00f3 un encuentro muy serio en defensa. El derbi se sald\u00f3 con seis cartulinas amarillas.<\/p>\n<h2>Merino se disfraza de &#8216;killer&#8217;<\/h2>\n<p>La primera ocasi\u00f3n llego por parte de los locales. Una p\u00e9rdida en el centro del campo del <a href=\"https:\/\/www.chelseafc.com\/en\">Chelsea<\/a> acab\u00f3 con un <strong>peligroso disparo de Trossard<\/strong> que se march\u00f3 rozando el larguero. En la siguiente jugada peligrosa fue <strong>Robert S\u00e1nchez el causante de la p\u00e9rdida<\/strong>. Un pase que iba hacia Fofana, se qued\u00f3 corto y <strong>Martinelli<\/strong> fue el que lleg\u00f3 al pase. El extremo brasile\u00f1o fue el que finiquit\u00f3 la jugada con un disparo a las manos del ex del Brighton.<\/p>\n<p>Una <strong>ca\u00edda de Cucurella dentro del \u00e1rea casi condena al Chelsea<\/strong>. Timber puso el bal\u00f3n hacia Mikel Merino y una secuencia de rebotes entre los defensas &#8216;blues&#8217;, que incluso toc\u00f3 el palo, acab\u00f3 siendo finalizada por Declan Rice que la mand\u00f3 fuera.<\/p>\n<p>Las ocasiones m\u00e1s claras llegaron por parte del Arsenal. El Chelsea estaba pagando la ausencia de un delantero centro puro. <strong>Desde un saque de esquina<\/strong>, los <em>Gunners<\/em> anotaron su primer gol. Precisamente, fue de su \u00abdelantero\u00bb, <strong>Mikel Merino<\/strong>. El navarro pein\u00f3 en el primer palo un centro de <strong>Odegaard<\/strong> y sum\u00f3 su sexto gol desde esta posici\u00f3n.<\/p>\n<figure style=\"width: 2333px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/GmKsGkbWoAANuvw?format=jpg&amp;name=4096x4096\" alt=\"Merino celebra el gol con la afici\u00f3n del Arsenal. Fuente: Arsenal en &quot;X&quot;.\" width=\"2333\" height=\"3500\" \/><figcaption class=\"wp-caption-text\">Merino celebra el gol con la afici\u00f3n del Arsenal. Fuente: Arsenal en \u00abX\u00bb.<\/figcaption><\/figure>\n<p><strong>Marc Cucurella estuvo cerca de igualar el encuentro en el minuto 38<\/strong>. Despu\u00e9s de varios disparos rechazados, el bal\u00f3n lleg\u00f3 al lateral que con una volea logr\u00f3 intimidar a Raya. A pesar de interceptar el bal\u00f3n, se le march\u00f3 por debajo de las piernas al portero, en direcci\u00f3n a c\u00f3rner. En los \u00faltimos minutos de la primera parte, el Chelsea dio un paso hacia delante en cuanto a ocasiones, pero no fue suficiente para lograr la igualada antes del descanso.<\/p>\n<h2>Arteta pone el cerrojo<\/h2>\n<p>En la segunda parte aumentaron las pulsaciones. Pedro Neto y Gabriel vieron la amarilla en los primeros diez minutos de juego y en ambos equipos era latente la rivalidad londinense. Hasta seis jugadores fueron amonestados a lo largo del encuentro.<\/p>\n<p>En una r\u00e1pida jugada de ataque, <strong>Pedro Neto realiz\u00f3 el primero de los pocos acercamientos del Chelsea<\/strong> en la segunda mitad. A pase de Nkunku, el portugu\u00e9s prob\u00f3 fortuna desde lejos con la pierna izquierda. En la r\u00e9plica de la jugada, <strong>Robert S\u00e1nchez salv\u00f3 al Chelsea con un parad\u00f3n a una volea de Mikel Merino<\/strong>. El portero espa\u00f1ol sac\u00f3 el bal\u00f3n sobre la l\u00ednea.<\/p>\n<p>Los cambios aportaron algo de frescura al Chelsea que sigui\u00f3 acumulando bal\u00f3n hasta acercarse al \u00e1rea &#8216;gunner&#8217;, pero no gener\u00f3 ninguna ocasi\u00f3n clara. Los de Mikel Arteta estuvieron bien posicionados hasta el final y no concedieron en defensa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mikel Merino da la victoria al Arsenal en el derbi de Londres con un gol de cabeza, su sexto este curso. El Chelsea no cre\u00f3 demasiado peligro y Enzo Maresca&hellip; <\/p>\n","protected":false},"author":233,"featured_media":44648,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[48,32],"tags":[231,397,431,1736,3812,230],"class_list":["post-44647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol-internacional","category-premier-league","tag-arsenal","tag-chelsea","tag-mikel-arteta","tag-mikel-merino","tag-odegaard","tag-premier-league"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Mikel Merino da la victoria al Arsenal en el derbi de Londres con un gol de cabeza, su sexto este curso. El Chelsea no cre\u00f3 demasiado peligro\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Marcos Del Bano Baena\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2025\/03\/16\/arsenal-1-chelsea-0-merino-se-gana-londres\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Arsenal 1 \u2013 Chelsea 0: Merino se gana Londres \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"Mikel Merino da la victoria al Arsenal en el derbi de Londres con un gol de cabeza, su sexto este curso. El Chelsea no cre\u00f3 demasiado peligro\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2025\/03\/16\/arsenal-1-chelsea-0-merino-se-gana-londres\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/03\/Merino-decide-el-derbi-de-Londres.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/03\/Merino-decide-el-derbi-de-Londres.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1086\" \/>\n\t\t<meta property=\"og:image:height\" content=\"624\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-03-16T15:24:17+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-03-16T15:26:32+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Arsenal 1 \u2013 Chelsea 0: Merino se gana Londres \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Mikel Merino da la victoria al Arsenal en el derbi de Londres con un gol de cabeza, su sexto este curso. El Chelsea no cre\u00f3 demasiado peligro\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/03\/Merino-decide-el-derbi-de-Londres.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/03\\\/16\\\/arsenal-1-chelsea-0-merino-se-gana-londres\\\/#blogposting\",\"name\":\"Arsenal 1 \\u2013 Chelsea 0: Merino se gana Londres \\u2013 Agente Libre Digital\",\"headline\":\"Arsenal 1 &#8211; Chelsea 0: Merino se gana Londres\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-del-bano-baena\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Merino-decide-el-derbi-de-Londres.jpg\",\"width\":1086,\"height\":624,\"caption\":\"Merino decide el derbi de Londres. AFC picks en \\\"X\\\".\"},\"datePublished\":\"2025-03-16T16:24:17+01:00\",\"dateModified\":\"2025-03-16T16:26:32+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/03\\\/16\\\/arsenal-1-chelsea-0-merino-se-gana-londres\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/03\\\/16\\\/arsenal-1-chelsea-0-merino-se-gana-londres\\\/#webpage\"},\"articleSection\":\"F\\u00fatbol Internacional, Premier League, Arsenal, Chelsea, Mikel Arteta, Mikel Merino, Odegaard, Premier league\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/03\\\/16\\\/arsenal-1-chelsea-0-merino-se-gana-londres\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/premier-league\\\/#listItem\",\"name\":\"Premier League\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/premier-league\\\/#listItem\",\"position\":2,\"name\":\"Premier League\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/premier-league\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/03\\\/16\\\/arsenal-1-chelsea-0-merino-se-gana-londres\\\/#listItem\",\"name\":\"Arsenal 1 &#8211; Chelsea 0: Merino se gana Londres\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/03\\\/16\\\/arsenal-1-chelsea-0-merino-se-gana-londres\\\/#listItem\",\"position\":3,\"name\":\"Arsenal 1 &#8211; Chelsea 0: Merino se gana Londres\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/premier-league\\\/#listItem\",\"name\":\"Premier League\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/03\\\/16\\\/arsenal-1-chelsea-0-merino-se-gana-londres\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/03\\\/16\\\/arsenal-1-chelsea-0-merino-se-gana-londres\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-del-bano-baena\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-del-bano-baena\\\/\",\"name\":\"Marcos Del Bano Baena\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/03\\\/16\\\/arsenal-1-chelsea-0-merino-se-gana-londres\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/819c4f9323cbff5bd7b2b37138b723ccfc249e824af35f334f827118cf092e48?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Marcos Del Bano Baena\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/03\\\/16\\\/arsenal-1-chelsea-0-merino-se-gana-londres\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/03\\\/16\\\/arsenal-1-chelsea-0-merino-se-gana-londres\\\/\",\"name\":\"Arsenal 1 \\u2013 Chelsea 0: Merino se gana Londres \\u2013 Agente Libre Digital\",\"description\":\"Mikel Merino da la victoria al Arsenal en el derbi de Londres con un gol de cabeza, su sexto este curso. El Chelsea no cre\\u00f3 demasiado peligro\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/03\\\/16\\\/arsenal-1-chelsea-0-merino-se-gana-londres\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-del-bano-baena\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-del-bano-baena\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Merino-decide-el-derbi-de-Londres.jpg\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/03\\\/16\\\/arsenal-1-chelsea-0-merino-se-gana-londres\\\/#mainImage\",\"width\":1086,\"height\":624,\"caption\":\"Merino decide el derbi de Londres. AFC picks en \\\"X\\\".\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2025\\\/03\\\/16\\\/arsenal-1-chelsea-0-merino-se-gana-londres\\\/#mainImage\"},\"datePublished\":\"2025-03-16T16:24:17+01:00\",\"dateModified\":\"2025-03-16T16:26:32+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Arsenal 1 \u2013 Chelsea 0: Merino se gana Londres \u2013 Agente Libre Digital","description":"Mikel Merino da la victoria al Arsenal en el derbi de Londres con un gol de cabeza, su sexto este curso. El Chelsea no cre\u00f3 demasiado peligro","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2025\/03\/16\/arsenal-1-chelsea-0-merino-se-gana-londres\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/03\/16\/arsenal-1-chelsea-0-merino-se-gana-londres\/#blogposting","name":"Arsenal 1 \u2013 Chelsea 0: Merino se gana Londres \u2013 Agente Libre Digital","headline":"Arsenal 1 &#8211; Chelsea 0: Merino se gana Londres","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-del-bano-baena\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/03\/Merino-decide-el-derbi-de-Londres.jpg","width":1086,"height":624,"caption":"Merino decide el derbi de Londres. AFC picks en \"X\"."},"datePublished":"2025-03-16T16:24:17+01:00","dateModified":"2025-03-16T16:26:32+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/03\/16\/arsenal-1-chelsea-0-merino-se-gana-londres\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/03\/16\/arsenal-1-chelsea-0-merino-se-gana-londres\/#webpage"},"articleSection":"F\u00fatbol Internacional, Premier League, Arsenal, Chelsea, Mikel Arteta, Mikel Merino, Odegaard, Premier league"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/03\/16\/arsenal-1-chelsea-0-merino-se-gana-londres\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/premier-league\/#listItem","name":"Premier League"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/premier-league\/#listItem","position":2,"name":"Premier League","item":"https:\/\/agentelibredigital.com\/index.php\/category\/premier-league\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/03\/16\/arsenal-1-chelsea-0-merino-se-gana-londres\/#listItem","name":"Arsenal 1 &#8211; Chelsea 0: Merino se gana Londres"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/03\/16\/arsenal-1-chelsea-0-merino-se-gana-londres\/#listItem","position":3,"name":"Arsenal 1 &#8211; Chelsea 0: Merino se gana Londres","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/premier-league\/#listItem","name":"Premier League"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/03\/16\/arsenal-1-chelsea-0-merino-se-gana-londres\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/03\/16\/arsenal-1-chelsea-0-merino-se-gana-londres\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-del-bano-baena\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-del-bano-baena\/","name":"Marcos Del Bano Baena","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/03\/16\/arsenal-1-chelsea-0-merino-se-gana-londres\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/819c4f9323cbff5bd7b2b37138b723ccfc249e824af35f334f827118cf092e48?s=96&d=mm&r=g","width":96,"height":96,"caption":"Marcos Del Bano Baena"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/03\/16\/arsenal-1-chelsea-0-merino-se-gana-londres\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2025\/03\/16\/arsenal-1-chelsea-0-merino-se-gana-londres\/","name":"Arsenal 1 \u2013 Chelsea 0: Merino se gana Londres \u2013 Agente Libre Digital","description":"Mikel Merino da la victoria al Arsenal en el derbi de Londres con un gol de cabeza, su sexto este curso. El Chelsea no cre\u00f3 demasiado peligro","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/03\/16\/arsenal-1-chelsea-0-merino-se-gana-londres\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-del-bano-baena\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-del-bano-baena\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/03\/Merino-decide-el-derbi-de-Londres.jpg","@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/03\/16\/arsenal-1-chelsea-0-merino-se-gana-londres\/#mainImage","width":1086,"height":624,"caption":"Merino decide el derbi de Londres. AFC picks en \"X\"."},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2025\/03\/16\/arsenal-1-chelsea-0-merino-se-gana-londres\/#mainImage"},"datePublished":"2025-03-16T16:24:17+01:00","dateModified":"2025-03-16T16:26:32+01:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"Arsenal 1 \u2013 Chelsea 0: Merino se gana Londres \u2013 Agente Libre Digital","og:description":"Mikel Merino da la victoria al Arsenal en el derbi de Londres con un gol de cabeza, su sexto este curso. El Chelsea no cre\u00f3 demasiado peligro","og:url":"https:\/\/agentelibredigital.com\/index.php\/2025\/03\/16\/arsenal-1-chelsea-0-merino-se-gana-londres\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/03\/Merino-decide-el-derbi-de-Londres.jpg","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/03\/Merino-decide-el-derbi-de-Londres.jpg","og:image:width":1086,"og:image:height":624,"article:published_time":"2025-03-16T15:24:17+00:00","article:modified_time":"2025-03-16T15:26:32+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"Arsenal 1 \u2013 Chelsea 0: Merino se gana Londres \u2013 Agente Libre Digital","twitter:description":"Mikel Merino da la victoria al Arsenal en el derbi de Londres con un gol de cabeza, su sexto este curso. El Chelsea no cre\u00f3 demasiado peligro","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2025\/03\/Merino-decide-el-derbi-de-Londres.jpg"},"aioseo_meta_data":{"post_id":"44647","title":null,"description":"Mikel Merino da la victoria al Arsenal en el derbi de Londres con un gol de cabeza, su sexto este curso. El Chelsea no cre\u00f3 demasiado peligro","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-03-16 15:24:17","updated":"2025-06-05 12:10:50","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/premier-league\/\" title=\"Premier League\">Premier League<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tArsenal 1 \u2013 Chelsea 0: Merino se gana Londres\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"Premier League","link":"https:\/\/agentelibredigital.com\/index.php\/category\/premier-league\/"},{"label":"Arsenal 1 &#8211; Chelsea 0: Merino se gana Londres","link":"https:\/\/agentelibredigital.com\/index.php\/2025\/03\/16\/arsenal-1-chelsea-0-merino-se-gana-londres\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/44647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/233"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=44647"}],"version-history":[{"count":3,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/44647\/revisions"}],"predecessor-version":[{"id":44652,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/44647\/revisions\/44652"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/44648"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=44647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=44647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=44647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}