{"id":37436,"date":"2024-12-07T18:42:20","date_gmt":"2024-12-07T17:42:20","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=37436"},"modified":"2024-12-07T18:48:29","modified_gmt":"2024-12-07T17:48:29","slug":"betis-barca-puntuaciones-fc-barcelona","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/07\/betis-barca-puntuaciones-fc-barcelona\/","title":{"rendered":"Betis-Bar\u00e7a: Puntuaciones FC Barcelona"},"content":{"rendered":"<h4><strong>El FC Barcelona pincha a domicilio por tercera vez este curso y aviva la liga<\/strong><\/h4>\n<p>Los de Hansi Flick empataron a dos y vuelve a allanarles el camino a Madrid y Atl\u00e9tico, sus principales perseguidores. El MVP del partido fue Lamine Yamal que sum\u00f3 otra asistencia.<\/p>\n<h2><strong>Titulares<\/strong><\/h2>\n<p>Pe\u00f1a: (8) Nada mas comenzar el encuentro\u00a0 hizo una parada de mucho m\u00e9rito a Abde en un mano a mano. En la segunda parte tras un disparo seco abajo sac\u00f3 una mano que record\u00f3 a Ter Stegen. En el penalti adivin\u00f3 el lado del golpe\u00f3 pero no pudo hacer nada. Gran partido del meta alicantino.<\/p>\n<p>Cubars\u00ed(6): Partido especial para el central ya que el a\u00f1o pasado fue en este mismo estadio donde hizo su debut con la el\u00e1stica azulgrana. Hoy correcto en defensa y muy pulcro en la salida de bal\u00f3n. Buen partido en lineas generales<\/p>\n<p>I\u00f1igo M(6): Es el jefe de la defensa blaugrana. En defensa resolvi\u00f3 bien y con el bal\u00f3n, al igual que Cubars\u00ed estuvo bien<\/p>\n<p>Balde(4): Flojo partido del lateral espa\u00f1ol. En defensa no ha tenido mucho trabajo pero se ha visto superado varias veces por su par. En ataque lo ha intentado pero no le ha salido nada.<\/p>\n<p>Kound\u00e9(5): Abde fue un constante dolor de cabeza para el lateral frances. De sus botas sali\u00f3 la asistencia del primer gol. Suma ya 6 pases de gol esta temporada.<\/p>\n<p>Casad\u00f3(6): Correcto durante todo el partido. Sabe donde tiene que estar siempre.<\/p>\n<p>Pedri(7): Una genialidad suya, fue la que le ayud\u00f3 a Kound\u00e9 a dar la asistencia que abr\u00eda el marcador. Cada partido deja destellos de su magia. Hoy gran partido otra vez.<\/p>\n<p>Olmo(5): El de Terrasa no ha tenido su mejor partido. Ha bajado varias veces a ayudar en defensa. Fue sustituido en el minuto 60.<\/p>\n<p>Raphinha(5): En el minuto 1 salv\u00f3 bajo palos el gol de Llorente. Ha hecho varios regates que solo se ven en f\u00fatbol sala. Hoy no ha podido ver puerta. Hansi lo cambi\u00f3 en el minuto 60 junto con Olmo ya que es el jugador que m\u00e1s minutos acumula de la plantilla.<\/p>\n<p>Lamine Y(9): Otro gran partido el suyo hoy. En la primera parte ha estado un poco desaparecido pero ya en la segunda mitad se ha ido entonando y suyo ha sido la asistencia del segundo gol. Fue nombrado MVP del partido<\/p>\n<p>Lewandowski(7): No ha generado muchas ocasiones pero siempre est\u00e1 donde se le necesita, y por esa raz\u00f3n suma ya 16 goles en liga lo que le hace m\u00e1s pichichi todav\u00eda.<\/p>\n<figure style=\"width: 1028px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/media.gettyimages.com\/id\/2188734778\/es\/foto\/seville-spain-ferran-torres-of-fc-barcelona-celebrates-scoring-his-teams-second-goal-by.jpg?s=612x612&amp;w=0&amp;k=20&amp;c=9SMPgHcdBlwo4LnWVHWMpGui64XGMaAyaNg0NbIXd9g=\" alt=\"Ferran Torres of FC Barcelona celebrates scoring his team's second goal by displaying a t-shirt honouring the victims of the floodings in Valencia...\" width=\"1028\" height=\"685\" \/><figcaption class=\"wp-caption-text\">Ferr\u00e1n celebrando el segundo gol. Fuente: Getty Images<\/figcaption><\/figure>\n<h2><strong>Suplentes<\/strong><\/h2>\n<p>De Jong(0): Entr\u00f3 en la ultima media hora del partido y fue el el que provoc\u00f3 el penalti que permiti\u00f3 al Betis meterse en el partido. No tuvo ninguna trascendencia en el partido.<\/p>\n<p>Ferr\u00e1n(6): Otro gol que suma el delantero de Foios. Ya son dos en sus \u00faltimos 2 partidos. Su insistencia tuvo \u00e9xito.<\/p>\n<p>Gavi: N\/C<\/p>\n<p>Fort: N\/C<\/p>\n<p>Pau V\u00edctor: N\/C<\/p>\n<p>Autor del art\u00edculo <a href=\"https:\/\/agentelibredigital.com\/?s=salva+lluch\">Salva Lluch<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El FC Barcelona pincha a domicilio por tercera vez este curso y aviva la liga Los de Hansi Flick empataron a dos y vuelve a allanarles el camino a Madrid&hellip; <\/p>\n","protected":false},"author":217,"featured_media":37460,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[12,46],"tags":[55,2799,1013,1062,612],"class_list":["post-37436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fc-barcelona","category-laliga-ea-sports","tag-fc-barcelona","tag-hansi-flick","tag-lewandoski","tag-raphinha","tag-real-betis-balompie"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Betis-Bar\u00e7a: Puntuaciones FC Barcelona\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Salva Lluch\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/07\/betis-barca-puntuaciones-fc-barcelona\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Betis-Bar\u00e7a: Puntuaciones FC Barcelona \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"Betis-Bar\u00e7a: Puntuaciones FC Barcelona\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/07\/betis-barca-puntuaciones-fc-barcelona\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/12\/gettyimages-2188734729-612x612-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/12\/gettyimages-2188734729-612x612-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"612\" \/>\n\t\t<meta property=\"og:image:height\" content=\"408\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-12-07T17:42:20+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-12-07T17:48:29+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Betis-Bar\u00e7a: Puntuaciones FC Barcelona \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Betis-Bar\u00e7a: Puntuaciones FC Barcelona\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/12\/gettyimages-2188734729-612x612-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/07\\\/betis-barca-puntuaciones-fc-barcelona\\\/#blogposting\",\"name\":\"Betis-Bar\\u00e7a: Puntuaciones FC Barcelona \\u2013 Agente Libre Digital\",\"headline\":\"Betis-Bar\\u00e7a: Puntuaciones FC Barcelona\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/salva-lluch\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/gettyimages-2188734729-612x612-1.jpg\",\"width\":612,\"height\":408,\"caption\":\"(Photo by Diego Souto\\\/Getty Images)\"},\"datePublished\":\"2024-12-07T18:42:20+01:00\",\"dateModified\":\"2024-12-07T18:48:29+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/07\\\/betis-barca-puntuaciones-fc-barcelona\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/07\\\/betis-barca-puntuaciones-fc-barcelona\\\/#webpage\"},\"articleSection\":\"FC Barcelona, LaLiga EA Sports, FC Barcelona, Hansi Flick, Lewandoski, raphinha, Real Betis Balompi\\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/07\\\/betis-barca-puntuaciones-fc-barcelona\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/fc-barcelona\\\/#listItem\",\"name\":\"FC Barcelona\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/fc-barcelona\\\/#listItem\",\"position\":2,\"name\":\"FC Barcelona\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/fc-barcelona\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/07\\\/betis-barca-puntuaciones-fc-barcelona\\\/#listItem\",\"name\":\"Betis-Bar\\u00e7a: Puntuaciones FC Barcelona\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/07\\\/betis-barca-puntuaciones-fc-barcelona\\\/#listItem\",\"position\":3,\"name\":\"Betis-Bar\\u00e7a: Puntuaciones FC Barcelona\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/fc-barcelona\\\/#listItem\",\"name\":\"FC Barcelona\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/07\\\/betis-barca-puntuaciones-fc-barcelona\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/07\\\/betis-barca-puntuaciones-fc-barcelona\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/salva-lluch\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/salva-lluch\\\/\",\"name\":\"Salva Lluch\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/07\\\/betis-barca-puntuaciones-fc-barcelona\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72be4057f9cc4b54209227cc595d32d95212e6df2927b98ee69497c26526d38d?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Salva Lluch\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/07\\\/betis-barca-puntuaciones-fc-barcelona\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/07\\\/betis-barca-puntuaciones-fc-barcelona\\\/\",\"name\":\"Betis-Bar\\u00e7a: Puntuaciones FC Barcelona \\u2013 Agente Libre Digital\",\"description\":\"Betis-Bar\\u00e7a: Puntuaciones FC Barcelona\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/07\\\/betis-barca-puntuaciones-fc-barcelona\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/salva-lluch\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/salva-lluch\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/gettyimages-2188734729-612x612-1.jpg\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/07\\\/betis-barca-puntuaciones-fc-barcelona\\\/#mainImage\",\"width\":612,\"height\":408,\"caption\":\"(Photo by Diego Souto\\\/Getty Images)\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/07\\\/betis-barca-puntuaciones-fc-barcelona\\\/#mainImage\"},\"datePublished\":\"2024-12-07T18:42:20+01:00\",\"dateModified\":\"2024-12-07T18:48:29+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Betis-Bar\u00e7a: Puntuaciones FC Barcelona \u2013 Agente Libre Digital","description":"Betis-Bar\u00e7a: Puntuaciones FC Barcelona","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/07\/betis-barca-puntuaciones-fc-barcelona\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/07\/betis-barca-puntuaciones-fc-barcelona\/#blogposting","name":"Betis-Bar\u00e7a: Puntuaciones FC Barcelona \u2013 Agente Libre Digital","headline":"Betis-Bar\u00e7a: Puntuaciones FC Barcelona","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/salva-lluch\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/12\/gettyimages-2188734729-612x612-1.jpg","width":612,"height":408,"caption":"(Photo by Diego Souto\/Getty Images)"},"datePublished":"2024-12-07T18:42:20+01:00","dateModified":"2024-12-07T18:48:29+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/07\/betis-barca-puntuaciones-fc-barcelona\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/07\/betis-barca-puntuaciones-fc-barcelona\/#webpage"},"articleSection":"FC Barcelona, LaLiga EA Sports, FC Barcelona, Hansi Flick, Lewandoski, raphinha, Real Betis Balompi\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/07\/betis-barca-puntuaciones-fc-barcelona\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/fc-barcelona\/#listItem","name":"FC Barcelona"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/fc-barcelona\/#listItem","position":2,"name":"FC Barcelona","item":"https:\/\/agentelibredigital.com\/index.php\/category\/fc-barcelona\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/07\/betis-barca-puntuaciones-fc-barcelona\/#listItem","name":"Betis-Bar\u00e7a: Puntuaciones FC Barcelona"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/07\/betis-barca-puntuaciones-fc-barcelona\/#listItem","position":3,"name":"Betis-Bar\u00e7a: Puntuaciones FC Barcelona","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/fc-barcelona\/#listItem","name":"FC Barcelona"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/07\/betis-barca-puntuaciones-fc-barcelona\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/07\/betis-barca-puntuaciones-fc-barcelona\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/salva-lluch\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/salva-lluch\/","name":"Salva Lluch","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/07\/betis-barca-puntuaciones-fc-barcelona\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/72be4057f9cc4b54209227cc595d32d95212e6df2927b98ee69497c26526d38d?s=96&d=mm&r=g","width":96,"height":96,"caption":"Salva Lluch"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/07\/betis-barca-puntuaciones-fc-barcelona\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/07\/betis-barca-puntuaciones-fc-barcelona\/","name":"Betis-Bar\u00e7a: Puntuaciones FC Barcelona \u2013 Agente Libre Digital","description":"Betis-Bar\u00e7a: Puntuaciones FC Barcelona","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/07\/betis-barca-puntuaciones-fc-barcelona\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/salva-lluch\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/salva-lluch\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/12\/gettyimages-2188734729-612x612-1.jpg","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/07\/betis-barca-puntuaciones-fc-barcelona\/#mainImage","width":612,"height":408,"caption":"(Photo by Diego Souto\/Getty Images)"},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/07\/betis-barca-puntuaciones-fc-barcelona\/#mainImage"},"datePublished":"2024-12-07T18:42:20+01:00","dateModified":"2024-12-07T18:48:29+01:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"Betis-Bar\u00e7a: Puntuaciones FC Barcelona \u2013 Agente Libre Digital","og:description":"Betis-Bar\u00e7a: Puntuaciones FC Barcelona","og:url":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/07\/betis-barca-puntuaciones-fc-barcelona\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/12\/gettyimages-2188734729-612x612-1.jpg","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/12\/gettyimages-2188734729-612x612-1.jpg","og:image:width":612,"og:image:height":408,"article:published_time":"2024-12-07T17:42:20+00:00","article:modified_time":"2024-12-07T17:48:29+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"Betis-Bar\u00e7a: Puntuaciones FC Barcelona \u2013 Agente Libre Digital","twitter:description":"Betis-Bar\u00e7a: Puntuaciones FC Barcelona","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/12\/gettyimages-2188734729-612x612-1.jpg"},"aioseo_meta_data":{"post_id":"37436","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-12-07 16:15:35","updated":"2025-06-05 07:01:02","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/fc-barcelona\/\" title=\"FC Barcelona\">FC Barcelona<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tBetis-Bar\u00e7a: Puntuaciones FC Barcelona\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"FC Barcelona","link":"https:\/\/agentelibredigital.com\/index.php\/category\/fc-barcelona\/"},{"label":"Betis-Bar\u00e7a: Puntuaciones FC Barcelona","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/07\/betis-barca-puntuaciones-fc-barcelona\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/37436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/217"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=37436"}],"version-history":[{"count":4,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/37436\/revisions"}],"predecessor-version":[{"id":37465,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/37436\/revisions\/37465"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/37460"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=37436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=37436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=37436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}