{"id":37053,"date":"2024-12-04T08:30:44","date_gmt":"2024-12-04T07:30:44","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=37053"},"modified":"2024-12-04T17:19:52","modified_gmt":"2024-12-04T16:19:52","slug":"cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/04\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\/","title":{"rendered":"CD Estepona &#8211; CD Legan\u00e9s: el sue\u00f1o malague\u00f1o ante un Haller hambriento"},"content":{"rendered":"<h4>El <a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/leganes\/\">CD Legan\u00e9s<\/a> visitar\u00e1 el Francisco Mu\u00f1oz P\u00e9rez para tratar de pasar a los dieciseisavos de final de la <a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/copa-del-rey\/\">Copa del Rey<\/a> ante el Estepona<\/h4>\n<p>Este mi\u00e9rcoles <strong>4 de diciembre a las 21:00<\/strong> horas, el sur de M\u00e1laga acoger\u00e1 un encuentro apasionante entre esteponeros y pepineros. <strong>Borja Jim\u00e9nez<\/strong>, entrenador de los visitantes, zanj\u00f3 que el ariete costamarfile\u00f1o ser\u00e1 hoy titular. Por otro lado, la entidad entrenada por <strong>Oriol Riera<\/strong> y presidida por <strong>Hidalgo<\/strong>, ex del <strong>Salamanca<\/strong>, han colgado el cartel de \u00abno hay billetes\u00bb y, con un aforo de <strong>3.800 espectadores<\/strong>, llenar\u00e1n el feudo rojillo para recibir al <strong>&#8216;Lega&#8217;<\/strong>. Dicho enfrentamiento, ser\u00e1 arbitrado por <strong>Hern\u00e1ndez Maeso<\/strong> y televisado en <strong>Movistar LaLiga TV 3<\/strong>.<\/p>\n<h2>La ilusi\u00f3n de cargarse a un primera<\/h2>\n<p>El equipo andaluz, de <strong>Segunda RFEF<\/strong>, volver\u00e1 a vivir otra noche m\u00e1gica de <a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/copa-del-rey\/\"><strong>Copa del Rey<\/strong><\/a>, tras ser una de las grandes sorpresas de la primera ronda eliminando al <strong>M\u00e1laga por 3-2 en la pr\u00f3rroga<\/strong>. En lo que es el <strong>grupo IV<\/strong> de la <strong>Segunda Federaci\u00f3n<\/strong>, los dirigidos por el ex jugador <strong>Oriol Riera<\/strong>, se sit\u00faan en un punto medio de la tabla, estando a dos puntos de posiciones play-off y a tres de puestos rojos.<\/p>\n<p>Los de\u00a0<strong>Estepona<\/strong>, sin embargo, no llegan en su mejor momento para mantenerse viviendo en una nube. <strong>Tres derrotas consecutivas<\/strong>, hacen ser un poco m\u00e1s pesimistas a la afici\u00f3n. A\u00fan as\u00ed, \u00e9stos mismos, conf\u00edan en que esto cambie esta noche, repitiendo la gesta en casa hace ya m\u00e1s de un mes en la primera ronda copera. El t\u00e9cnico puede poner sobre el tapete una\u00a0<b>alineaci\u00f3n similar<\/b>\u00a0a la que logr\u00f3\u00a0<b>eliminar\u00a0<\/b>a los\u00a0<b>malaguistas<\/b>\u00a0con dos jugadores interesantes en su delantera, el costamarfile\u00f1o\u00a0<b>Jacques Dago y el ex del Recreativo Rub\u00e9n Mesa.<\/b>\u00a0Para contrarrestar a los pepineros, Riera podr\u00eda plantear una defensa con tres centrales. La \u00fanica\u00a0<b>baja\u00a0<\/b>es la de\u00a0<b>Fran Callej\u00f3n<\/b>, el mediocentro se lesion\u00f3 hace unas semanas.<\/p>\n<figure style=\"width: 680px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/aficiondeportiva.es\/wp-content\/uploads\/2024\/12\/Gdt1U-UXAAArYxJ.jpeg\" alt=\"\" width=\"680\" height=\"510\" \/><figcaption class=\"wp-caption-text\">Once titular del CD Estepona en su \u00faltimo compromiso. Fuente: X Estepona<\/figcaption><\/figure>\n<h2>Un Legan\u00e9s necesidad de querer seguir avanzando<\/h2>\n<p>El\u00a0<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/leganes\/\"><strong>CD Legan\u00e9s<\/strong> <\/a>\u00a0accedi\u00f3 a esta ronda tras vencer al\u00a0<strong>Ciudad de Lucena (1-2)<\/strong>\u00a0en la primera eliminatoria, con goles de <strong>Munir y <a href=\"https:\/\/onefootball.com\/es\/noticias\/juan-cruz-argentina-o-espana-quien-sabe-40371467\">Juan Cruz<\/a><\/strong>. Los del t\u00e9cnico abulense,\u00a0buscar\u00e1n hacer valer su condici\u00f3n de favoritos ante un rival de menor categor\u00eda, si bien contar\u00e1n con las bajas de <strong>Brasanac y Miguel<\/strong>, con molestias, y la duda de <strong>Ciss\u00e9<\/strong>. Asimismo, <strong>Nastasic y Neyou<\/strong> permanecer\u00e1n en el municipio del sur madrile\u00f1o tras el excesivo minutaje con la mirada puesta en el partido ante la <strong>Real Sociedad<\/strong> del domingo en <strong>Butarque<\/strong>.<\/p>\n<p>Se espera que jugadores como <strong>S\u00e9bastien Haller<\/strong> den un paso al frente y demuestren, en lo que puede ser (o no), un escenario perfecto para reivindicarse. Esto ha sido confirmado por <strong>Borja<\/strong> en la rueda de prensa previa: \u00abS\u00ed, la idea de ma\u00f1ana es que<strong>\u00a0\u2018Seb\u2019\u00a0sea titular<\/strong>. Queremos que acumule esos minutos que no est\u00e1 teniendo en liga y que haga un buen partido. Ha entrenado con normalidad y esperemos que ma\u00f1ana tenga suerte de cara al gol. Ojal\u00e1 haga su primer gol oficial con nosotros, que tenemos much\u00edsimas ganas\u00bb.<\/p>\n<p>Los pepineros tambi\u00e9n deber\u00e1n asumir algunas complicaciones, ya que, como bien dec\u00eda el m\u00edster de los blanquiazules, <strong>el verde es de c\u00e9sped artificial<\/strong>: \u00abEs verdad que volvemos a un campo de hierba artificial. Ah\u00ed, hemos tenido mala suerte en el sorteo. A los futbolistas les afecta en articulaciones los cambios de superficie. El d\u00eda despu\u00e9s ser\u00e1 complejo.\u00bb<\/p>\n<figure id=\"attachment_36479\" aria-describedby=\"caption-attachment-36479\" style=\"width: 455px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-36479\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/11\/GbKQdxBW0AAxyBD-300x300.webp\" alt=\"Legan\u00e9s\" width=\"455\" height=\"455\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/11\/GbKQdxBW0AAxyBD-300x300.webp 300w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/11\/GbKQdxBW0AAxyBD-150x150.webp 150w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/11\/GbKQdxBW0AAxyBD.webp 680w\" sizes=\"auto, (max-width: 455px) 100vw, 455px\" \/><figcaption id=\"caption-attachment-36479\" class=\"wp-caption-text\">Roberto L\u00f3pez sorteando a futbolistas del Ciudad de Lucena en la Copa del Rey. (Foto: CD Legan\u00e9s \/redes sociales X)<\/figcaption><\/figure>\n<h2>Antecedentes<\/h2>\n<p>Ambos equipos, como era de esperar, no se han llegado a enfrentar nunca y ma\u00f1ana ser\u00e1 la primera vez que lo hagan.<\/p>\n<h2>Posibles alineaciones<\/h2>\n<p><strong>CD Estepona (1-4-3-3): <\/strong>Alfonso; Candelas, Mirapeix, Mar\u00edn, Lara; Bl\u00e1zquez, Nacho Goma, Jorge Garc\u00eda; Dago, Caro y Castillo.<\/p>\n<p><strong><a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/leganes\/\">CD Legan\u00e9s<\/a> (1-4-2-3-1): <\/strong>Juan Soriano; Adri\u00e0 Altimira, Jackson Porozo, Jorge S\u00e1enz, Iker Bachiller; Juli\u00e1n Chicco, Renato Tapia; Naim Garc\u00eda, Munir, Roberto L\u00f3pez; y Diego Garc\u00eda.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Art\u00edculo<\/strong>\u00a0redactado por\u00a0<em><strong><a href=\"https:\/\/agentelibredigital.com\/index.php\/author\/mario-garcia\/\">Mario Garc\u00eda Lorente<\/a><\/strong><\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El CD Legan\u00e9s visitar\u00e1 el Francisco Mu\u00f1oz P\u00e9rez para tratar de pasar a los dieciseisavos de final de la Copa del Rey ante el Estepona Este mi\u00e9rcoles 4 de diciembre&hellip; <\/p>\n","protected":false},"author":201,"featured_media":36477,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[2999,9,2911],"tags":[1227,631,2440,3420,1553,502,2926,124,3219,3158,1189,106,333,778,3422,1665,3244,3450,115],"class_list":["post-37053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2a-rfef","category-copa-del-rey","category-leganes","tag-2-rfef","tag-alaves","tag-borja-jimenez","tag-brasanac","tag-butarque","tag-cd-leganes","tag-cisse","tag-copa-del-rey","tag-estepona","tag-haller","tag-juan-cruz","tag-laliga-ea-sports","tag-malaga","tag-miguel-de-la-fuente","tag-munir","tag-nastasic","tag-neyou","tag-oriol-riera","tag-real-sociedad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El CD Legan\u00e9s visitar\u00e1 el Francisco Mu\u00f1oz P\u00e9rez para tratar de pasar a los dieciseisavos de final de la Copa del Rey ante el Estepona con Haller como titular\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Mario Garcia Lorente\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/04\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"CD Estepona \u2013 CD Legan\u00e9s: el sue\u00f1o malague\u00f1o ante un Haller hambriento \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"El CD Legan\u00e9s visitar\u00e1 el Francisco Mu\u00f1oz P\u00e9rez para tratar de pasar a los dieciseisavos de final de la Copa del Rey ante el Estepona con Haller como titular\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/04\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/11\/GbKDwx3WcAAIbYo.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/11\/GbKDwx3WcAAIbYo.webp\" \/>\n\t\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t\t<meta property=\"og:image:height\" content=\"425\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-12-04T07:30:44+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-12-04T16:19:52+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"CD Estepona \u2013 CD Legan\u00e9s: el sue\u00f1o malague\u00f1o ante un Haller hambriento \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El CD Legan\u00e9s visitar\u00e1 el Francisco Mu\u00f1oz P\u00e9rez para tratar de pasar a los dieciseisavos de final de la Copa del Rey ante el Estepona con Haller como titular\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/11\/GbKDwx3WcAAIbYo.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/04\\\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\\\/#blogposting\",\"name\":\"CD Estepona \\u2013 CD Legan\\u00e9s: el sue\\u00f1o malague\\u00f1o ante un Haller hambriento \\u2013 Agente Libre Digital\",\"headline\":\"CD Estepona &#8211; CD Legan\\u00e9s: el sue\\u00f1o malague\\u00f1o ante un Haller hambriento\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/mario-garcia\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/GbKDwx3WcAAIbYo.webp\",\"width\":680,\"height\":425,\"caption\":\"La alineaci\\u00f3n del 'Lega' ante el Ciudad de Lucena en Copa del Rey. (Foto: CD Legan\\u00e9s \\\/redes sociales X)\"},\"datePublished\":\"2024-12-04T08:30:44+01:00\",\"dateModified\":\"2024-12-04T17:19:52+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/04\\\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/04\\\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\\\/#webpage\"},\"articleSection\":\"2\\u00aa RFEF, Copa del Rey, Legan\\u00e9s, 2 RFEF, Alav\\u00e9s, Borja Jim\\u00e9nez, Brasanac, Butarque, CD Legan\\u00e9s, Ciss\\u00e9, Copa del Rey, Estepona, Haller, Juan Cruz, LaLiga EA Sports, M\\u00e1laga, Miguel de la Fuente, Munir, Nastasic, Neyou, Oriol Riera, Real sociedad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/04\\\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/copa-del-rey\\\/#listItem\",\"name\":\"Copa del Rey\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/copa-del-rey\\\/#listItem\",\"position\":2,\"name\":\"Copa del Rey\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/copa-del-rey\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/04\\\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\\\/#listItem\",\"name\":\"CD Estepona &#8211; CD Legan\\u00e9s: el sue\\u00f1o malague\\u00f1o ante un Haller hambriento\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/04\\\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\\\/#listItem\",\"position\":3,\"name\":\"CD Estepona &#8211; CD Legan\\u00e9s: el sue\\u00f1o malague\\u00f1o ante un Haller hambriento\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/copa-del-rey\\\/#listItem\",\"name\":\"Copa del Rey\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/04\\\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/04\\\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/mario-garcia\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/mario-garcia\\\/\",\"name\":\"Mario Garcia Lorente\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/04\\\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9cee5b687c544978451f4233e6af30db0c89983359bc0411d1434d76906390a1?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Mario Garcia Lorente\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/04\\\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/04\\\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\\\/\",\"name\":\"CD Estepona \\u2013 CD Legan\\u00e9s: el sue\\u00f1o malague\\u00f1o ante un Haller hambriento \\u2013 Agente Libre Digital\",\"description\":\"El CD Legan\\u00e9s visitar\\u00e1 el Francisco Mu\\u00f1oz P\\u00e9rez para tratar de pasar a los dieciseisavos de final de la Copa del Rey ante el Estepona con Haller como titular\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/04\\\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/mario-garcia\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/mario-garcia\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/GbKDwx3WcAAIbYo.webp\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/04\\\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\\\/#mainImage\",\"width\":680,\"height\":425,\"caption\":\"La alineaci\\u00f3n del 'Lega' ante el Ciudad de Lucena en Copa del Rey. (Foto: CD Legan\\u00e9s \\\/redes sociales X)\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/12\\\/04\\\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\\\/#mainImage\"},\"datePublished\":\"2024-12-04T08:30:44+01:00\",\"dateModified\":\"2024-12-04T17:19:52+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"CD Estepona \u2013 CD Legan\u00e9s: el sue\u00f1o malague\u00f1o ante un Haller hambriento \u2013 Agente Libre Digital","description":"El CD Legan\u00e9s visitar\u00e1 el Francisco Mu\u00f1oz P\u00e9rez para tratar de pasar a los dieciseisavos de final de la Copa del Rey ante el Estepona con Haller como titular","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/04\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/04\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\/#blogposting","name":"CD Estepona \u2013 CD Legan\u00e9s: el sue\u00f1o malague\u00f1o ante un Haller hambriento \u2013 Agente Libre Digital","headline":"CD Estepona &#8211; CD Legan\u00e9s: el sue\u00f1o malague\u00f1o ante un Haller hambriento","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/mario-garcia\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/11\/GbKDwx3WcAAIbYo.webp","width":680,"height":425,"caption":"La alineaci\u00f3n del 'Lega' ante el Ciudad de Lucena en Copa del Rey. (Foto: CD Legan\u00e9s \/redes sociales X)"},"datePublished":"2024-12-04T08:30:44+01:00","dateModified":"2024-12-04T17:19:52+01:00","inLanguage":"es-ES","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/04\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/04\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\/#webpage"},"articleSection":"2\u00aa RFEF, Copa del Rey, Legan\u00e9s, 2 RFEF, Alav\u00e9s, Borja Jim\u00e9nez, Brasanac, Butarque, CD Legan\u00e9s, Ciss\u00e9, Copa del Rey, Estepona, Haller, Juan Cruz, LaLiga EA Sports, M\u00e1laga, Miguel de la Fuente, Munir, Nastasic, Neyou, Oriol Riera, Real sociedad"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/04\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/copa-del-rey\/#listItem","name":"Copa del Rey"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/copa-del-rey\/#listItem","position":2,"name":"Copa del Rey","item":"https:\/\/agentelibredigital.com\/index.php\/category\/copa-del-rey\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/04\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\/#listItem","name":"CD Estepona &#8211; CD Legan\u00e9s: el sue\u00f1o malague\u00f1o ante un Haller hambriento"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/04\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\/#listItem","position":3,"name":"CD Estepona &#8211; CD Legan\u00e9s: el sue\u00f1o malague\u00f1o ante un Haller hambriento","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/copa-del-rey\/#listItem","name":"Copa del Rey"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/04\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/04\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/mario-garcia\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/mario-garcia\/","name":"Mario Garcia Lorente","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/04\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/9cee5b687c544978451f4233e6af30db0c89983359bc0411d1434d76906390a1?s=96&d=mm&r=g","width":96,"height":96,"caption":"Mario Garcia Lorente"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/04\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/04\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\/","name":"CD Estepona \u2013 CD Legan\u00e9s: el sue\u00f1o malague\u00f1o ante un Haller hambriento \u2013 Agente Libre Digital","description":"El CD Legan\u00e9s visitar\u00e1 el Francisco Mu\u00f1oz P\u00e9rez para tratar de pasar a los dieciseisavos de final de la Copa del Rey ante el Estepona con Haller como titular","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/04\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/mario-garcia\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/mario-garcia\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/11\/GbKDwx3WcAAIbYo.webp","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/04\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\/#mainImage","width":680,"height":425,"caption":"La alineaci\u00f3n del 'Lega' ante el Ciudad de Lucena en Copa del Rey. (Foto: CD Legan\u00e9s \/redes sociales X)"},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/04\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\/#mainImage"},"datePublished":"2024-12-04T08:30:44+01:00","dateModified":"2024-12-04T17:19:52+01:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"CD Estepona \u2013 CD Legan\u00e9s: el sue\u00f1o malague\u00f1o ante un Haller hambriento \u2013 Agente Libre Digital","og:description":"El CD Legan\u00e9s visitar\u00e1 el Francisco Mu\u00f1oz P\u00e9rez para tratar de pasar a los dieciseisavos de final de la Copa del Rey ante el Estepona con Haller como titular","og:url":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/04\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/11\/GbKDwx3WcAAIbYo.webp","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/11\/GbKDwx3WcAAIbYo.webp","og:image:width":680,"og:image:height":425,"article:published_time":"2024-12-04T07:30:44+00:00","article:modified_time":"2024-12-04T16:19:52+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"CD Estepona \u2013 CD Legan\u00e9s: el sue\u00f1o malague\u00f1o ante un Haller hambriento \u2013 Agente Libre Digital","twitter:description":"El CD Legan\u00e9s visitar\u00e1 el Francisco Mu\u00f1oz P\u00e9rez para tratar de pasar a los dieciseisavos de final de la Copa del Rey ante el Estepona con Haller como titular","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/11\/GbKDwx3WcAAIbYo.webp"},"aioseo_meta_data":{"post_id":"37053","title":null,"description":"El CD Legan\u00e9s visitar\u00e1 el Francisco Mu\u00f1oz P\u00e9rez para tratar de pasar a los dieciseisavos de final de la Copa del Rey ante el Estepona con Haller como titular","keywords":null,"keyphrases":{"focus":{"keyphrase":"Legan\u00e9s","score":76,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":3,"maxScore":9,"error":1},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-12-04 16:19:52","updated":"2025-06-05 06:44:52","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/copa-del-rey\/\" title=\"Copa del Rey\">Copa del Rey<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCD Estepona \u2013 CD Legan\u00e9s: el sue\u00f1o malague\u00f1o ante un Haller hambriento\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"Copa del Rey","link":"https:\/\/agentelibredigital.com\/index.php\/category\/copa-del-rey\/"},{"label":"CD Estepona &#8211; CD Legan\u00e9s: el sue\u00f1o malague\u00f1o ante un Haller hambriento","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/12\/04\/cd-estepona-cd-leganes-el-sueno-malagueno-ante-un-haller-hambriento\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/37053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/201"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=37053"}],"version-history":[{"count":1,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/37053\/revisions"}],"predecessor-version":[{"id":37059,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/37053\/revisions\/37059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/36477"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=37053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=37053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=37053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}