{"id":35394,"date":"2024-11-10T21:27:36","date_gmt":"2024-11-10T20:27:36","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=35394"},"modified":"2024-11-10T21:27:36","modified_gmt":"2024-11-10T20:27:36","slug":"villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/11\/10\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\/","title":{"rendered":"Villarreal B 4-0 Alcorc\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso"},"content":{"rendered":"<h4>Cabanes, un doblete de Eyong y Quintero dan la victoria al Villarreal B para igualar a puntos al Castilla y mantenerse vivos en la lucha por el descenso<\/h4>\n<h2>Primera parte<\/h2>\n<p>Arrancaba el f\u00fatbol en el <strong>Mini Estadi<\/strong> con unas condiciones perfectas en el terreno de juego. Hab\u00eda sorpresas en el once del Villarreal B, con muchos cambios respecto a jornadas anteriores; <strong>Miguel \u00c1lvarez<\/strong> dejaba en el banquillo a jugadores como<strong> Rodri o Quintero<\/strong>, que hab\u00edan sido diferenciales desde el inicio de la temporada. Buen comienzo del conjunto groguet, que se adelantaba en el minuto 14 con un disparo de <strong>Eyong<\/strong> desde dentro del \u00e1rea para batir a Ayesa.<\/p>\n<p>El equipo visitante buscaba rehacerse, pero ve\u00eda que diez minutos m\u00e1s tarde llegaba el segundo del Submarino Amarillo. <strong>Cabanes<\/strong> cog\u00eda el bal\u00f3n en el centro del campo, avanzaba hasta la frontal, y con un derechazo mandaba el bal\u00f3n a la red. Mucha <strong>efectividad<\/strong> del equipo de Miguel \u00c1lvarez, algo que le hab\u00eda faltado en partidos anteriores. El conjunto visitante intentaba acercarse en el marcador por medio de<strong> Imanol<\/strong>, que prob\u00f3 con un disparo t\u00edmido atrapado por Iker sin dificultad. Poco peligro generado por parte de la zona ofensiva del Alcorc\u00f3n, incapaces de generar ocasiones de gol. Terminaba la primera mitad con una<strong> ventaja de dos goles<\/strong> para el equipo amarillo.<\/p>\n<figure style=\"width: 720px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/GcDBt_JWgAAne5u?format=jpg&amp;name=900x900\" alt=\"Imagen\" width=\"720\" height=\"900\" \/><figcaption class=\"wp-caption-text\">Eyoung marca el primero del Villarreal B. Fuente: Cantera Grogueta<\/figcaption><\/figure>\n<h2>Segunda parte<\/h2>\n<p>El <strong>Alcorc\u00f3n<\/strong> comenz\u00f3 bien el segundo tiempo, controlando el bal\u00f3n y metiendo al equipo amarillo pr\u00e1cticamente en su \u00e1rea. El equipo de Pablo generaba cada vez m\u00e1s peligro, lo que llev\u00f3 a Miguel \u00c1lvarez a reaccionar desde el banquillo, retirando a <strong>V\u00edctor Moreno y Sol\u00e0<\/strong> para dar entrada a<strong> Rodri y Cristo<\/strong>. El Alcorc\u00f3n segu\u00eda insistiendo, esta vez a trav\u00e9s de Aparicio, quien recort\u00f3 dentro del \u00e1rea pero no logr\u00f3 colocar su disparo a puerta.<\/p>\n<p>En una jugada aislada, <strong>Imanol<\/strong> derrib\u00f3 a <strong>Thiago Ojeda<\/strong> dentro del \u00e1rea, lo que le cost\u00f3 la <strong>expulsi\u00f3n<\/strong> por doble amarilla, mientras que el \u00e1rbitro<strong> Ramos Andr\u00e9s decretaba pena m\u00e1xima<\/strong>. Thiago, protagonista de la jugada, fue el encargado de ejecutar el penalti, pero <strong>Ayesa<\/strong> realiz\u00f3 una gran parada para evitar el tercero.<\/p>\n<p>Con un jugador menos y veinte minutos por delante, el partido se pon\u00eda cuesta arriba para el Alcorc\u00f3n. Aprovechando que el Alcorc\u00f3n estaba volcado en ataque, una contra liderada por<strong> Quintero<\/strong> sentenci\u00f3 el partido con un disparo raso, imposible de detener para Ayesa. En el descuento, Eyong recog\u00eda un rechaze para poner el 4-0. Los cambios del Villarreal B aportaron pausa al juego, y el equipo domin\u00f3 los \u00faltimos diez minutos. La apuesta de <strong>Miguel \u00c1lvarez<\/strong> de revolucionar el once titular result\u00f3 ser decisiva.<\/p>\n<figure style=\"width: 900px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/GcC-ggNWgAA7zbe?format=jpg&amp;name=900x900\" alt=\"Imagen\" width=\"900\" height=\"600\" \/><figcaption class=\"wp-caption-text\">El Villarreal B manda fuera a Valencia. Fuente: Cantera Grogueta<\/figcaption><\/figure>\n<h2>Ficha t\u00e9cnica<\/h2>\n<p><strong>XI Villarreal B:\u00a0<\/strong>Iker \u00c1lvarez; Budesca, Espigares, Hugo P\u00e9rez, Sol\u00e0 (Cristo 65&#8242;); Requena (Tiago 85&#8242;), Thiago Ojeda, V\u00edctor Moreno (Rodri 65&#8242;), Diatta (Quintero 77&#8242;); Etta Eyong y Pau Cabanes (Fabio Blanco 77&#8242;)<\/p>\n<p><strong>XI Alcorc\u00f3n:\u00a0<\/strong>Ayesa; Juan Sebasti\u00e1n, Joan ( Rentero 89&#8242;), \u00c1lvaro, Manrique; Rayco (Eric 80&#8242;), Imanol, Yael (Da Costa 80&#8242;), Lache (David Navarro 75&#8242;); Capi (Navarro 75&#8242;) y Aparicio<\/p>\n<p><strong>Goleadores Villarreal B:\u00a0<\/strong>Eyoung (14&#8242;)\/ Cabanes (24&#8242;)\/ Quintero (82&#8242;)\/ Eyong (90&#8242;)<\/p>\n<p><strong>Amonestados Villarreal B:\u00a0<\/strong>Eyong (38&#8242;)\/ Cabanes (67&#8242;)\/<\/p>\n<p><strong>Amonestados Alcorc\u00f3n:\u00a0<\/strong>Lache (19&#8242;)\/ Capi (35&#8242;)\/ Joan (38&#8242;)\/ Imanol (67&#8242;) (71&#8242;)\/ \u00c1lvaro (69&#8242;)\/ Eric (85&#8242;)<\/p>\n<p><strong>\u00c1rbitro:\u00a0<\/strong>Ramo \u00c1ndres<\/p>\n<p><strong>Estadio:<\/strong> Mini Estadi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cabanes, un doblete de Eyong y Quintero dan la victoria al Villarreal B para igualar a puntos al Castilla y mantenerse vivos en la lucha por el descenso Primera parte&hellip; <\/p>\n","protected":false},"author":176,"featured_media":35414,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[7,47],"tags":[1330,506,218,1091],"class_list":["post-35394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1a-rfef","category-futbol-espanol","tag-1-rfef","tag-ad-alcorcon","tag-futbol-espanol","tag-villarreal-b"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Villarreal B 4-0 Alcorc\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Alejandro Perez Sole\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2024\/11\/10\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Villarreal B 4-0 Alcorc\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"Villarreal B 4-0 Alcorc\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2024\/11\/10\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/11\/GcC_UWBWAAAUJfT.jpeg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/11\/GcC_UWBWAAAUJfT.jpeg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-11-10T20:27:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-11-10T20:27:36+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Villarreal B 4-0 Alcorc\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Villarreal B 4-0 Alcorc\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/11\/GcC_UWBWAAAUJfT.jpeg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/11\\\/10\\\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\\\/#blogposting\",\"name\":\"Villarreal B 4-0 Alcorc\\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso \\u2013 Agente Libre Digital\",\"headline\":\"Villarreal B 4-0 Alcorc\\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/alejandro-perez-sole\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/GcC_UWBWAAAUJfT.jpeg\",\"width\":720,\"height\":900,\"caption\":\"El Villarreal B celebra el gol de Cabanes. Fuente: Cantera Grogueta\"},\"datePublished\":\"2024-11-10T21:27:36+01:00\",\"dateModified\":\"2024-11-10T21:27:36+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/11\\\/10\\\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/11\\\/10\\\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\\\/#webpage\"},\"articleSection\":\"1\\u00aa RFEF, F\\u00fatbol Espa\\u00f1ol, 1 RFEF, AD Alcorc\\u00f3n, futbol espa\\u00f1ol, Villarreal B\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/11\\\/10\\\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/1a-rfef\\\/#listItem\",\"name\":\"1\\u00aa RFEF\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/1a-rfef\\\/#listItem\",\"position\":2,\"name\":\"1\\u00aa RFEF\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/1a-rfef\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/11\\\/10\\\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\\\/#listItem\",\"name\":\"Villarreal B 4-0 Alcorc\\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/11\\\/10\\\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\\\/#listItem\",\"position\":3,\"name\":\"Villarreal B 4-0 Alcorc\\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/1a-rfef\\\/#listItem\",\"name\":\"1\\u00aa RFEF\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/11\\\/10\\\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/11\\\/10\\\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/alejandro-perez-sole\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/alejandro-perez-sole\\\/\",\"name\":\"Alejandro Perez Sole\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/11\\\/10\\\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2eb02e84fe9fd09df995cd867fcbf60633bd9afc861bd820d111bf70da436175?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Alejandro Perez Sole\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/11\\\/10\\\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/11\\\/10\\\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\\\/\",\"name\":\"Villarreal B 4-0 Alcorc\\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso \\u2013 Agente Libre Digital\",\"description\":\"Villarreal B 4-0 Alcorc\\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/11\\\/10\\\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/alejandro-perez-sole\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/alejandro-perez-sole\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/GcC_UWBWAAAUJfT.jpeg\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/11\\\/10\\\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\\\/#mainImage\",\"width\":720,\"height\":900,\"caption\":\"El Villarreal B celebra el gol de Cabanes. Fuente: Cantera Grogueta\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/11\\\/10\\\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\\\/#mainImage\"},\"datePublished\":\"2024-11-10T21:27:36+01:00\",\"dateModified\":\"2024-11-10T21:27:36+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Villarreal B 4-0 Alcorc\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso \u2013 Agente Libre Digital","description":"Villarreal B 4-0 Alcorc\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2024\/11\/10\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/11\/10\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\/#blogposting","name":"Villarreal B 4-0 Alcorc\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso \u2013 Agente Libre Digital","headline":"Villarreal B 4-0 Alcorc\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/alejandro-perez-sole\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/11\/GcC_UWBWAAAUJfT.jpeg","width":720,"height":900,"caption":"El Villarreal B celebra el gol de Cabanes. Fuente: Cantera Grogueta"},"datePublished":"2024-11-10T21:27:36+01:00","dateModified":"2024-11-10T21:27:36+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/11\/10\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/11\/10\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\/#webpage"},"articleSection":"1\u00aa RFEF, F\u00fatbol Espa\u00f1ol, 1 RFEF, AD Alcorc\u00f3n, futbol espa\u00f1ol, Villarreal B"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/11\/10\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/1a-rfef\/#listItem","name":"1\u00aa RFEF"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/1a-rfef\/#listItem","position":2,"name":"1\u00aa RFEF","item":"https:\/\/agentelibredigital.com\/index.php\/category\/1a-rfef\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/11\/10\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\/#listItem","name":"Villarreal B 4-0 Alcorc\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/11\/10\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\/#listItem","position":3,"name":"Villarreal B 4-0 Alcorc\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/1a-rfef\/#listItem","name":"1\u00aa RFEF"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/11\/10\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/11\/10\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/alejandro-perez-sole\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/alejandro-perez-sole\/","name":"Alejandro Perez Sole","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/11\/10\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/2eb02e84fe9fd09df995cd867fcbf60633bd9afc861bd820d111bf70da436175?s=96&d=mm&r=g","width":96,"height":96,"caption":"Alejandro Perez Sole"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/11\/10\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2024\/11\/10\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\/","name":"Villarreal B 4-0 Alcorc\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso \u2013 Agente Libre Digital","description":"Villarreal B 4-0 Alcorc\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/11\/10\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/alejandro-perez-sole\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/alejandro-perez-sole\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/11\/GcC_UWBWAAAUJfT.jpeg","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/11\/10\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\/#mainImage","width":720,"height":900,"caption":"El Villarreal B celebra el gol de Cabanes. Fuente: Cantera Grogueta"},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/11\/10\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\/#mainImage"},"datePublished":"2024-11-10T21:27:36+01:00","dateModified":"2024-11-10T21:27:36+01:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"Villarreal B 4-0 Alcorc\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso \u2013 Agente Libre Digital","og:description":"Villarreal B 4-0 Alcorc\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso","og:url":"https:\/\/agentelibredigital.com\/index.php\/2024\/11\/10\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/11\/GcC_UWBWAAAUJfT.jpeg","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/11\/GcC_UWBWAAAUJfT.jpeg","og:image:width":720,"og:image:height":900,"article:published_time":"2024-11-10T20:27:36+00:00","article:modified_time":"2024-11-10T20:27:36+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"Villarreal B 4-0 Alcorc\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso \u2013 Agente Libre Digital","twitter:description":"Villarreal B 4-0 Alcorc\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/11\/GcC_UWBWAAAUJfT.jpeg"},"aioseo_meta_data":{"post_id":"35394","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-11-10 19:41:16","updated":"2025-06-05 05:35:55","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/1a-rfef\/\" title=\"1\u00aa RFEF\">1\u00aa RFEF<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tVillarreal B 4-0 Alcorc\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"1\u00aa RFEF","link":"https:\/\/agentelibredigital.com\/index.php\/category\/1a-rfef\/"},{"label":"Villarreal B 4-0 Alcorc\u00f3n: Quintero se suma a la dupla goleadora para pelear el descenso","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/11\/10\/villarreal-b-4-0-alcorcon-quintero-se-suma-a-la-dupla-goleadora-para-pelear-el-descenso\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/35394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/176"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=35394"}],"version-history":[{"count":3,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/35394\/revisions"}],"predecessor-version":[{"id":35426,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/35394\/revisions\/35426"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/35414"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=35394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=35394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=35394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}