{"id":34395,"date":"2024-10-26T01:41:03","date_gmt":"2024-10-25T23:41:03","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=34395"},"modified":"2024-10-26T01:52:51","modified_gmt":"2024-10-25T23:52:51","slug":"sainz-se-lleva-los-libres-2-en-mexico","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/26\/sainz-se-lleva-los-libres-2-en-mexico\/","title":{"rendered":"Sainz se lleva los libres 2 en M\u00e9xico"},"content":{"rendered":"<h4>El piloto de Ferrari fue el m\u00e1s r\u00e1pido en la segunda sesi\u00f3n de entrenamientos en el GP de M\u00e9xico<\/h4>\n<p>A las 00:00 horas en Espa\u00f1a daba comienzo la segunda sesi\u00f3n de entrenamientos libres del <strong>GP de F1 de M\u00e9xico<\/strong>. El Aut\u00f3dromo Hermanos Rodr\u00edguez acog\u00eda una nueva hora y media de pruebas donde los equipos buscaban poner a punto sus coches de cara a la clasificaci\u00f3n.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"es\">FINAL FP2 \ud83c\uddf2\ud83c\uddfd\ud83c\udfc1.<\/p>\n<p>Carlos Sainz ha sido el piloto m\u00e1s r\u00e1pido en esta segunda sesi\u00f3n y sigue ilusionando a los tifosi \ud83d\udc40\ud83d\udd34.<\/p>\n<p>Sesiones fuera de lo normal en cuanto a la tabla de tiempos que hay coger con pinzas \u26a0\ufe0f.<\/p>\n<p>Los RB siguen sorprendiendo con su ritmo \ud83d\udca5.<a href=\"https:\/\/twitter.com\/hashtag\/F1?src=hash&amp;ref_src=twsrc%5Etfw\">#F1<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/MexicoGP?src=hash&amp;ref_src=twsrc%5Etfw\">#MexicoGP<\/a> <a href=\"https:\/\/t.co\/jHQrTfTJ49\">pic.twitter.com\/jHQrTfTJ49<\/a><\/p>\n<p>\u2014 Agente Libre \ud83d\udea9 (@AgenteLibre_dig) <a href=\"https:\/\/twitter.com\/AgenteLibre_dig\/status\/1849961471125475796?ref_src=twsrc%5Etfw\">October 25, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2>Inicio accidentado<\/h2>\n<p>El arranque de la sesi\u00f3n estar\u00eda marcado por el accidente de <strong>Russell<\/strong>. El piloto brit\u00e1nico perdi\u00f3 el control de su <strong>Mercedes<\/strong> en la salida de la curva 8 y <a href=\"https:\/\/x.com\/F1\/status\/1849938363442479159\/photo\/1\">se fue contra las protecciones<\/a>. Esto oblig\u00f3 a la aparici\u00f3n de la bandera roja, que no permiti\u00f3 rodar durante unos 20 minutos. Fue un jarro de agua fr\u00eda para un George que <a href=\"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/25\/russell-lider-solido-en-la-fp1\/\">fue el m\u00e1s r\u00e1pido en los libres 1<\/a>. De hecho, se le vio cojeando cuando regresaba al garaje.<\/p>\n<p>A su vez, antes del choque se reportaron problemas por parte de <strong>Verstappen<\/strong>. El l\u00edder del campeonato se baj\u00f3 r\u00e1pidamente de su monoplaza y los mec\u00e1nicos se pusieron manos a la obra. Al parecer, hab\u00eda un problema con la unidad de potencia. Por otro lado, <strong>Albon ni siquiera pudo salir a pista<\/strong> tras su fuerte contratiempo en la primera sesi\u00f3n de entrenamientos.<\/p>\n<figure id=\"attachment_34396\" aria-describedby=\"caption-attachment-34396\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-34396 size-large\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/f1-grand-prix-of-mexico-practice-2-1024x683.jpg\" alt=\"M\u00e9xico\" width=\"1024\" height=\"683\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/f1-grand-prix-of-mexico-practice-2-1024x683.jpg 1024w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/f1-grand-prix-of-mexico-practice-2-300x200.jpg 300w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/f1-grand-prix-of-mexico-practice-2-768x512.jpg 768w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/f1-grand-prix-of-mexico-practice-2-1536x1024.jpg 1536w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/f1-grand-prix-of-mexico-practice-2-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-34396\" class=\"wp-caption-text\">George Russell en los libres del GP de M\u00e9xico. Fuente: Chris Grayden.<\/figcaption><\/figure>\n<h2>Vuelta a la &#8216;normalidad&#8217;<\/h2>\n<p>Ya sin mayores detenciones, la sesi\u00f3n pudo seguir su curso. Estuvo marcada por el uso de las <strong>nuevas ruedas Pirelli<\/strong>, que generaron diversos problemas a varios pilotos. Y es que, especialmente en la zona de las curvas enlazadas, <strong>se perd\u00eda la parte trasera del coche f\u00e1cilmente<\/strong>.<\/p>\n<p>En cualquier caso, <strong>Carlos Sainz<\/strong> se manten\u00eda en primera posici\u00f3n por delante de su compa\u00f1ero de equipo y de los <strong>McLaren<\/strong>. Mientras tanto, Max segu\u00eda con problemas en su monoplaza y se ve\u00eda obligado a regresar al garaje. De hecho, a estas alturas de la pr\u00e1ctica (faltaban 45 minutos), <strong>todav\u00eda no hab\u00eda conseguido cerrar una vuelta limpia<\/strong>. Y finalmente no lo lograr\u00eda, pues no volvi\u00f3 a salir a pista.<\/p>\n<figure id=\"attachment_34400\" aria-describedby=\"caption-attachment-34400\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-34400 size-large\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/f1-grand-prix-of-mexico-practice-4-1024x682.jpg\" alt=\"M\u00e9xico\" width=\"1024\" height=\"682\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/f1-grand-prix-of-mexico-practice-4-1024x682.jpg 1024w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/f1-grand-prix-of-mexico-practice-4-300x200.jpg 300w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/f1-grand-prix-of-mexico-practice-4-768x512.jpg 768w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/f1-grand-prix-of-mexico-practice-4-1536x1023.jpg 1536w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/f1-grand-prix-of-mexico-practice-4-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-34400\" class=\"wp-caption-text\">Franco Colapinto en el GP de M\u00e9xico. Fuente: Rudy Cazzevoli.<\/figcaption><\/figure>\n<h2>Sesi\u00f3n con poco fuera de lo normal<\/h2>\n<p>Los compases finales de los libres 2 no contar\u00edan con demasiada emoci\u00f3n. Y es que, m\u00e1s all\u00e1 de que alg\u00fan que otro intento fuera bueno, lo cierto es que estas ruedas no se iban a usar. Por lo que las conclusiones no son del todo certeras de cara al d\u00eda de ma\u00f1ana.<\/p>\n<p>Algunos pilotos como <strong>Zhou<\/strong> sufrir\u00edan da\u00f1os en su coche, pero sin ser especialmente graves. Finalmente se onde\u00f3 la bandera de cuadros y <strong>Carlos<\/strong> qued\u00f3 en primera posici\u00f3n. Seguido de <strong>Piastri<\/strong> y de <strong>Yuki Tsunoda<\/strong>. Respecto a los hombres de <strong>Aston Martin<\/strong>, no destacaron a lo largo de la hora y media de entrenamientos y acabaron fuera de los que ser\u00e1n los puestos de puntos (Stroll 14\u00ba; Alonso 11\u00ba).<\/p>\n<figure id=\"attachment_34407\" aria-describedby=\"caption-attachment-34407\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-34407 size-large\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/Gaxf8KFXwAAGIgH-1024x576.jpeg\" alt=\"M\u00e9xico\" width=\"1024\" height=\"576\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/Gaxf8KFXwAAGIgH-1024x576.jpeg 1024w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/Gaxf8KFXwAAGIgH-300x169.jpeg 300w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/Gaxf8KFXwAAGIgH-768x432.jpeg 768w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/Gaxf8KFXwAAGIgH-1536x864.jpeg 1536w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/Gaxf8KFXwAAGIgH.jpeg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-34407\" class=\"wp-caption-text\">Top 3 de los libres 2. Fuente: F1 v\u00eda X.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El piloto de Ferrari fue el m\u00e1s r\u00e1pido en la segunda sesi\u00f3n de entrenamientos en el GP de M\u00e9xico A las 00:00 horas en Espa\u00f1a daba comienzo la segunda sesi\u00f3n&hellip; <\/p>\n","protected":false},"author":220,"featured_media":34399,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[42,50],"tags":[539,3276,136,504,2686,138,518,520],"class_list":["post-34395","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-formula-1","category-motor","tag-alonso","tag-entrenamientos","tag-f1","tag-libres-2","tag-mexico","tag-motor","tag-russell","tag-sainz"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El piloto de Ferrari fue el m\u00e1s r\u00e1pido en la segunda sesi\u00f3n de entrenamientos en el Gran Premio de M\u00e9xico en el Aut\u00f3dromo Hermanos Rodr\u00edguez\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Nico Tomas\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/26\/sainz-se-lleva-los-libres-2-en-mexico\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sainz se lleva los libres 2 en M\u00e9xico \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"El piloto de Ferrari fue el m\u00e1s r\u00e1pido en la segunda sesi\u00f3n de entrenamientos en el Gran Premio de M\u00e9xico en el Aut\u00f3dromo Hermanos Rodr\u00edguez\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/26\/sainz-se-lleva-los-libres-2-en-mexico\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/f1-grand-prix-of-mexico-practice-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/f1-grand-prix-of-mexico-practice-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-10-25T23:41:03+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-10-25T23:52:51+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sainz se lleva los libres 2 en M\u00e9xico \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El piloto de Ferrari fue el m\u00e1s r\u00e1pido en la segunda sesi\u00f3n de entrenamientos en el Gran Premio de M\u00e9xico en el Aut\u00f3dromo Hermanos Rodr\u00edguez\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/f1-grand-prix-of-mexico-practice-scaled.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/26\\\/sainz-se-lleva-los-libres-2-en-mexico\\\/#blogposting\",\"name\":\"Sainz se lleva los libres 2 en M\\u00e9xico \\u2013 Agente Libre Digital\",\"headline\":\"Sainz se lleva los libres 2 en M\\u00e9xico\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/nico-tomas\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/f1-grand-prix-of-mexico-practice-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Carlos Sainz en el GP de M\\u00e9xico. Fuente: James C. Tilton.\"},\"datePublished\":\"2024-10-26T01:41:03+02:00\",\"dateModified\":\"2024-10-26T01:52:51+02:00\",\"inLanguage\":\"es-ES\",\"commentCount\":3,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/26\\\/sainz-se-lleva-los-libres-2-en-mexico\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/26\\\/sainz-se-lleva-los-libres-2-en-mexico\\\/#webpage\"},\"articleSection\":\"Formula 1, Motor, Alonso, Entrenamientos, F1, Libres 2, M\\u00e9xico, Motor, Russell, Sainz\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/26\\\/sainz-se-lleva-los-libres-2-en-mexico\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/formula-1\\\/#listItem\",\"name\":\"Formula 1\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/formula-1\\\/#listItem\",\"position\":2,\"name\":\"Formula 1\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/formula-1\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/26\\\/sainz-se-lleva-los-libres-2-en-mexico\\\/#listItem\",\"name\":\"Sainz se lleva los libres 2 en M\\u00e9xico\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/26\\\/sainz-se-lleva-los-libres-2-en-mexico\\\/#listItem\",\"position\":3,\"name\":\"Sainz se lleva los libres 2 en M\\u00e9xico\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/formula-1\\\/#listItem\",\"name\":\"Formula 1\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/26\\\/sainz-se-lleva-los-libres-2-en-mexico\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/26\\\/sainz-se-lleva-los-libres-2-en-mexico\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/nico-tomas\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/nico-tomas\\\/\",\"name\":\"Nico Tomas\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/26\\\/sainz-se-lleva-los-libres-2-en-mexico\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9b16bd614f48eb100a79d4318c343386cea161e6ab3c37de38d317e29b004bcf?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Nico Tomas\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/26\\\/sainz-se-lleva-los-libres-2-en-mexico\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/26\\\/sainz-se-lleva-los-libres-2-en-mexico\\\/\",\"name\":\"Sainz se lleva los libres 2 en M\\u00e9xico \\u2013 Agente Libre Digital\",\"description\":\"El piloto de Ferrari fue el m\\u00e1s r\\u00e1pido en la segunda sesi\\u00f3n de entrenamientos en el Gran Premio de M\\u00e9xico en el Aut\\u00f3dromo Hermanos Rodr\\u00edguez\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/26\\\/sainz-se-lleva-los-libres-2-en-mexico\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/nico-tomas\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/nico-tomas\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/f1-grand-prix-of-mexico-practice-scaled.jpg\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/26\\\/sainz-se-lleva-los-libres-2-en-mexico\\\/#mainImage\",\"width\":2560,\"height\":1707,\"caption\":\"Carlos Sainz en el GP de M\\u00e9xico. Fuente: James C. Tilton.\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/26\\\/sainz-se-lleva-los-libres-2-en-mexico\\\/#mainImage\"},\"datePublished\":\"2024-10-26T01:41:03+02:00\",\"dateModified\":\"2024-10-26T01:52:51+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sainz se lleva los libres 2 en M\u00e9xico \u2013 Agente Libre Digital","description":"El piloto de Ferrari fue el m\u00e1s r\u00e1pido en la segunda sesi\u00f3n de entrenamientos en el Gran Premio de M\u00e9xico en el Aut\u00f3dromo Hermanos Rodr\u00edguez","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/26\/sainz-se-lleva-los-libres-2-en-mexico\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/26\/sainz-se-lleva-los-libres-2-en-mexico\/#blogposting","name":"Sainz se lleva los libres 2 en M\u00e9xico \u2013 Agente Libre Digital","headline":"Sainz se lleva los libres 2 en M\u00e9xico","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/nico-tomas\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/f1-grand-prix-of-mexico-practice-scaled.jpg","width":2560,"height":1707,"caption":"Carlos Sainz en el GP de M\u00e9xico. Fuente: James C. Tilton."},"datePublished":"2024-10-26T01:41:03+02:00","dateModified":"2024-10-26T01:52:51+02:00","inLanguage":"es-ES","commentCount":3,"mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/26\/sainz-se-lleva-los-libres-2-en-mexico\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/26\/sainz-se-lleva-los-libres-2-en-mexico\/#webpage"},"articleSection":"Formula 1, Motor, Alonso, Entrenamientos, F1, Libres 2, M\u00e9xico, Motor, Russell, Sainz"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/26\/sainz-se-lleva-los-libres-2-en-mexico\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/formula-1\/#listItem","name":"Formula 1"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/formula-1\/#listItem","position":2,"name":"Formula 1","item":"https:\/\/agentelibredigital.com\/index.php\/category\/formula-1\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/26\/sainz-se-lleva-los-libres-2-en-mexico\/#listItem","name":"Sainz se lleva los libres 2 en M\u00e9xico"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/26\/sainz-se-lleva-los-libres-2-en-mexico\/#listItem","position":3,"name":"Sainz se lleva los libres 2 en M\u00e9xico","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/formula-1\/#listItem","name":"Formula 1"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/26\/sainz-se-lleva-los-libres-2-en-mexico\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/26\/sainz-se-lleva-los-libres-2-en-mexico\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/nico-tomas\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/nico-tomas\/","name":"Nico Tomas","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/26\/sainz-se-lleva-los-libres-2-en-mexico\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/9b16bd614f48eb100a79d4318c343386cea161e6ab3c37de38d317e29b004bcf?s=96&d=mm&r=g","width":96,"height":96,"caption":"Nico Tomas"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/26\/sainz-se-lleva-los-libres-2-en-mexico\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/26\/sainz-se-lleva-los-libres-2-en-mexico\/","name":"Sainz se lleva los libres 2 en M\u00e9xico \u2013 Agente Libre Digital","description":"El piloto de Ferrari fue el m\u00e1s r\u00e1pido en la segunda sesi\u00f3n de entrenamientos en el Gran Premio de M\u00e9xico en el Aut\u00f3dromo Hermanos Rodr\u00edguez","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/26\/sainz-se-lleva-los-libres-2-en-mexico\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/nico-tomas\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/nico-tomas\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/f1-grand-prix-of-mexico-practice-scaled.jpg","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/26\/sainz-se-lleva-los-libres-2-en-mexico\/#mainImage","width":2560,"height":1707,"caption":"Carlos Sainz en el GP de M\u00e9xico. Fuente: James C. Tilton."},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/26\/sainz-se-lleva-los-libres-2-en-mexico\/#mainImage"},"datePublished":"2024-10-26T01:41:03+02:00","dateModified":"2024-10-26T01:52:51+02:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"Sainz se lleva los libres 2 en M\u00e9xico \u2013 Agente Libre Digital","og:description":"El piloto de Ferrari fue el m\u00e1s r\u00e1pido en la segunda sesi\u00f3n de entrenamientos en el Gran Premio de M\u00e9xico en el Aut\u00f3dromo Hermanos Rodr\u00edguez","og:url":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/26\/sainz-se-lleva-los-libres-2-en-mexico\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/f1-grand-prix-of-mexico-practice-scaled.jpg","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/f1-grand-prix-of-mexico-practice-scaled.jpg","og:image:width":2560,"og:image:height":1707,"article:published_time":"2024-10-25T23:41:03+00:00","article:modified_time":"2024-10-25T23:52:51+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"Sainz se lleva los libres 2 en M\u00e9xico \u2013 Agente Libre Digital","twitter:description":"El piloto de Ferrari fue el m\u00e1s r\u00e1pido en la segunda sesi\u00f3n de entrenamientos en el Gran Premio de M\u00e9xico en el Aut\u00f3dromo Hermanos Rodr\u00edguez","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/f1-grand-prix-of-mexico-practice-scaled.jpg"},"aioseo_meta_data":{"post_id":"34395","title":null,"description":"El piloto de Ferrari fue el m\u00e1s r\u00e1pido en la segunda sesi\u00f3n de entrenamientos en el Gran Premio de M\u00e9xico en el Aut\u00f3dromo Hermanos Rodr\u00edguez","keywords":null,"keyphrases":{"focus":{"keyphrase":"M\u00e9xico","score":91,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-10-25 23:41:03","updated":"2025-06-05 04:49:02","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/formula-1\/\" title=\"Formula 1\">Formula 1<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSainz se lleva los libres 2 en M\u00e9xico\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"Formula 1","link":"https:\/\/agentelibredigital.com\/index.php\/category\/formula-1\/"},{"label":"Sainz se lleva los libres 2 en M\u00e9xico","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/26\/sainz-se-lleva-los-libres-2-en-mexico\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/34395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/220"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=34395"}],"version-history":[{"count":3,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/34395\/revisions"}],"predecessor-version":[{"id":34410,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/34395\/revisions\/34410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/34399"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=34395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=34395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=34395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}