{"id":33310,"date":"2024-10-11T17:43:34","date_gmt":"2024-10-11T15:43:34","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=33310"},"modified":"2024-10-11T17:43:34","modified_gmt":"2024-10-11T15:43:34","slug":"morata-se-sincera-sobre-su-etapa-en-espana","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/11\/morata-se-sincera-sobre-su-etapa-en-espana\/","title":{"rendered":"Morata se sincera sobre su etapa en Espa\u00f1a"},"content":{"rendered":"<h4>En una entrevista en el programa <a href=\"https:\/\/www.cope.es\/programas\/herrera-en-cope\/noticias\/alvaro-morata-rompe-silencio-alberto-herrera-habla-primera-vez-episodios-depresion-20241009_3025201.amp.html\">Herrera en COPE<\/a>, el actual delantero del <a href=\"https:\/\/agentelibredigital.com\/?s=Milan\">Milan<\/a> cuenta los problemas y motivos que le llevaron a abandonar Espa\u00f1a.<\/h4>\n<p>El panorama actual de <a href=\"https:\/\/agentelibredigital.com\/?s=%C3%81lvaro+Morata\">\u00c1lvaro Morata<\/a> no est\u00e1 siendo todo lo que tranquilo que podr\u00eda ser. Adem\u00e1s del panorama deportivo con la escuadra <em>rossonera<\/em> y la pol\u00e9mica que tuvo con el alcalde de Corbetta por anunciar la llegada de su familia al pueblo, se le suma su marcha no tan agradable del <strong>Atl\u00e9tico de Madrid<\/strong>. Aprovechando su concentraci\u00f3n con la selecci\u00f3n espa\u00f1ola, <strong>Morata ha declarado en la radio COPE los problemas mentales que ha sufrido estando en Espa\u00f1a<\/strong> y que le hicieron pensar su continuidad como jugador de f\u00fatbol.<\/p>\n<figure id=\"attachment_33322\" aria-describedby=\"caption-attachment-33322\" style=\"width: 768px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-33322\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/6706b62a7777a.r_d.1554-578.jpeg\" alt=\"\" width=\"768\" height=\"432\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/6706b62a7777a.r_d.1554-578.jpeg 768w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/6706b62a7777a.r_d.1554-578-300x169.jpeg 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption id=\"caption-attachment-33322\" class=\"wp-caption-text\">\u00c1lvaro Morata siendo entrevistado en el programa Herrera en COPE. Fuente: Web de la COPE.<\/figcaption><\/figure>\n<p>El delantero de 31 a\u00f1os <strong>se ha referido a ataques de p\u00e1nico y a las cr\u00edticas recibidas como un motivo claro sobre su marcha del conjunto colchonero<\/strong>. <strong>Morata<\/strong> ha relatado que incluso <strong>tres meses antes de levantar la Eurocopa con la selecci\u00f3n espa\u00f1ola no sab\u00eda si volver\u00eda a jugar al f\u00fatbol<\/strong>, llegando a pedir ayuda de camino al entrenamiento por la situaci\u00f3n que estaba sufriendo e incluso ven\u00eda a la Eurocopa con una depresi\u00f3n.<\/p>\n<p>Pese a sufrir un incidente con el alcalde de Corbetta <strong>Marco Ballarini<\/strong> por anunciar en Instagram su llegada al municipio para alojarse con su familia, <strong>Morata<\/strong> busca en el <strong>Milan<\/strong> el nivel que tuvo en la <strong>Juventus<\/strong> y que le hizo ganarse el cari\u00f1o de los<em> tifosi bianconeros y <\/em>de la <a href=\"https:\/\/agentelibredigital.com\/?s=Serie+A\">Serie A<\/a>. Poco a poco <strong>va siendo importante en los esquemas t\u00e1cticos de Paulo Fonseca, siendo titular en 4 de los 7 partidos disputados con los <em>rossoneri<\/em> logrando anotar 2 goles y 1 asistencia<\/strong>, uno de ellos en el debut liguero contra el Torino. Queda mucha temporada para ver si \u00c1lvaro Morata recupera el nivel y vuelve a seguir dando alegr\u00edas como en la selecci\u00f3n espa\u00f1ola.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una entrevista en el programa Herrera en COPE, el actual delantero del Milan cuenta los problemas y motivos que le llevaron a abandonar Espa\u00f1a. El panorama actual de \u00c1lvaro&hellip; <\/p>\n","protected":false},"author":179,"featured_media":33311,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[48,33],"tags":[1177,82,94],"class_list":["post-33310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol-internacional","category-serie-a","tag-alvaro-morata","tag-milan","tag-serie-a"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Morata se sincera sobre su etapa en Espa\u00f1a En una entrevista en la COPE, \u00c1lvaro Morata cuenta los problemas y motivos que le llevaron a abandonar Espa\u00f1a\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Marcos Iglesias\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/11\/morata-se-sincera-sobre-su-etapa-en-espana\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Morata se sincera sobre su etapa en Espa\u00f1a\" \/>\n\t\t<meta property=\"og:description\" content=\"Morata se sincera sobre su etapa en Espa\u00f1a En una entrevista en la COPE, \u00c1lvaro Morata cuenta los problemas y motivos que le llevaron a abandonar Espa\u00f1a\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/11\/morata-se-sincera-sobre-su-etapa-en-espana\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/fiorentina-v-ac-milan-serie-a-2-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/fiorentina-v-ac-milan-serie-a-2-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1710\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-10-11T15:43:34+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-10-11T15:43:34+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Morata se sincera sobre su etapa en Espa\u00f1a\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Morata se sincera sobre su etapa en Espa\u00f1a En una entrevista en la COPE, \u00c1lvaro Morata cuenta los problemas y motivos que le llevaron a abandonar Espa\u00f1a\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/fiorentina-v-ac-milan-serie-a-2-scaled.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/11\\\/morata-se-sincera-sobre-su-etapa-en-espana\\\/#blogposting\",\"name\":\"Morata se sincera sobre su etapa en Espa\\u00f1a\",\"headline\":\"Morata se sincera sobre su etapa en Espa\\u00f1a\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-iglesias\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/fiorentina-v-ac-milan-serie-a-2-scaled.jpg\",\"width\":2560,\"height\":1710,\"caption\":\"\\u00c1lvaro Morata dando indicaciones en un partido. Fuente: Gabriele Maltinti\\\/Getty Images.\"},\"datePublished\":\"2024-10-11T17:43:34+02:00\",\"dateModified\":\"2024-10-11T17:43:34+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/11\\\/morata-se-sincera-sobre-su-etapa-en-espana\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/11\\\/morata-se-sincera-sobre-su-etapa-en-espana\\\/#webpage\"},\"articleSection\":\"F\\u00fatbol Internacional, Serie A, \\u00c1lvaro Morata, Milan, Serie A\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/11\\\/morata-se-sincera-sobre-su-etapa-en-espana\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/serie-a\\\/#listItem\",\"name\":\"Serie A\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/serie-a\\\/#listItem\",\"position\":2,\"name\":\"Serie A\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/serie-a\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/11\\\/morata-se-sincera-sobre-su-etapa-en-espana\\\/#listItem\",\"name\":\"Morata se sincera sobre su etapa en Espa\\u00f1a\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/11\\\/morata-se-sincera-sobre-su-etapa-en-espana\\\/#listItem\",\"position\":3,\"name\":\"Morata se sincera sobre su etapa en Espa\\u00f1a\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/serie-a\\\/#listItem\",\"name\":\"Serie A\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/11\\\/morata-se-sincera-sobre-su-etapa-en-espana\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/11\\\/morata-se-sincera-sobre-su-etapa-en-espana\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-iglesias\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-iglesias\\\/\",\"name\":\"Marcos Iglesias\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/11\\\/morata-se-sincera-sobre-su-etapa-en-espana\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b12d4fac150c550921f0486912033479abc571a43af887303e0aa75b2023fa6a?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Marcos Iglesias\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/11\\\/morata-se-sincera-sobre-su-etapa-en-espana\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/11\\\/morata-se-sincera-sobre-su-etapa-en-espana\\\/\",\"name\":\"Morata se sincera sobre su etapa en Espa\\u00f1a\",\"description\":\"Morata se sincera sobre su etapa en Espa\\u00f1a En una entrevista en la COPE, \\u00c1lvaro Morata cuenta los problemas y motivos que le llevaron a abandonar Espa\\u00f1a\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/11\\\/morata-se-sincera-sobre-su-etapa-en-espana\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-iglesias\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/marcos-iglesias\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/fiorentina-v-ac-milan-serie-a-2-scaled.jpg\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/11\\\/morata-se-sincera-sobre-su-etapa-en-espana\\\/#mainImage\",\"width\":2560,\"height\":1710,\"caption\":\"\\u00c1lvaro Morata dando indicaciones en un partido. Fuente: Gabriele Maltinti\\\/Getty Images.\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/10\\\/11\\\/morata-se-sincera-sobre-su-etapa-en-espana\\\/#mainImage\"},\"datePublished\":\"2024-10-11T17:43:34+02:00\",\"dateModified\":\"2024-10-11T17:43:34+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Morata se sincera sobre su etapa en Espa\u00f1a","description":"Morata se sincera sobre su etapa en Espa\u00f1a En una entrevista en la COPE, \u00c1lvaro Morata cuenta los problemas y motivos que le llevaron a abandonar Espa\u00f1a","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/11\/morata-se-sincera-sobre-su-etapa-en-espana\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/11\/morata-se-sincera-sobre-su-etapa-en-espana\/#blogposting","name":"Morata se sincera sobre su etapa en Espa\u00f1a","headline":"Morata se sincera sobre su etapa en Espa\u00f1a","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-iglesias\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/fiorentina-v-ac-milan-serie-a-2-scaled.jpg","width":2560,"height":1710,"caption":"\u00c1lvaro Morata dando indicaciones en un partido. Fuente: Gabriele Maltinti\/Getty Images."},"datePublished":"2024-10-11T17:43:34+02:00","dateModified":"2024-10-11T17:43:34+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/11\/morata-se-sincera-sobre-su-etapa-en-espana\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/11\/morata-se-sincera-sobre-su-etapa-en-espana\/#webpage"},"articleSection":"F\u00fatbol Internacional, Serie A, \u00c1lvaro Morata, Milan, Serie A"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/11\/morata-se-sincera-sobre-su-etapa-en-espana\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/serie-a\/#listItem","name":"Serie A"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/serie-a\/#listItem","position":2,"name":"Serie A","item":"https:\/\/agentelibredigital.com\/index.php\/category\/serie-a\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/11\/morata-se-sincera-sobre-su-etapa-en-espana\/#listItem","name":"Morata se sincera sobre su etapa en Espa\u00f1a"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/11\/morata-se-sincera-sobre-su-etapa-en-espana\/#listItem","position":3,"name":"Morata se sincera sobre su etapa en Espa\u00f1a","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/serie-a\/#listItem","name":"Serie A"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/11\/morata-se-sincera-sobre-su-etapa-en-espana\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/11\/morata-se-sincera-sobre-su-etapa-en-espana\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-iglesias\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-iglesias\/","name":"Marcos Iglesias","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/11\/morata-se-sincera-sobre-su-etapa-en-espana\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b12d4fac150c550921f0486912033479abc571a43af887303e0aa75b2023fa6a?s=96&d=mm&r=g","width":96,"height":96,"caption":"Marcos Iglesias"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/11\/morata-se-sincera-sobre-su-etapa-en-espana\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/11\/morata-se-sincera-sobre-su-etapa-en-espana\/","name":"Morata se sincera sobre su etapa en Espa\u00f1a","description":"Morata se sincera sobre su etapa en Espa\u00f1a En una entrevista en la COPE, \u00c1lvaro Morata cuenta los problemas y motivos que le llevaron a abandonar Espa\u00f1a","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/11\/morata-se-sincera-sobre-su-etapa-en-espana\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-iglesias\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/marcos-iglesias\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/fiorentina-v-ac-milan-serie-a-2-scaled.jpg","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/11\/morata-se-sincera-sobre-su-etapa-en-espana\/#mainImage","width":2560,"height":1710,"caption":"\u00c1lvaro Morata dando indicaciones en un partido. Fuente: Gabriele Maltinti\/Getty Images."},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/11\/morata-se-sincera-sobre-su-etapa-en-espana\/#mainImage"},"datePublished":"2024-10-11T17:43:34+02:00","dateModified":"2024-10-11T17:43:34+02:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"Morata se sincera sobre su etapa en Espa\u00f1a","og:description":"Morata se sincera sobre su etapa en Espa\u00f1a En una entrevista en la COPE, \u00c1lvaro Morata cuenta los problemas y motivos que le llevaron a abandonar Espa\u00f1a","og:url":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/11\/morata-se-sincera-sobre-su-etapa-en-espana\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/fiorentina-v-ac-milan-serie-a-2-scaled.jpg","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/fiorentina-v-ac-milan-serie-a-2-scaled.jpg","og:image:width":2560,"og:image:height":1710,"article:published_time":"2024-10-11T15:43:34+00:00","article:modified_time":"2024-10-11T15:43:34+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"Morata se sincera sobre su etapa en Espa\u00f1a","twitter:description":"Morata se sincera sobre su etapa en Espa\u00f1a En una entrevista en la COPE, \u00c1lvaro Morata cuenta los problemas y motivos que le llevaron a abandonar Espa\u00f1a","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/10\/fiorentina-v-ac-milan-serie-a-2-scaled.jpg"},"aioseo_meta_data":{"post_id":"33310","title":"#post_title","description":"#post_title En una entrevista en la COPE, \u00c1lvaro Morata cuenta los problemas y motivos que le llevaron a abandonar Espa\u00f1a","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-10-11 15:43:34","updated":"2025-06-05 04:02:00","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/serie-a\/\" title=\"Serie A\">Serie A<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMorata se sincera sobre su etapa en Espa\u00f1a\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"Serie A","link":"https:\/\/agentelibredigital.com\/index.php\/category\/serie-a\/"},{"label":"Morata se sincera sobre su etapa en Espa\u00f1a","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/10\/11\/morata-se-sincera-sobre-su-etapa-en-espana\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/33310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/179"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=33310"}],"version-history":[{"count":1,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/33310\/revisions"}],"predecessor-version":[{"id":33338,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/33310\/revisions\/33338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/33311"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=33310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=33310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=33310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}