{"id":32080,"date":"2024-09-26T23:50:03","date_gmt":"2024-09-26T21:50:03","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=32080"},"modified":"2024-09-26T23:50:03","modified_gmt":"2024-09-26T21:50:03","slug":"simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/26\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\/","title":{"rendered":"Simeone: El que cometiera un fallo ganaba, y por suerte cay\u00f3 para nosotros"},"content":{"rendered":"<h4>El Cholo Simeone ha comparecido en rueda de prensa despu\u00e9s de la victoria de su equipo<\/h4>\n<p>El <a href=\"https:\/\/www.atleticodemadrid.com\/postpartidos\/celta-atletico-de-madrid-18-06-2024-16-09\">Atl\u00e9tico de Madrid<\/a> ha ganado 0-1 al RC Celta de manera in-extremis, gracias a un gol de Juli\u00e1n \u00c1lvarez. Tras el partido, <a href=\"https:\/\/agentelibredigital.com\/?s=simeone\">Simeone<\/a> ha comparecido en la tradicional rueda de prensa para dar sus sensaciones sobre el partido.<\/p>\n<h2>\u00bfSe fich\u00f3 a Juli\u00e1n \u00c1lvarez para estas cosas?<\/h2>\n<p><em><strong>\u00abSon futbolistas especiales. Necesitamos tiempo para que \u00e9l y Alex encuentren sociedades porque creo que el equipo est\u00e1 jugando muy bien en lo defensivo. En estos 7 partidos que jugamos, llevamos un trabajo colectivo muy bueno, con mucha paciencia. Salvo el partido con el Rayo Vallecano en el primer tiempo, el equipo se comport\u00f3 defensivamente muy bien. Necesitamos mejorar ofensivamente, necesitamos mejorar en las sociedades. El primer paso es m\u00edo, ya que tengo que encontrar quienes pueden asociarse mejor para generar ese juego que se necesita para atacar. Lo encontraremos porque los chicos est\u00e1n predispuestos para todo. Entre qui\u00e9n entre, en lugar donde lo haga, busca lo m\u00e1s importante que necesitamos que es sumar los tres puntos. Yo creo que hoy, con una paciencia defensiva importante, nos llevamos tres puntos, contra un rival que no pierde desde febrero (en casa). Desde que subi\u00f3 el entrenador de la cantera, con los chicos que conoc\u00eda, fueron generando lo que se ve, un equipo que juega muy bien, que ataca muy bien. Sab\u00edamos que el que se equivocaba perd\u00eda. Nosotros tuvimos la fortuna de aprovechar la situaci\u00f3n que tuvimos.\u00bb<\/strong><\/em><\/p>\n<h2>\u00bfQu\u00e9 supone la victoria para el equipo?<\/h2>\n<p><em><strong>\u00abSignifica que venimos trabajando bien. Repito, salvo el primer tiempo con el Rayo, los dem\u00e1s partidos creo que se controlo de una buena manera el recorrido del partido para donde quer\u00eda ir y para donde se estaba llevando. Necesitamos mejorar en esas sociedades ofensivas que tenemos y que obviamente me tengo que encargar de que aparezcan y que ellos puedan encontrarlas naturalmente. Nos hace bien ganar este partido porque tenemos un rival en la liga que es el Barcelona que gan\u00f3 sus 7 partidos, sac\u00f3 los 21 puntos. Hay que felicitarlo porque lo est\u00e1 haciendo muy bien.\u00bb<\/strong><\/em><\/p>\n<h2>Importancia de la porter\u00eda a cero<\/h2>\n<p><em><strong>\u00abS\u00ed en el primer tiempo m\u00e1s. Yo creo que en el primer tiempo estuvimos correctos en defensa, pero no generamos situaciones de ataque productivas para poner a nuestros futbolistas de cara a que pase algo. Ellos defendieron bien tambi\u00e9n. En el segundo tiempo, los cambios nos fueron alimentando poco a poco de m\u00e1s cosas para mejor. La entrada de Rodrigo, la de Riquelme, la de Juli\u00e1n, la de Correa, la de Llorente en el carril derecho al final del partido. Creo que nos fueron dando cosas en un partido en el que se ve\u00eda que \u00edbamos a tener posibilidades los dos equipos. Las tuvieron ellos, en la jugada anterior a la nuestra. Por suerte, hicieron muy bien, Griezmann y Juli\u00e1n para llevarnos un partido muy bueno y muy importante. \u00ab<\/strong><\/em><\/p>\n<h2>\u00bfSe va satisfecho con el partido?<\/h2>\n<p><em><strong>\u00abOblak par\u00f3 una buena pelota de Aspas. Fue la misma que par\u00f3 el portero de ellos a Riquelme. Despu\u00e9s no hubo otra tan peligrosa como aparenta. Lo que veo es que el equipo est\u00e1 trabajando bien, que tenemos que mejorar en la parte ofensiva. Siempre es seg\u00fan por donde uno lo mire. Si uno ve que el Celta no pierde como local desde febrero, algo bueno habremos hecho.\u00bb<\/strong><\/em><\/p>\n<h2>Sobre Gallagher y Le Normand<\/h2>\n<p><em><strong>\u00abMe pone muy contento el rendimiento de Gallagher y Robin. Necesitamos absolutamente a Sorloth y aparecer\u00e1. No tengo ninguna duda. Est\u00e1 al caer. Aparecer\u00e1. Y Juli\u00e1n apareci\u00f3 en un momento determinante. Necesitamos de los goles de la gente que vino para ayudarnos a seguir creciendo en esta parcela. Y bueno, la contundencia que hablamos. El d\u00eda del Espanyol tuvimos siete ocasiones de gol, no pudimos meterla. Hoy tuvimos dos, la de Riquelme y la de Juli\u00e1n, y conseguimos marcar. Hay que tratar de quedarse ni contento del todo contra el Espanyol, ni contento del todo hoy. Manteniendo la tranquilidad. Sabiendo que somos un equipo que debemos tener paciencia. Tener la porter\u00eda a cero, que hay el partido entra en un lugar donde nos gusta. \u00ab<\/strong><\/em><\/p>\n<h2>Cambios respecto a la temporada pasada<\/h2>\n<p><em><strong>\u00abHay un trabajo colectivo defensivo que es mucho mejor. Eso hace que todav\u00eda no encontremos esa parcela de poder jugar ofensivamente mejor, que la podemos mejorar porque tenemos argumentos para mejorarla y seguir manteniendo esa estructura defensiva que nos fortalece fuera de casa. Est\u00e1 claro que hay una estructura diferente a los planteos en otros partidos. Por ah\u00ed, vamos pensando en querer atacar m\u00e1s. Y ahora atacamos un poco menos fuera de casa y por eso ahora tenemos resultados m\u00e1s importantes.\u00bb<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Cholo Simeone ha comparecido en rueda de prensa despu\u00e9s de la victoria de su equipo El Atl\u00e9tico de Madrid ha ganado 0-1 al RC Celta de manera in-extremis, gracias&hellip; <\/p>\n","protected":false},"author":49,"featured_media":32085,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[13,46],"tags":[62,2353,1242,113],"class_list":["post-32080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atletico-de-madrid","category-laliga-ea-sports","tag-atletico-de-madrid","tag-la-liga-ea-sport","tag-rc-celta","tag-simeone"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Simeone: El que cometiera un fallo ganaba, y por suerte cay\u00f3 para nosotros El Cholo Simeone ha comparecido en rueda de prensa despu\u00e9s de la victoria de su equipo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Rafael Pereda\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/26\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Simeone: El que cometiera un fallo ganaba, y por suerte cay\u00f3 para nosotros \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"Simeone: El que cometiera un fallo ganaba, y por suerte cay\u00f3 para nosotros El Cholo Simeone ha comparecido en rueda de prensa despu\u00e9s de la victoria de su equipo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/26\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/rc-celta-de-vigo-v-atletico-de-madrid-la-liga-ea-sports-3-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/rc-celta-de-vigo-v-atletico-de-madrid-la-liga-ea-sports-3-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1923\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-09-26T21:50:03+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-09-26T21:50:03+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Simeone: El que cometiera un fallo ganaba, y por suerte cay\u00f3 para nosotros \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Simeone: El que cometiera un fallo ganaba, y por suerte cay\u00f3 para nosotros El Cholo Simeone ha comparecido en rueda de prensa despu\u00e9s de la victoria de su equipo\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/rc-celta-de-vigo-v-atletico-de-madrid-la-liga-ea-sports-3-scaled.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/26\\\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\\\/#blogposting\",\"name\":\"Simeone: El que cometiera un fallo ganaba, y por suerte cay\\u00f3 para nosotros \\u2013 Agente Libre Digital\",\"headline\":\"Simeone: El que cometiera un fallo ganaba, y por suerte cay\\u00f3 para nosotros\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/rafael-pereda\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/rc-celta-de-vigo-v-atletico-de-madrid-la-liga-ea-sports-3-scaled.jpg\",\"width\":2560,\"height\":1923,\"caption\":\"Simeone dando indicaciones durante el partido. Fuente Getty Images\\\/ Octavio Passos\"},\"datePublished\":\"2024-09-26T23:50:03+02:00\",\"dateModified\":\"2024-09-26T23:50:03+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/26\\\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/26\\\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\\\/#webpage\"},\"articleSection\":\"Atl\\u00e9tico de Madrid, LaLiga EA Sports, Atl\\u00e9tico de Madrid, La liga EA Sport, RC Celta, Simeone\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/26\\\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/atletico-de-madrid\\\/#listItem\",\"name\":\"Atl\\u00e9tico de Madrid\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/atletico-de-madrid\\\/#listItem\",\"position\":2,\"name\":\"Atl\\u00e9tico de Madrid\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/atletico-de-madrid\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/26\\\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\\\/#listItem\",\"name\":\"Simeone: El que cometiera un fallo ganaba, y por suerte cay\\u00f3 para nosotros\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/26\\\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\\\/#listItem\",\"position\":3,\"name\":\"Simeone: El que cometiera un fallo ganaba, y por suerte cay\\u00f3 para nosotros\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/atletico-de-madrid\\\/#listItem\",\"name\":\"Atl\\u00e9tico de Madrid\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/26\\\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/26\\\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/rafael-pereda\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/rafael-pereda\\\/\",\"name\":\"Rafael Pereda\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/26\\\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b011881c808245d96da0fec527c19d4905183fa8f648250e570f070e9c6c144f?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Rafael Pereda\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/26\\\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/26\\\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\\\/\",\"name\":\"Simeone: El que cometiera un fallo ganaba, y por suerte cay\\u00f3 para nosotros \\u2013 Agente Libre Digital\",\"description\":\"Simeone: El que cometiera un fallo ganaba, y por suerte cay\\u00f3 para nosotros El Cholo Simeone ha comparecido en rueda de prensa despu\\u00e9s de la victoria de su equipo\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/26\\\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/rafael-pereda\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/rafael-pereda\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/rc-celta-de-vigo-v-atletico-de-madrid-la-liga-ea-sports-3-scaled.jpg\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/26\\\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\\\/#mainImage\",\"width\":2560,\"height\":1923,\"caption\":\"Simeone dando indicaciones durante el partido. Fuente Getty Images\\\/ Octavio Passos\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/26\\\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\\\/#mainImage\"},\"datePublished\":\"2024-09-26T23:50:03+02:00\",\"dateModified\":\"2024-09-26T23:50:03+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Simeone: El que cometiera un fallo ganaba, y por suerte cay\u00f3 para nosotros \u2013 Agente Libre Digital","description":"Simeone: El que cometiera un fallo ganaba, y por suerte cay\u00f3 para nosotros El Cholo Simeone ha comparecido en rueda de prensa despu\u00e9s de la victoria de su equipo","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/26\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/26\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\/#blogposting","name":"Simeone: El que cometiera un fallo ganaba, y por suerte cay\u00f3 para nosotros \u2013 Agente Libre Digital","headline":"Simeone: El que cometiera un fallo ganaba, y por suerte cay\u00f3 para nosotros","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/rafael-pereda\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/rc-celta-de-vigo-v-atletico-de-madrid-la-liga-ea-sports-3-scaled.jpg","width":2560,"height":1923,"caption":"Simeone dando indicaciones durante el partido. Fuente Getty Images\/ Octavio Passos"},"datePublished":"2024-09-26T23:50:03+02:00","dateModified":"2024-09-26T23:50:03+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/26\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/26\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\/#webpage"},"articleSection":"Atl\u00e9tico de Madrid, LaLiga EA Sports, Atl\u00e9tico de Madrid, La liga EA Sport, RC Celta, Simeone"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/26\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/atletico-de-madrid\/#listItem","name":"Atl\u00e9tico de Madrid"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/atletico-de-madrid\/#listItem","position":2,"name":"Atl\u00e9tico de Madrid","item":"https:\/\/agentelibredigital.com\/index.php\/category\/atletico-de-madrid\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/26\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\/#listItem","name":"Simeone: El que cometiera un fallo ganaba, y por suerte cay\u00f3 para nosotros"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/26\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\/#listItem","position":3,"name":"Simeone: El que cometiera un fallo ganaba, y por suerte cay\u00f3 para nosotros","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/atletico-de-madrid\/#listItem","name":"Atl\u00e9tico de Madrid"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/26\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/26\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/rafael-pereda\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/rafael-pereda\/","name":"Rafael Pereda","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/26\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b011881c808245d96da0fec527c19d4905183fa8f648250e570f070e9c6c144f?s=96&d=mm&r=g","width":96,"height":96,"caption":"Rafael Pereda"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/26\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/26\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\/","name":"Simeone: El que cometiera un fallo ganaba, y por suerte cay\u00f3 para nosotros \u2013 Agente Libre Digital","description":"Simeone: El que cometiera un fallo ganaba, y por suerte cay\u00f3 para nosotros El Cholo Simeone ha comparecido en rueda de prensa despu\u00e9s de la victoria de su equipo","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/26\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/rafael-pereda\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/rafael-pereda\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/rc-celta-de-vigo-v-atletico-de-madrid-la-liga-ea-sports-3-scaled.jpg","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/26\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\/#mainImage","width":2560,"height":1923,"caption":"Simeone dando indicaciones durante el partido. Fuente Getty Images\/ Octavio Passos"},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/26\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\/#mainImage"},"datePublished":"2024-09-26T23:50:03+02:00","dateModified":"2024-09-26T23:50:03+02:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"Simeone: El que cometiera un fallo ganaba, y por suerte cay\u00f3 para nosotros \u2013 Agente Libre Digital","og:description":"Simeone: El que cometiera un fallo ganaba, y por suerte cay\u00f3 para nosotros El Cholo Simeone ha comparecido en rueda de prensa despu\u00e9s de la victoria de su equipo","og:url":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/26\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/rc-celta-de-vigo-v-atletico-de-madrid-la-liga-ea-sports-3-scaled.jpg","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/rc-celta-de-vigo-v-atletico-de-madrid-la-liga-ea-sports-3-scaled.jpg","og:image:width":2560,"og:image:height":1923,"article:published_time":"2024-09-26T21:50:03+00:00","article:modified_time":"2024-09-26T21:50:03+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"Simeone: El que cometiera un fallo ganaba, y por suerte cay\u00f3 para nosotros \u2013 Agente Libre Digital","twitter:description":"Simeone: El que cometiera un fallo ganaba, y por suerte cay\u00f3 para nosotros El Cholo Simeone ha comparecido en rueda de prensa despu\u00e9s de la victoria de su equipo","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/rc-celta-de-vigo-v-atletico-de-madrid-la-liga-ea-sports-3-scaled.jpg"},"aioseo_meta_data":{"post_id":"32080","title":null,"description":"#post_title El Cholo Simeone ha comparecido en rueda de prensa despu\u00e9s de la victoria de su equipo","keywords":null,"keyphrases":{"focus":{"keyphrase":"Simeone","score":68,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":[],"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-09-26 21:50:03","updated":"2025-06-05 03:10:56","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/atletico-de-madrid\/\" title=\"Atl\u00e9tico de Madrid\">Atl\u00e9tico de Madrid<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSimeone: El que cometiera un fallo ganaba, y por suerte cay\u00f3 para nosotros\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"Atl\u00e9tico de Madrid","link":"https:\/\/agentelibredigital.com\/index.php\/category\/atletico-de-madrid\/"},{"label":"Simeone: El que cometiera un fallo ganaba, y por suerte cay\u00f3 para nosotros","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/26\/simeone-el-que-cometiera-un-fallo-ganaba-y-por-suerte-cayo-para-nosotros\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/32080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=32080"}],"version-history":[{"count":1,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/32080\/revisions"}],"predecessor-version":[{"id":32096,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/32080\/revisions\/32096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/32085"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=32080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=32080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=32080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}