{"id":30483,"date":"2024-09-15T16:47:16","date_gmt":"2024-09-15T14:47:16","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=30483"},"modified":"2024-09-15T16:47:16","modified_gmt":"2024-09-15T14:47:16","slug":"unionistas-no-se-rinde","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/15\/unionistas-no-se-rinde\/","title":{"rendered":"Unionistas no se rinde"},"content":{"rendered":"<h2>Unionistas vence por 2-1 al filial cul\u00e9 anotando el tanto de la victoria sobre la bocina en un encuentro ajustado entre dos candidatos al play off de ascenso<\/h2>\n<p style=\"text-align: left\">En la ma\u00f1ana del <strong>domingo 15 de septiembre <a href=\"https:\/\/unionistascf.com\/\">Unionistas de Salamanca<\/a> y FC Barcelona B<\/strong> se enfrentaban en la cuarta jornada de la <a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/1a-rfef\/\"><strong>1RFEF<\/strong><\/a> <strong>en el Estadio Reina Sof\u00eda<\/strong>.<\/p>\n<h3>Primera mitad con poco juego<\/h3>\n<p>El partido comenz\u00f3 activo, y cuando tan solo hab\u00edan corrido <strong>5 minutos de partido<\/strong>, una gran <strong>jugada asociativa entre los jugadores cul\u00e9s la culminaba Toni Fern\u00e1ndez para abrir el marcado<\/strong>r.<\/p>\n<p>A partir del primer tanto, <strong>el partido se entorpeci\u00f3 con faltas<\/strong> y ninguno de los equipos consegu\u00eda acercarse al \u00e1rea con peligro.<\/p>\n<figure id=\"attachment_30492\" aria-describedby=\"caption-attachment-30492\" style=\"width: 1928px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-30492\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_20240915_132129-scaled.jpg\" alt=\"\" width=\"1928\" height=\"2560\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_20240915_132129-scaled.jpg 1928w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_20240915_132129-226x300.jpg 226w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_20240915_132129-771x1024.jpg 771w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_20240915_132129-768x1020.jpg 768w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_20240915_132129-1157x1536.jpg 1157w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_20240915_132129-1542x2048.jpg 1542w\" sizes=\"auto, (max-width: 1928px) 100vw, 1928px\" \/><figcaption id=\"caption-attachment-30492\" class=\"wp-caption-text\">Iv\u00e1n Moreno y Pau Mart\u00ednez yendo al saque de esquina. Fuente \u00c1ngel Luis Yuste.<\/figcaption><\/figure>\n<p>En los \u00faltimos minutos del primer acto <strong>Unionistas lo intento con insistencia pero la defensa rival se manten\u00eda f\u00e9rrea<\/strong>.<\/p>\n<h3>Unionistas insiste y lo consigue<\/h3>\n<p>La segunda mitad comenz\u00f3 como acab\u00f3 la primera, <strong>Unionistas lo intentaba,<\/strong> incluso, <strong>Santamar\u00eda estrell\u00f3 un bal\u00f3n en el travesa\u00f1o<\/strong>.<\/p>\n<p>En el <strong>minuto 74<\/strong>, una jugada trabada por varios rebotes, la aprovechaba <strong>Euald Verg\u00e9s que se la daba a J.Arriba en la frontal del \u00e1rea cul\u00e9 y pon\u00eda el bal\u00f3n en la escuadra<\/strong> de la meta de Astralaga empatando el partido.<\/p>\n<p>A partir del gol local, <strong>el partido enloqueci\u00f3<\/strong>, ambos equipos quer\u00edan los 3 puntos, y en una contra <strong>C\u00e9dric provocaba<\/strong> una falta al borde del \u00e1rea charra, que conllevaba <strong>la tarjeta roja para Ramiro<\/strong>.<\/p>\n<figure id=\"attachment_30495\" aria-describedby=\"caption-attachment-30495\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-30495\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_20240915_135020-scaled.jpg\" alt=\"\" width=\"2560\" height=\"2051\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_20240915_135020-scaled.jpg 2560w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_20240915_135020-300x240.jpg 300w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_20240915_135020-1024x820.jpg 1024w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_20240915_135020-768x615.jpg 768w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_20240915_135020-1536x1231.jpg 1536w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_20240915_135020-2048x1641.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-30495\" class=\"wp-caption-text\">Jugadores de Unionistas y Barcelona B esperando al saque de esquina. Fuente \u00c1ngel Luis Yuste.<\/figcaption><\/figure>\n<p style=\"text-align: left\">Tras la roja <strong>parec\u00eda que Unionistas iba a tener que aguantar el resultado<\/strong>, pero lejos de eso, de nuevo, <strong>Euald, pon\u00eda un gran centro lateral para que, otra vez, J. Arriba rematase<\/strong> desde el punto de penalti <strong>y pusiera la guinda de la remontada salmantina<\/strong>.<\/p>\n<p>Con el pitido final, <strong>Unionistas suma 7 puntos<\/strong> y se coloca en la parte alta de la tabla, mientras, el <strong>FC Barcelona B se queda con 4<\/strong> puntos en la zona media baja de la tabla.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unionistas vence por 2-1 al filial cul\u00e9 anotando el tanto de la victoria sobre la bocina en un encuentro ajustado entre dos candidatos al play off de ascenso En la&hellip; <\/p>\n","protected":false},"author":57,"featured_media":30491,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[7,47],"tags":[],"class_list":["post-30483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1a-rfef","category-futbol-espanol"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Unionistas vence por 2-1 al filial cul\u00e9 anotando el tanto de la victoria sobre la bocina en un encuentro igualado y tenso.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Angel Yuste\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/15\/unionistas-no-se-rinde\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Unionistas no se rinde \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"Unionistas vence por 2-1 al filial cul\u00e9 anotando el tanto de la victoria sobre la bocina en un encuentro igualado y tenso.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/15\/unionistas-no-se-rinde\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_20240915_1351402-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_20240915_1351402-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1362\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1118\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-09-15T14:47:16+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-09-15T14:47:16+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Unionistas no se rinde \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Unionistas vence por 2-1 al filial cul\u00e9 anotando el tanto de la victoria sobre la bocina en un encuentro igualado y tenso.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_20240915_1351402-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/15\\\/unionistas-no-se-rinde\\\/#blogposting\",\"name\":\"Unionistas no se rinde \\u2013 Agente Libre Digital\",\"headline\":\"Unionistas no se rinde\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/angel-yuste\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/IMG_20240915_1351402-1.jpg\",\"width\":1362,\"height\":1118},\"datePublished\":\"2024-09-15T16:47:16+02:00\",\"dateModified\":\"2024-09-15T16:47:16+02:00\",\"inLanguage\":\"es-ES\",\"commentCount\":4,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/15\\\/unionistas-no-se-rinde\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/15\\\/unionistas-no-se-rinde\\\/#webpage\"},\"articleSection\":\"1\\u00aa RFEF, F\\u00fatbol Espa\\u00f1ol\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/15\\\/unionistas-no-se-rinde\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/1a-rfef\\\/#listItem\",\"name\":\"1\\u00aa RFEF\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/1a-rfef\\\/#listItem\",\"position\":2,\"name\":\"1\\u00aa RFEF\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/1a-rfef\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/15\\\/unionistas-no-se-rinde\\\/#listItem\",\"name\":\"Unionistas no se rinde\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/15\\\/unionistas-no-se-rinde\\\/#listItem\",\"position\":3,\"name\":\"Unionistas no se rinde\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/1a-rfef\\\/#listItem\",\"name\":\"1\\u00aa RFEF\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/15\\\/unionistas-no-se-rinde\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/15\\\/unionistas-no-se-rinde\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/angel-yuste\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/angel-yuste\\\/\",\"name\":\"Angel Yuste\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/15\\\/unionistas-no-se-rinde\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ff839ca1409153ee729d2114851ac59fc8944763cfdffb926e743de531c3e31?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Angel Yuste\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/15\\\/unionistas-no-se-rinde\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/15\\\/unionistas-no-se-rinde\\\/\",\"name\":\"Unionistas no se rinde \\u2013 Agente Libre Digital\",\"description\":\"Unionistas vence por 2-1 al filial cul\\u00e9 anotando el tanto de la victoria sobre la bocina en un encuentro igualado y tenso.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/15\\\/unionistas-no-se-rinde\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/angel-yuste\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/angel-yuste\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/IMG_20240915_1351402-1.jpg\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/15\\\/unionistas-no-se-rinde\\\/#mainImage\",\"width\":1362,\"height\":1118},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/15\\\/unionistas-no-se-rinde\\\/#mainImage\"},\"datePublished\":\"2024-09-15T16:47:16+02:00\",\"dateModified\":\"2024-09-15T16:47:16+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Unionistas no se rinde \u2013 Agente Libre Digital","description":"Unionistas vence por 2-1 al filial cul\u00e9 anotando el tanto de la victoria sobre la bocina en un encuentro igualado y tenso.","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/15\/unionistas-no-se-rinde\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/15\/unionistas-no-se-rinde\/#blogposting","name":"Unionistas no se rinde \u2013 Agente Libre Digital","headline":"Unionistas no se rinde","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/angel-yuste\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_20240915_1351402-1.jpg","width":1362,"height":1118},"datePublished":"2024-09-15T16:47:16+02:00","dateModified":"2024-09-15T16:47:16+02:00","inLanguage":"es-ES","commentCount":4,"mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/15\/unionistas-no-se-rinde\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/15\/unionistas-no-se-rinde\/#webpage"},"articleSection":"1\u00aa RFEF, F\u00fatbol Espa\u00f1ol"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/15\/unionistas-no-se-rinde\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/1a-rfef\/#listItem","name":"1\u00aa RFEF"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/1a-rfef\/#listItem","position":2,"name":"1\u00aa RFEF","item":"https:\/\/agentelibredigital.com\/index.php\/category\/1a-rfef\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/15\/unionistas-no-se-rinde\/#listItem","name":"Unionistas no se rinde"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/15\/unionistas-no-se-rinde\/#listItem","position":3,"name":"Unionistas no se rinde","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/1a-rfef\/#listItem","name":"1\u00aa RFEF"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/15\/unionistas-no-se-rinde\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/15\/unionistas-no-se-rinde\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/angel-yuste\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/angel-yuste\/","name":"Angel Yuste","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/15\/unionistas-no-se-rinde\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/9ff839ca1409153ee729d2114851ac59fc8944763cfdffb926e743de531c3e31?s=96&d=mm&r=g","width":96,"height":96,"caption":"Angel Yuste"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/15\/unionistas-no-se-rinde\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/15\/unionistas-no-se-rinde\/","name":"Unionistas no se rinde \u2013 Agente Libre Digital","description":"Unionistas vence por 2-1 al filial cul\u00e9 anotando el tanto de la victoria sobre la bocina en un encuentro igualado y tenso.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/15\/unionistas-no-se-rinde\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/angel-yuste\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/angel-yuste\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_20240915_1351402-1.jpg","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/15\/unionistas-no-se-rinde\/#mainImage","width":1362,"height":1118},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/15\/unionistas-no-se-rinde\/#mainImage"},"datePublished":"2024-09-15T16:47:16+02:00","dateModified":"2024-09-15T16:47:16+02:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"Unionistas no se rinde \u2013 Agente Libre Digital","og:description":"Unionistas vence por 2-1 al filial cul\u00e9 anotando el tanto de la victoria sobre la bocina en un encuentro igualado y tenso.","og:url":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/15\/unionistas-no-se-rinde\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_20240915_1351402-1.jpg","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_20240915_1351402-1.jpg","og:image:width":1362,"og:image:height":1118,"article:published_time":"2024-09-15T14:47:16+00:00","article:modified_time":"2024-09-15T14:47:16+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"Unionistas no se rinde \u2013 Agente Libre Digital","twitter:description":"Unionistas vence por 2-1 al filial cul\u00e9 anotando el tanto de la victoria sobre la bocina en un encuentro igualado y tenso.","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_20240915_1351402-1.jpg"},"aioseo_meta_data":{"post_id":"30483","title":null,"description":"Unionistas vence por 2-1 al filial cul\u00e9 anotando el tanto de la victoria sobre la bocina en un encuentro igualado y tenso.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-09-15 14:21:15","updated":"2025-06-05 01:59:58","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/1a-rfef\/\" title=\"1\u00aa RFEF\">1\u00aa RFEF<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tUnionistas no se rinde\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"1\u00aa RFEF","link":"https:\/\/agentelibredigital.com\/index.php\/category\/1a-rfef\/"},{"label":"Unionistas no se rinde","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/15\/unionistas-no-se-rinde\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/30483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=30483"}],"version-history":[{"count":4,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/30483\/revisions"}],"predecessor-version":[{"id":30498,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/30483\/revisions\/30498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/30491"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=30483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=30483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=30483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}