{"id":30404,"date":"2024-09-14T22:02:16","date_gmt":"2024-09-14T20:02:16","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=30404"},"modified":"2024-09-14T22:06:22","modified_gmt":"2024-09-14T20:06:22","slug":"ruben-albes-estamos-lejos-del-potencial-que-podemos-tener","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/14\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\/","title":{"rendered":"Rub\u00e9n Alb\u00e9s: \u201cEstamos lejos del potencial que podemos tener\u201d"},"content":{"rendered":"<h4>Rub\u00e9n Alb\u00e9s, entrenador del conjunto asturiano, compareci\u00f3 ante los medios tras la derrota del <a href=\"https:\/\/agentelibredigital.com\/?s=Real+Sporting\" target=\"_blank\" rel=\"noopener\">Real Sporting<\/a> (1-0) en Campos de Sport El Sardinero ante el <a href=\"https:\/\/agentelibredigital.com\/?s=Racing+Santander\" target=\"_blank\" rel=\"noopener\">Real Racing Club<\/a>. El Sporting, con un excelente Rub\u00e9n Y\u00e1\u00f1ez, no fue capaz de hacer frente al equipo del asturiano Jos\u00e9 Alberto.<\/h4>\n<p>\u201cLa primera parte ha estado <strong>igualada<\/strong>. El partido estaba para el que acertara. Era complicado por el campo. Cometimos un error en un saque de banda, antes tuvimos la opci\u00f3n de Gaspi. En la segunda parte fue <strong>m\u00e1s coraz\u00f3n que f\u00fatbol<\/strong>. Por empuje intentamos empatar\u201d.<\/p>\n<div class=\"google-auto-placed ap_container\">\n<div id=\"aswift_4_host\">\u201cA partir del 20&#8242; pasamos al 4-3-3 con m\u00e1s control, pero no fuimos capaces de acertar. Luego buscamos otra vez con dos delanteros, ah\u00ed <strong>nos falt\u00f3 control<\/strong>. No nos hicimos con las acciones en el juego directo. No fue por el cambio de Nacho Mart\u00edn. <strong>Pusimos todo lo ofensivo que ten\u00edamos<\/strong>\u201d.<\/div>\n<div><\/div>\n<div>Rub\u00e9n Alb\u00e9s se\u00f1al\u00f3 lo que menos le gust\u00f3 del partido:<b> \u201c<\/b>Las <strong>situaciones al espacio<\/strong> son todas de contraataque por las p\u00e9rdidas de los dos equipos. En los \u00faltimos minutos, s\u00e9 que era dif\u00edcil por la emoci\u00f3n del Racing, pero pusimos mucho coraz\u00f3n y poco f\u00fatbol\u201d.<\/div>\n<\/div>\n<p>Sobre Cote, que fue sustituido en el minuto 44: \u201cProbablemente tenga alg\u00fan tipo de lesi\u00f3n, pero estamos a la espera de las pruebas\u201d.<\/p>\n<p>Alb\u00e9s habl\u00f3 sobre el equipo rival: \u201cFelicit\u00e9 a Jos\u00e9 Alberto antes del partido. <strong>Propuestas as\u00ed son bonitas de ver como espectador<\/strong>. La nuestra creo que tambi\u00e9n. Hoy hemos sido dos equipos que han salido a ganar. Fastidiados porque se lo han llevado ellos\u201d. Tambi\u00e9n afirm\u00f3 que \u201chan tenido la p\u00e9rdida de Peque pero han tra\u00eddo a Pablo. Han tenido retoques y <strong>es m\u00e1s fuerte que la temporada pasada<\/strong>. La idea es la misma. Han cambiado piezas, han hecho buen trabajo\u201d.<\/p>\n<p>\u201cEn nuestro mejor momento, <strong>est\u00e1bamos por encima de lo que estaba proponiendo el Racing<\/strong>. Cuando llega el gol, no limitamos las p\u00e9rdidas y somos lentos en circulaci\u00f3n. Tambi\u00e9n el temor a que saltara la pelota. No va en relaci\u00f3n al atrevimiento\u201d, sentenci\u00f3.<\/p>\n<p>\u201c<strong>El c\u00e9sped no es excusa<\/strong> porque si hubiera estado bien, el Racing juega espectacular\u201d, se\u00f1al\u00f3 Alb\u00e9s. \u201cSe ha visto un partido m\u00e1s feo, de mucho duelo, contacto y p\u00e9rdidas. Es cierto que el que se adelantara ten\u00eda una gran ventaja. Se puso a favor de ellos\u201d.<\/p>\n<p>\u201c<b>Estamos lejos del potencial que podemos tener<\/b>. Lo cre\u00eda en la victoria y en la derrota. Tenemos que seguir conoci\u00e9ndonos, dando soluciones a problemas que surjan durante la temporada\u201d, relat\u00f3 el entrenador. \u201cYo llego nuevo, tambi\u00e9n hay futbolistas nuevos. Estamos en dos puntos diferentes con el Racing, pero no es excusa para no haber sumado hoy. Tendremos que hacer m\u00e1s para que ese proceso se acelere\u201d concluy\u00f3.<\/p>\n<p><a href=\"https:\/\/youtu.be\/D9iRj8GuoQo?si=qwkyA7b7L6808RRt\" target=\"_blank\" rel=\"noopener\">Enlace a la rueda de prensa.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rub\u00e9n Alb\u00e9s, entrenador del conjunto asturiano, compareci\u00f3 ante los medios tras la derrota del Real Sporting (1-0) en Campos de Sport El Sardinero ante el Real Racing Club. El Sporting,&hellip; <\/p>\n","protected":false},"author":92,"featured_media":30414,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1,47,8],"tags":[],"class_list":["post-30404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-futbol-espanol","category-laliga-hypermotion"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Rub\u00e9n Alb\u00e9s: \u201cEstamos lejos del potencial que podemos tener\u201d\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Brenda Garc\u00eda\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/14\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Rub\u00e9n Alb\u00e9s: \u201cEstamos lejos del potencial que podemos tener\u201d \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"Rub\u00e9n Alb\u00e9s: \u201cEstamos lejos del potencial que podemos tener\u201d\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/14\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_7874.jpeg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_7874.jpeg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2224\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1238\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-09-14T20:02:16+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-09-14T20:06:22+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Rub\u00e9n Alb\u00e9s: \u201cEstamos lejos del potencial que podemos tener\u201d \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Rub\u00e9n Alb\u00e9s: \u201cEstamos lejos del potencial que podemos tener\u201d\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_7874.jpeg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/14\\\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\\\/#blogposting\",\"name\":\"Rub\\u00e9n Alb\\u00e9s: \\u201cEstamos lejos del potencial que podemos tener\\u201d \\u2013 Agente Libre Digital\",\"headline\":\"Rub\\u00e9n Alb\\u00e9s: \\u201cEstamos lejos del potencial que podemos tener\\u201d\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/brenda-garcia\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/IMG_7874.jpeg\",\"width\":2224,\"height\":1238},\"datePublished\":\"2024-09-14T22:02:16+02:00\",\"dateModified\":\"2024-09-14T22:06:22+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/14\\\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/14\\\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\\\/#webpage\"},\"articleSection\":\"Blog, F\\u00fatbol Espa\\u00f1ol, LaLiga Hypermotion\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/14\\\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/blog\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/blog\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/14\\\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\\\/#listItem\",\"name\":\"Rub\\u00e9n Alb\\u00e9s: \\u201cEstamos lejos del potencial que podemos tener\\u201d\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/14\\\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\\\/#listItem\",\"position\":3,\"name\":\"Rub\\u00e9n Alb\\u00e9s: \\u201cEstamos lejos del potencial que podemos tener\\u201d\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/14\\\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/14\\\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/brenda-garcia\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/brenda-garcia\\\/\",\"name\":\"Brenda Garc\\u00eda\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/14\\\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc971056321eb11bd4ad6a5d3ee76f7f4b6ab0cd0b3e35a0b1a24ea5284ed3a6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Brenda Garc\\u00eda\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/14\\\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/14\\\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\\\/\",\"name\":\"Rub\\u00e9n Alb\\u00e9s: \\u201cEstamos lejos del potencial que podemos tener\\u201d \\u2013 Agente Libre Digital\",\"description\":\"Rub\\u00e9n Alb\\u00e9s: \\u201cEstamos lejos del potencial que podemos tener\\u201d\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/14\\\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/brenda-garcia\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/brenda-garcia\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/IMG_7874.jpeg\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/14\\\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\\\/#mainImage\",\"width\":2224,\"height\":1238},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/09\\\/14\\\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\\\/#mainImage\"},\"datePublished\":\"2024-09-14T22:02:16+02:00\",\"dateModified\":\"2024-09-14T22:06:22+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Rub\u00e9n Alb\u00e9s: \u201cEstamos lejos del potencial que podemos tener\u201d \u2013 Agente Libre Digital","description":"Rub\u00e9n Alb\u00e9s: \u201cEstamos lejos del potencial que podemos tener\u201d","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/14\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/14\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\/#blogposting","name":"Rub\u00e9n Alb\u00e9s: \u201cEstamos lejos del potencial que podemos tener\u201d \u2013 Agente Libre Digital","headline":"Rub\u00e9n Alb\u00e9s: \u201cEstamos lejos del potencial que podemos tener\u201d","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/brenda-garcia\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_7874.jpeg","width":2224,"height":1238},"datePublished":"2024-09-14T22:02:16+02:00","dateModified":"2024-09-14T22:06:22+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/14\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/14\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\/#webpage"},"articleSection":"Blog, F\u00fatbol Espa\u00f1ol, LaLiga Hypermotion"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/14\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/blog\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/blog\/#listItem","position":2,"name":"Blog","item":"https:\/\/agentelibredigital.com\/index.php\/category\/blog\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/14\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\/#listItem","name":"Rub\u00e9n Alb\u00e9s: \u201cEstamos lejos del potencial que podemos tener\u201d"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/14\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\/#listItem","position":3,"name":"Rub\u00e9n Alb\u00e9s: \u201cEstamos lejos del potencial que podemos tener\u201d","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/blog\/#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/14\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/14\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/brenda-garcia\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/brenda-garcia\/","name":"Brenda Garc\u00eda","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/14\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/fc971056321eb11bd4ad6a5d3ee76f7f4b6ab0cd0b3e35a0b1a24ea5284ed3a6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Brenda Garc\u00eda"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/14\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/14\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\/","name":"Rub\u00e9n Alb\u00e9s: \u201cEstamos lejos del potencial que podemos tener\u201d \u2013 Agente Libre Digital","description":"Rub\u00e9n Alb\u00e9s: \u201cEstamos lejos del potencial que podemos tener\u201d","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/14\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/brenda-garcia\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/brenda-garcia\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_7874.jpeg","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/14\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\/#mainImage","width":2224,"height":1238},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/14\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\/#mainImage"},"datePublished":"2024-09-14T22:02:16+02:00","dateModified":"2024-09-14T22:06:22+02:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"Rub\u00e9n Alb\u00e9s: \u201cEstamos lejos del potencial que podemos tener\u201d \u2013 Agente Libre Digital","og:description":"Rub\u00e9n Alb\u00e9s: \u201cEstamos lejos del potencial que podemos tener\u201d","og:url":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/14\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_7874.jpeg","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_7874.jpeg","og:image:width":2224,"og:image:height":1238,"article:published_time":"2024-09-14T20:02:16+00:00","article:modified_time":"2024-09-14T20:06:22+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"Rub\u00e9n Alb\u00e9s: \u201cEstamos lejos del potencial que podemos tener\u201d \u2013 Agente Libre Digital","twitter:description":"Rub\u00e9n Alb\u00e9s: \u201cEstamos lejos del potencial que podemos tener\u201d","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/09\/IMG_7874.jpeg"},"aioseo_meta_data":{"post_id":"30404","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-09-14 19:44:44","updated":"2025-06-05 01:56:57","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/blog\/\" title=\"Blog\">Blog<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRub\u00e9n Alb\u00e9s: \u201cEstamos lejos del potencial que podemos tener\u201d\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"Blog","link":"https:\/\/agentelibredigital.com\/index.php\/category\/blog\/"},{"label":"Rub\u00e9n Alb\u00e9s: \u201cEstamos lejos del potencial que podemos tener\u201d","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/09\/14\/ruben-albes-estamos-lejos-del-potencial-que-podemos-tener\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/30404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/92"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=30404"}],"version-history":[{"count":12,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/30404\/revisions"}],"predecessor-version":[{"id":30424,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/30404\/revisions\/30424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/30414"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=30404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=30404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=30404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}