{"id":29328,"date":"2024-08-31T19:53:02","date_gmt":"2024-08-31T17:53:02","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=29328"},"modified":"2024-08-31T19:53:02","modified_gmt":"2024-08-31T17:53:02","slug":"pezzolano-se-disculpa-tras-la-humillacion-en-montjuic","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/31\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\/","title":{"rendered":"Pezzolano se disculpa tras la humillaci\u00f3n en Montjuic"},"content":{"rendered":"<p><em><strong>El entrenador del conjunto pucelano ha salido a atender a los medios de comunicaci\u00f3n en la sala de prensa del Llu\u00eds Companys despu\u00e9s de ser masacrados con un abultado 7-0 propiciado por el <a href=\"https:\/\/agentelibredigital.com\/?s=barcelona\">F.C Barcelona<\/a>. El equipo blaugrana supero en todo momento al conjunto vallisoletano quienes poco pudieron hacer ante tal asedio. Pezzolano pidi\u00f3 disculpas a la afici\u00f3n o habla sobre el estado de forma de <a href=\"https:\/\/agentelibredigital.com\/?s=Raul+moro\">Ra\u00fal Moro\u00a0<\/a><\/strong><\/em><\/p>\n<p><a href=\"https:\/\/agentelibredigital.com\/?s=pezzolano\">Paulo Pezzolano<\/a> entro en rueda de prensa predispuesto a hablar sobre el partido. Empez\u00f3 pidiendo disculpas a la afici\u00f3n y aclamando lo corta que es la plantilla y que ni con lo mejor sobre el verde pudieron competir.<strong> \u00abPedir disculpas a la afici\u00f3n y la ciudad. No se lo merecen. No se compiti\u00f3. Fue lamentable y no hay excusas. Pusimos a los mejores que ten\u00edamos en cancha y no pudimos competir. Tenemos una plantilla corta y vamos a sufrir mucho\u00bb.<\/strong><\/p>\n<p>Como segunda intervenci\u00f3n tiro hacia la sobrepoblaci\u00f3n evidente en ciertas posiciones y la carencia de sustitutos en otras. <strong>\u00abTenemos que trabajar. Tenemos puestos sobrepoblados en la plantilla y otros cortos, con pocos o ning\u00fan jugador\u00bb<\/strong> .Despu\u00e9s hablo sobre el estado de forma de Ra\u00fal Moro, con quien, tienen intenciones de progresar hasta poder completar el encuentro entero. <strong>\u00abLa idea con Moro es que sume minutos y siga mejorando para que aguante los 90 con m\u00e1s frecuencia\u00bb<\/strong><\/p>\n<p>El t\u00e9cnico del <a href=\"https:\/\/agentelibredigital.com\/?s=Real+Valladolid\"><strong>Real Valladolid<\/strong><\/a> finaliz\u00f3 con unas disculpas a la <strong>afici\u00f3n<\/strong> y a la ciudad. Despu\u00e9s de haber dado una<strong> imagen lamentable<\/strong> al aficionado vallisoletano con una mas que <strong>dolorosa goleada.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El entrenador del conjunto pucelano ha salido a atender a los medios de comunicaci\u00f3n en la sala de prensa del Llu\u00eds Companys despu\u00e9s de ser masacrados con un abultado 7-0&hellip; <\/p>\n","protected":false},"author":211,"featured_media":29336,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[47,46,2851],"tags":[723,967,239,1090,123,1053],"class_list":["post-29328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol-espanol","category-laliga-ea-sports","category-real-valladolid-2","tag-barcelona","tag-montjuic","tag-paulo-pezzolano","tag-raul-moro","tag-real-valladolid","tag-rueda-de-prensa"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Pezzolano se disculpa tras la humillaci\u00f3n en Montjuic Paulo Pezzolano ha atendido a los medios de comunicaci\u00f3n despu\u00e9s de recibir una gran goleada muy dolorosa.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Ruben Garcia Moran\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/31\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Pezzolano se disculpa tras la humillaci\u00f3n en Montjuic \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"Pezzolano se disculpa tras la humillaci\u00f3n en Montjuic Paulo Pezzolano ha atendido a los medios de comunicaci\u00f3n despu\u00e9s de recibir una gran goleada muy dolorosa.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/31\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/Pecho-yano.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/Pecho-yano.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1700\" \/>\n\t\t<meta property=\"og:image:height\" content=\"956\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-08-31T17:53:02+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-08-31T17:53:02+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Pezzolano se disculpa tras la humillaci\u00f3n en Montjuic \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Pezzolano se disculpa tras la humillaci\u00f3n en Montjuic Paulo Pezzolano ha atendido a los medios de comunicaci\u00f3n despu\u00e9s de recibir una gran goleada muy dolorosa.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/Pecho-yano.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/31\\\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\\\/#blogposting\",\"name\":\"Pezzolano se disculpa tras la humillaci\\u00f3n en Montjuic \\u2013 Agente Libre Digital\",\"headline\":\"Pezzolano se disculpa tras la humillaci\\u00f3n en Montjuic\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/ruben-garcia-moran\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Pecho-yano.jpg\",\"width\":1700,\"height\":956},\"datePublished\":\"2024-08-31T19:53:02+02:00\",\"dateModified\":\"2024-08-31T19:53:02+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/31\\\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/31\\\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\\\/#webpage\"},\"articleSection\":\"F\\u00fatbol Espa\\u00f1ol, LaLiga EA Sports, Real Valladolid, Barcelona, montjuic, Paulo Pezzolano, Ra\\u00fal Moro, Real Valladolid, Rueda de prensa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/31\\\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/laliga-ea-sports\\\/#listItem\",\"name\":\"LaLiga EA Sports\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/laliga-ea-sports\\\/#listItem\",\"position\":2,\"name\":\"LaLiga EA Sports\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/laliga-ea-sports\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/31\\\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\\\/#listItem\",\"name\":\"Pezzolano se disculpa tras la humillaci\\u00f3n en Montjuic\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/31\\\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\\\/#listItem\",\"position\":3,\"name\":\"Pezzolano se disculpa tras la humillaci\\u00f3n en Montjuic\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/laliga-ea-sports\\\/#listItem\",\"name\":\"LaLiga EA Sports\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/31\\\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/31\\\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/ruben-garcia-moran\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/ruben-garcia-moran\\\/\",\"name\":\"Ruben Garcia Moran\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/31\\\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/252dc484a4bf7d338eb78941920455792eb98fc9c711ef0b771341d8ba01e5b2?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Ruben Garcia Moran\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/31\\\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/31\\\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\\\/\",\"name\":\"Pezzolano se disculpa tras la humillaci\\u00f3n en Montjuic \\u2013 Agente Libre Digital\",\"description\":\"Pezzolano se disculpa tras la humillaci\\u00f3n en Montjuic Paulo Pezzolano ha atendido a los medios de comunicaci\\u00f3n despu\\u00e9s de recibir una gran goleada muy dolorosa.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/31\\\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/ruben-garcia-moran\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/ruben-garcia-moran\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Pecho-yano.jpg\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/31\\\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\\\/#mainImage\",\"width\":1700,\"height\":956},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/31\\\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\\\/#mainImage\"},\"datePublished\":\"2024-08-31T19:53:02+02:00\",\"dateModified\":\"2024-08-31T19:53:02+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Pezzolano se disculpa tras la humillaci\u00f3n en Montjuic \u2013 Agente Libre Digital","description":"Pezzolano se disculpa tras la humillaci\u00f3n en Montjuic Paulo Pezzolano ha atendido a los medios de comunicaci\u00f3n despu\u00e9s de recibir una gran goleada muy dolorosa.","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/31\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/31\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\/#blogposting","name":"Pezzolano se disculpa tras la humillaci\u00f3n en Montjuic \u2013 Agente Libre Digital","headline":"Pezzolano se disculpa tras la humillaci\u00f3n en Montjuic","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/ruben-garcia-moran\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/Pecho-yano.jpg","width":1700,"height":956},"datePublished":"2024-08-31T19:53:02+02:00","dateModified":"2024-08-31T19:53:02+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/31\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/31\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\/#webpage"},"articleSection":"F\u00fatbol Espa\u00f1ol, LaLiga EA Sports, Real Valladolid, Barcelona, montjuic, Paulo Pezzolano, Ra\u00fal Moro, Real Valladolid, Rueda de prensa"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/31\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-ea-sports\/#listItem","name":"LaLiga EA Sports"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-ea-sports\/#listItem","position":2,"name":"LaLiga EA Sports","item":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-ea-sports\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/31\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\/#listItem","name":"Pezzolano se disculpa tras la humillaci\u00f3n en Montjuic"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/31\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\/#listItem","position":3,"name":"Pezzolano se disculpa tras la humillaci\u00f3n en Montjuic","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-ea-sports\/#listItem","name":"LaLiga EA Sports"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/31\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/31\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/ruben-garcia-moran\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/ruben-garcia-moran\/","name":"Ruben Garcia Moran","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/31\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/252dc484a4bf7d338eb78941920455792eb98fc9c711ef0b771341d8ba01e5b2?s=96&d=mm&r=g","width":96,"height":96,"caption":"Ruben Garcia Moran"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/31\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/31\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\/","name":"Pezzolano se disculpa tras la humillaci\u00f3n en Montjuic \u2013 Agente Libre Digital","description":"Pezzolano se disculpa tras la humillaci\u00f3n en Montjuic Paulo Pezzolano ha atendido a los medios de comunicaci\u00f3n despu\u00e9s de recibir una gran goleada muy dolorosa.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/31\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/ruben-garcia-moran\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/ruben-garcia-moran\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/Pecho-yano.jpg","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/31\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\/#mainImage","width":1700,"height":956},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/31\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\/#mainImage"},"datePublished":"2024-08-31T19:53:02+02:00","dateModified":"2024-08-31T19:53:02+02:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"Pezzolano se disculpa tras la humillaci\u00f3n en Montjuic \u2013 Agente Libre Digital","og:description":"Pezzolano se disculpa tras la humillaci\u00f3n en Montjuic Paulo Pezzolano ha atendido a los medios de comunicaci\u00f3n despu\u00e9s de recibir una gran goleada muy dolorosa.","og:url":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/31\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/Pecho-yano.jpg","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/Pecho-yano.jpg","og:image:width":1700,"og:image:height":956,"article:published_time":"2024-08-31T17:53:02+00:00","article:modified_time":"2024-08-31T17:53:02+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"Pezzolano se disculpa tras la humillaci\u00f3n en Montjuic \u2013 Agente Libre Digital","twitter:description":"Pezzolano se disculpa tras la humillaci\u00f3n en Montjuic Paulo Pezzolano ha atendido a los medios de comunicaci\u00f3n despu\u00e9s de recibir una gran goleada muy dolorosa.","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/Pecho-yano.jpg"},"aioseo_meta_data":{"post_id":"29328","title":null,"description":"#post_title Paulo Pezzolano ha atendido a los medios de comunicaci\u00f3n despu\u00e9s de recibir una gran goleada muy dolorosa.","keywords":null,"keyphrases":{"focus":{"keyphrase":"Pezzolano se disculpa tras la humillaci\u00f3n en Montjuic","score":50,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":3,"maxScore":9,"error":1,"length":9},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":3,"maxScore":9,"error":1},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":[],"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-08-31 17:53:02","updated":"2025-06-05 01:11:05","seo_analyzer_scan_date":null,"focus_keyword":"Pezzolano se disculpa tras la humillaci\u00f3n en Montjuic","additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-ea-sports\/\" title=\"LaLiga EA Sports\">LaLiga EA Sports<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPezzolano se disculpa tras la humillaci\u00f3n en Montjuic\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"LaLiga EA Sports","link":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-ea-sports\/"},{"label":"Pezzolano se disculpa tras la humillaci\u00f3n en Montjuic","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/31\/pezzolano-se-disculpa-tras-la-humillacion-en-montjuic\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/29328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/211"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=29328"}],"version-history":[{"count":1,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/29328\/revisions"}],"predecessor-version":[{"id":29341,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/29328\/revisions\/29341"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/29336"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=29328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=29328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=29328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}