{"id":27977,"date":"2024-08-18T21:07:46","date_gmt":"2024-08-18T19:07:46","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=27977"},"modified":"2024-08-18T21:11:10","modified_gmt":"2024-08-18T19:11:10","slug":"cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\/","title":{"rendered":"Cr\u00f3nica Real Sociedad &#8211; Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas"},"content":{"rendered":"<h2>A la Real Sociedad se le hace cuesta arriba el estreno liguero, el Rayo Vallecano de \u00cd\u00f1igo P\u00e9rez empieza pisando fuerte<\/h2>\n<h2>Primera Parte<\/h2>\n<p>Salida valiente del Rayo Vallecano en el Reale Arena. <strong>En el inicio del partido, a los diez segundos, Ratiu tuvo el gol en sus botas y es que un remate de rabona en el interior del \u00e1rea casi acaba en gol tras un fallo del portero de la Real Sociedad, Remiro y que salv\u00f3 el defensa de la Real Sociedad, Jon Pacheco bajo los palos<\/strong>. Sin embargo, tras el susto inicial, la Real Sociedad se supo recomponer aunque arriesgando en las salidas de bal\u00f3n. Tampoco se acercaba con peligro a la porter\u00eda de C\u00e1rdenas, aunque poco a poco se empez\u00f3 a adue\u00f1ar del partido.<\/p>\n<p><strong>La primera de la Real llegaba en el minuto 11 tras un centro de Sheraldo Becker que remata Brais M\u00e9ndez, aunque se marcha fuera de la porter\u00eda.<\/strong> Se acercaba el primer cuarto de hora del partido y la Real Sociedad lo sigue intentando, ya con un Rayo Vallecano m\u00e1s aplacado. <strong>Sin embargo, un pelotazo de Turrientes, el canterano de la Real Sociedad y campe\u00f3n ol\u00edmpico, sorprende desde los 25 metros en el minuto 17, y sale fuera tras un parad\u00f3n de C\u00e1rdenas.\u00a0<\/strong><\/p>\n<p>Muy atenta la defensa del Rayo Vallecano, que frena a Kubo en ataque durante la primera parte del encuentro. A pesar de esto, Kubo y Sheraldo Becker destrozan a la defensa del Rayo, ante un Mikel Oyarzabal cuyo gol iba a porter\u00eda, pero que Mumin evita. La acci\u00f3n m\u00e1s clara para los donostiarras hasta el momento. <strong>Hern\u00e1ndez Hern\u00e1ndez ense\u00f1a la primera tarjeta amarilla del partido al medio centro de la Real, Gonz\u00e1lez de Zarate.<\/strong><\/p>\n<figure id=\"attachment_27985\" aria-describedby=\"caption-attachment-27985\" style=\"width: 736px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-27985 size-full\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/rayo-vallecano-real-sociedad-2.jpg\" alt=\"\" width=\"736\" height=\"414\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/rayo-vallecano-real-sociedad-2.jpg 736w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/rayo-vallecano-real-sociedad-2-300x169.jpg 300w\" sizes=\"auto, (max-width: 736px) 100vw, 736px\" \/><figcaption id=\"caption-attachment-27985\" class=\"wp-caption-text\">Disputa de bal\u00f3n entre \u00d3scar Valent\u00edn (Rayo Vallecano) y Javi L\u00f3pez (Real Sociedad). Fuente: As<\/figcaption><\/figure>\n<p><strong>Primera media hora del partido y un c\u00f3rner para la Real casi acaba en gol de Elustondo, que estaba completamente solo ante la porter\u00eda<\/strong>. Llega la <strong>segunda tarjeta amarilla del partido para Unai L\u00f3pez tras un agarr\u00f3n a Turrientes<\/strong>. Ratiu y De Frutos lo segu\u00edan intentando con una jugada clara en el \u00e1rea rival que buscaba a Nteka, pero que salva la defensa de la Real. Ahora, una <strong>falta peligrosa para el Rayo Vallecano que lanza Lejeune pone en jaque a la Real, pero el arquero de la Real, Alex Remiro, atrapa con facilidad<\/strong>. En el minuto 40, el Rayo Vallecano lo intentaba esta vez de c\u00f3rner, tras una jugada ensayada que acaba en la cabeza de Ratiu pero que despeja inteligentemente Oyarzabal.<\/p>\n<p>A pocos minutos del final de la primera parte, Sheraldo Becker lo sigue intentando desde la banda. <strong>Se a\u00f1ade tal s\u00f3lo un minuto de prolongaci\u00f3n en este primer tramo del encuentro, que parece terminarse con un 0-0 en el Reale Arena<\/strong>, pero con opciones todav\u00eda para ambos equipos.<\/p>\n<h2>Segunda Parte<\/h2>\n<p>La segunda parte del encuentro comenzaba con cambios en los dos banquillos. Por un lado,\u00a0 entra Zubimendi por Urko Gonz\u00e1lez para la Real Sociedad; y, entra Gumbau, el nuevo fichaje de verano del Rayo Vallecano, por Unai L\u00f3pez. Ambos cambios por tarjeta amarilla.<\/p>\n<p><strong>A pocos minutos del comienzo de la segunda parte, se produjo un choque triple entre Brais M\u00e9ndez, Embarba y \u00d3scar Valent\u00edn<\/strong>. Enseguida, el colegiado llamaba a las asistencias m\u00e9dicas de ambos equipos. Sin embargo, se reincorporaron sin problema los tres jugadores. Otra vez, el Rayo Vallecano dominaba los primeros minutos de juego de la segunda parte. Pese a esto, el colegiado ense\u00f1aba la tercera amarilla del partido, segunda para un jugador de la zaga rayista, Lejeune. Enseguida, la Real aprovechaba la ocasi\u00f3n y entre Oyarzabal y Brais se acercaron con peligro a la porter\u00eda rival de Daniel C\u00e1rdenas, aunque sin oportunidades. <strong>A continuaci\u00f3n, una contra peligrosa de la Real Sociedad tras una p\u00e9rdida muy peligrosa de Gumbau casi acaba en gol, aunque Sheraldo Becker perdona. Ahora es turno del Rayo Vallecano, una falta que cuelga Gumbau para que cabecera Lejeune, se desv\u00eda por poco.\u00a0<\/strong><\/p>\n<p>Se presentaba animada la segunda parte del encuentro y el colegiado no tarda en ense\u00f1ar m\u00e1s tarjetas amarillas, una para Brais y otra para Nteka tras intentar llevarse el bal\u00f3n de todas formas en el interior del \u00e1rea. Tambi\u00e9n para Embarba que tras un forcejeo con Kubo se lleva los abucheos del Reale Arena. <strong>Minuto 60 de partido y de nuevo c\u00f3rner peligroso para la Real Sociedad. Acci\u00f3n muy clara en las botas de Javi L\u00f3pez que Nteka despeja por los pelos y evita el gol.\u00a0<\/strong><\/p>\n<p>Nuevos movimientos en los banquillos. Sergio Camello, el oro y h\u00e9roe ol\u00edmpico, para el Rayo Vallecano. <strong>Error de nuevo de Remiro, el guardameta de la Real Sociedad que no est\u00e1 muy fino en el inicio ligero. Gumbau aprovecha la ocasi\u00f3n, pero es el propio Remiro el que evita el desastre. No obstante, en el minuto 66 de partido se estrena el marcador, a favor del Rayo Vallecano, tras un golazo de Jorge de Frutos<\/strong> que aprovecha la jugada del central del conjunto vallecano, Mumin.<\/p>\n<figure id=\"attachment_27991\" aria-describedby=\"caption-attachment-27991\" style=\"width: 1052px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-27991 size-full\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/17240060518274.webp\" alt=\"\" width=\"1052\" height=\"701\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/17240060518274.webp 1052w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/17240060518274-300x200.webp 300w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/17240060518274-1024x682.webp 1024w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/17240060518274-768x512.webp 768w\" sizes=\"auto, (max-width: 1052px) 100vw, 1052px\" \/><figcaption id=\"caption-attachment-27991\" class=\"wp-caption-text\">Los jugadores del Rayo celebran el gol de Jorge de Frutos. Fuente: LALIGA<\/figcaption><\/figure>\n<p>Ahora, doble cambio para la Real Sociedad. Se marcha Kubo y entra Barrenetxa y sale Turrientes y entra Sergio G\u00f3mez. <strong>La Real Sociedad busca el empate. As\u00ed, una muy buena jugada de Zubimendi que mete el pase a Javi L\u00f3pez que ve a Brais que lo intenta de tac\u00f3n, pero que C\u00e1rdenas saca bajo los palos, casi acaba en gol. La jugada m\u00e1s clara para la Real hasta el momento<\/strong>. Carrusel de cambios en el Reale Arena. En el Rayo entran Chavarr\u00eda\u00a0y\u00a0Path\u00e9 Ciss, cogiendo el relevo de\u00a0Embarba\u00a0y\u00a0De Frutos. Por parte local entra\u00a0Aramburu\u00a0por\u00a0Hamari Traor\u00e9. Otra vez aparece Zubimendi en ataque y lo intenta desde fuera con la zurda, aunque con poca fortuna. De esta forma, se producen nuevos cambios en los banquillos. Balliu por Ratiu para el Rayo Vallecano y Sucic por Oyarzabal para la Real.<\/p>\n<p><strong>Cuando parec\u00eda que estaba la balanza del lado de la Real, Sergio Camello y su racha goleadora pon\u00eda por delante de nuevo al Rayo Vallecano en el minuto 85 del encuentro. La ventaja de dos goles para el Rayo desespera a la Real que se queda sin opciones en ataque. Siete minutos de a\u00f1adido en el Reale Arena<\/strong> y la Real sigue intent\u00e1ndolo. Tanto es as\u00ed que <strong>el colegiado revisa una acci\u00f3n entre \u00d3scar Valent\u00edn y Barrenetxa, que no acaba en penalti para los locales. Sin embargo, cuando parec\u00eda que estaba todo decidido, Zubimendi define muy bien y marca gol para los donostiarras<\/strong>. Sin embargo, el partido se salda con la victoria para la zaga rayista fuera de cara. Buen estreno liguero para los de Vallecas, y una Real Sociedad que no convence. A\u00fan as\u00ed, La Liga s\u00f3lo acaba de empezar.<\/p>\n<h2>Ficha t\u00e9cnica<\/h2>\n<p><strong>Once Real Sociedad<\/strong>: Remiro (P); Javi L\u00f3pez, Jon Pacheco, Elustondo, Hamari Traore (Aramburu), Take Kubo (Barrenetxa), Urko Gonz\u00e1lez (Mart\u00edn Zubimendi), Be\u00f1at Turrientes (Sergio G\u00f3mez), Brais, Sheraldo Becker y Oyarzabal (Sucic).<\/p>\n<p><strong>Once Rayo Vallecano:<\/strong> Daniel C\u00e1rdenas (P); Luis Espino, Lejeune, Abdul Mumin, Andrei Ratiu (Balliu), Embarba (Chavarr\u00eda), \u00d3scar Valent\u00edn, Unai L\u00f3pez (Gumbau), De Frutos (Path\u00e9 Ciss), Nteka (Sergio Camello) e Isi Palaz\u00f3n<\/p>\n<p><strong>Horario:<\/strong> 19:00h<\/p>\n<p><strong>\u00c1rbitro: <\/strong>Hern\u00e1ndez Hern\u00e1ndez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A la Real Sociedad se le hace cuesta arriba el estreno liguero, el Rayo Vallecano de \u00cd\u00f1igo P\u00e9rez empieza pisando fuerte Primera Parte Salida valiente del Rayo Vallecano en el&hellip; <\/p>\n","protected":false},"author":188,"featured_media":27991,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[46,18,16],"tags":[2353,169,115],"class_list":["post-27977","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-laliga-ea-sports","category-rayo-vallecano","category-real-sociedad","tag-la-liga-ea-sport","tag-rayo-vallecano","tag-real-sociedad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Cr\u00f3nica Real Sociedad \u2013 Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Maria Rayo\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Cr\u00f3nica Real Sociedad \u2013 Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"Cr\u00f3nica Real Sociedad \u2013 Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/17240060518274.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/17240060518274.webp\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1052\" \/>\n\t\t<meta property=\"og:image:height\" content=\"701\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-08-18T19:07:46+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-08-18T19:11:10+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Cr\u00f3nica Real Sociedad \u2013 Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Cr\u00f3nica Real Sociedad \u2013 Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/17240060518274.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\\\/#blogposting\",\"name\":\"Cr\\u00f3nica Real Sociedad \\u2013 Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas \\u2013 Agente Libre Digital\",\"headline\":\"Cr\\u00f3nica Real Sociedad &#8211; Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/mario-rayo\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/17240060518274.webp\",\"width\":1052,\"height\":701},\"datePublished\":\"2024-08-18T21:07:46+02:00\",\"dateModified\":\"2024-08-18T21:11:10+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\\\/#webpage\"},\"articleSection\":\"LaLiga EA Sports, Rayo Vallecano, Real Sociedad, La liga EA Sport, Rayo Vallecano, Real sociedad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/real-sociedad\\\/#listItem\",\"name\":\"Real Sociedad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/real-sociedad\\\/#listItem\",\"position\":2,\"name\":\"Real Sociedad\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/real-sociedad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\\\/#listItem\",\"name\":\"Cr\\u00f3nica Real Sociedad &#8211; Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\\\/#listItem\",\"position\":3,\"name\":\"Cr\\u00f3nica Real Sociedad &#8211; Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/real-sociedad\\\/#listItem\",\"name\":\"Real Sociedad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/mario-rayo\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/mario-rayo\\\/\",\"name\":\"Maria Rayo\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0c273b5f868396972d1f917cd59f144a316405ceb883d2f0dc843569f3f83d8c?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Maria Rayo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\\\/\",\"name\":\"Cr\\u00f3nica Real Sociedad \\u2013 Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas \\u2013 Agente Libre Digital\",\"description\":\"Cr\\u00f3nica Real Sociedad \\u2013 Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/mario-rayo\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/mario-rayo\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/17240060518274.webp\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\\\/#mainImage\",\"width\":1052,\"height\":701},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\\\/#mainImage\"},\"datePublished\":\"2024-08-18T21:07:46+02:00\",\"dateModified\":\"2024-08-18T21:11:10+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Cr\u00f3nica Real Sociedad \u2013 Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas \u2013 Agente Libre Digital","description":"Cr\u00f3nica Real Sociedad \u2013 Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\/#blogposting","name":"Cr\u00f3nica Real Sociedad \u2013 Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas \u2013 Agente Libre Digital","headline":"Cr\u00f3nica Real Sociedad &#8211; Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/mario-rayo\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/17240060518274.webp","width":1052,"height":701},"datePublished":"2024-08-18T21:07:46+02:00","dateModified":"2024-08-18T21:11:10+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\/#webpage"},"articleSection":"LaLiga EA Sports, Rayo Vallecano, Real Sociedad, La liga EA Sport, Rayo Vallecano, Real sociedad"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/real-sociedad\/#listItem","name":"Real Sociedad"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/real-sociedad\/#listItem","position":2,"name":"Real Sociedad","item":"https:\/\/agentelibredigital.com\/index.php\/category\/real-sociedad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\/#listItem","name":"Cr\u00f3nica Real Sociedad &#8211; Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\/#listItem","position":3,"name":"Cr\u00f3nica Real Sociedad &#8211; Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/real-sociedad\/#listItem","name":"Real Sociedad"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/mario-rayo\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/mario-rayo\/","name":"Maria Rayo","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/0c273b5f868396972d1f917cd59f144a316405ceb883d2f0dc843569f3f83d8c?s=96&d=mm&r=g","width":96,"height":96,"caption":"Maria Rayo"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\/","name":"Cr\u00f3nica Real Sociedad \u2013 Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas \u2013 Agente Libre Digital","description":"Cr\u00f3nica Real Sociedad \u2013 Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/mario-rayo\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/mario-rayo\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/17240060518274.webp","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\/#mainImage","width":1052,"height":701},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\/#mainImage"},"datePublished":"2024-08-18T21:07:46+02:00","dateModified":"2024-08-18T21:11:10+02:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"Cr\u00f3nica Real Sociedad \u2013 Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas \u2013 Agente Libre Digital","og:description":"Cr\u00f3nica Real Sociedad \u2013 Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas","og:url":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/17240060518274.webp","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/17240060518274.webp","og:image:width":1052,"og:image:height":701,"article:published_time":"2024-08-18T19:07:46+00:00","article:modified_time":"2024-08-18T19:11:10+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"Cr\u00f3nica Real Sociedad \u2013 Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas \u2013 Agente Libre Digital","twitter:description":"Cr\u00f3nica Real Sociedad \u2013 Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/17240060518274.webp"},"aioseo_meta_data":{"post_id":"27977","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"Cr\u00f3nica Real Sociedad - Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas","score":51,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":3,"maxScore":9,"error":1,"length":14},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":3,"maxScore":9,"error":1},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1},"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-08-18 19:07:46","updated":"2025-06-05 00:16:53","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/real-sociedad\/\" title=\"Real Sociedad\">Real Sociedad<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCr\u00f3nica Real Sociedad \u2013 Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"Real Sociedad","link":"https:\/\/agentelibredigital.com\/index.php\/category\/real-sociedad\/"},{"label":"Cr\u00f3nica Real Sociedad &#8211; Rayo Vallecano: estreno liguero de sobresaliente para los de Vallecas","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/cronica-real-sociedad-rayo-vallecano-estreno-liguero-de-sobresaliente-para-los-de-vallecas\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/27977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/188"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=27977"}],"version-history":[{"count":1,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/27977\/revisions"}],"predecessor-version":[{"id":27997,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/27977\/revisions\/27997"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/27991"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=27977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=27977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=27977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}