{"id":27961,"date":"2024-08-18T18:56:09","date_gmt":"2024-08-18T16:56:09","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=27961"},"modified":"2024-08-18T18:56:09","modified_gmt":"2024-08-18T16:56:09","slug":"el-levante-conquista-el-molinon","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/el-levante-conquista-el-molinon\/","title":{"rendered":"El Levante conquista El Molin\u00f3n"},"content":{"rendered":"<h4>El Levante comienza la temporada llev\u00e1ndose los 3 puntos ante el Sporting<\/h4>\n<p>Los de Calero comenzaron la temporada con una c\u00f3moda victoria en uno de los campos m\u00e1s complicados de la segunda divisi\u00f3n. Con goles de <strong>Carlos \u00c1lvarez y Kochorashvili<\/strong>, el <a href=\"https:\/\/agentelibredigital.com\/?s=levante\">Levante<\/a> vence al <a href=\"https:\/\/agentelibredigital.com\/?s=sporting%20de%20gijon\">Sporting<\/a> en su primer partido de la <a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/\">Liga Hypermotion<\/a>.<\/p>\n<h2>Primera parte<\/h2>\n<p>El comienzo del partido fue fren\u00e9tico. En tan solo dos minutos de encuentro, una p\u00e9rdida de <strong>Carlos \u00c1lvarez<\/strong>, le dej\u00f3 a <strong>Gaspi<\/strong> al borde del \u00e1rea. Gaspi, con un pase preciso, dej\u00f3 solo a <strong>Dubasin<\/strong> para que finalizara, pero el gol fue anulado por el VAR por <strong>fuera de juego<\/strong>. El conjunto levantino no se achant\u00f3 ante este gol y Carlos \u00c1lvarez tuvo la primera del partido, pero se march\u00f3 cerca del poste.<\/p>\n<p>Aunque el dominio de los primeros minutos fue local, apareci\u00f3 <strong>Carlos \u00c1lvarez<\/strong> para rematar un centro de Andr\u00e9s y poner el <strong>primero<\/strong> en el marcador. Pasaban los minutos y ambos equipos bajaron el ritmo del partido. Tras un choque anterior, Nacho M\u00e9ndez tuvo que abandonar el juego, pero no cont\u00f3 como ventana de cambio debido a que se activ\u00f3 el protocolo debido a una conmoci\u00f3n cerebral.<\/p>\n<p>Llegada la media hora de partido, el encuentro se calm\u00f3 y las ocasiones dejaron de aparecer con frecuencia. Por su parte, al <a href=\"https:\/\/www.levanteud.com\/\">Levante<\/a> se le vio c\u00f3modo y comenz\u00f3 a crear oportunidades a partir de contragolpes. Y esta insistencia levantina dio sus frutos. Con una falta al primer palo que sorprende al guardameta rojiblanco, <strong>Kochorashvili<\/strong> puso el segundo antes del descanso.<\/p>\n<p>Y con un marcador de <strong>0-2<\/strong>, el partido se fue al <strong>descanso<\/strong> en El Molin\u00f3n.<\/p>\n<figure style=\"width: 854px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/GVRszFmWsAA3Pfs?format=jpg&amp;name=medium\" alt=\"Carlos \u00c1lvarez con el bal\u00f3n. Fuente: Levante UD.\" width=\"854\" height=\"1024\" \/><figcaption class=\"wp-caption-text\">Carlos \u00c1lvarez con el bal\u00f3n. Fuente: Levante UD.<\/figcaption><\/figure>\n<h2>Segunda parte<\/h2>\n<p>Con el comienzo de la segunda parte, el Sporting se vio obligado a atacar. Y tantas ocasiones siempre tienen sus frutos. Tras un magn\u00edfico centro de Cote, Dubasin con un cabezazo picado recort\u00f3 distancias en el marcador. Los locales se crecieron con el gol y se hicieron con el control del partido. Las ocasiones y el dominio continuaron, pero sin acierto de los locales.<\/p>\n<p>No paraba de llegar el conjunto rojiblanco al \u00e1rea de Andr\u00e9s Fern\u00e1ndez, pero los minutos pasaban y el gol del empate no llegaba. Finalmente, el marcador qued\u00f3 1-2 para el conjunto levantino que se lleva el primer partido de la temporada.<\/p>\n<figure style=\"width: 680px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/GVRw2HhXMAA0VOx?format=jpg&amp;name=small\" alt=\"\" width=\"680\" height=\"509\" \/><figcaption class=\"wp-caption-text\">Carlos \u00c1lvarez con el bal\u00f3n. Fuente: Levante UD.<\/figcaption><\/figure>\n<h2>Ficha t\u00e9cnica<\/h2>\n<p><strong>XI Sporting de Gij\u00f3n:\u00a0<\/strong>Rub\u00e9n Y\u00e1\u00f1ez, Curbelo, Diego S\u00e1nchez, Cote (Pablo Garc\u00eda 87&#8242;), Guille Rosas; Jes\u00fas Bernal (Queipo 69&#8242;), Nacho M\u00e9ndez (Nacho Mart\u00edn 28&#8242;), Olaetxea; Dubasin (Campu 78&#8242;), Gaspar Campos, Juan Otero.<\/p>\n<p><strong>XI Levante:\u00a0<\/strong>Andr\u00e9s Fern\u00e1ndez, Cabello, Elguezabal, Andr\u00e9s Garc\u00eda, Marcos Navarro (Dela 80&#8242;); Kochorashvili, Carlos \u00c1lvarez (Algobia 62&#8242;), Oriol Rey, Brugu\u00e9 (Esp\u00ed 85&#8242;), Morales (Lozano 76&#8242;); Bouldini (Iv\u00e1n Romero 62&#8242;).<\/p>\n<p><strong>Goles<\/strong>: Carlos \u00c1lvarez (14&#8242;), Kochorashvili (42&#8242;), Dubasin (59&#8242;)<\/p>\n<p><strong>Amonestaciones Sporting de Gij\u00f3n<\/strong>: Olaetxea (Amarilla 39&#8242;), Cote (Amarilla 56&#8242;)<\/p>\n<p><strong>Amonestaciones Levante<\/strong>: Elguezabal (Amarilla 44&#8242;), Marcos Navarro (Amarilla 80&#8242;)<\/p>\n<p><strong>\u00c1rbitro<\/strong>: Guzm\u00e1n Mansilla<\/p>\n<p><strong>Estadio<\/strong>: El Molin\u00f3n<\/p>\n<p>&nbsp;<\/p>\n<p>Autor del art\u00edculo: <strong>Rub\u00e9n Duque<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Levante comienza la temporada llev\u00e1ndose los 3 puntos ante el Sporting Los de Calero comenzaron la temporada con una c\u00f3moda victoria en uno de los campos m\u00e1s complicados de&hellip; <\/p>\n","protected":false},"author":174,"featured_media":27979,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[47,8],"tags":[2101,1658,2929,785,1251],"class_list":["post-27961","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol-espanol","category-laliga-hypermotion","tag-calero","tag-carlos-alvarez","tag-kochorashvili","tag-levante","tag-sporting-de-gijon"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Levante conquista El Molin\u00f3n Los de Calero comenzaron la temporada con una c\u00f3moda victoria en uno de los campos m\u00e1s complicados de la segunda divisi\u00f3n.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Ruben Duque\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/el-levante-conquista-el-molinon\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Levante conquista El Molin\u00f3n \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"El Levante conquista El Molin\u00f3n Los de Calero comenzaron la temporada con una c\u00f3moda victoria en uno de los campos m\u00e1s complicados de la segunda divisi\u00f3n.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/el-levante-conquista-el-molinon\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/levnate.avif\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/levnate.avif\" \/>\n\t\t<meta property=\"og:image:width\" content=\"736\" \/>\n\t\t<meta property=\"og:image:height\" content=\"414\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-08-18T16:56:09+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-08-18T16:56:09+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Levante conquista El Molin\u00f3n \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Levante conquista El Molin\u00f3n Los de Calero comenzaron la temporada con una c\u00f3moda victoria en uno de los campos m\u00e1s complicados de la segunda divisi\u00f3n.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/levnate.avif\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/el-levante-conquista-el-molinon\\\/#blogposting\",\"name\":\"El Levante conquista El Molin\\u00f3n \\u2013 Agente Libre Digital\",\"headline\":\"El Levante conquista El Molin\\u00f3n\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/ruben-duque\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/levnate.avif\",\"width\":736,\"height\":414},\"datePublished\":\"2024-08-18T18:56:09+02:00\",\"dateModified\":\"2024-08-18T18:56:09+02:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/el-levante-conquista-el-molinon\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/el-levante-conquista-el-molinon\\\/#webpage\"},\"articleSection\":\"F\\u00fatbol Espa\\u00f1ol, LaLiga Hypermotion, Calero, Carlos \\u00c1lvarez, Kochorashvili, Levante, Sporting de Gij\\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/el-levante-conquista-el-molinon\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/laliga-hypermotion\\\/#listItem\",\"name\":\"LaLiga Hypermotion\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/laliga-hypermotion\\\/#listItem\",\"position\":2,\"name\":\"LaLiga Hypermotion\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/laliga-hypermotion\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/el-levante-conquista-el-molinon\\\/#listItem\",\"name\":\"El Levante conquista El Molin\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/el-levante-conquista-el-molinon\\\/#listItem\",\"position\":3,\"name\":\"El Levante conquista El Molin\\u00f3n\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/laliga-hypermotion\\\/#listItem\",\"name\":\"LaLiga Hypermotion\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/el-levante-conquista-el-molinon\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/el-levante-conquista-el-molinon\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/ruben-duque\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/ruben-duque\\\/\",\"name\":\"Ruben Duque\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/el-levante-conquista-el-molinon\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c36b05b380907a190dfe49bcb1280defbe7fd74a6f25dffbbaddd8a4aa0a416f?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Ruben Duque\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/el-levante-conquista-el-molinon\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/el-levante-conquista-el-molinon\\\/\",\"name\":\"El Levante conquista El Molin\\u00f3n \\u2013 Agente Libre Digital\",\"description\":\"El Levante conquista El Molin\\u00f3n Los de Calero comenzaron la temporada con una c\\u00f3moda victoria en uno de los campos m\\u00e1s complicados de la segunda divisi\\u00f3n.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/el-levante-conquista-el-molinon\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/ruben-duque\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/ruben-duque\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/levnate.avif\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/el-levante-conquista-el-molinon\\\/#mainImage\",\"width\":736,\"height\":414},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/08\\\/18\\\/el-levante-conquista-el-molinon\\\/#mainImage\"},\"datePublished\":\"2024-08-18T18:56:09+02:00\",\"dateModified\":\"2024-08-18T18:56:09+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El Levante conquista El Molin\u00f3n \u2013 Agente Libre Digital","description":"El Levante conquista El Molin\u00f3n Los de Calero comenzaron la temporada con una c\u00f3moda victoria en uno de los campos m\u00e1s complicados de la segunda divisi\u00f3n.","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/el-levante-conquista-el-molinon\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/el-levante-conquista-el-molinon\/#blogposting","name":"El Levante conquista El Molin\u00f3n \u2013 Agente Libre Digital","headline":"El Levante conquista El Molin\u00f3n","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/ruben-duque\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/levnate.avif","width":736,"height":414},"datePublished":"2024-08-18T18:56:09+02:00","dateModified":"2024-08-18T18:56:09+02:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/el-levante-conquista-el-molinon\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/el-levante-conquista-el-molinon\/#webpage"},"articleSection":"F\u00fatbol Espa\u00f1ol, LaLiga Hypermotion, Calero, Carlos \u00c1lvarez, Kochorashvili, Levante, Sporting de Gij\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/el-levante-conquista-el-molinon\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/#listItem","name":"LaLiga Hypermotion"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/#listItem","position":2,"name":"LaLiga Hypermotion","item":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/el-levante-conquista-el-molinon\/#listItem","name":"El Levante conquista El Molin\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/el-levante-conquista-el-molinon\/#listItem","position":3,"name":"El Levante conquista El Molin\u00f3n","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/#listItem","name":"LaLiga Hypermotion"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/el-levante-conquista-el-molinon\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/el-levante-conquista-el-molinon\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/ruben-duque\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/ruben-duque\/","name":"Ruben Duque","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/el-levante-conquista-el-molinon\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c36b05b380907a190dfe49bcb1280defbe7fd74a6f25dffbbaddd8a4aa0a416f?s=96&d=mm&r=g","width":96,"height":96,"caption":"Ruben Duque"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/el-levante-conquista-el-molinon\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/el-levante-conquista-el-molinon\/","name":"El Levante conquista El Molin\u00f3n \u2013 Agente Libre Digital","description":"El Levante conquista El Molin\u00f3n Los de Calero comenzaron la temporada con una c\u00f3moda victoria en uno de los campos m\u00e1s complicados de la segunda divisi\u00f3n.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/el-levante-conquista-el-molinon\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/ruben-duque\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/ruben-duque\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/levnate.avif","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/el-levante-conquista-el-molinon\/#mainImage","width":736,"height":414},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/el-levante-conquista-el-molinon\/#mainImage"},"datePublished":"2024-08-18T18:56:09+02:00","dateModified":"2024-08-18T18:56:09+02:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"El Levante conquista El Molin\u00f3n \u2013 Agente Libre Digital","og:description":"El Levante conquista El Molin\u00f3n Los de Calero comenzaron la temporada con una c\u00f3moda victoria en uno de los campos m\u00e1s complicados de la segunda divisi\u00f3n.","og:url":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/el-levante-conquista-el-molinon\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/levnate.avif","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/levnate.avif","og:image:width":736,"og:image:height":414,"article:published_time":"2024-08-18T16:56:09+00:00","article:modified_time":"2024-08-18T16:56:09+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"El Levante conquista El Molin\u00f3n \u2013 Agente Libre Digital","twitter:description":"El Levante conquista El Molin\u00f3n Los de Calero comenzaron la temporada con una c\u00f3moda victoria en uno de los campos m\u00e1s complicados de la segunda divisi\u00f3n.","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/08\/levnate.avif"},"aioseo_meta_data":{"post_id":"27961","title":null,"description":"#post_title Los de Calero comenzaron la temporada con una c\u00f3moda victoria en uno de los campos m\u00e1s complicados de la segunda divisi\u00f3n.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-08-18 15:56:41","updated":"2025-06-05 00:16:52","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/\" title=\"LaLiga Hypermotion\">LaLiga Hypermotion<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl Levante conquista El Molin\u00f3n\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"LaLiga Hypermotion","link":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/"},{"label":"El Levante conquista El Molin\u00f3n","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/08\/18\/el-levante-conquista-el-molinon\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/27961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=27961"}],"version-history":[{"count":1,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/27961\/revisions"}],"predecessor-version":[{"id":27981,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/27961\/revisions\/27981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/27979"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=27961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=27961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=27961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}