{"id":2112,"date":"2023-11-16T17:11:12","date_gmt":"2023-11-16T16:11:12","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=2112"},"modified":"2023-11-16T17:19:36","modified_gmt":"2023-11-16T16:19:36","slug":"el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2023\/11\/16\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\/","title":{"rendered":"El \u00abefecto Dusko\u00bb barre al Barcelona en el Buesa Arena"},"content":{"rendered":"<h4>Baskonia vence en un gran partido coral a un Barcelona que lleg\u00f3 a ir treinta puntos abajo en el partido<\/h4>\n<p>Los 10.033 asistentes al <strong>Fernando Buesa Arena<\/strong> han disfrutado, posiblemente, del mejor partido de su equipo hasta la fecha. El conjunto vitoriano se ha impuesto por 94-71 a un Barcelona, que tan solo hab\u00eda cosechado una derrota en la competici\u00f3n a manos del invicto Real Madrid a domicilio a finales de octubre. <strong>Markus <a href=\"https:\/\/agentelibredigital.com\/?s=howard\">Howard<\/a><\/strong> con 26 puntos y <strong>Cody Miller-McIntyre<\/strong> con 20, han sido los jugadores m\u00e1s <strong>destacados<\/strong> por parte de <a href=\"https:\/\/agentelibredigital.com\/?s=baskonia\"><strong>Baskonia<\/strong><\/a>. Por el lado blaugrana, Laprovittola con 14 puntos y los 12 puntos de Da Silva en el primer cuarto, los hombres m\u00e1s destacados en un partido, muy flojo de los hombres de Grimau.<\/p>\n<h2>Primer cuarto ofensivo<\/h2>\n<p>Tras el saque inicial, ambos equipos marcaban un <strong>ritmo alto<\/strong> en ataque. Muchos intercambios de canastas, con la presencia notoria de Markus Howard y de Da Silva. El alem\u00e1n firmaba 10 puntos de forma consecutiva para el conjunto visitante. Tras el <strong>13-12<\/strong> en el marcador a los hombres de Grimau se les apag\u00f3 la chispa anotadora, mientras que en Baskonia, era todo lo contrario con Howard y Miller-McIntyre sensacionales y jugadores como <strong>Sedekerskis o Moneke<\/strong> que se un\u00edan a la fiesta para poner el <strong>26-18<\/strong> en el marcador para acabar el cuarto.<\/p>\n<h2>Sin reacci\u00f3n<\/h2>\n<p>Tras el breve paso por banquillos, el <strong>segundo cuarto<\/strong> iba a ser <strong>clave<\/strong> en el devenir del encuentro. Lejos de mejorar defensivamente, el Barcelona encajaba un <strong>parcial de 8-0<\/strong> que obligaba a Roger Grimau a parar el encuentro ante una defensa que no pod\u00eda parar a jugadores como <strong>Howard<\/strong>, que firmaron un gran cuarto para que su equipo, Baskonia, se distanciara en el marcador <strong>quince puntos arriba<\/strong>. Tras varios fogonazos desde el triple con Abrines, y, puntos desde la pintura de Willy Hernang\u00f3mez lograban mantener con vida a un Barcelona horrible en defensa. <strong>Baskonia<\/strong> segu\u00eda <strong>enchufado<\/strong> y en apenas 4 minutos dos <strong>triples<\/strong> de Cody Miller-McIntyre, que firm\u00f3 12 puntos en el segundo cuarto, aument\u00f3 la renta baskonista en 26 puntos hasta 56-29. <strong>Nula<\/strong> aportaci\u00f3n ofensiva en este cuarto <strong>del <a href=\"https:\/\/agentelibredigital.com\/?s=barcelona\">Barcelona<\/a><\/strong> que apenas pudo anotar 11 puntos y recibi\u00f3 en cambio <strong>29 puntos<\/strong>.<\/p>\n<figure style=\"width: 680px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/F_AHYLhXIAAdiEC?format=jpg&amp;name=small\" alt=\"Image\" width=\"680\" height=\"453\" \/><figcaption class=\"wp-caption-text\">Sedekerskis en una acci\u00f3n. Fuente: Baskonia<\/figcaption><\/figure>\n<h2>Tras vestuarios<\/h2>\n<p>Como era de esperar, el Barcelona sali\u00f3 con otra <strong>chispa y ritmo<\/strong> al tercer cuarto. En apenas 2 minutos el argentino Laprovittola <strong>bajaba la renta<\/strong> en 19 puntos y obligaba al t\u00e9cnico local <a href=\"https:\/\/agentelibredigital.com\/?s=dusko+ivanovic\">Dusko Ivanovic<\/a> a pedir un tiempo muerto con 55-36 en el luminoso. Intercambio de canastas entre Howard y Laprovittola segu\u00edan manteniendo la <strong>renta en veinte puntos<\/strong> arriba para Baskonia, donde el Barcelona de la mano de Satoransky y Abrines anotaron <strong>4 triples<\/strong> en el tercer cuarto para bajar al final del <strong>tercer cuarto<\/strong> la renta hasta los <strong>17 abajo<\/strong> con el objetivo de seguir recortando puntos durante el \u00faltimo cuarto.<\/p>\n<h2>Fiesta local<\/h2>\n<p>Baskonia no se achant\u00f3 ante la reacci\u00f3n blaugrana y sigui\u00f3 su <strong>gran juego ofensivo<\/strong> bajo la batuta de Ivanovic con un gran <strong>acierto desde el triple<\/strong> de Markus Howard y de Chima Moneke que detuvieron cualquier fogonazo visitante. La renta local segu\u00eda en aumento mientras que la actitud defensiva del Barcelona no mejor\u00f3 y fruto de ello llego la renta de <strong>91-61<\/strong> en el marcador, la mayor hasta entonces en el partido que l\u00f3gicamente freno Grimau con un t<strong>iempo muerto<\/strong>. Tras una peque\u00f1a reacci\u00f3n visitante de la mano de Brizuela y Jokubaitis, el Barcelona logr\u00f3 <strong>bajar la diferencia<\/strong> hasta el 94-71 final. Con esta victoria Baskonia consigue un <strong>balance de 4-4<\/strong> en el marcador, mientras que el Barcelona se encuentra <strong>6-2<\/strong> empatado en el segundo puesto con Virtus Bolonia. Esta<strong> doble jornada semanal<\/strong>, llevar\u00e1 a los vitorianos el viernes a las 20.00 horas a Francia para medirse al <a href=\"https:\/\/agentelibredigital.com\/?s=asvel\"><strong>Asvel Basket<\/strong><\/a>. El Barcelona en cambio, recibir\u00e1 en el Palau a un <a href=\"https:\/\/agentelibredigital.com\/?s=valencia+basket\"><strong>Valencia Basket<\/strong><\/a> que ya fue capaz de ganar a los catalanes en la <a href=\"https:\/\/agentelibredigital.com\/?s=liga+endesa\"><strong>Liga Endesa<\/strong><\/a> esta temporada.<\/p>\n<figure style=\"width: 680px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/F_AdJiRWMAAVV5k?format=jpg&amp;name=small\" alt=\"Image\" width=\"680\" height=\"453\" \/><figcaption class=\"wp-caption-text\">Markus Howard celebrando una canasta. Fuente: Baskonia<\/figcaption><\/figure>\n<h2>El \u00abefecto Dusko\u00bb<\/h2>\n<p>Se cumpl\u00eda el tercer partido en <a href=\"https:\/\/agentelibredigital.com\/?s=euroliga\">Euroliga<\/a> de Dusko Ivanovic con Baskonia en esta cuarta etapa profesional. Tras la <strong>victoria<\/strong> ag\u00f3nica ante <strong><a href=\"https:\/\/agentelibredigital.com\/?s=partiz%C3%A1n\">Partiz\u00e1n<\/a> (84-83)<\/strong> en el Buesa Arena, Baskonia fue capaza de<strong> ganar<\/strong> en un colosal partido a <strong><a href=\"https:\/\/agentelibredigital.com\/?s=olympiacos\">Olympiacos<\/a> por 74-75<\/strong> gracias a un Howard, una vez m\u00e1s, imperial. La tercera ha llegado ante Barcelona, en un partido muy completo de Baskonia que le a\u00fapa en la clasificaci\u00f3n. Si bien es cierto que la racha positiva de Baskonia es evidente, la de <strong>Liga Endesa no es igual<\/strong>. Tras <strong>derrotas<\/strong> frente <strong><a href=\"https:\/\/agentelibredigital.com\/?s=gran+canaria\">Gran Canaria<\/a> y <a href=\"https:\/\/agentelibredigital.com\/?s=obradoiro\">Obradoiro<\/a><\/strong>, Baskonia necesita enchufarse ante la posibilidad de no participar en la pr\u00f3xima edici\u00f3n de la <strong>Copa del Rey.<\/strong><\/p>\n<figure style=\"width: 680px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/F_Alg23XcAA_0ky?format=jpg&amp;name=small\" alt=\"Image\" width=\"680\" height=\"453\" \/><figcaption class=\"wp-caption-text\">Dusko Ivanovic. Fuente: Baskonia<\/figcaption><\/figure>\n<h2>MVP baskonista<\/h2>\n<p>Tras una gran actuaci\u00f3n individual del americano con pasaporte b\u00falgaro <strong>Cody Miller-McIntyre<\/strong> con 20 puntos, 7 asistencias, 4 rebotes y 2 robos se ha convertido con un total de 29 de valoraci\u00f3n, en el <strong><a href=\"https:\/\/agentelibredigital.com\/?s=mvp\">MVP<\/a> de la jornada 8 de la Euroliga<\/strong>. Con estos n\u00fameros, el base consigue realizar su <strong>mejor participaci\u00f3n<\/strong> con la el\u00e1stica de Baskonia. Adem\u00e1s, con m\u00e1s de <strong>28 minutos jugados<\/strong> est\u00e1 siendo uno de los fijos para el coach montenegrino.<\/p>\n<h2>Ficha t\u00e9cnica:<\/h2>\n<p><strong>Baskonia (94)<\/strong>: <strong>Howard (26)<\/strong>, <strong>McIntyre (20)<\/strong>, Moneke (19), <strong>Sedekerskis (9)<\/strong>, Kotsar (6), <strong>Costello (5)<\/strong>, <strong>Dani D\u00edez (5)<\/strong>, Chiozza (4), Khalifa Diop (-), Raieste (-).<\/p>\n<p><strong>Barcelona (71)<\/strong>: <strong>Laprovittola (14)<\/strong>, <strong>Da Silva (12)<\/strong>, Abrines (9), Willy (9), Jokubaitis (9),<strong> Kalinic (6)<\/strong>, <strong>Satoransky (6)<\/strong>, Brizuela (2), Parker (2), <strong>Jan<\/strong> <strong>Vesely (2)<\/strong>, Nnaji (-), Parra (-).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Baskonia vence en un gran partido coral a un Barcelona que lleg\u00f3 a ir treinta puntos abajo en el partido Los 10.033 asistentes al Fernando Buesa Arena han disfrutado, posiblemente,&hellip; <\/p>\n","protected":false},"author":52,"featured_media":2125,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[49,41],"tags":[403,481,482,404,55],"class_list":["post-2112","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baloncesto","category-euroliga","tag-baloncesto","tag-baskonia","tag-buesa-arena","tag-euroliga","tag-fc-barcelona"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"El \u00abefecto Dusko\u00bb barre al Barcelona en el Buesa Arena\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Ibai Rodriguez\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2023\/11\/16\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El \u00abefecto Dusko\u00bb barre al Barcelona en el Buesa Arena \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"El \u00abefecto Dusko\u00bb barre al Barcelona en el Buesa Arena\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2023\/11\/16\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/11\/F_AGNFdXYAEGvOZ.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/11\/F_AGNFdXYAEGvOZ.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"679\" \/>\n\t\t<meta property=\"og:image:height\" content=\"453\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-11-16T16:11:12+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-11-16T16:19:36+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El \u00abefecto Dusko\u00bb barre al Barcelona en el Buesa Arena \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El \u00abefecto Dusko\u00bb barre al Barcelona en el Buesa Arena\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/11\/F_AGNFdXYAEGvOZ.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/11\\\/16\\\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\\\/#blogposting\",\"name\":\"El \\u00abefecto Dusko\\u00bb barre al Barcelona en el Buesa Arena \\u2013 Agente Libre Digital\",\"headline\":\"El \\u00abefecto Dusko\\u00bb barre al Barcelona en el Buesa Arena\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/ibai-rodriguez\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/F_AGNFdXYAEGvOZ.jpg\",\"width\":679,\"height\":453,\"caption\":\"Cody Miller-McIntyre, MVP de la jornada. Fuente: Baskonia\"},\"datePublished\":\"2023-11-16T17:11:12+01:00\",\"dateModified\":\"2023-11-16T17:19:36+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/11\\\/16\\\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/11\\\/16\\\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\\\/#webpage\"},\"articleSection\":\"Baloncesto, Euroliga, baloncesto, Baskonia, Buesa Arena, euroliga, FC Barcelona\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/11\\\/16\\\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/euroliga\\\/#listItem\",\"name\":\"Euroliga\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/euroliga\\\/#listItem\",\"position\":2,\"name\":\"Euroliga\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/euroliga\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/11\\\/16\\\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\\\/#listItem\",\"name\":\"El \\u00abefecto Dusko\\u00bb barre al Barcelona en el Buesa Arena\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/11\\\/16\\\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\\\/#listItem\",\"position\":3,\"name\":\"El \\u00abefecto Dusko\\u00bb barre al Barcelona en el Buesa Arena\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/euroliga\\\/#listItem\",\"name\":\"Euroliga\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/11\\\/16\\\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/11\\\/16\\\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/ibai-rodriguez\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/ibai-rodriguez\\\/\",\"name\":\"Ibai Rodriguez\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/11\\\/16\\\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b818207514879eeeb06a91550426cb31fa71ff8335f66bd3bb6a99f7a6c11cf6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Ibai Rodriguez\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/11\\\/16\\\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/11\\\/16\\\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\\\/\",\"name\":\"El \\u00abefecto Dusko\\u00bb barre al Barcelona en el Buesa Arena \\u2013 Agente Libre Digital\",\"description\":\"El \\u00abefecto Dusko\\u00bb barre al Barcelona en el Buesa Arena\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/11\\\/16\\\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/ibai-rodriguez\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/ibai-rodriguez\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/F_AGNFdXYAEGvOZ.jpg\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/11\\\/16\\\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\\\/#mainImage\",\"width\":679,\"height\":453,\"caption\":\"Cody Miller-McIntyre, MVP de la jornada. Fuente: Baskonia\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2023\\\/11\\\/16\\\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\\\/#mainImage\"},\"datePublished\":\"2023-11-16T17:11:12+01:00\",\"dateModified\":\"2023-11-16T17:19:36+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El \u00abefecto Dusko\u00bb barre al Barcelona en el Buesa Arena \u2013 Agente Libre Digital","description":"El \u00abefecto Dusko\u00bb barre al Barcelona en el Buesa Arena","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2023\/11\/16\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/11\/16\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\/#blogposting","name":"El \u00abefecto Dusko\u00bb barre al Barcelona en el Buesa Arena \u2013 Agente Libre Digital","headline":"El \u00abefecto Dusko\u00bb barre al Barcelona en el Buesa Arena","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/ibai-rodriguez\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/11\/F_AGNFdXYAEGvOZ.jpg","width":679,"height":453,"caption":"Cody Miller-McIntyre, MVP de la jornada. Fuente: Baskonia"},"datePublished":"2023-11-16T17:11:12+01:00","dateModified":"2023-11-16T17:19:36+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/11\/16\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/11\/16\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\/#webpage"},"articleSection":"Baloncesto, Euroliga, baloncesto, Baskonia, Buesa Arena, euroliga, FC Barcelona"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/11\/16\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/euroliga\/#listItem","name":"Euroliga"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/euroliga\/#listItem","position":2,"name":"Euroliga","item":"https:\/\/agentelibredigital.com\/index.php\/category\/euroliga\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/11\/16\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\/#listItem","name":"El \u00abefecto Dusko\u00bb barre al Barcelona en el Buesa Arena"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/11\/16\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\/#listItem","position":3,"name":"El \u00abefecto Dusko\u00bb barre al Barcelona en el Buesa Arena","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/euroliga\/#listItem","name":"Euroliga"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/11\/16\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/11\/16\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/ibai-rodriguez\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/ibai-rodriguez\/","name":"Ibai Rodriguez","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/11\/16\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b818207514879eeeb06a91550426cb31fa71ff8335f66bd3bb6a99f7a6c11cf6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Ibai Rodriguez"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/11\/16\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2023\/11\/16\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\/","name":"El \u00abefecto Dusko\u00bb barre al Barcelona en el Buesa Arena \u2013 Agente Libre Digital","description":"El \u00abefecto Dusko\u00bb barre al Barcelona en el Buesa Arena","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/11\/16\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/ibai-rodriguez\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/ibai-rodriguez\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/11\/F_AGNFdXYAEGvOZ.jpg","@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/11\/16\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\/#mainImage","width":679,"height":453,"caption":"Cody Miller-McIntyre, MVP de la jornada. Fuente: Baskonia"},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2023\/11\/16\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\/#mainImage"},"datePublished":"2023-11-16T17:11:12+01:00","dateModified":"2023-11-16T17:19:36+01:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"El \u00abefecto Dusko\u00bb barre al Barcelona en el Buesa Arena \u2013 Agente Libre Digital","og:description":"El \u00abefecto Dusko\u00bb barre al Barcelona en el Buesa Arena","og:url":"https:\/\/agentelibredigital.com\/index.php\/2023\/11\/16\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/11\/F_AGNFdXYAEGvOZ.jpg","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/11\/F_AGNFdXYAEGvOZ.jpg","og:image:width":679,"og:image:height":453,"article:published_time":"2023-11-16T16:11:12+00:00","article:modified_time":"2023-11-16T16:19:36+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"El \u00abefecto Dusko\u00bb barre al Barcelona en el Buesa Arena \u2013 Agente Libre Digital","twitter:description":"El \u00abefecto Dusko\u00bb barre al Barcelona en el Buesa Arena","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/11\/F_AGNFdXYAEGvOZ.jpg"},"aioseo_meta_data":{"post_id":"2112","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-11-16 16:11:12","updated":"2025-06-04 18:35:57","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/euroliga\/\" title=\"Euroliga\">Euroliga<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl \u00abefecto Dusko\u00bb barre al Barcelona en el Buesa Arena\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"Euroliga","link":"https:\/\/agentelibredigital.com\/index.php\/category\/euroliga\/"},{"label":"El \u00abefecto Dusko\u00bb barre al Barcelona en el Buesa Arena","link":"https:\/\/agentelibredigital.com\/index.php\/2023\/11\/16\/el-efecto-dusko-barre-al-barcelona-en-el-buesa-arena\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/2112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=2112"}],"version-history":[{"count":3,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/2112\/revisions"}],"predecessor-version":[{"id":2132,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/2112\/revisions\/2132"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/2125"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=2112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=2112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=2112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}