{"id":17654,"date":"2024-04-11T00:16:43","date_gmt":"2024-04-10T22:16:43","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=17654"},"modified":"2024-04-11T00:16:43","modified_gmt":"2024-04-10T22:16:43","slug":"simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/11\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\/","title":{"rendered":"Simeone: \u00abTenemos que prepararnos para lo que pase en el campo\u00bb"},"content":{"rendered":"<h4>Tras la finalizaci\u00f3n del encuentro, el t\u00e9cnico del Atl\u00e9tico de Madrid compadeci\u00f3 ante los medios de comunicaci\u00f3n para analizar el partido frente al Borussia Dortmund<\/h4>\n<p><a href=\"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/10\/un-difuso-colchon-para-los-colchoneros\/\">El conjunto colchonero sac\u00f3 una valiosa victoria del Metropolitano tras derrotar al equipo alem\u00e1n por dos a uno.<\/a> Los tantos de <strong>De Paul<\/strong> y <strong>Lino<\/strong> pusieron por delante a un <strong>Atleti<\/strong> que <strong>perdon\u00f3<\/strong> la sentencia de la eliminatoria <strong>hasta en dos ocasiones<\/strong>. Algo que han terminado pagando, pues el <strong>Borussia Dortmund<\/strong> recort\u00f3 distancias a falta de <strong>10 minutos<\/strong> para finalizar el encuentro, dejando claro a los rojiblancos que <strong>tendr\u00e1n que sufrir en Alemania<\/strong> para lograr el pase a la <strong>semifinal<\/strong>. Tras lo sucedido, <strong>Simeone<\/strong> analiz\u00f3 las claves del enfrentamiento.<\/p>\n<h2>An\u00e1lisis del encuentro<\/h2>\n<p>El Cholo se mostr\u00f3 sincero a la hora de hablar sobre el partido de sus jugadores. <strong>\u00abNos vamos con la sensaci\u00f3n de haber ganado el primer partido que es muy importante. Los chicos hicieron un esfuerzo enorme con 70 minutos controlando el partido e incluso con situaciones para sentenciar. Ellos tambi\u00e9n pudieron empatar, se ha visto en los cuatro partidos que no es nada f\u00e1cil ganar, as\u00ed que nosotros estamos contentos\u00bb.<\/strong><\/p>\n<h2>Sensaciones del equipo<\/h2>\n<p>A pesar de los sustos finales del Borussia Dortmund, a Simeone se le vio contento y orgulloso por sus pupilos. <strong>\u00abEstoy contento por el equipo, me ha dado buenas sensaciones despu\u00e9s de diez d\u00edas que no hab\u00edamos jugado hasta el Villarreal m\u00e1s otros 15 del par\u00f3n. Hemos tenido muy buena presi\u00f3n robando en campo rival y ahora iremos a su campo sabiendo con lo que nos vamos a encontrar\u00bb.<\/strong><\/p>\n<h2>Sequ\u00eda de Morata<\/h2>\n<p>El delantero espa\u00f1ol est\u00e1 pasando por un momento muy delicado esta temporada. Aun as\u00ed, Simeone mostr\u00f3 su confianza total en el jugador. <strong>\u00abSon rachas naturales, Morata tuvo desde julio al mes de enero seis meses impresionantes y ahora est\u00e1 atravesando un momento m\u00e1s dif\u00edcil. Est\u00e1 trabajando como queremos y como el equipo necesita y estoy seguro de que a base de trabajo volver\u00e1\u00bb.<\/strong><\/p>\n<h2>Lino, sancionado para la vuelta<\/h2>\n<p>El brasile\u00f1o, goleador de la noche, no estar\u00e1 en Alemania tras ver la amarilla que le har\u00e1 perderse la vuelta. Sobre esto, Simeone tuvo unas palabras. <strong>\u00abLino est\u00e1 trabajando enormemente y tiene unas condiciones f\u00edsicas espectaculares, pero necesitamos exigirle tener m\u00e1s gol porque lo tiene porque se los vamos a sacar\u00bb.<\/strong><\/p>\n<h2>Estado f\u00edsico de los jugadores<\/h2>\n<p>Una vez m\u00e1s, se ha visto que los jugadores rojiblancos est\u00e1n un punto por detr\u00e1s en lo f\u00edsico con respecto al resto de clubes en Champions y Simeone lo sabe. \u00ab<strong>Mantener el mismo nivel durante los noventa minutos es muy dif\u00edcil y es normal que en Champions te encuentres con rivales que generan mucho, por eso est\u00e1n en lugar donde est\u00e1n. Los cambios que realizaron le dieron mucha frescura y rapidez, son muy buenos\u00bb.<\/strong><\/p>\n<h2>La vuelta en Alemania<\/h2>\n<p>El siguiente paso del Atl\u00e9tico de Madrid ser\u00e1 viajar a Alemania para la vuelta de los cuartos de final. Algo que no parece nada f\u00e1cil por la atm\u00f3sfera que se crea en el templo del Borussia Dortmund. A pesar de ello, Simeone est\u00e1 tranquilo.<strong> \u00abNosotros tenemos que prepararnos para lo que pase dentro del campo de juego. Est\u00e1 claro que la gente empuja como nos empujan a nosotros aqu\u00ed. Nosotros tendremos que buscar las situaciones que nos favorecen a partir de lo que nos encontremos\u00bb.<\/strong><\/p>\n<h2>Carga de partidos<\/h2>\n<p>El conjunto rojiblanco tendr\u00e1 en las pr\u00f3ximas semana una gran cantidad de encuentros y con poco descanso entre ellos. Eso s\u00ed, el t\u00e9cnico argentino se muestra agradecido. <strong>\u00abEstamos con la alegr\u00eda de seguir competiendo en estos torneos a estas alturas. Nos genera un esfuerzo doble y por eso intentamos preparar la temporada esperando que pasen estas cosas\u00bb.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras la finalizaci\u00f3n del encuentro, el t\u00e9cnico del Atl\u00e9tico de Madrid compadeci\u00f3 ante los medios de comunicaci\u00f3n para analizar el partido frente al Borussia Dortmund El conjunto colchonero sac\u00f3 una&hellip; <\/p>\n","protected":false},"author":2,"featured_media":17657,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[13,36],"tags":[62,80],"class_list":["post-17654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atletico-de-madrid","category-uefa-champions-league","tag-atletico-de-madrid","tag-uefa-champions-league"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Simeone: \u00abTenemos que prepararnos para lo que pase en el campo\u00bb Tras la finalizaci\u00f3n del encuentro, el t\u00e9cnico del Atl\u00e9tico de Madrid compadeci\u00f3 ante los medios para analizar el partido frente al Borussia Dortmund\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Agente Libre\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/11\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Simeone: \u00abTenemos que prepararnos para lo que pase en el campo\u00bb \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"Simeone: \u00abTenemos que prepararnos para lo que pase en el campo\u00bb Tras la finalizaci\u00f3n del encuentro, el t\u00e9cnico del Atl\u00e9tico de Madrid compadeci\u00f3 ante los medios para analizar el partido frente al Borussia Dortmund\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/11\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/fbl-eur-c1-atletico-madrid-dortmund-2-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/fbl-eur-c1-atletico-madrid-dortmund-2-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-04-10T22:16:43+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-04-10T22:16:43+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Simeone: \u00abTenemos que prepararnos para lo que pase en el campo\u00bb \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Simeone: \u00abTenemos que prepararnos para lo que pase en el campo\u00bb Tras la finalizaci\u00f3n del encuentro, el t\u00e9cnico del Atl\u00e9tico de Madrid compadeci\u00f3 ante los medios para analizar el partido frente al Borussia Dortmund\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/fbl-eur-c1-atletico-madrid-dortmund-2-scaled.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/11\\\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\\\/#blogposting\",\"name\":\"Simeone: \\u00abTenemos que prepararnos para lo que pase en el campo\\u00bb \\u2013 Agente Libre Digital\",\"headline\":\"Simeone: \\u00abTenemos que prepararnos para lo que pase en el campo\\u00bb\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/agente-libre\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/fbl-eur-c1-atletico-madrid-dortmund-2-scaled.jpg\",\"width\":2560,\"height\":1706,\"caption\":\"Atletico Madrid's Argentinian coach Diego Simeone looks on prior to the UEFA Champions League quarter final first leg football match between Club Atletico de Madrid and Borussia Dortmund at the Metropolitano stadium in Madrid on April 10, 2024. (Photo by Pierre-Philippe MARCOU \\\/ AFP) (Photo by PIERRE-PHILIPPE MARCOU\\\/AFP via Getty Images)\"},\"datePublished\":\"2024-04-11T00:16:43+02:00\",\"dateModified\":\"2024-04-11T00:16:43+02:00\",\"inLanguage\":\"es-ES\",\"commentCount\":778,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/11\\\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/11\\\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\\\/#webpage\"},\"articleSection\":\"Atl\\u00e9tico de Madrid, UEFA Champions League, Atl\\u00e9tico de Madrid, UEFA Champions League\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/11\\\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/atletico-de-madrid\\\/#listItem\",\"name\":\"Atl\\u00e9tico de Madrid\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/atletico-de-madrid\\\/#listItem\",\"position\":2,\"name\":\"Atl\\u00e9tico de Madrid\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/atletico-de-madrid\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/11\\\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\\\/#listItem\",\"name\":\"Simeone: \\u00abTenemos que prepararnos para lo que pase en el campo\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/11\\\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\\\/#listItem\",\"position\":3,\"name\":\"Simeone: \\u00abTenemos que prepararnos para lo que pase en el campo\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/atletico-de-madrid\\\/#listItem\",\"name\":\"Atl\\u00e9tico de Madrid\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/11\\\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/11\\\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/agente-libre\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/agente-libre\\\/\",\"name\":\"Agente Libre\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/11\\\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ee68409ae66b7f9297ba1e9e0bb866885e1bcce95483c1a82d51d7c34d6766a?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Agente Libre\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/11\\\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/11\\\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\\\/\",\"name\":\"Simeone: \\u00abTenemos que prepararnos para lo que pase en el campo\\u00bb \\u2013 Agente Libre Digital\",\"description\":\"Simeone: \\u00abTenemos que prepararnos para lo que pase en el campo\\u00bb Tras la finalizaci\\u00f3n del encuentro, el t\\u00e9cnico del Atl\\u00e9tico de Madrid compadeci\\u00f3 ante los medios para analizar el partido frente al Borussia Dortmund\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/11\\\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/agente-libre\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/agente-libre\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/fbl-eur-c1-atletico-madrid-dortmund-2-scaled.jpg\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/11\\\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\\\/#mainImage\",\"width\":2560,\"height\":1706,\"caption\":\"Atletico Madrid's Argentinian coach Diego Simeone looks on prior to the UEFA Champions League quarter final first leg football match between Club Atletico de Madrid and Borussia Dortmund at the Metropolitano stadium in Madrid on April 10, 2024. (Photo by Pierre-Philippe MARCOU \\\/ AFP) (Photo by PIERRE-PHILIPPE MARCOU\\\/AFP via Getty Images)\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/11\\\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\\\/#mainImage\"},\"datePublished\":\"2024-04-11T00:16:43+02:00\",\"dateModified\":\"2024-04-11T00:16:43+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Simeone: \u00abTenemos que prepararnos para lo que pase en el campo\u00bb \u2013 Agente Libre Digital","description":"Simeone: \u00abTenemos que prepararnos para lo que pase en el campo\u00bb Tras la finalizaci\u00f3n del encuentro, el t\u00e9cnico del Atl\u00e9tico de Madrid compadeci\u00f3 ante los medios para analizar el partido frente al Borussia Dortmund","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/11\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/11\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\/#blogposting","name":"Simeone: \u00abTenemos que prepararnos para lo que pase en el campo\u00bb \u2013 Agente Libre Digital","headline":"Simeone: \u00abTenemos que prepararnos para lo que pase en el campo\u00bb","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/agente-libre\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/fbl-eur-c1-atletico-madrid-dortmund-2-scaled.jpg","width":2560,"height":1706,"caption":"Atletico Madrid's Argentinian coach Diego Simeone looks on prior to the UEFA Champions League quarter final first leg football match between Club Atletico de Madrid and Borussia Dortmund at the Metropolitano stadium in Madrid on April 10, 2024. (Photo by Pierre-Philippe MARCOU \/ AFP) (Photo by PIERRE-PHILIPPE MARCOU\/AFP via Getty Images)"},"datePublished":"2024-04-11T00:16:43+02:00","dateModified":"2024-04-11T00:16:43+02:00","inLanguage":"es-ES","commentCount":778,"mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/11\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/11\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\/#webpage"},"articleSection":"Atl\u00e9tico de Madrid, UEFA Champions League, Atl\u00e9tico de Madrid, UEFA Champions League"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/11\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/atletico-de-madrid\/#listItem","name":"Atl\u00e9tico de Madrid"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/atletico-de-madrid\/#listItem","position":2,"name":"Atl\u00e9tico de Madrid","item":"https:\/\/agentelibredigital.com\/index.php\/category\/atletico-de-madrid\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/11\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\/#listItem","name":"Simeone: \u00abTenemos que prepararnos para lo que pase en el campo\u00bb"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/11\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\/#listItem","position":3,"name":"Simeone: \u00abTenemos que prepararnos para lo que pase en el campo\u00bb","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/atletico-de-madrid\/#listItem","name":"Atl\u00e9tico de Madrid"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/11\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/11\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/agente-libre\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/agente-libre\/","name":"Agente Libre","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/11\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/9ee68409ae66b7f9297ba1e9e0bb866885e1bcce95483c1a82d51d7c34d6766a?s=96&d=mm&r=g","width":96,"height":96,"caption":"Agente Libre"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/11\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/11\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\/","name":"Simeone: \u00abTenemos que prepararnos para lo que pase en el campo\u00bb \u2013 Agente Libre Digital","description":"Simeone: \u00abTenemos que prepararnos para lo que pase en el campo\u00bb Tras la finalizaci\u00f3n del encuentro, el t\u00e9cnico del Atl\u00e9tico de Madrid compadeci\u00f3 ante los medios para analizar el partido frente al Borussia Dortmund","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/11\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/agente-libre\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/agente-libre\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/fbl-eur-c1-atletico-madrid-dortmund-2-scaled.jpg","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/11\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\/#mainImage","width":2560,"height":1706,"caption":"Atletico Madrid's Argentinian coach Diego Simeone looks on prior to the UEFA Champions League quarter final first leg football match between Club Atletico de Madrid and Borussia Dortmund at the Metropolitano stadium in Madrid on April 10, 2024. (Photo by Pierre-Philippe MARCOU \/ AFP) (Photo by PIERRE-PHILIPPE MARCOU\/AFP via Getty Images)"},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/11\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\/#mainImage"},"datePublished":"2024-04-11T00:16:43+02:00","dateModified":"2024-04-11T00:16:43+02:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"Simeone: \u00abTenemos que prepararnos para lo que pase en el campo\u00bb \u2013 Agente Libre Digital","og:description":"Simeone: \u00abTenemos que prepararnos para lo que pase en el campo\u00bb Tras la finalizaci\u00f3n del encuentro, el t\u00e9cnico del Atl\u00e9tico de Madrid compadeci\u00f3 ante los medios para analizar el partido frente al Borussia Dortmund","og:url":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/11\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/fbl-eur-c1-atletico-madrid-dortmund-2-scaled.jpg","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/fbl-eur-c1-atletico-madrid-dortmund-2-scaled.jpg","og:image:width":2560,"og:image:height":1706,"article:published_time":"2024-04-10T22:16:43+00:00","article:modified_time":"2024-04-10T22:16:43+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"Simeone: \u00abTenemos que prepararnos para lo que pase en el campo\u00bb \u2013 Agente Libre Digital","twitter:description":"Simeone: \u00abTenemos que prepararnos para lo que pase en el campo\u00bb Tras la finalizaci\u00f3n del encuentro, el t\u00e9cnico del Atl\u00e9tico de Madrid compadeci\u00f3 ante los medios para analizar el partido frente al Borussia Dortmund","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/fbl-eur-c1-atletico-madrid-dortmund-2-scaled.jpg"},"aioseo_meta_data":{"post_id":"17654","title":null,"description":"#post_title Tras la finalizaci\u00f3n del encuentro, el t\u00e9cnico del Atl\u00e9tico de Madrid compadeci\u00f3 ante los medios para analizar el partido frente al Borussia Dortmund","keywords":[],"keyphrases":{"focus":{"keyphrase":"Simeone","score":83,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":[],"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-04-10 21:05:24","updated":"2025-06-04 21:55:59","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/atletico-de-madrid\/\" title=\"Atl\u00e9tico de Madrid\">Atl\u00e9tico de Madrid<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSimeone: \u00abTenemos que prepararnos para lo que pase en el campo\u00bb\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"Atl\u00e9tico de Madrid","link":"https:\/\/agentelibredigital.com\/index.php\/category\/atletico-de-madrid\/"},{"label":"Simeone: \u00abTenemos que prepararnos para lo que pase en el campo\u00bb","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/11\/simeone-tenemos-que-prepararnos-para-lo-que-pase-en-el-campo\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/17654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=17654"}],"version-history":[{"count":3,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/17654\/revisions"}],"predecessor-version":[{"id":17663,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/17654\/revisions\/17663"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/17657"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=17654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=17654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=17654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}