{"id":17534,"date":"2024-04-09T08:30:39","date_gmt":"2024-04-09T06:30:39","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=17534"},"modified":"2024-04-09T02:25:23","modified_gmt":"2024-04-09T00:25:23","slug":"el-futuro-de-sergio-ramos-esta-en-el-aire","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/09\/el-futuro-de-sergio-ramos-esta-en-el-aire\/","title":{"rendered":"El futuro de Sergio Ramos est\u00e1 en el aire"},"content":{"rendered":"<p>El central hispalense est\u00e1 muy contento en <strong>Sevilla<\/strong>, pero <strong>no esperar\u00e1 hasta verano<\/strong> para<strong> firmar su continuidad<\/strong> en la capital andaluza.<\/p>\n<h3><strong>Sergio Ramos no esperar\u00e1 eternamente al Sevilla<\/strong><\/h3>\n<p>Esta temporada el camero ha tenido que esperar hasta los<strong> \u00faltimos d\u00edas del mercado<\/strong> de traspasos para regresar a su <a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/sevilla\/\"><strong>Sevilla<\/strong>,<\/a> el futbolista estuvo cerca de fichar por la liga de <strong>Arabia Saud\u00ed<\/strong> a finales del mes de agosto. Se decidieron por el camero finalmente y acabaron firm\u00e1ndolo hasta final de temporada y por una cifra muy inferior a la que le ofrec\u00edan otros proyectos.<\/p>\n<p><strong>Sergio <\/strong>volvi\u00f3 con la<strong> ilusi\u00f3n<\/strong> de aquel ni\u00f1o que se form\u00f3 en <strong>Sevilla<\/strong> y para intentar <strong>conseguir levantar un t\u00edtulo con el equipo<\/strong> que le hizo ser futbolista, sin embargo, <strong>no ha sido posible debido a la p\u00e9sima gesti\u00f3n del club y al mal rendimiento del equipo durante la temporada<\/strong>.<\/p>\n<p>Hubo momentos en los que se pensaba que el equipo descender\u00eda a segunda divisi\u00f3n, pero la llegada de <strong>Quique S\u00e1nchez Flores<\/strong>, el <strong>rendimiento<\/strong> del propio Sergio y la<strong> irrupci\u00f3n en el primer equipo de futbolistas como Isaac Romero, Kike Sala y Juanlu S\u00e1nchez<\/strong> cambiaron el rumbo del equipo y ahora est\u00e1n en una zona m\u00e1s o menos tranquila de la tabla, con una distancia de seis puntos de esa <strong>zona de descenso.<\/strong><\/p>\n<p>Esta temporada ha demostrado seguir estando a un gran nivel, gracias a sus 7 goles entre<strong> liga, Champions League y Copa del Rey.<\/strong> Es el <strong>capit\u00e1n<\/strong> de la zaga sevillista y ha salvado en varias ocasiones a su equipo con grandes acciones defensivas. A sus 38 a\u00f1os sigue estando en plena forma. El Sevilla quiere renovarlo, pero no a cualquier precio y es muy dif\u00edcil que siga en el club a menos que Sergio vuelva a hacer un <strong>gran esfuerzo econ\u00f3mico.<\/strong><\/p>\n<figure id=\"attachment_17545\" aria-describedby=\"caption-attachment-17545\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17545 size-full\" src=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/getafe-cf-v-sevilla-fc-laliga-ea-sports-1-scaled.jpg\" alt=\"ramos\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/getafe-cf-v-sevilla-fc-laliga-ea-sports-1-scaled.jpg 2560w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/getafe-cf-v-sevilla-fc-laliga-ea-sports-1-300x200.jpg 300w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/getafe-cf-v-sevilla-fc-laliga-ea-sports-1-1024x683.jpg 1024w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/getafe-cf-v-sevilla-fc-laliga-ea-sports-1-768x512.jpg 768w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/getafe-cf-v-sevilla-fc-laliga-ea-sports-1-1536x1024.jpg 1536w, https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/getafe-cf-v-sevilla-fc-laliga-ea-sports-1-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><figcaption id=\"caption-attachment-17545\" class=\"wp-caption-text\">Sergio Ramos marcando gol en el Coliseum\/ Fuente: Gonzalo Arroyo Moreno\/AFP via Getty Images.<\/figcaption><\/figure>\n<p><strong>Autor: Manuel \u00c1lvarez Lozano<\/strong><\/p>\n<p><strong>Sigan toda la informaci\u00f3n y actualidad deportiva en Twitter: <a href=\"https:\/\/x.com\/AgenteLibre_dig?s=20\">@agentelibre_dig<\/a>, <\/strong><strong>y<\/strong><strong> en Instagram: <a href=\"https:\/\/www.instagram.com\/agentelibre_dig\">@agentelibre_dig.<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El central hispalense est\u00e1 muy contento en Sevilla, pero no esperar\u00e1 hasta verano para firmar su continuidad en la capital andaluza. Sergio Ramos no esperar\u00e1 eternamente al Sevilla Esta temporada&hellip; <\/p>\n","protected":false},"author":178,"featured_media":17546,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[47,46,24,36],"tags":[63,124,218,106,698,700],"class_list":["post-17534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol-espanol","category-laliga-ea-sports","category-sevilla","category-uefa-champions-league","tag-champions-league","tag-copa-del-rey","tag-futbol-espanol","tag-laliga-ea-sports","tag-sergio-ramos","tag-sevilla-fc"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Sergio Ramos quiere tener claro su futuro antes de verano, su continuidad en el Sevilla FC depender\u00e1 de \u00e9l mismo porque la situaci\u00f3n del equipo es muy delicada. #\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Manuel Alvarez Lozano\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/09\/el-futuro-de-sergio-ramos-esta-en-el-aire\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El futuro de Sergio Ramos est\u00e1 en el aire \u2013\" \/>\n\t\t<meta property=\"og:description\" content=\"Sergio Ramos quiere tener claro su futuro antes de verano, su continuidad en el Sevilla FC depender\u00e1 de \u00e9l mismo porque la situaci\u00f3n del equipo es muy delicada. #\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/09\/el-futuro-de-sergio-ramos-esta-en-el-aire\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/fbl-eur-c1-lens-sevilla-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/fbl-eur-c1-lens-sevilla-scaled.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-04-09T06:30:39+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-04-09T00:25:23+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El futuro de Sergio Ramos est\u00e1 en el aire \u2013\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Sergio Ramos quiere tener claro su futuro antes de verano, su continuidad en el Sevilla FC depender\u00e1 de \u00e9l mismo porque la situaci\u00f3n del equipo es muy delicada. #\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/fbl-eur-c1-lens-sevilla-scaled.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/09\\\/el-futuro-de-sergio-ramos-esta-en-el-aire\\\/#blogposting\",\"name\":\"El futuro de Sergio Ramos est\\u00e1 en el aire \\u2013\",\"headline\":\"El futuro de Sergio Ramos est\\u00e1 en el aire\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/manuel-alvarez-lozano\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/fbl-eur-c1-lens-sevilla-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Sergio Ramos en el Sevilla\\\/ Fuente: SAMEER AL-DOUMY\\\/AFP via Getty Images.\"},\"datePublished\":\"2024-04-09T08:30:39+02:00\",\"dateModified\":\"2024-04-09T02:25:23+02:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1503,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/09\\\/el-futuro-de-sergio-ramos-esta-en-el-aire\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/09\\\/el-futuro-de-sergio-ramos-esta-en-el-aire\\\/#webpage\"},\"articleSection\":\"F\\u00fatbol Espa\\u00f1ol, LaLiga EA Sports, Sevilla, UEFA Champions League, Champions League, Copa del Rey, futbol espa\\u00f1ol, LaLiga EA Sports, Sergio Ramos, Sevilla FC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/09\\\/el-futuro-de-sergio-ramos-esta-en-el-aire\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/sevilla\\\/#listItem\",\"name\":\"Sevilla\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/sevilla\\\/#listItem\",\"position\":2,\"name\":\"Sevilla\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/sevilla\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/09\\\/el-futuro-de-sergio-ramos-esta-en-el-aire\\\/#listItem\",\"name\":\"El futuro de Sergio Ramos est\\u00e1 en el aire\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/09\\\/el-futuro-de-sergio-ramos-esta-en-el-aire\\\/#listItem\",\"position\":3,\"name\":\"El futuro de Sergio Ramos est\\u00e1 en el aire\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/sevilla\\\/#listItem\",\"name\":\"Sevilla\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/09\\\/el-futuro-de-sergio-ramos-esta-en-el-aire\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/09\\\/el-futuro-de-sergio-ramos-esta-en-el-aire\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/manuel-alvarez-lozano\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/manuel-alvarez-lozano\\\/\",\"name\":\"Manuel Alvarez Lozano\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/09\\\/el-futuro-de-sergio-ramos-esta-en-el-aire\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c11721a4f4a2a3d4b2ca65c152b7828895f8639ae97a6c5e86b08bf7370ca418?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Manuel Alvarez Lozano\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/09\\\/el-futuro-de-sergio-ramos-esta-en-el-aire\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/09\\\/el-futuro-de-sergio-ramos-esta-en-el-aire\\\/\",\"name\":\"El futuro de Sergio Ramos est\\u00e1 en el aire \\u2013\",\"description\":\"Sergio Ramos quiere tener claro su futuro antes de verano, su continuidad en el Sevilla FC depender\\u00e1 de \\u00e9l mismo porque la situaci\\u00f3n del equipo es muy delicada. #\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/09\\\/el-futuro-de-sergio-ramos-esta-en-el-aire\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/manuel-alvarez-lozano\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/manuel-alvarez-lozano\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/fbl-eur-c1-lens-sevilla-scaled.jpg\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/09\\\/el-futuro-de-sergio-ramos-esta-en-el-aire\\\/#mainImage\",\"width\":2560,\"height\":1707,\"caption\":\"Sergio Ramos en el Sevilla\\\/ Fuente: SAMEER AL-DOUMY\\\/AFP via Getty Images.\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/09\\\/el-futuro-de-sergio-ramos-esta-en-el-aire\\\/#mainImage\"},\"datePublished\":\"2024-04-09T08:30:39+02:00\",\"dateModified\":\"2024-04-09T02:25:23+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El futuro de Sergio Ramos est\u00e1 en el aire \u2013","description":"Sergio Ramos quiere tener claro su futuro antes de verano, su continuidad en el Sevilla FC depender\u00e1 de \u00e9l mismo porque la situaci\u00f3n del equipo es muy delicada. #","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/09\/el-futuro-de-sergio-ramos-esta-en-el-aire\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/09\/el-futuro-de-sergio-ramos-esta-en-el-aire\/#blogposting","name":"El futuro de Sergio Ramos est\u00e1 en el aire \u2013","headline":"El futuro de Sergio Ramos est\u00e1 en el aire","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/manuel-alvarez-lozano\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/fbl-eur-c1-lens-sevilla-scaled.jpg","width":2560,"height":1707,"caption":"Sergio Ramos en el Sevilla\/ Fuente: SAMEER AL-DOUMY\/AFP via Getty Images."},"datePublished":"2024-04-09T08:30:39+02:00","dateModified":"2024-04-09T02:25:23+02:00","inLanguage":"es-ES","commentCount":1503,"mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/09\/el-futuro-de-sergio-ramos-esta-en-el-aire\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/09\/el-futuro-de-sergio-ramos-esta-en-el-aire\/#webpage"},"articleSection":"F\u00fatbol Espa\u00f1ol, LaLiga EA Sports, Sevilla, UEFA Champions League, Champions League, Copa del Rey, futbol espa\u00f1ol, LaLiga EA Sports, Sergio Ramos, Sevilla FC"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/09\/el-futuro-de-sergio-ramos-esta-en-el-aire\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/sevilla\/#listItem","name":"Sevilla"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/sevilla\/#listItem","position":2,"name":"Sevilla","item":"https:\/\/agentelibredigital.com\/index.php\/category\/sevilla\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/09\/el-futuro-de-sergio-ramos-esta-en-el-aire\/#listItem","name":"El futuro de Sergio Ramos est\u00e1 en el aire"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/09\/el-futuro-de-sergio-ramos-esta-en-el-aire\/#listItem","position":3,"name":"El futuro de Sergio Ramos est\u00e1 en el aire","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/sevilla\/#listItem","name":"Sevilla"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/09\/el-futuro-de-sergio-ramos-esta-en-el-aire\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/09\/el-futuro-de-sergio-ramos-esta-en-el-aire\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/manuel-alvarez-lozano\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/manuel-alvarez-lozano\/","name":"Manuel Alvarez Lozano","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/09\/el-futuro-de-sergio-ramos-esta-en-el-aire\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c11721a4f4a2a3d4b2ca65c152b7828895f8639ae97a6c5e86b08bf7370ca418?s=96&d=mm&r=g","width":96,"height":96,"caption":"Manuel Alvarez Lozano"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/09\/el-futuro-de-sergio-ramos-esta-en-el-aire\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/09\/el-futuro-de-sergio-ramos-esta-en-el-aire\/","name":"El futuro de Sergio Ramos est\u00e1 en el aire \u2013","description":"Sergio Ramos quiere tener claro su futuro antes de verano, su continuidad en el Sevilla FC depender\u00e1 de \u00e9l mismo porque la situaci\u00f3n del equipo es muy delicada. #","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/09\/el-futuro-de-sergio-ramos-esta-en-el-aire\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/manuel-alvarez-lozano\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/manuel-alvarez-lozano\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/fbl-eur-c1-lens-sevilla-scaled.jpg","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/09\/el-futuro-de-sergio-ramos-esta-en-el-aire\/#mainImage","width":2560,"height":1707,"caption":"Sergio Ramos en el Sevilla\/ Fuente: SAMEER AL-DOUMY\/AFP via Getty Images."},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/09\/el-futuro-de-sergio-ramos-esta-en-el-aire\/#mainImage"},"datePublished":"2024-04-09T08:30:39+02:00","dateModified":"2024-04-09T02:25:23+02:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"El futuro de Sergio Ramos est\u00e1 en el aire \u2013","og:description":"Sergio Ramos quiere tener claro su futuro antes de verano, su continuidad en el Sevilla FC depender\u00e1 de \u00e9l mismo porque la situaci\u00f3n del equipo es muy delicada. #","og:url":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/09\/el-futuro-de-sergio-ramos-esta-en-el-aire\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/fbl-eur-c1-lens-sevilla-scaled.jpg","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/fbl-eur-c1-lens-sevilla-scaled.jpg","og:image:width":2560,"og:image:height":1707,"article:published_time":"2024-04-09T06:30:39+00:00","article:modified_time":"2024-04-09T00:25:23+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"El futuro de Sergio Ramos est\u00e1 en el aire \u2013","twitter:description":"Sergio Ramos quiere tener claro su futuro antes de verano, su continuidad en el Sevilla FC depender\u00e1 de \u00e9l mismo porque la situaci\u00f3n del equipo es muy delicada. #","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/fbl-eur-c1-lens-sevilla-scaled.jpg"},"aioseo_meta_data":{"post_id":"17534","title":"#post_title #separator_sa","description":"Sergio Ramos quiere tener claro su futuro antes de verano, su continuidad en el Sevilla FC depender\u00e1 de \u00e9l mismo porque la situaci\u00f3n del equipo es muy delicada. #","keywords":[],"keyphrases":{"focus":{"keyphrase":"ramos","score":91,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":3,"maxScore":9,"error":1},"keyphraseInSubHeadings":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-04-08 23:26:49","updated":"2025-06-04 21:53:58","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/sevilla\/\" title=\"Sevilla\">Sevilla<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl futuro de Sergio Ramos est\u00e1 en el aire\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"Sevilla","link":"https:\/\/agentelibredigital.com\/index.php\/category\/sevilla\/"},{"label":"El futuro de Sergio Ramos est\u00e1 en el aire","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/09\/el-futuro-de-sergio-ramos-esta-en-el-aire\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/17534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/178"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=17534"}],"version-history":[{"count":11,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/17534\/revisions"}],"predecessor-version":[{"id":17548,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/17534\/revisions\/17548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/17546"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=17534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=17534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=17534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}