{"id":17381,"date":"2024-04-07T19:03:55","date_gmt":"2024-04-07T17:03:55","guid":{"rendered":"https:\/\/agentelibredigital.com\/?p=17381"},"modified":"2024-04-07T19:03:55","modified_gmt":"2024-04-07T17:03:55","slug":"el-villarreal-b-resucita-ante-el-burgos","status":"publish","type":"post","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/07\/el-villarreal-b-resucita-ante-el-burgos\/","title":{"rendered":"El Villarreal B resucita ante el Burgos"},"content":{"rendered":"<h4>La buena segunda parte blanquinegra no es suficiente para igualar el marcador y se llevan otra derrota a domicilio<\/h4>\n<p>El Villarreal CF B se ha impuesto por 2-1 al <a href=\"https:\/\/agentelibredigital.com\/?s=burgos+cf\">Burgos CF<\/a> en esta jornada 34 de <a href=\"https:\/\/agentelibredigital.com\/?s=la+liga+hypermotion\">La Liga Hypermotion<\/a>. El Villarreal B fue superior en el primer tiempo y el Burgos en el segundo, pero los locales son m\u00e1s eficaces y se terminan por llevar el encuentro.<\/p>\n<h2>Dominio recompensado groguet<\/h2>\n<p>El partido comenzar\u00eda con un Villarreal B mucho m\u00e1s enchufado que el <a href=\"https:\/\/www.burgoscf.es\/\">Burgos<\/a> y se iba a hacer con el bal\u00f3n. La primera ocasi\u00f3n groguet no tardar\u00eda demasiado en llegar, ya que a los 40 segundos de partido, Carlo Garc\u00eda disparar\u00eda desde fuera del \u00e1rea ligeramente desviado. El Burgos seguir\u00eda sin espabilar y el Villarreal B encerr\u00f3 al Burgos en su \u00e1rea. El filial groguet se estaba sintiendo bien y no tardo en plasmarlo en el marcador. <strong>En el minuto 15, el submarino amarillo servir\u00eda un c\u00f3rner que ser\u00eda muy mal defendido por la defensa blanquinegra y dejar\u00eda a Alex For\u00e9s solo contra Caro en el \u00e1rea peque\u00f1a. El andaluz realizar\u00eda una genial parada al remate del 9 amarillo , pero poco podr\u00eda hacer ante el remate de chilena de Pau Navarro, que estrenar\u00eda el marcador.<\/strong><\/p>\n<p>El porvenir del partido no variar\u00eda en los siguientes minutos. El Burgos empez\u00f3 a tener alg\u00fan acercamiento, pero sin presentar grandes signos de mejora. Tras un c\u00f3rner blanquinegro, el Villarreal B saldr\u00eda a la contra y Ontiveros se quedar\u00eda solo ante Caro, pero no se sabe muy bien si pretende hacer una vaselina que le sale muy mal o lanzar un centro hacia su compa\u00f1ero, pero la realidad es que el bal\u00f3n se termina dirigiendo hacia la cabeza de Alex For\u00e9s y Alex Sancris tiene que intervenir de cabeza para evitar el remate a placer. A ra\u00edz de esta ocasi\u00f3n el partido se iba igualando y el Burgos comenzaba a sentirse c\u00f3modo. Cuando mejor se sent\u00eda el Burgos, <strong>en el minuto 42, en una segunda jugada tras el lanzamiento de una falta, Carlo Garc\u00eda se iba a llevar el bal\u00f3n tras agarrar claramente a Curro, regatear\u00eda a Grego Sierra y disparar\u00eda a porter\u00eda, d\u00f3nde se encontrar\u00eda con la intervenci\u00f3n de Caro, pero el rechace caer\u00eda en Alex For\u00e9s que disparar\u00eda puerta vac\u00eda y marcar\u00eda tras ser fallido el intento de tapar el disparo de Aitor C\u00f3rdoba.<\/strong> De esta manera, se pondr\u00eda el 2-0 en el marcador. Antes de llegar al descanso, Alex Sancris estrellar\u00eda una falta en el larguero en su intento de reducir la diferencia en el marcador.<\/p>\n<figure style=\"width: 904px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/GKk33sgWMAAKbFc?format=jpg&amp;name=4096x4096\" alt=\"Imagen\" width=\"904\" height=\"510\" \/><figcaption class=\"wp-caption-text\">Alex For\u00e9s celebrando el gol. Fuente Cantera Grogueta<\/figcaption><\/figure>\n<h2>Reacci\u00f3n insuficiente blanquinegra<\/h2>\n<p>Al descanso, el Burgos mover\u00eda ficha y har\u00eda un cambio ofensivo, quitando a Elguezabal, que hab\u00eda visto amarilla, por Joni Montiel. El partido parec\u00eda seguir el mismo rumbo hasta que una buena jugada trenzada por banda izquierda por los burgaleses, despertar\u00eda al Burgos. En el minuto 55, se realizar\u00eda una sucesi\u00f3n de saques de esquina a favor de los visitantes. El gol del Burgos estar\u00eda a punto de llegar en tres ocasiones. La primera ser\u00eda un despeje hacia atr\u00e1s de Tasende que casi se cuela en su porter\u00eda. La segunda ser\u00eda un centro al segundo palo que Ojeda rematar\u00eda contra Iker \u00c1lvarez y la \u00faltima de las mencionadas ser\u00eda un disparo desde fuera del \u00e1rea de Joni Montiel que ser\u00eda correspondida con una gran parada de Iker \u00c1lvarez. El Burgos tendr\u00eda ah\u00ed su momento. Despu\u00e9s seguir\u00eda teniendo el control y durante muchos momentos cerca del \u00e1rea groguet, pero no conseguir\u00eda crear grandes ocasiones de gol. En el 61 se dar\u00eda entrada a Bermejo en lugar de Ojeda para intentar m\u00e1s desborde, pero no lo terminar\u00eda de conseguir. Las ocasiones m\u00e1s claras llegar\u00edan de disparos desde fuera del \u00e1rea. En el minuto 71, el Burgos realizar\u00eda cambios a la desesperada y dar\u00eda entrada a Borja Gonz\u00e1lez, Mumo y Ander Mart\u00edn que sustituir\u00edan a Matos, Atienza y Sancris. <strong>En el minuto 83, el \u00e1rbitro se iba a comer un claro penalti sobre Ander Mart\u00edn, que sorprendentemente no ser\u00eda llamado por el VAR. El f\u00fatbol compensar\u00eda el penalti no pitado al Burgos a la jugada siguiente, tras un c\u00f3rner botado por Joni Montiel que Fer Ni\u00f1o cabecear\u00eda al fondo de las mallas para reducir la distancia en el marcador.<\/strong> Justo despu\u00e9s Miguel \u00c1lvarez retirar\u00eda a dos de sus dos mejores jugadores en el d\u00eda de hoy, Alex For\u00e9s y Carlos Romero para dar entrada a Jorge Pascual y Requena. En el 86, Curro tendr\u00eda en sus botas el empate, tras una buena jugada y disparo desde fuera del \u00e1rea, pero su remate se ir\u00eda rozando el palo. El partido iba a continuar con un Burgos lanzado a por el empate con m\u00e1s coraz\u00f3n que cabeza y se notar\u00eda en las pocas ocasiones de calidad que iba a gozar hasta el final del encuentro. Despu\u00e9s de casi 5 minutos de descuento, se dar\u00eda por finalizado y se concretar\u00eda la victoria local.<\/p>\n<figure style=\"width: 898px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pbs.twimg.com\/media\/GKkoocNW4AA7GV9?format=jpg&amp;name=4096x4096\" alt=\"Imagen\" width=\"898\" height=\"599\" \/><figcaption class=\"wp-caption-text\">Ontiveros dando un pase. Fuente Cantera Grogueta<\/figcaption><\/figure>\n<h2>El Villarreal B corta su mala racha y el Burgos la prolonga<\/h2>\n<p>Con esta victoria, <strong>el Villarreal CF B se mantiene 22\u00ba, pero su suma de puntos aumentada hasta los 33 puntos, que le colocan a 2 de la salvaci\u00f3n<\/strong>, a la espera de terminar la jornada. Adem\u00e1s, <strong>ve interrumpida su terrible racha negativa de 5 derrotas seguidas y 7 partidos sin ganar,<\/strong> para reencontrarse con la victoria casi dos meses despu\u00e9s.<\/p>\n<p><strong>El Burgos CF por su parte, se queda con 50 puntos y baja hasta la 11\u00ba plaza. Se queda a expensas de lo que haga el Valladolid a 3 puntos de la zona de play-off.<\/strong> Con esta derrota, <strong>acumula por primera en la temporada su 4\u00ba partido consecutivo sin ganar.<\/strong> Sigue sin obtener buenos resultados fuera de casa y firma otra derrota m\u00e1s en este 2024, en el que ha perdido todos los partidos a domicilio salvo uno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La buena segunda parte blanquinegra no es suficiente para igualar el marcador y se llevan otra derrota a domicilio El Villarreal CF B se ha impuesto por 2-1 al Burgos&hellip; <\/p>\n","protected":false},"author":49,"featured_media":17404,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[47,8],"tags":[569,218,1082,1091],"class_list":["post-17381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol-espanol","category-laliga-hypermotion","tag-burgos-cf","tag-futbol-espanol","tag-la-liga-hypermotion","tag-villarreal-b"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"El Villarreal B resucita ante el Burgos La buena segunda parte blanquinegra no es suficiente para igualar el marcador y se llevan otra derrota a domicilio\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Rafael Pereda\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/07\/el-villarreal-b-resucita-ante-el-burgos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Villarreal B resucita ante el Burgos \u2013 Agente Libre Digital\" \/>\n\t\t<meta property=\"og:description\" content=\"El Villarreal B resucita ante el Burgos La buena segunda parte blanquinegra no es suficiente para igualar el marcador y se llevan otra derrota a domicilio\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/07\/el-villarreal-b-resucita-ante-el-burgos\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/burgos-villarreal-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/burgos-villarreal-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1890\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1890\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-04-07T17:03:55+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-04-07T17:03:55+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Villarreal B resucita ante el Burgos \u2013 Agente Libre Digital\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El Villarreal B resucita ante el Burgos La buena segunda parte blanquinegra no es suficiente para igualar el marcador y se llevan otra derrota a domicilio\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@AgenteLibre_dig\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/burgos-villarreal-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/07\\\/el-villarreal-b-resucita-ante-el-burgos\\\/#blogposting\",\"name\":\"El Villarreal B resucita ante el Burgos \\u2013 Agente Libre Digital\",\"headline\":\"El Villarreal B resucita ante el Burgos\",\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/rafael-pereda\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/burgos-villarreal-1.jpg\",\"width\":1890,\"height\":1890,\"caption\":\"Pau Navarro celebrando el gol junto a Pablo I\\u00f1iguez. Fuente Cantera Grogueta\"},\"datePublished\":\"2024-04-07T19:03:55+02:00\",\"dateModified\":\"2024-04-07T19:03:55+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/07\\\/el-villarreal-b-resucita-ante-el-burgos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/07\\\/el-villarreal-b-resucita-ante-el-burgos\\\/#webpage\"},\"articleSection\":\"F\\u00fatbol Espa\\u00f1ol, LaLiga Hypermotion, Burgos CF, futbol espa\\u00f1ol, La liga HYpermotion, Villarreal B\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/07\\\/el-villarreal-b-resucita-ante-el-burgos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agentelibredigital.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/laliga-hypermotion\\\/#listItem\",\"name\":\"LaLiga Hypermotion\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/laliga-hypermotion\\\/#listItem\",\"position\":2,\"name\":\"LaLiga Hypermotion\",\"item\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/laliga-hypermotion\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/07\\\/el-villarreal-b-resucita-ante-el-burgos\\\/#listItem\",\"name\":\"El Villarreal B resucita ante el Burgos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/07\\\/el-villarreal-b-resucita-ante-el-burgos\\\/#listItem\",\"position\":3,\"name\":\"El Villarreal B resucita ante el Burgos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/category\\\/laliga-hypermotion\\\/#listItem\",\"name\":\"LaLiga Hypermotion\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\",\"name\":\"Agente Libre Digital\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"telephone\":\"+34665330413\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Agente-5-1.png\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/07\\\/el-villarreal-b-resucita-ante-el-burgos\\\/#organizationLogo\",\"width\":500,\"height\":500},\"image\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/07\\\/el-villarreal-b-resucita-ante-el-burgos\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/AgenteLibre_dig\",\"https:\\\/\\\/www.instagram.com\\\/agentelibre_dig\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/rafael-pereda\\\/#author\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/rafael-pereda\\\/\",\"name\":\"Rafael Pereda\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/07\\\/el-villarreal-b-resucita-ante-el-burgos\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b011881c808245d96da0fec527c19d4905183fa8f648250e570f070e9c6c144f?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Rafael Pereda\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/07\\\/el-villarreal-b-resucita-ante-el-burgos\\\/#webpage\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/07\\\/el-villarreal-b-resucita-ante-el-burgos\\\/\",\"name\":\"El Villarreal B resucita ante el Burgos \\u2013 Agente Libre Digital\",\"description\":\"El Villarreal B resucita ante el Burgos La buena segunda parte blanquinegra no es suficiente para igualar el marcador y se llevan otra derrota a domicilio\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/07\\\/el-villarreal-b-resucita-ante-el-burgos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/rafael-pereda\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/author\\\/rafael-pereda\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/burgos-villarreal-1.jpg\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/07\\\/el-villarreal-b-resucita-ante-el-burgos\\\/#mainImage\",\"width\":1890,\"height\":1890,\"caption\":\"Pau Navarro celebrando el gol junto a Pablo I\\u00f1iguez. Fuente Cantera Grogueta\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/index.php\\\/2024\\\/04\\\/07\\\/el-villarreal-b-resucita-ante-el-burgos\\\/#mainImage\"},\"datePublished\":\"2024-04-07T19:03:55+02:00\",\"dateModified\":\"2024-04-07T19:03:55+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#website\",\"url\":\"https:\\\/\\\/agentelibredigital.com\\\/\",\"name\":\"agentelibredigital.com\",\"alternateName\":\"Agente Libre\",\"description\":\"La nueva generaci\\u00f3n del periodismo deportivo.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/agentelibredigital.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El Villarreal B resucita ante el Burgos \u2013 Agente Libre Digital","description":"El Villarreal B resucita ante el Burgos La buena segunda parte blanquinegra no es suficiente para igualar el marcador y se llevan otra derrota a domicilio","canonical_url":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/07\/el-villarreal-b-resucita-ante-el-burgos\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/07\/el-villarreal-b-resucita-ante-el-burgos\/#blogposting","name":"El Villarreal B resucita ante el Burgos \u2013 Agente Libre Digital","headline":"El Villarreal B resucita ante el Burgos","author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/rafael-pereda\/#author"},"publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/burgos-villarreal-1.jpg","width":1890,"height":1890,"caption":"Pau Navarro celebrando el gol junto a Pablo I\u00f1iguez. Fuente Cantera Grogueta"},"datePublished":"2024-04-07T19:03:55+02:00","dateModified":"2024-04-07T19:03:55+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/07\/el-villarreal-b-resucita-ante-el-burgos\/#webpage"},"isPartOf":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/07\/el-villarreal-b-resucita-ante-el-burgos\/#webpage"},"articleSection":"F\u00fatbol Espa\u00f1ol, LaLiga Hypermotion, Burgos CF, futbol espa\u00f1ol, La liga HYpermotion, Villarreal B"},{"@type":"BreadcrumbList","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/07\/el-villarreal-b-resucita-ante-el-burgos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","position":1,"name":"Home","item":"https:\/\/agentelibredigital.com","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/#listItem","name":"LaLiga Hypermotion"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/#listItem","position":2,"name":"LaLiga Hypermotion","item":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/","nextItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/07\/el-villarreal-b-resucita-ante-el-burgos\/#listItem","name":"El Villarreal B resucita ante el Burgos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/07\/el-villarreal-b-resucita-ante-el-burgos\/#listItem","position":3,"name":"El Villarreal B resucita ante el Burgos","previousItem":{"@type":"ListItem","@id":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/#listItem","name":"LaLiga Hypermotion"}}]},{"@type":"Organization","@id":"https:\/\/agentelibredigital.com\/#organization","name":"Agente Libre Digital","description":"La nueva generaci\u00f3n del periodismo deportivo.","url":"https:\/\/agentelibredigital.com\/","telephone":"+34665330413","logo":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2023\/10\/Agente-5-1.png","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/07\/el-villarreal-b-resucita-ante-el-burgos\/#organizationLogo","width":500,"height":500},"image":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/07\/el-villarreal-b-resucita-ante-el-burgos\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/AgenteLibre_dig","https:\/\/www.instagram.com\/agentelibre_dig\/"]},{"@type":"Person","@id":"https:\/\/agentelibredigital.com\/index.php\/author\/rafael-pereda\/#author","url":"https:\/\/agentelibredigital.com\/index.php\/author\/rafael-pereda\/","name":"Rafael Pereda","image":{"@type":"ImageObject","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/07\/el-villarreal-b-resucita-ante-el-burgos\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b011881c808245d96da0fec527c19d4905183fa8f648250e570f070e9c6c144f?s=96&d=mm&r=g","width":96,"height":96,"caption":"Rafael Pereda"}},{"@type":"WebPage","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/07\/el-villarreal-b-resucita-ante-el-burgos\/#webpage","url":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/07\/el-villarreal-b-resucita-ante-el-burgos\/","name":"El Villarreal B resucita ante el Burgos \u2013 Agente Libre Digital","description":"El Villarreal B resucita ante el Burgos La buena segunda parte blanquinegra no es suficiente para igualar el marcador y se llevan otra derrota a domicilio","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/agentelibredigital.com\/#website"},"breadcrumb":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/07\/el-villarreal-b-resucita-ante-el-burgos\/#breadcrumblist"},"author":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/rafael-pereda\/#author"},"creator":{"@id":"https:\/\/agentelibredigital.com\/index.php\/author\/rafael-pereda\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/burgos-villarreal-1.jpg","@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/07\/el-villarreal-b-resucita-ante-el-burgos\/#mainImage","width":1890,"height":1890,"caption":"Pau Navarro celebrando el gol junto a Pablo I\u00f1iguez. Fuente Cantera Grogueta"},"primaryImageOfPage":{"@id":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/07\/el-villarreal-b-resucita-ante-el-burgos\/#mainImage"},"datePublished":"2024-04-07T19:03:55+02:00","dateModified":"2024-04-07T19:03:55+02:00"},{"@type":"WebSite","@id":"https:\/\/agentelibredigital.com\/#website","url":"https:\/\/agentelibredigital.com\/","name":"agentelibredigital.com","alternateName":"Agente Libre","description":"La nueva generaci\u00f3n del periodismo deportivo.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/agentelibredigital.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Agente Libre Digital \u2013 La nueva generaci\u00f3n del periodismo deportivo.","og:type":"article","og:title":"El Villarreal B resucita ante el Burgos \u2013 Agente Libre Digital","og:description":"El Villarreal B resucita ante el Burgos La buena segunda parte blanquinegra no es suficiente para igualar el marcador y se llevan otra derrota a domicilio","og:url":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/07\/el-villarreal-b-resucita-ante-el-burgos\/","og:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/burgos-villarreal-1.jpg","og:image:secure_url":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/burgos-villarreal-1.jpg","og:image:width":1890,"og:image:height":1890,"article:published_time":"2024-04-07T17:03:55+00:00","article:modified_time":"2024-04-07T17:03:55+00:00","twitter:card":"summary","twitter:site":"@AgenteLibre_dig","twitter:title":"El Villarreal B resucita ante el Burgos \u2013 Agente Libre Digital","twitter:description":"El Villarreal B resucita ante el Burgos La buena segunda parte blanquinegra no es suficiente para igualar el marcador y se llevan otra derrota a domicilio","twitter:creator":"@AgenteLibre_dig","twitter:image":"https:\/\/agentelibredigital.com\/wp-content\/uploads\/2024\/04\/burgos-villarreal-1.jpg"},"aioseo_meta_data":{"post_id":"17381","title":null,"description":"#post_title La buena segunda parte blanquinegra no es suficiente para igualar el marcador y se llevan otra derrota a domicilio","keywords":[],"keyphrases":{"focus":{"keyphrase":"Burgos","score":85,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-04-07 17:03:55","updated":"2025-06-04 21:52:01","seo_analyzer_scan_date":null,"focus_keyword":"Burgos","additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/\" title=\"LaLiga Hypermotion\">LaLiga Hypermotion<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl Villarreal B resucita ante el Burgos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/agentelibredigital.com"},{"label":"LaLiga Hypermotion","link":"https:\/\/agentelibredigital.com\/index.php\/category\/laliga-hypermotion\/"},{"label":"El Villarreal B resucita ante el Burgos","link":"https:\/\/agentelibredigital.com\/index.php\/2024\/04\/07\/el-villarreal-b-resucita-ante-el-burgos\/"}],"_links":{"self":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/17381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/comments?post=17381"}],"version-history":[{"count":1,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/17381\/revisions"}],"predecessor-version":[{"id":17405,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/posts\/17381\/revisions\/17405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media\/17404"}],"wp:attachment":[{"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/media?parent=17381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/categories?post=17381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentelibredigital.com\/index.php\/wp-json\/wp\/v2\/tags?post=17381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}